{"text_format":"1","workbook":"xlsx","n_sheets":9,"sheets":["Copyright","Cover","Instruction","All Result","Sheet1","FW nonmetal nonplant","FW nonmetal nonplant_WS","FW nonmetal plant","FW nonmetal plant_WS"],"not_rendered":{"charts":0,"images":0,"macros":1,"external_links":0,"defined_names":3,"comments":3,"pivot_tables":0},"unopened":[],"bounds":{"document_bytes":16777216,"sheet_cells":100000,"rows_first":2000,"rows_last":500,"rows_between":2000,"halvings":0,"cell_chars":16384,"cell_head_chars":4096},"cells_cut":0,"cells_raw":0,"read":"whole","date_system":"1900"}

{"sheet":"Copyright","index":0,"n_rows":0,"n_cols":0,"rows_kept":0,"cut":false,"hidden":false,"merged":[]}

{"sheet":"Cover","index":1,"n_rows":20,"n_cols":7,"rows_kept":20,"cut":false,"hidden":false,"merged":[[18,6,18,8],[14,6,14,8],[13,6,13,8],[4,4,4,10],[9,6,9,8],[12,6,12,8],[5,5,6,9]]}
[]
[]
[]
[]
[null,null,null,null,"Ecotoxicity Data Quality Assessment Method V2.4"]
[null,null,null,null,null,"To be used to assess the quality of data used for the Australian and New Zealand Guidelines for Fresh and Marine Water Quality (including sediment) and the Australian National Environment Protection (Assessment of Site Contamination) Measure"]
[]
[]
[]
[null,null,null,null,null,null,"Developed by "]
[]
[]
[null,null,null,null,null,null,"Zoe Zhang"]
[null,null,null,null,null,null,"   Dr. Michael Warne"]
[null,null,null,null,null,null,"Alison Vieritz "]
[]
[]
[]
[null,null,null,null,null,null,"Water Quality & Investigations "]
[null,null,null,null,null,"                 Department of Science, Information Technology and Innovation"]

{"sheet":"Instruction","index":2,"n_rows":21,"n_cols":10,"rows_kept":21,"cut":false,"hidden":false,"merged":[[27,6,27,16],[14,6,14,7],[5,4,5,7]]}
[]
[]
[null,"Click here to see \"All Result\" -->","All Result"]
[]
[]
[null,null,null,null,"Freshwater "]
[]
[null,"Tabs contain questionaries -->           ","Freshwater/metal/nonplant",null,"Freshwater/non-metal/non-plant ",null,null,"Freshwater/metal/plant",null,"Freshwater/non-metal/plant"]
[]
[]
[]
[null,"Tabs contain score of paper and short answers to questions -->","Freshwater/metal/nonplant Worksheet",null,"Freshwater/non-metal/non-plant Worksheet",null,null,"Freshwater/metal/plant Worksheet",null,"Freshwater/non-metal/plant/ Worksheet"]
[]
[]
[null,null,"Marine ",null,null,null,"Terrestrial",null,null,"Sediment "]
[]
[null,"Tab contain questionaries -->","Marine or estuarine/non-plant",null,"Marine or estuarine/Plant",null,null,"Terrestrial Data QA",null,"Sediment Data QA"]
[]
[]
[]
[null,"Tab Contains all scores of paper --> ","Marine or estuarine/non-Plant Worksheet",null,"Marine or estuarine/Plant_Worksheet",null,null,"Terrestrial Quality",null,"Sediment Quality"]

{"sheet":"All Result","index":3,"n_rows":272,"n_cols":24,"rows_kept":272,"cut":false,"hidden":false,"merged":[]}
["Chemical:","PFOS"]
["Medium:","Freshwater"]
[{"$f":"'FW nonmetal plant'!C2","v":"Category"},{"$f":"'FW nonmetal plant'!C3","v":"Paper and data unique identifier(eg. 1-1,10-150)"},{"$f":"'FW nonmetal plant'!C70","v":"Total score"},{"$f":"'FW nonmetal plant'!C72","v":"Quality Score"},"Comment ",{"$f":"'FW nonmetal plant'!G3","v":"Species (Scientific name)"},{"$f":"'FW nonmetal plant'!G4","v":"Lifestage"},{"$f":"'FW nonmetal plant'!G5","v":"Exposure duration"},{"$f":"'FW nonmetal plant'!G6","v":"Measure of toxicity"},{"$f":"'FW nonmetal plant'!G7","v":"Toxicity endpoint"},{"$f":"'FW nonmetal plant'!G8","v":"Toxicity value"},{"$f":"'FW nonmetal plant'!J2","v":"Taxonomic group"},{"$f":"'FW nonmetal plant'!J3","v":"Phylum"},{"$f":"'FW nonmetal plant'!J4","v":"Class"},{"$f":"'FW nonmetal plant'!J5","v":"Media"},{"$f":"'FW nonmetal plant'!J6","v":"Temperature "},{"$f":"'FW nonmetal plant'!J7","v":"Acute Or Chronic "},{"$f":"'FW nonmetal plant'!J8","v":"PH"},"Hardness","Citation","Citation No.","Vessel Material Type","Chemical form","Nominal/Measured"]
["Freshwater/non-metal/non- plant","3001-2",61,0.67032967032967028,"The highest possible grade for this datum is acceptable.","Daphnia magna","<24hr neonate","21 day","LOEC","Reproduction","8 mg/L","Macroinvertebrate","Arthropoda","Branchiopoda","M4 culture medium ",20,"Chronic",7,"N.A.","Liang, R., J. He, Y. Shi, Z. Li, S. Sarvajayakesavalu, Y. Baninla, F. Guo, J. Chen, X. Xu and Y. Lu. 2017. Effects of perfluorooctane sulfonate on immobilization, heartbeat, reproductive and biochemical performance of Daphnia magna. Chemosphere 168: 1613-1618.","3001","Beakers - material not stated","PFOS-K > 98% purity from Fluka (CAS RN: 2795-39-3)","Nominal concs"]
["Freshwater/non-metal/non- plant","3001-3",61,0.67032967032967028,"The highest possible grade for this datum is acceptable.","Daphnia magna","<24hr neonate","21 day","LOEC","Reproduction","4 mg/L","Macroinvertebrate","Arthropoda","Branchiopoda","M4 culture medium ",20,"Chronic",7,"N.A.","Liang, R., J. He, Y. Shi, Z. Li, S. Sarvajayakesavalu, Y. Baninla, F. Guo, J. Chen, X. Xu and Y. Lu. 2017. Effects of perfluorooctane sulfonate on immobilization, heartbeat, reproductive and biochemical performance of Daphnia magna. Chemosphere 168: 1613-1618.","3001","Beakers - material not stated","PFOS-K > 98% purity from Fluka (CAS RN: 2795-39-3)","Nominal concs"]
["Freshwater/non-metal/non- plant","3001-4",61,0.67032967032967028,"The highest possible grade for this datum is acceptable.","Daphnia magna","<24hr neonate","21 day","LOEC","Reproduction","16 mg/L","Macroinvertebrate","Arthropoda","Branchiopoda","M4 culture medium ",20,"Chronic",7,"N.A.","Liang, R., J. He, Y. Shi, Z. Li, S. Sarvajayakesavalu, Y. Baninla, F. Guo, J. Chen, X. Xu and Y. Lu. 2017. Effects of perfluorooctane sulfonate on immobilization, heartbeat, reproductive and biochemical performance of Daphnia magna. Chemosphere 168: 1613-1618.","3001","Beakers - material not stated","PFOS-K > 98% purity from Fluka (CAS RN: 2795-39-3)","Nominal concs"]
["Freshwater/non-metal/non- plant","3001-5",61,0.67032967032967028,"The highest possible grade for this datum is acceptable.","Daphnia magna","<24hr neonate","21 day","NOEC","Reproduction","8 mg/L","Macroinvertebrate","Arthropoda","Branchiopoda","M4 culture medium ",20,"Chronic",7,"N.A.","Liang, R., J. He, Y. Shi, Z. Li, S. Sarvajayakesavalu, Y. Baninla, F. Guo, J. Chen, X. Xu and Y. Lu. 2017. Effects of perfluorooctane sulfonate on immobilization, heartbeat, reproductive and biochemical performance of Daphnia magna. Chemosphere 168: 1613-1618.","3001","Beakers - material not stated","PFOS-K > 98% purity from Fluka (CAS RN: 2795-39-3)","Nominal concs"]
["Freshwater/non-metal/non- plant","3003-1",64,0.70329670329670335,"","Rana pipiens","Tadpoles","40 days","NOEC","Development","10 µg/L","Amphibian","Chordata","Amphibia","UV irradiated well water","20±2","Chronic","not stated","N.A.","Hoover, G.M., M.F. Chislock, B.J. Tornabene, S.C. Guffey, Y.J. Choi, C. De Perre, J.T. Hoverman, L.S. Lee and M.S. Sepulveda. 2017. Uptake and depuration of four per/polyfluoroalkyl substances (PFASs) in northern leopard frog Rana pipiens tadpoles. Environmental Science and Technology Letters 4: 399-403","3003","Plastic aquaria","PFOS, form not stated, 98% purity from Sigma Aldrich","Measured"]
["Freshwater/non-metal/non- plant","3003-2",64,0.70329670329670335,"","Rana pipiens","juvenile","40 days","LOEC","Development","100 µg/L","Amphibian","Chordata","Amphibia","UV irradiated well water",20,"Chronic","not stated","N.A.","Hoover, G.M., M.F. Chislock, B.J. Tornabene, S.C. Guffey, Y.J. Choi, C. De Perre, J.T. Hoverman, L.S. Lee and M.S. Sepulveda. 2017. Uptake and depuration of four per/polyfluoroalkyl substances (PFASs) in northern leopard frog Rana pipiens tadpoles. Environmental Science and Technology Letters 4: 399-403","3003","Plastic aquaria","PFOS, form not stated, 98% purity from Sigma Aldrich","Measured"]
["Freshwater/non-metal/non- plant","3004-2",60,0.65934065934065933,"The highest possible grade for this datum is acceptable.","Dugesia japonica","Fragment","10 day","LOEC","Reproduction","0.5 mg/L","Macroinvertebrate","Platyhelminthes","Trepaxonemata","Aerated tap water with dimethyl sulfoxide","22oC","Acute ","Not stated","Not stated","Yuan, Z., J. Zhang, W. Meng and Y. Zhou. 2014. Effects of perfluorooctane sulfonate on behavioural activity, regeneration and antioxidant enzymes in planarian Dugesia japonica. Chemistry and Ecology 30: 187-195","3004","Beakers - material not stated","PFOS-K, 99% purity from Sigma Aldrich","Assumed nominal, not stated"]
["Freshwater/non-metal/non- plant","3006-1",59,0.64835164835164838,"The highest possible grade for this datum is acceptable.","Daphnia magna","<24hr neonate","25 days","NOEC","Reproduction","10 µg/L","Macroinvertebrate","Arthropoda","Branchiopoda","reconstituted hard water","Not stated","Chronic","not stated","N.A.","Jeong, T-Y., M-S. Yuk, J. Jeon and S.D. Kim. 2016. Multigenerational effect of perfluorooctane sulfonate (PFOS) on the individual fitness and population growth of Daphnia magna. Science of the Total Environment 569-570: 1553-1560.\n","3006","Polypropylene beakers","PFOS-K, 99% purity from Fluka","Nominal concs"]
["Freshwater/non-metal/non- plant","3006-2",59,0.64835164835164838,"The highest possible grade for this datum is acceptable.","Daphnia magna","<24hr neonate","25 days","LOEC","Reproduction","100 µg/L","Macroinvertebrate","Arthropoda","Branchiopoda","reconstituted hard water","Not stated","Chronic","not stated","N.A.","Jeong, T-Y., M-S. Yuk, J. Jeon and S.D. Kim. 2016. Multigenerational effect of perfluorooctane sulfonate (PFOS) on the individual fitness and population growth of Daphnia magna. Science of the Total Environment 569-570: 1553-1560.\n","3006","Polypropylene beakers","PFOS-K, 99% purity from Fluka","Nominal concs"]
["Freshwater/non-metal/non- plant","3006-3",59,0.64835164835164838,"The highest possible grade for this datum is acceptable.","Daphnia magna","<24hr neonate","25 days","NOEC","Reproduction","1000 µg/L","Macroinvertebrate","Arthropoda","Branchiopoda","reconstituted hard water","Not stated","Chronic","not stated","N.A.","Jeong, T-Y., M-S. Yuk, J. Jeon and S.D. Kim. 2016. Multigenerational effect of perfluorooctane sulfonate (PFOS) on the individual fitness and population growth of Daphnia magna. Science of the Total Environment 569-570: 1553-1560.\n","3006","Polypropylene beakers","PFOS-K, 99% purity from Fluka","Nominal concs"]
["Freshwater/non-metal/non- plant","3006-4",59,0.64835164835164838,"The highest possible grade for this datum is acceptable.","Daphnia magna","<24hr neonate","25 days","NOEC","Reproduction","10000 µg/L","Macroinvertebrate","Arthropoda","Branchiopoda","reconstituted hard water","Not stated","Chronic","not stated","N.A.","Jeong, T-Y., M-S. Yuk, J. Jeon and S.D. Kim. 2016. Multigenerational effect of perfluorooctane sulfonate (PFOS) on the individual fitness and population growth of Daphnia magna. Science of the Total Environment 569-570: 1553-1560.\n","3006","Polypropylene beakers","PFOS-K, 99% purity from Fluka","Nominal concs"]
["Freshwater/non-metal/non- plant","3011-10",47,0.51648351648351654,"The highest possible grade for this datum is acceptable.","Aedes aegypti","1st instar larvae","20 days","NOEC","Growth","50 µg/L","Macroinvertebrate","Arthropoda","Insecta","Moderately hard water",25,"Chronic","Not stated","N.A.","Olson, A.D. 2017. An investigation into the toxicity, biocomentration, and risk of perfluoroalkyl substances in aquatic taxa. PhD Thesis submitted to the Graduate Facility of Texas Technical University, May 2017. p208","3011","HDPE plastic beakers","PFOS, form or purity not stated","Measured"]
["Freshwater/non-metal/non- plant","3011-3",69,0.75824175824175821,"","Lymnaea stagnalis","Adult","21 day","NOEC","Mortality","3 mg/L","Snail","Mollusca","Gastropoda","Aerated synthetic fresh water","20±1","Chronic","not stated","N.A.","Olson, A.D. 2017. An investigation into the toxicity, biocomentration, and risk of perfluoroalkyl substances in aquatic taxa. PhD Thesis submitted to the Graduate Facility of Texas Technical University, May 2017. p208","3011","Polyethylene beakers","PFOS, form or purity not stated","Measured"]
["Freshwater/non-metal/non- plant","3011-4",69,0.75824175824175821,"","Lymnaea stagnalis","Adult","21 day","LOEC","Mortality","6 mg/L","Snail","Mollusca","Gastropoda","Aerated synthetic fresh water","20±1","Chronic","not stated","N.A.","Olson, A.D. 2017. An investigation into the toxicity, biocomentration, and risk of perfluoroalkyl substances in aquatic taxa. PhD Thesis submitted to the Graduate Facility of Texas Technical University, May 2017. p208","3011","Polyethylene beakers","PFOS, form or purity not stated","Measured"]
["Freshwater/non-metal/non- plant","3011-5",69,0.75824175824175821,"","Lymnaea stagnalis","Juvenile","21 day","NOEC","Growth","25 mg/L","Snail","Mollusca","Gastropoda","Aerated synthetic fresh water","20±1","Chronic","not stated","N.A.","Olson, A.D. 2017. An investigation into the toxicity, biocomentration, and risk of perfluoroalkyl substances in aquatic taxa. PhD Thesis submitted to the Graduate Facility of Texas Technical University, May 2017. p208","3011","Polyethylene beakers","PFOS, form or purity not stated","Measured"]
["Freshwater/non-metal/non- plant","3011-6",69,0.75824175824175821,"","Lymnaea stagnalis","Juvenile","21 day","LOEC","Growth","50 mg/L","Snail","Mollusca","Gastropoda","Aerated synthetic fresh water","20±1","Chronic","not stated","N.A.","Olson, A.D. 2017. An investigation into the toxicity, biocomentration, and risk of perfluoroalkyl substances in aquatic taxa. PhD Thesis submitted to the Graduate Facility of Texas Technical University, May 2017. p208","3011","Polyethylene beakers","PFOS, form or purity not stated","Measured"]
["Freshwater/non-metal/non- plant","3011-8",52,0.5714285714285714,"The highest possible grade for this datum is acceptable.","Aedes aegypti","1st instar larvae","40 days","LOEC","Mortality","50 µg/L","Macroinvertebrate","Arthropoda","Insecta","Moderately hard water",25,"Chronic","Not stated","N.A.","Olson, A.D. 2017. An investigation into the toxicity, biocomentration, and risk of perfluoroalkyl substances in aquatic taxa. PhD Thesis submitted to the Graduate Facility of Texas Technical University, May 2017. p208","3011","HDPE plastic beakers","PFOS, form or purity not stated","Measured"]
["Freshwater/non-metal/non- plant","3011-9",47,0.51648351648351654,"The highest possible grade for this datum is acceptable.","Aedes aegypti","1st instar larvae","20 days","LOEC","Growth","50 µg/L","Macroinvertebrate","Arthropoda","Insecta","Moderately hard water",25,"Chronic","Not stated","N.A.","Olson, A.D. 2017. An investigation into the toxicity, biocomentration, and risk of perfluoroalkyl substances in aquatic taxa. PhD Thesis submitted to the Graduate Facility of Texas Technical University, May 2017. p208","3011","HDPE plastic beakers","PFOS, form or purity not stated","Measured"]
["Freshwater/non-metal/non- plant","3018-10",71,0.78021978021978022,"","Pseudorasbora parva","Not stated","30 days","EC10","Mortality","2.12 mg/L","Fish","Chordata","Actinopterygii","Activated carbon-dechlorinated tap water ","22±2","Chronic",7,"CaCO3 190±0.1 mg/L","Yang, S., F. Xu, F. Wu, S. Wang and B. Zheng. 2014. Development of PFOS and PFOA criteria for the protection of freshwater aquatic life in China. Science of the Total Environment 470-471: 677-683","3018","Beakers - material not stated","PFOS-K, 99% purity from Schultz Company","Measured"]
["Freshwater/non-metal/non- plant","3018-11",71,0.78021978021978022,"","Bufo gargarizans","Tadpoles","30 days","EC10","Mortality","2.00 mg/L","Amphibian","Chordata","Amphibia","Activated carbon-dechlorinated tap water ","22 ± 2","Chronic","7.0 ± 0.5","CaCO3 190 ± 0.1","Yang, S., F. Xu, F. Wu, S. Wang and B. Zheng. 2014. Development of PFOS and PFOA criteria for the protection of freshwater aquatic life in China. Science of the Total Environment 470-471: 677-683","3018","Beakers - material not stated","PFOS-K, 99% purity from Schultz Company","Measured"]
["Freshwater/non-metal/non- plant","3018-12",71,0.78021978021978022,"","Daphnia magna","<24hr neonate","30 day","IC10","Mortality","4.17 mg/L","Microinvertebrate","Arthropoda","Branchiopoda","Activated carbon-dechlorinated tap water ",22,"Chronic",7,"N.A.","Yang, S., F. Xu, F. Wu, S. Wang and B. Zheng. 2014. Development of PFOS and PFOA criteria for the protection of freshwater aquatic life in China. Science of the Total Environment 470-471: 677-683","3018","Beakers - material not stated","PFOS-K, 99% purity from Schultz Company","Measured"]
["Freshwater/non-metal/non- plant","3018-13",71,0.78021978021978022,"","Daphnia magna","<24hr neonate","30 day","IC10","Reproduction","2.26 mg/L","Microinvertebrate","Arthropoda","Branchiopoda","Activated carbon-dechlorinated tap water ",22,"Chronic",7,"N.A.","Yang, S., F. Xu, F. Wu, S. Wang and B. Zheng. 2014. Development of PFOS and PFOA criteria for the protection of freshwater aquatic life in China. Science of the Total Environment 470-471: 677-683","3018","Beakers - material not stated","PFOS-K, 99% purity from Schultz Company","Measured"]
["Freshwater/non-metal/plant","3018-9",68,0.77272727272727271,"","Desmodesmus communis (formerly Scenedesmus quadricauda)","logarithmic growth phase","96 hrs","LC50","Growth inhibition","89.34 mg/L","Microalga","Chlorophyta","Chlorophyceae","M4 culture medium ","22±2","Chronic","7.0±0.5","CaCO3 190±0.1 mg/L","Yang, S., F. Xu, F. Wu, S. Wang and B. Zheng. 2014. Development of PFOS and PFOA criteria for the protection of freshwater aquatic life in China. Science of the Total Environment 470-471: 677-683","3018","Beakers - material not stated","PFOS-K, 99% purity from Schultz Company","Measured"]
["Freshwater/non-metal/non- plant","3020-1",50,0.5494505494505495,"","Cyclops diaptomus","Not stated","35 day","NOEC","Abundance","10 mg/L","Macroinvertebrate","Arthropoda","Maxillopoda","Natural pond water","10-18 (incresed 2 degree each week over the study)","Chronic","8.28-8.37","N.A.","Sanderson, H., T.M. Boudreau, S.A. Mabury, W-J. Cheong and K.R. Solomon. 2002. Ecological impact and environmental fate of perfluorooctane sulfonate on the zooplankton community in indoor microcosms. Environmental Toxicology and Chemistry 21: 1490-1496.","3020","Polyvinyl chloride aquariums","PFOS-K, treatment concs based on PFOS anion from 3M","Measured"]
["Freshwater/non-metal/non- plant","3020-2",50,0.5494505494505495,"","Cyclops diaptomus","Not stated","35 day","LOEC","Survival","30 mg/L","Macroinvertebrate","Arthropoda","Maxillopoda","Natural pond water","10-18 (incresed 2 degree each week over the study)","Chronic","Not stated","N.A.","Sanderson, H., T.M. Boudreau, S.A. Mabury, W-J. Cheong and K.R. Solomon. 2002. Ecological impact and environmental fate of perfluorooctane sulfonate on the zooplankton community in indoor microcosms. Environmental Toxicology and Chemistry 21: 1490-1496.","3020","Polyvinyl chloride aquariums","PFOS-K, treatment concs based on PFOS anion from 3M","Measured"]
["Freshwater/non-metal/non- plant","3023-1",54,0.59340659340659341,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","15 days","NOEC","Growth","200 µg/L","Fish","Chordata","Actinopterygii","Not stated","Not stated","Chronic","Not stated","N.A.","Shi, X., C. Liu, G. Wu and B. Zhou. 2009. Waterborne exposure to PFOS causes disruption of the hypothalamus-pituitary-thyroid axis in zebrafish larvae. Chemosphere 77: 1010-1018","3023","Glass beakers","PFOS-K, >99% from Tokyo Kasei Kogyo Co.","Nominal concs"]
["Freshwater/non-metal/non- plant","3023-2",54,0.59340659340659341,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","15 days","LOEC","Growth","400 µg/L","Fish","Chordata","Actinopterygii","Not stated","Not stated","Chronic","Not stated","N.A.","Shi, X., C. Liu, G. Wu and B. Zhou. 2009. Waterborne exposure to PFOS causes disruption of the hypothalamus-pituitary-thyroid axis in zebrafish larvae. Chemosphere 77: 1010-1018","3023","Glass beakers","PFOS-K, >99% from Tokyo Kasei Kogyo Co.","Nominal concs"]
["Freshwater/non-metal/non- plant","3026-1",47,0.51648351648351654,"The highest possible grade for this datum is acceptable.","Caenorhabditis elegans","Adult","24 hrs","LC50","Mortality","4.522 mg/L","Microinvertebrates","Nematoda","Chromadorea","Nematode Growth Medium","20oC","Acute ","Not stated","N.A.","Kim, H.M., N.P. Long, S.J. Yoon, N.H. Anh, S.J. Kim, J.H. Park and S.W. Kwon. 2020. Omics approach reveals perturbation of metabolism and pheontypie in Caenorhabditis elegans triggered by perfluorinated compounds. Science of the Total Environment 703: 135500","3026","NGM plate - material not stated","PFOS, form and purity not stated from Sgima Aldrich","Nominal concs"]
["Freshwater/non-metal/non- plant","3026-2",52,0.5714285714285714,"The highest possible grade for this datum is acceptable.","Caenorhabditis elegans","Adult","5 day","LOEC","Reproduction","500 ug/L","Microinvertebrates","Nematoda","Chromadorea","Nematode Growth Medium","20oC","Acute ","Not stated","N.A.","Kim, H.M., N.P. Long, S.J. Yoon, N.H. Anh, S.J. Kim, J.H. Park and S.W. Kwon. 2020. Omics approach reveals perturbation of metabolism and pheontypie in Caenorhabditis elegans triggered by perfluorinated compounds. Science of the Total Environment 703: 135500","3026","NGM plate - material not stated","PFOS, form and purity not stated from Sgima Aldrich","Nominal concs"]
["Freshwater/non-metal/non- plant","3027-1",53,0.58241758241758246,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","4 day","LC50","Mortality","44011 ug/L","Fish","Chordata","Actinopterygii","Not stated","Not stated","Acute ","Not stated","N.A.","Blanc,M., J. Ruegg, N. Scherbak, and S.H. Keiter. 2019. Environmental Chemicals Differentially Affect Epigenetic-Related Mechanisms in the Zebrafish Liver (ZF-L) Cell Line and in Zebrafish Embryos. Aquat. Toxicol.215:105272-9999","3027","24 well plates","PFOS-K, >98% (CAS RN: 2795-39-3) from Sigma Aldrich","Nominal concs"]
["Freshwater/non-metal/non- plant","3028-1",56,0.61538461538461542,"The highest possible grade for this datum is acceptable.","Lithobates catesbeiana (formerly Rana catesbeiana)","Tadpoles","4 day","LC50","Mortality","144 mg/L","Amphibian","Chordata","Amphibia","Not stated","21oC","Acute ","Not stated","N.A.","Flynn,R.W., M.F. Chislock, M.E. Gannon, S.J. Bauer, B.J. Tornabene, J.T. Hoverman, and M. Sepulveda. 2019. Acute and Chronic Effects of Perfluoroalkyl Substance Mixtures on Larval American Bullfrogs (Rana catesbeiana). Chemosphere236:7 p.","3028","Plastic tubs","PFOS, form or purity not stated from Sigma Aldrich product number #77282-10G","Nominal exposures"]
["Freshwater/non-metal/non- plant","3028-2",56,0.61538461538461542,"The highest possible grade for this datum is acceptable.","Lithobates catesbeiana (formerly Rana catesbeiana)","Tadpoles","72 d","LOEC","Growth","144 ug/L","Amphibian","Chordata","Amphibia","Filtered well water","21oC","Chronic","Not stated","N.A.","Flynn,R.W., M.F. Chislock, M.E. Gannon, S.J. Bauer, B.J. Tornabene, J.T. Hoverman, and M. Sepulveda. 2019. Acute and Chronic Effects of Perfluoroalkyl Substance Mixtures on Larval American Bullfrogs (Rana catesbeiana). Chemosphere236:7 p.","3028","Plastic tubs","PFOS, form or purity not stated from Sigma Aldrich product number #77282-10G","Nominal exposures"]
["Freshwater/non-metal/non- plant","3029-1",59,0.64835164835164838,"","Xenopus tropicalis (formerly Silurana tropicalis)","embryo","58 days","NOEC","Growth","590 ug/L","Amphibian","Chordata","Amphibia","Dechlorinated tap water","25.5-26.5oC","Chronic","Not stated","N.A.","Fort,D.J., M.B. Mathis, P.D. Guiney, and J.A. Weeks. 2019. Evaluation of the Developmental Toxicity of Perfluorooctanesulfonate in the Anuran, Silurana tropicalis. J. Appl. Toxicol.39(2): 365-374","3029","Not stated","PFOS, form not stated, 98% purity from Sigma Aldrich (CAS RN: 1763-23-1)","Measured concs (at start and end of exposure)"]
["Freshwater/non-metal/non- plant","3029-2",59,0.64835164835164838,"","Xenopus tropicalis (formerly Silurana tropicalis)","embryo","58 days","LOEC","Growth","1050 ug/L","Amphibian","Chordata","Amphibia","Dechlorinated tap water","25.5-26.5oC","Chronic","Not stated","N.A.","Fort,D.J., M.B. Mathis, P.D. Guiney, and J.A. Weeks. 2019. Evaluation of the Developmental Toxicity of Perfluorooctanesulfonate in the Anuran, Silurana tropicalis. J. Appl. Toxicol.39(2): 365-374","3029","Not stated","PFOS, form not stated, 98% purity from Sigma Aldrich (CAS RN: 1763-23-1)","Measured concs (at start and end of exposure)"]
["Freshwater/non-metal/non- plant","3029-3",59,0.64835164835164838,"","Xenopus tropicalis (formerly Silurana tropicalis)","embryo","58 days","NOEC","Mortality","1050 ug/L","Amphibian","Chordata","Amphibia","Dechlorinated tap water","25.5-26.5oC","Chronic","Not stated","N.A.","Fort,D.J., M.B. Mathis, P.D. Guiney, and J.A. Weeks. 2019. Evaluation of the Developmental Toxicity of Perfluorooctanesulfonate in the Anuran, Silurana tropicalis. J. Appl. Toxicol.39(2): 365-374","3029","Not stated","PFOS, form not stated, 98% purity from Sigma Aldrich (CAS RN: 1763-23-1)","Measured concs (at start and end of exposure)"]
["Freshwater/non-metal/non- plant","3029-4",59,0.64835164835164838,"","Xenopus tropicalis (formerly Silurana tropicalis)","embryo","150 days post metamorphosis","NOEC","Mortality","1100 ug/L","Amphibian","Chordata","Amphibia","Dechlorinated tap water","25.5-26.5oC","Chronic","Not stated","N.A.","Fort,D.J., M.B. Mathis, P.D. Guiney, and J.A. Weeks. 2019. Evaluation of the Developmental Toxicity of Perfluorooctanesulfonate in the Anuran, Silurana tropicalis. J. Appl. Toxicol.39(2): 365-374","3029","Not stated","PFOS, form not stated, 98% purity from Sigma Aldrich (CAS RN: 1763-23-1)","Measured concs (at start and end of exposure)"]
["Freshwater/non-metal/non- plant","3029-5",59,0.64835164835164838,"","Xenopus tropicalis (formerly Silurana tropicalis)","embryo","150 days post metamorphosis","NOEC","Growth","1100 ug/L","Amphibian","Chordata","Amphibia","Dechlorinated tap water","25.5-26.5oC","Chronic","Not stated","N.A.","Fort,D.J., M.B. Mathis, P.D. Guiney, and J.A. Weeks. 2019. Evaluation of the Developmental Toxicity of Perfluorooctanesulfonate in the Anuran, Silurana tropicalis. J. Appl. Toxicol.39(2): 365-374","3029","Not stated","PFOS, form not stated, 98% purity from Sigma Aldrich (CAS RN: 1763-23-1)","Measured concs (at start and end of exposure)"]
["Freshwater/non-metal/non- plant","3029-6",59,0.64835164835164838,"","Xenopus tropicalis (formerly Silurana tropicalis)","Embryo, NF stage 10","150 days post metamorphosis","NOEC","Reproduction","290 ug/L","Amphibian","Chordata","Amphibia","Dechlorinated tap water","25.5-26.5oC","Chronic","7.5±0.3","N.A.","Fort,D.J., M.B. Mathis, P.D. Guiney, and J.A. Weeks. 2019. Evaluation of the Developmental Toxicity of Perfluorooctanesulfonate in the Anuran, Silurana tropicalis. J. Appl. Toxicol.39(2): 365-374","3029","Not stated","PFOS, form not stated, 98% purity from Sigma Aldrich (CAS RN: 1763-23-1)","Measured concs (at start and end of exposure)"]
["Freshwater/non-metal/non- plant","3029-7",59,0.64835164835164838,"","Xenopus tropicalis (formerly Silurana tropicalis)","embryo","150 days post metamorphosis","LOEC","Reproduction","620 ug/L","Amphibian","Chordata","Amphibia","Dechlorinated tap water","25.5-26.5oC","Chronic","Not stated","N.A.","Fort,D.J., M.B. Mathis, P.D. Guiney, and J.A. Weeks. 2019. Evaluation of the Developmental Toxicity of Perfluorooctanesulfonate in the Anuran, Silurana tropicalis. J. Appl. Toxicol.39(2): 365-374","3029","Not stated","PFOS, form not stated, 98% purity from Sigma Aldrich (CAS RN: 1763-23-1)","Measured concs (at start and end of exposure)"]
["Freshwater/non-metal/non- plant","3029-8",64,0.70329670329670335,"","Xenopus tropicalis (formerly Silurana tropicalis)","embryo","58 days","NOEC","Growth","620 ug/L","Amphibian","Chordata","Amphibia","Dechlorinated tap water","25.5-26.5oC","Chronic","Not stated","N.A.","Fort,D.J., M.B. Mathis, P.D. Guiney, and J.A. Weeks. 2019. Evaluation of the Developmental Toxicity of Perfluorooctanesulfonate in the Anuran, Silurana tropicalis. J. Appl. Toxicol.39(2): 365-374","3029","Not stated","PFOS, form not stated, 98% purity from Sigma Aldrich (CAS RN: 1763-23-1)","Measured concs (at start and end of exposure)"]
["Freshwater/non-metal/non- plant","3029-9",64,0.70329670329670335,"","Xenopus tropicalis (formerly Silurana tropicalis)","embryo","58 days","LOEC","Growth","1050 ug/L","Amphibian","Chordata","Amphibia","Dechlorinated tap water","25.5-26.5oC","Chronic","Not stated","N.A.","Fort,D.J., M.B. Mathis, P.D. Guiney, and J.A. Weeks. 2019. Evaluation of the Developmental Toxicity of Perfluorooctanesulfonate in the Anuran, Silurana tropicalis. J. Appl. Toxicol.39(2): 365-374","3029","Not stated","PFOS, form not stated, 98% purity from Sigma Aldrich (CAS RN: 1763-23-1)","Measured concs (at start and end of exposure)"]
["Freshwater/non-metal/non- plant","3030-1",53,0.58241758241758246,"The highest possible grade for this datum is acceptable.","Oryzias latipes","Adult","21 day","LOEC","Reproduction","1000 ug/L","Fish","Chordata","Actinopterygii","Fish culture water","25°C","Chronic","7-7.4","N.A.","Kang,J.S., T.G. Ahn, and J.W. Park. 2019. Perfluorooctanoic Acid (PFOA) and Perfluooctane Sulfonate (PFOS) Induce Different Modes of Action in Reproduction to Japanese Medaka (Oryzias latipes). J. Hazard. Mater.368:97-103","3030","Glass tanks","PFOS, 98% purity CAS RN: 1763-23-1 from Sigma Aldrich","Assumed to be nominal. Not stated"]
["Freshwater/non-metal/non- plant","3030-2",53,0.58241758241758246,"The highest possible grade for this datum is acceptable.","Oryzias latipes","Adult","14 days","LOEC","Reproduction","1000 ug/L","Fish","Chordata","Actinopterygii","Fish culture water","25°C","Acute ","7-7.4","N.A.","Kang,J.S., T.G. Ahn, and J.W. Park. 2019. Perfluorooctanoic Acid (PFOA) and Perfluooctane Sulfonate (PFOS) Induce Different Modes of Action in Reproduction to Japanese Medaka (Oryzias latipes). J. Hazard. Mater.368:97-103","3030","Glass tanks","PFOS, 98% purity CAS RN: 1763-23-1 from Sigma Aldrich","Assumed to be nominal. Not stated"]
["Freshwater/non-metal/non- plant","3030-3",53,0.58241758241758246,"The highest possible grade for this datum is acceptable.","Oryzias latipes","Adult","7 days","LOEC","Reproduction","1000 ug/L","Fish","Chordata","Actinopterygii","Fish culture water","25°C","Acute ","7-7.4","N.A.","Kang,J.S., T.G. Ahn, and J.W. Park. 2019. Perfluorooctanoic Acid (PFOA) and Perfluooctane Sulfonate (PFOS) Induce Different Modes of Action in Reproduction to Japanese Medaka (Oryzias latipes). J. Hazard. Mater.368:97-103","3030","Glass tanks","PFOS, 98% purity CAS RN: 1763-23-1 from Sigma Aldrich","Assumed to be nominal. Not stated"]
["Freshwater/non-metal/non- plant","3031-1",68,0.74725274725274726,"","Chironomus riparius","larvae, F6","150 days","LOEC","Growth","10 ug/L","Insect","Arthropoda","Insecta","Reconstituted water","18.7 and 21.2oC","Chronic","7.9-8.2","350-590","Marziali, L., F. Rosignoli, S. Valsecchi, S. Polesello and F. Stefani. (2019). Effects of perfluoralkyl substances (PFASs) on a multigenerational scale: a case study with Chironomus riparius (Diptera, Chironomidae). Environmental Toxicology and Chemistry 38: 988-999","3031","Glass","\"Pure PFOS from Sigma-Aldrich\"","Nominal exposures. Only one exposure concentration and time not defined"]
["Freshwater/non-metal/non- plant","3031-2",68,0.74725274725274726,"","Chironomus riparius","larvae, F1","25 days","LOEC","Growth","10 ug/L","Insect","Arthropoda","Insecta","Reconstituted water","18.7 and 21.2oC","Chronic","7.9-8.2","350-590","Marziali, L., F. Rosignoli, S. Valsecchi, S. Polesello and F. Stefani. (2019). Effects of perfluoralkyl substances (PFASs) on a multigenerational scale: a case study with Chironomus riparius (Diptera, Chironomidae). Environmental Toxicology and Chemistry 38: 988-999","3031","Glass","\"Pure PFOS from Sigma-Aldrich\"","Nominal exposures. Only one exposure concentration and time not defined"]
["Freshwater/non-metal/non- plant","3031-3",68,0.74725274725274726,"","Chironomus riparius","larvae, F2","150 days","LOEC","Reproduction","10 ug/L","Insect","Arthropoda","Insecta","Reconstituted water","18.7 and 21.2oC","Chronic","7.9-8.2","350-590","Marziali, L., F. Rosignoli, S. Valsecchi, S. Polesello and F. Stefani. (2019). Effects of perfluoralkyl substances (PFASs) on a multigenerational scale: a case study with Chironomus riparius (Diptera, Chironomidae). Environmental Toxicology and Chemistry 38: 988-999","3031","Glass","\"Pure PFOS from Sigma-Aldrich\"","Nominal exposures. Only one exposure concentration and time not defined"]
["Freshwater/non-metal/non- plant","3031-4",62,0.68131868131868134,"","Chironomus riparius","Larvae, F6","150 days post fertilisation","LOEC","Development","10 ug/L","Macroinvertebrate","Arthropoda","Insecta","Reconstituted water","18.7 and 21.2oC","Chronic","7.9-8.2","350-590","Marziali, L., F. Rosignoli, S. Valsecchi, S. Polesello and F. Stefani. (2019). Effects of perfluoralkyl substances (PFASs) on a multigenerational scale: a case study with Chironomus riparius (Diptera, Chironomidae). Environmental Toxicology and Chemistry 38: 988-999","3031","Glass","\"Pure PFOS from Sigma-Aldrich\"","Nominal exposures. Only one exposure concentration and time not defined"]
["Freshwater/non-metal/non- plant","3032-1",68,0.74725274725274726,"The highest possible grade for this datum is acceptable.","Daphnia magna","Neonate","21 day","LOEC","Reproduction","620 ug/L","Macroinvertebrate","Arthropoda","Branchiopoda","Daphnia culture media","19-21oC","Chronic","7.9-8.2","N.A.","Yang, H.B., Zhao, Y.Z., Tang, Y., Gong, H.Q., Guo, F., Sun, W.H., Liu, S.S., Tan, H. and Chen, F. (2019). Antioxidant defence system is responsible for the toxicological interactions of mixtures: A case study on PFOS and PFOA in Daphnia magna. Science of the Total Environment. (Published June 2019)","3032","Glass beakers","PFOS-K, 98% purity (CASRN 2795-39-3) from Sigma Aldrich","Assumed to be nominal"]
["Freshwater/non-metal/non- plant","3032-2",68,0.74725274725274726,"The highest possible grade for this datum is acceptable.","Daphnia magna","Neonate","21 day","NOEC","Growth","620 ug/L","Macroinvertebrate","Arthropoda","Branchiopoda","Daphnia culture media","19-21oC","Chronic","7.9-8.2","N.A.","Yang, H.B., Zhao, Y.Z., Tang, Y., Gong, H.Q., Guo, F., Sun, W.H., Liu, S.S., Tan, H. and Chen, F. (2019). Antioxidant defence system is responsible for the toxicological interactions of mixtures: A case study on PFOS and PFOA in Daphnia magna. Science of the Total Environment. (Published June 2019)","3032","Glass beakers","PFOS-K, 98% purity (CASRN 2795-39-3) from Sigma Aldrich","Assumed to be nominal"]
["Freshwater/non-metal/non- plant","3032-3",68,0.74725274725274726,"The highest possible grade for this datum is acceptable.","Daphnia magna","Neonate","21 day","LOEC","Growth","940 ug/L","Macroinvertebrate","Arthropoda","Branchiopoda","Daphnia culture media","19-21oC","Chronic","7.9-8.2","N.A.","Yang, H.B., Zhao, Y.Z., Tang, Y., Gong, H.Q., Guo, F., Sun, W.H., Liu, S.S., Tan, H. and Chen, F. (2019). Antioxidant defence system is responsible for the toxicological interactions of mixtures: A case study on PFOS and PFOA in Daphnia magna. Science of the Total Environment. (Published June 2019)","3032","Glass beakers","PFOS-K, 98% purity (CASRN 2795-39-3) from Sigma Aldrich","Assumed to be nominal"]
["Freshwater/non-metal/non- plant","3032-4",66,0.72527472527472525,"The highest possible grade for this datum is acceptable.","Daphnia magna","Neonate","21 day","LOEC","Reproduction","620 ug/L","Macroinvertebrate","Arthropoda","Branchiopoda","Daphnia culture medium","19-21oC","Chronic","7.9-8.2","N.A.","Yang, H.B., Zhao, Y.Z., Tang, Y., Gong, H.Q., Guo, F., Sun, W.H., Liu, S.S., Tan, H. and Chen, F. (2019). Antioxidant defence system is responsible for the toxicological interactions of mixtures: A case study on PFOS and PFOA in Daphnia magna. Science of the Total Environment. (Published June 2019)","3032","Glass beakers","PFOS-K, 98% purity (CASRN 2795-39-3) from Sigma Aldrich","Assumed to be nominal"]
["Freshwater/non-metal/non- plant","3032-5",66,0.72527472527472525,"The highest possible grade for this datum is acceptable.","Daphnia magna","Neonate","21 day","LOEC","Reproduction","620 ug/L","Macroinvertebrate","Arthropoda","Branchiopoda","Daphnia culture medium","19-21oC","Chronic","7.9-8.2","N.A.","Yang, H.B., Zhao, Y.Z., Tang, Y., Gong, H.Q., Guo, F., Sun, W.H., Liu, S.S., Tan, H. and Chen, F. (2019). Antioxidant defence system is responsible for the toxicological interactions of mixtures: A case study on PFOS and PFOA in Daphnia magna. Science of the Total Environment. (Published June 2019)","3032","Glass beakers","PFOS-K, 98% purity (CASRN 2795-39-3) from Sigma Aldrich","Assumed to be nominal"]
["Freshwater/non-metal/non- plant","3033-1",55,0.60439560439560436,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","120 days","NOEC","Reproduction","100 ug/L","Fish","Chordata","Actinopterygii","Culture medium","28oC","Chronic","Not stated","N.A.","Du,J., J. Tang, S. Xu, J. Ge, Y. Dong, H. Li, and M. Jin. 2018. Parental Transfer of Perfluorooctane Sulfonate and ZnO Nanoparticles Chronic Co-Exposure and Inhibition of Growth in F1 Offspring. Regul. Toxicol. Pharmacol.98:41-49","3033","Glass beakers","PFOS >98% purity (CASRN 2795-39-3) from Sigma ","Nominal"]
["Freshwater/non-metal/non- plant","3033-10",55,0.60439560439560436,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","120 days","NOEC","Growth","200 ug/L","Fish","Chordata","Actinopterygii","Culture medium","28oC","Chronic","Not stated","N.A.","Du,J., J. Tang, S. Xu, J. Ge, Y. Dong, H. Li, and M. Jin. 2018. Parental Transfer of Perfluorooctane Sulfonate and ZnO Nanoparticles Chronic Co-Exposure and Inhibition of Growth in F1 Offspring. Regul. Toxicol. Pharmacol.98:41-49","3033","PFOS >98% purity (CASRN 2795-39-3) from Sigma ","Nominal. F1 not exposed, but F0 parents exposed - valid?"]
["Freshwater/non-metal/non- plant","3033-11",60,0.65934065934065933,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","120 days","NOEC","Growth","50 ug/L","Fish","Chordata","Actinopterygii","Culture medium","28oC","Chronic","Not stated","N.A.","Du,J., J. Tang, S. Xu, J. Ge, Y. Dong, H. Li, and M. Jin. 2018. Parental Transfer of Perfluorooctane Sulfonate and ZnO Nanoparticles Chronic Co-Exposure and Inhibition of Growth in F1 Offspring. Regul. Toxicol. Pharmacol.98:41-49","3033","Glass beakers","PFOS >98% purity (CASRN 2795-39-3) from Sigma ","Nominal"]
["Freshwater/non-metal/non- plant","3033-12",60,0.65934065934065933,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","120 days","NOEC","Growth","200 ug/L","Fish","Chordata","Actinopterygii","Culture medium","28oC","Chronic","Not stated","N.A.","Du,J., J. Tang, S. Xu, J. Ge, Y. Dong, H. Li, and M. Jin. 2018. Parental Transfer of Perfluorooctane Sulfonate and ZnO Nanoparticles Chronic Co-Exposure and Inhibition of Growth in F1 Offspring. Regul. Toxicol. Pharmacol.98:41-49","3033","Glass beakers","PFOS >98% purity (CASRN 2795-39-3) from Sigma ","Nominal"]
["Freshwater/non-metal/non- plant","3033-13",60,0.65934065934065933,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","120 days","LOEC","Growth","200 ug/L","Fish","Chordata","Actinopterygii","Culture medium","28oC","Chronic","Not stated","N.A.","Du,J., J. Tang, S. Xu, J. Ge, Y. Dong, H. Li, and M. Jin. 2018. Parental Transfer of Perfluorooctane Sulfonate and ZnO Nanoparticles Chronic Co-Exposure and Inhibition of Growth in F1 Offspring. Regul. Toxicol. Pharmacol.98:41-49","3033","Glass beakers","PFOS >98% purity (CASRN 2795-39-3) from Sigma ","Nominal"]
["Freshwater/non-metal/non- plant","3033-14",60,0.65934065934065933,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","120 days","LOEC","Reproduction","200 ug/L","Fish","Chordata","Actinopterygii","Culture medium","28oC","Chronic","Not stated","N.A.","Du,J., J. Tang, S. Xu, J. Ge, Y. Dong, H. Li, and M. Jin. 2018. Parental Transfer of Perfluorooctane Sulfonate and ZnO Nanoparticles Chronic Co-Exposure and Inhibition of Growth in F1 Offspring. Regul. Toxicol. Pharmacol.98:41-49","3033","PFOS >98% purity (CASRN 2795-39-3) from Sigma ","Nominal. F1 not exposed, but F0 parents exposed - valid?"]
["Freshwater/non-metal/non- plant","3033-15",60,0.65934065934065933,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","120 days","LOEC","Development","200 ug/L","Fish","Chordata","Actinopterygii","Culture medium","28oC","Chronic","Not stated","N.A.","Du,J., J. Tang, S. Xu, J. Ge, Y. Dong, H. Li, and M. Jin. 2018. Parental Transfer of Perfluorooctane Sulfonate and ZnO Nanoparticles Chronic Co-Exposure and Inhibition of Growth in F1 Offspring. Regul. Toxicol. Pharmacol.98:41-49","3033","PFOS >98% purity (CASRN 2795-39-3) from Sigma ","Nominal. F1 not exposed, but F0 parents exposed - valid?"]
["Freshwater/non-metal/non- plant","3033-2",55,0.60439560439560436,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","120 days","LOEC","Reproduction","200 ug/L","Fish","Chordata","Actinopterygii","Culture medium","28oC","Chronic","Not stated","N.A.","Du,J., J. Tang, S. Xu, J. Ge, Y. Dong, H. Li, and M. Jin. 2018. Parental Transfer of Perfluorooctane Sulfonate and ZnO Nanoparticles Chronic Co-Exposure and Inhibition of Growth in F1 Offspring. Regul. Toxicol. Pharmacol.98:41-49","3033","Glass beakers","PFOS >98% purity (CASRN 2795-39-3) from Sigma ","Nominal"]
["Freshwater/non-metal/non- plant","3033-3",55,0.60439560439560436,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","120 days","NOEC","Mortality","100  ug/L","Fish","Chordata","Actinopterygii","Culture medium","28oC","Chronic","Not stated","N.A.","Du,J., J. Tang, S. Xu, J. Ge, Y. Dong, H. Li, and M. Jin. 2018. Parental Transfer of Perfluorooctane Sulfonate and ZnO Nanoparticles Chronic Co-Exposure and Inhibition of Growth in F1 Offspring. Regul. Toxicol. Pharmacol.98:41-49","3033","Glass beakers","PFOS >98% purity (CASRN 2795-39-3) from Sigma ","Nominal"]
["Freshwater/non-metal/non- plant","3033-4",55,0.60439560439560436,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","120 days","LOEC","Mortality","200 ug/L","Fish","Chordata","Actinopterygii","Culture medium","28oC","Chronic","Not stated","N.A.","Du,J., J. Tang, S. Xu, J. Ge, Y. Dong, H. Li, and M. Jin. 2018. Parental Transfer of Perfluorooctane Sulfonate and ZnO Nanoparticles Chronic Co-Exposure and Inhibition of Growth in F1 Offspring. Regul. Toxicol. Pharmacol.98:41-49","3033","Glass beakers","PFOS >98% purity (CASRN 2795-39-3) from Sigma ","Nominal"]
["Freshwater/non-metal/non- plant","3033-5",55,0.60439560439560436,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","120 days","NOEC","Growth","200 ug/L","Fish","Chordata","Actinopterygii","Culture medium","28oC","Chronic","Not stated","N.A.","Du,J., J. Tang, S. Xu, J. Ge, Y. Dong, H. Li, and M. Jin. 2018. Parental Transfer of Perfluorooctane Sulfonate and ZnO Nanoparticles Chronic Co-Exposure and Inhibition of Growth in F1 Offspring. Regul. Toxicol. Pharmacol.98:41-49","3033","Glass beakers","PFOS >98% purity (CASRN 2795-39-3) from Sigma ","Nominal"]
["Freshwater/non-metal/non- plant","3033-6",55,0.60439560439560436,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","120 days","NOEC","Growth","100 ug/L","Fish","Chordata","Actinopterygii","Culture medium","28oC","Chronic","Not stated","N.A.","Du,J., J. Tang, S. Xu, J. Ge, Y. Dong, H. Li, and M. Jin. 2018. Parental Transfer of Perfluorooctane Sulfonate and ZnO Nanoparticles Chronic Co-Exposure and Inhibition of Growth in F1 Offspring. Regul. Toxicol. Pharmacol.98:41-49","3033","Glass beakers","PFOS >98% purity (CASRN 2795-39-3) from Sigma ","Nominal"]
["Freshwater/non-metal/non- plant","3033-7",55,0.60439560439560436,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","120 days","LOEC","Growth","200 ug/L","Fish","Chordata","Actinopterygii","Culture medium","28oC","Chronic","Not stated","N.A.","Du,J., J. Tang, S. Xu, J. Ge, Y. Dong, H. Li, and M. Jin. 2018. Parental Transfer of Perfluorooctane Sulfonate and ZnO Nanoparticles Chronic Co-Exposure and Inhibition of Growth in F1 Offspring. Regul. Toxicol. Pharmacol.98:41-49","3033","Glass beakers","PFOS >98% purity (CASRN 2795-39-3) from Sigma ","Nominal"]
["Freshwater/non-metal/non- plant","3033-8",55,0.60439560439560436,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","120 days","NOEC","Mortality","200 ug/L","Fish","Chordata","Actinopterygii","Culture medium","28oC","Chronic","Not stated","N.A.","Du,J., J. Tang, S. Xu, J. Ge, Y. Dong, H. Li, and M. Jin. 2018. Parental Transfer of Perfluorooctane Sulfonate and ZnO Nanoparticles Chronic Co-Exposure and Inhibition of Growth in F1 Offspring. Regul. Toxicol. Pharmacol.98:41-49","3033","PFOS >98% purity (CASRN 2795-39-3) from Sigma ","Nominal. F1 not exposed, but F0 parents exposed - valid?"]
["Freshwater/non-metal/non- plant","3033-9",55,0.60439560439560436,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","120 days","NOEC","Reproduction","200 ug/L","Fish","Chordata","Actinopterygii","Culture medium","28oC","Chronic","Not stated","N.A.","Du,J., J. Tang, S. Xu, J. Ge, Y. Dong, H. Li, and M. Jin. 2018. Parental Transfer of Perfluorooctane Sulfonate and ZnO Nanoparticles Chronic Co-Exposure and Inhibition of Growth in F1 Offspring. Regul. Toxicol. Pharmacol.98:41-49","3033","PFOS >98% purity (CASRN 2795-39-3) from Sigma ","Nominal. F1 not exposed, but F0 parents exposed - valid?"]
["Freshwater/non-metal/non- plant","3034-1",54,0.59340659340659341,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","7 day","NOEC","Growth","8002 ug/L","Fish","Chordata","Actinopterygii","Danieaus medium","Not stated","Chronic","Not stated","N.A.","Sant,K.E., H.M. Jacobs, K.A. Borofski, J.B. Moss, and A.R. Timme-Laragy. 2017. Embryonic Exposures to Perfluorooctanesulfonic Acid (PFOS) Disrupt Pancreatic Organogenesis in the Zebrafish, Danio rerio. Environ. Pollut.220:807-817","3034","Glass petri dishes","Heptadecafluorooctaensulfonic acid PFOS from Sigma Aldrich, purity not provided"]
["Freshwater/non-metal/non- plant","3034-2",54,0.59340659340659341,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","7 day","LOEC","Growth","16004 ug/L","Fish","Chordata","Actinopterygii","Danieaus medium","Not stated","Chronic","Not stated","N.A.","Sant,K.E., H.M. Jacobs, K.A. Borofski, J.B. Moss, and A.R. Timme-Laragy. 2017. Embryonic Exposures to Perfluorooctanesulfonic Acid (PFOS) Disrupt Pancreatic Organogenesis in the Zebrafish, Danio rerio. Environ. Pollut.220:807-817","3034","Glass petri dishes","Heptadecafluorooctaensulfonic acid PFOS from Sigma Aldrich, purity not provided"]
["Freshwater/non-metal/non- plant","3035-1",56,0.61538461538461542,"","Danio rerio","Embryo","14 days","NOEC","Mortality","330 ug/L","Fish","Chordata","Actinopterygii","Culture medium","Not stated","Chronic","Not stated","N.A.","Du,J., S. Wang, H. You, and Z. Liu. 2016. Effects of ZnO Nanoparticles on Perfluorooctane Sulfonate Induced Thyroid-Disrupting on Zebrafish Larvae. J. Environ. Sci.47:153-164","3035","Glass beakers","PFOS >98% (CAS RN 2795-39-3) from Fluka","Measured concs"]
["Freshwater/non-metal/non- plant","3035-2",56,0.61538461538461542,"","Danio rerio","Embryo","14 days","LOEC","Mortality","640 ug/L","Fish","Chordata","Actinopterygii","Culture medium","Not stated","Chronic","Not stated","N.A.","Du,J., S. Wang, H. You, and Z. Liu. 2016. Effects of ZnO Nanoparticles on Perfluorooctane Sulfonate Induced Thyroid-Disrupting on Zebrafish Larvae. J. Environ. Sci.47:153-164","3035","Glass beakers","PFOS >98% (CAS RN 2795-39-3) from Fluka","Measured concs"]
["Freshwater/non-metal/non- plant","3035-3",56,0.61538461538461542,"","Danio rerio","Embryo","14 days","NOEC","Growth","120 ug/L","Fish","Chordata","Actinopterygii","Culture medium","Not stated","Chronic","Not stated","N.A.","Du,J., S. Wang, H. You, and Z. Liu. 2016. Effects of ZnO Nanoparticles on Perfluorooctane Sulfonate Induced Thyroid-Disrupting on Zebrafish Larvae. J. Environ. Sci.47:153-164","3035","Glass beakers","PFOS >98% (CAS RN 2795-39-3) from Fluka","Measured concs"]
["Freshwater/non-metal/non- plant","3035-4",56,0.61538461538461542,"","Danio rerio","Embryo","14 days","LOEC","Growth","330 ug/L","Fish","Chordata","Actinopterygii","Culture medium","Not stated","Chronic","Not stated","N.A.","Du,J., S. Wang, H. You, and Z. Liu. 2016. Effects of ZnO Nanoparticles on Perfluorooctane Sulfonate Induced Thyroid-Disrupting on Zebrafish Larvae. J. Environ. Sci.47:153-164","3035","Glass beakers","PFOS >98% (CAS RN 2795-39-3) from Fluka","Measured concs"]
["Freshwater/non-metal/non- plant","3035-5",56,0.61538461538461542,"","Danio rerio","Embryo","14 days","NOEC","Growth","640 ug/L","Fish","Chordata","Actinopterygii","Culture medium","Not stated","Chronic","Not stated","N.A.","Du,J., S. Wang, H. You, and Z. Liu. 2016. Effects of ZnO Nanoparticles on Perfluorooctane Sulfonate Induced Thyroid-Disrupting on Zebrafish Larvae. J. Environ. Sci.47:153-164","3035","Glass beakers","PFOS >98% (CAS RN 2795-39-3) from Fluka","Measured concs"]
["Freshwater/non-metal/non- plant","3035-6",61,0.67032967032967028,"","Danio rerio","Embryo","14 days","NOEC","Development","330 ug/L","Fish","Chordata","Actinopterygii","Culture medium","Not stated","Chronic","Not stated","N.A.","Du,J., S. Wang, H. You, and Z. Liu. 2016. Effects of ZnO Nanoparticles on Perfluorooctane Sulfonate Induced Thyroid-Disrupting on Zebrafish Larvae. J. Environ. Sci.47:153-164","3035","Glass beakers","PFOS >98% (CAS RN 2795-39-3) from Fluka","Measured concs"]
["Freshwater/non-metal/non- plant","3035-7",61,0.67032967032967028,"","Danio rerio","Embryo","14 days","LOEC","Development","640 ug/L","Fish","Chordata","Actinopterygii","Culture medium","Not stated","Chronic","Not stated","N.A.","Du,J., S. Wang, H. You, and Z. Liu. 2016. Effects of ZnO Nanoparticles on Perfluorooctane Sulfonate Induced Thyroid-Disrupting on Zebrafish Larvae. J. Environ. Sci.47:153-164","3035","Glass beakers","PFOS >98% (CAS RN 2795-39-3) from Fluka","Measured concs"]
["Freshwater/non-metal/non- plant","3036-1",68,0.74725274725274726,"","Physa pomilia","Adult","14 days","LC50","Mortality","94.99 mg/L","Snail","Mollusca","Gastropoda","Moderately hard water","21±1","Chronic","Not stated","N.A.","Funkhouser, M. (2014). The toxicological effects of Perfluorooctane sulfonate (PFOS) on a freshwater gastropod, Physa pomilia, and a parthenogenetic decapod, Procambarus fallax f. virginalis (Doctoral dissertation).","3036","Polyproplylene beakers","PFOS-K, >98% purity from Sigma Aldrich","Measured concs. Snails reach reproductive age at 31d"]
["Freshwater/non-metal/non- plant","3036-10",58,0.63736263736263732,"","Procambrius fallax f. virginalis","Juvenile","28 days","NOEC","Mortality","200 ug/L","Macroinvertebrate","Arthropoda","Malacostraca","Moderately hard water","20±1","Chronic","Not stated","N.A.","Funkhouser, M. (2014). The toxicological effects of Perfluorooctane sulfonate (PFOS) on a freshwater gastropod, Physa pomilia, and a parthenogenetic decapod, Procambarus fallax f. virginalis (Doctoral dissertation).","3036","Polyproplylene beakers","PFOS-K, >98% purity from Sigma Aldrich","Measured concs"]
["Freshwater/non-metal/non- plant","3036-12",58,0.63736263736263732,"","Procambrius fallax f. virginalis","Juvenile","28 days","LOEC","Mortality","500 ug/L","Macroinvertebrate","Arthropoda","Malacostraca","Moderately hard water","20±1","Chronic","Not stated","N.A.","Funkhouser, M. (2014). The toxicological effects of Perfluorooctane sulfonate (PFOS) on a freshwater gastropod, Physa pomilia, and a parthenogenetic decapod, Procambarus fallax f. virginalis (Doctoral dissertation).","3036","Polyproplylene beakers","PFOS-K, >98% purity from Sigma Aldrich","Measured concs"]
["Freshwater/non-metal/non- plant","3036-2",68,0.74725274725274726,"","Physa pomilia","Adult","14 days","NOEC","Mortality","100 mg/L","Snail","Mollusca","Gastropoda","Moderately hard water","21±1","Chronic","Not stated","N.A.","Funkhouser, M. (2014). The toxicological effects of Perfluorooctane sulfonate (PFOS) on a freshwater gastropod, Physa pomilia, and a parthenogenetic decapod, Procambarus fallax f. virginalis (Doctoral dissertation).","3036","Polyproplylene beakers","PFOS-K, >98% purity from Sigma Aldrich","Measured concs"]
["Freshwater/non-metal/non- plant","3036-3",58,0.63736263736263732,"","Physa pomilia","Adult","14 days","LOEC","Mortality","125 mg/L","Snail","Mollusca","Gastropoda","Moderately hard water","21±1","Chronic","Not stated","N.A.","Funkhouser, M. (2014). The toxicological effects of Perfluorooctane sulfonate (PFOS) on a freshwater gastropod, Physa pomilia, and a parthenogenetic decapod, Procambarus fallax f. virginalis (Doctoral dissertation).","3036","Polyproplylene beakers","PFOS-K, >98% purity from Sigma Aldrich","Measured concs. Snails reach reproductive age at 31d"]
["Freshwater/non-metal/non- plant","3036-4",58,0.63736263736263732,"","Physa pomilia","F0 eggs to F1 eggs","44 days","LC50","Mortality","35.9 mg/L","Snail","Mollusca","Gastropoda","Moderately hard water","21±1","Chronic","Not stated","N.A.","Funkhouser, M. (2014). The toxicological effects of Perfluorooctane sulfonate (PFOS) on a freshwater gastropod, Physa pomilia, and a parthenogenetic decapod, Procambarus fallax f. virginalis (Doctoral dissertation).","3036","Polyproplylene beakers","PFOS-K, >98% purity from Sigma Aldrich","Measured concs"]
["Freshwater/non-metal/non- plant","3036-5",58,0.63736263736263732,"","Physa pomilia","F0 eggs to adults","28 days","NOEC","Growth","20 mg/L","Snail","Mollusca","Gastropoda","Moderately hard water","21±1","Chronic","Not stated","N.A.","Funkhouser, M. (2014). The toxicological effects of Perfluorooctane sulfonate (PFOS) on a freshwater gastropod, Physa pomilia, and a parthenogenetic decapod, Procambarus fallax f. virginalis (Doctoral dissertation).","3036","Polyproplylene beakers","PFOS-K, >98% purity from Sigma Aldrich","Measured concs. Snails reach reproductive age at 31d"]
["Freshwater/non-metal/non- plant","3036-6",58,0.63736263736263732,"","Physa pomilia","F0 eggs to adults","28 days","LOEC","Growth","40 mg/L","Snail","Mollusca","Gastropoda","Moderately hard water","21±1","Chronic","Not stated","N.A.","Funkhouser, M. (2014). The toxicological effects of Perfluorooctane sulfonate (PFOS) on a freshwater gastropod, Physa pomilia, and a parthenogenetic decapod, Procambarus fallax f. virginalis (Doctoral dissertation).","3036","Polyproplylene beakers","PFOS-K, >98% purity from Sigma Aldrich","Measured concs. Snails reach reproductive age at 31d"]
["Freshwater/non-metal/non- plant","3036-7",58,0.63736263736263732,"","Physa pomilia","F0 eggs to F1 eggs","44 days","NOEC","Reproduction","10 mg/L","Snail","Mollusca","Gastropoda","Moderately hard water","21±1","Chronic","Not stated","N.A.","Funkhouser, M. (2014). The toxicological effects of Perfluorooctane sulfonate (PFOS) on a freshwater gastropod, Physa pomilia, and a parthenogenetic decapod, Procambarus fallax f. virginalis (Doctoral dissertation).","3036","Polyproplylene beakers","PFOS-K, >98% purity from Sigma Aldrich","Measured concs"]
["Freshwater/non-metal/non- plant","3036-8",58,0.63736263736263732,"","Physa pomilia","F0 eggs to F1 eggs","44 days","LOEC","Reproduction","20 mg/L","Snail","Mollusca","Gastropoda","Moderately hard water","21±1","Chronic","Not stated","N.A.","Funkhouser, M. (2014). The toxicological effects of Perfluorooctane sulfonate (PFOS) on a freshwater gastropod, Physa pomilia, and a parthenogenetic decapod, Procambarus fallax f. virginalis (Doctoral dissertation).","3036","Polyproplylene beakers and HDPE carbouys","PFOS-K, >98% purity from Sigma Aldrich","Measured concs"]
["Freshwater/non-metal/non- plant","3036-9",58,0.63736263736263732,"","Procambrius fallax f. virginalis","Juvenile","28 days","LC50","Mortality","167 ug/L","Macroinvertebrate","Arthropoda","Malacostraca","Moderately hard water","20±1","Chronic","Not stated","N.A.","Funkhouser, M. (2014). The toxicological effects of Perfluorooctane sulfonate (PFOS) on a freshwater gastropod, Physa pomilia, and a parthenogenetic decapod, Procambarus fallax f. virginalis (Doctoral dissertation).","3036","Polyproplylene beakers and HDPE carbouys","PFOS-K, >98% purity from Sigma Aldrich","Measured concs"]
["Freshwater/non-metal/non- plant","3037-1",55,0.60439560439560436,"","Anguilla anguilla","Adult","28 days","NOEC","Mortality","11 ug/L","Fish","Chordata","Actinopterygii","Tap water"," 20 ± 2","Chronic","Not stated","N.A.","Roland, K., Kestemont, P., Loos, R., Tavazzi, S., Paracchini, B., Belpaire, C., Dieu, M., Raes, M. and Silvestre, F. (2014). Looking for protein expression signatures in European eel peripheral blood mononuclear cells after in vivo exposure to perfluorooctane sulfonate and a real world field study. Science of the Total Environment, 468, 958-967.","3037","Tanks. Not stated","PFOS-K, 98% purity from Sigma Aldrich","Measured concs (0.81 ug/L and 11 ug/L); nominal exposure of 1 and 10 ug/L plus a control"]
["Freshwater/non-metal/non- plant","3037-2",55,0.60439560439560436,"","Anguilla anguilla","Adult","28 days","NOEC","Growth","11 ug/L","Fish","Chordata","Actinopterygii","Tap water"," 20 ± 2","Chronic","Not stated","N.A.","Roland, K., Kestemont, P., Loos, R., Tavazzi, S., Paracchini, B., Belpaire, C., Dieu, M., Raes, M. and Silvestre, F. (2014). Looking for protein expression signatures in European eel peripheral blood mononuclear cells after in vivo exposure to perfluorooctane sulfonate and a real world field study. Science of the Total Environment, 468, 958-967.","3037","Tanks. Not stated","PFOS-K, 98% purity from Sigma Aldrich","Measured concs (0.81 ug/L and 11 ug/L); nominal exposure of 1 and 10 ug/L plus a control"]
["Freshwater/non-metal/non- plant","3038-1",58,0.63736263736263732,"","Danio rerio","Parents of F1 embryos exposed for 120 days, embryos not exposed","120 days","LOEC","Mortality","250 ug/L","Fish","Chordata","Actinopterygii","RO water","27.5-28.5oC","Chronic","7-7.5","N.A.","Chen, J., S.R. Das, J.L. Du, M.M. Covi, C. Bai, Y. Chen, X. Liu, G. Zhu, R.L. Tanguay, Q. Dong and C. Huang. 2013. Chronic PFOS exposures induce life stage-specific behavioural deficits in adult zebrafish and produce malformation and behavioural deficits in F1 offspring. Environmental Toxicology and Chemistry 32: 201-206","3038","Petri dish (F0 embryos); stainless steel tanks (F0 larvae); well plate (F1 embryos)","PFOS, 96% purity (CASRN 1763-23-1) from Sigma Aldrich","Assumed nominal"]
["Freshwater/non-metal/non- plant","3038-2",58,0.63736263736263732,"","Danio rerio","Parents of F1 embryos exposed for 120 days, embryos not exposed","120 days","LOEC","Development","250 ug/L","Fish","Chordata","Actinopterygii","RO water","27.5-28.5oC","Chronic","7-7.5","N.A.","Chen, J., S.R. Das, J.L. Du, M.M. Covi, C. Bai, Y. Chen, X. Liu, G. Zhu, R.L. Tanguay, Q. Dong and C. Huang. 2013. Chronic PFOS exposures induce life stage-specific behavioural deficits in adult zebrafish and produce malformation and behavioural deficits in F1 offspring. Environmental Toxicology and Chemistry 32: 201-206","3038","Petri dish (F0 embryos); stainless steel tanks (F0 larvae); well plate (F1 embryos)","PFOS, 96% purity (CASRN 1763-23-1) from Sigma Aldrich","Assumed nominal"]
["Freshwater/non-metal/non- plant","3039-1",57,0.62637362637362637,"","Xenopus laevis","Tadpoles NF stage 46/47","120 days","NOEC","Mortality","608 ug/L","Amphibian","Chordata","Sarcopterygii","Charcoal filtered tap water","20-24oC","Chronic","6.5-7.0","CaCO3 150","Lou, Q.Q., Zhang, Y.F., Zhou, Z., Shi, Y.L., Ge, Y.N., Ren, D.K., Xu, H.M., Zhao, Y.X., Wei, W.J. and Qin, Z.F., (2013). Effects of perfluorooctanesulfonate and perfluorobutanesulfonate on the growth and sexual development of Xenopus laevis. Ecotoxicology, 22(7), 1133-1144.","3039","Tanks, material not stated","PFOS, form not stated, 98% purity from Matrix Scientific ","Measured concs"]
["Freshwater/non-metal/non- plant","3039-2",57,0.62637362637362637,"","Xenopus laevis","Tadpoles NF stage 46/47","120 days","NOEC","Growth","608 ug/L","Amphibian","Chordata","Sarcopterygii","Charcoal filtered tap water","20-24oC","Chronic","6.5-7.0","CaCO3 150","Lou, Q.Q., Zhang, Y.F., Zhou, Z., Shi, Y.L., Ge, Y.N., Ren, D.K., Xu, H.M., Zhao, Y.X., Wei, W.J. and Qin, Z.F., (2013). Effects of perfluorooctanesulfonate and perfluorobutanesulfonate on the growth and sexual development of Xenopus laevis. Ecotoxicology, 22(7), 1133-1144.","3039","Tanks, material not stated","PFOS, form not stated, 98% purity from Matrix Scientific ","Measured concs"]
["Freshwater/non-metal/plant","3040-1",57,0.64772727272727271,"The highest possible grade for this datum is acceptable.","Tetradesmus obliquus (formerly Scenedesmus obliquus and Acutodesmus obliquus)","Exponential growth phase","96 hrs","EC50","Reproduction","126 mg/L","Microalga","Chlorophyta",null,"HB-4 culture medium","24oC","Chronic","Not stated","N.A.","Zhang, D. Y., Xu, X. L., Lu, Y., Xu, H. Y., & Yan, H. M. (2012). The effects of perfluorooctane sulfonate (PFOS) on physiological status and proliferation capacity of Scenedesmus obliqnus. In Applied Mechanics and Materials (Vol. 209, pp. 1131-1135). Trans Tech Publications.","3040","Not stated","PFOS-K, analytical purity from AccuStandard compay","Assumed nominal"]
["Freshwater/non-metal/plant","3040-2",47,0.53409090909090906,"The highest possible grade for this datum is acceptable.","Tetradesmus obliquus (formerly Scenedesmus obliquus and Acutodesmus obliquus)","Exponential growth phase","96 hrs","NOEC","Reproduction","25 mg/L","Microalga","Chlorophyta",null,"HB-4 culture medium","24oC","Chronic","Not stated","N.A.","Zhang, D. Y., Xu, X. L., Lu, Y., Xu, H. Y., & Yan, H. M. (2012). The effects of perfluorooctane sulfonate (PFOS) on physiological status and proliferation capacity of Scenedesmus obliqnus. In Applied Mechanics and Materials (Vol. 209, pp. 1131-1135). Trans Tech Publications.","3040","Not stated","PFOS-K, analytical purity from AccuStandard compay","Assumed nominal"]
["Freshwater/non-metal/plant","3040-3",47,0.53409090909090906,"The highest possible grade for this datum is acceptable.","Tetradesmus obliquus (formerly Scenedesmus obliquus and Acutodesmus obliquus)","Exponential growth phase","96 hrs","LOEC","Reproduction","50 mg/L","Microalga","Chlorophyta",null,"HB-4 culture medium","24oC","Chronic","Not stated","N.A.","Zhang, D. Y., Xu, X. L., Lu, Y., Xu, H. Y., & Yan, H. M. (2012). The effects of perfluorooctane sulfonate (PFOS) on physiological status and proliferation capacity of Scenedesmus obliqnus. In Applied Mechanics and Materials (Vol. 209, pp. 1131-1135). Trans Tech Publications.","3040","Not stated","PFOS-K, analytical purity from AccuStandard compay","Assumed nominal"]
["Freshwater/non-metal/non- plant","3041-1",51,0.56043956043956045,"The highest possible grade for this datum is acceptable.","Dugesia japonica","Fragment","22 days","LOEC","Development - Eye spots","5000 ug/L","Macroinvertebrate","Platyhelminthes","Turbellaria","Spring water","22oC","Acute ","6.5-7.0","Not stated","Zhao,B., X. Shao, B. Zhao, Z. Yuan, and J. Zhang. 2018. Application of Blueberry Anthocyanins Reduces Perfluorooctane Sulfonate Toxicity on Planarians (Dugesia japonica) in Locomotion, Regeneration, and Gene Expression and Contents. Environ. Sci. Pollut. Res.25(22): 22095-22105","3041","Glass petri dishes","PFOS, 99% purity from Sigma Aldrich","Assumed nominal, not stated"]
["Freshwater/non-metal/non- plant","3041-2",51,0.56043956043956045,"The highest possible grade for this datum is acceptable.","Dugesia japonica","Fragment","22 days","LOEC","Development - Auricles","5000 ug/L","Macroinvertebrate","Platyhelminthes","Turbellaria","Spring water","22oC","Chronic","6.5-7.0","Not stated","Zhao,B., X. Shao, B. Zhao, Z. Yuan, and J. Zhang. 2018. Application of Blueberry Anthocyanins Reduces Perfluorooctane Sulfonate Toxicity on Planarians (Dugesia japonica) in Locomotion, Regeneration, and Gene Expression and Contents. Environ. Sci. Pollut. Res.25(22): 22095-22105","3041","Glass petri dishes","PFOS, 99% purity from Sigma Aldrich","Assumed nominal, not stated"]
["Freshwater/non-metal/non- plant","3042-1",57,0.62637362637362637,"","Danio rerio","Adult","28 days","LOEC","Mortality","10 ug/L","Fish","Chordata","Actinopterygii","Carbon-filtered tap water","21-25oC","Chronic","7-7.6","N.A.","Wen, W., X. Xia, D. Zhou, H. Wang, Y. Zhai, H. Lin and J. Chen. 2019. Bioconcentration and tissue distribution of shorter and longer chain perfluoroalkyl acids (PFAAs) in zebrafish (Danio rerio): Effects of perfluorinated carbon chain length and zebrafish protein content. Environmental Pollution","3042","Glass petri dishes","PFOS, 99% purity from Sigma Aldrich","Assumed nominal, not stated"]
["Freshwater/non-metal/non- plant","3042-2",57,0.62637362637362637,"","Danio rerio","Adult","28 days","LOEC","Growth","10 ug/L","Fish","Chordata","Actinopterygii","Carbon-filtered tap water","21-25oC","Chronic","7-7.6","N.A.","Wen, W., X. Xia, D. Zhou, H. Wang, Y. Zhai, H. Lin and J. Chen. 2019. Bioconcentration and tissue distribution of shorter and longer chain perfluoroalkyl acids (PFAAs) in zebrafish (Danio rerio): Effects of perfluorinated carbon chain length and zebrafish protein content. Environmental Pollution","3042","Polypropylene tank","PFOS 98% from Acros Organics Mixture study - not PFOS alone","Measured"]
["Freshwater/non-metal/non- plant","3042-3",57,0.62637362637362637,"","Danio rerio","Adult","28 days","LOEC","Growth","10 ug/L","Fish","Chordata","Actinopterygii","Carbon-filtered tap water","21-25oC","Chronic","7-7.6","N.A.","Wen, W., X. Xia, D. Zhou, H. Wang, Y. Zhai, H. Lin and J. Chen. 2019. Bioconcentration and tissue distribution of shorter and longer chain perfluoroalkyl acids (PFAAs) in zebrafish (Danio rerio): Effects of perfluorinated carbon chain length and zebrafish protein content. Environmental Pollution","3042","Polypropylene tank","PFOS 98% from Acros Organics Mixture study - not PFOS alone","Measured"]
["Freshwater/non-metal/non- plant","3043-1",68,0.74725274725274726,"","Chironomus riparius","Larvae F10","38 days","NOEC","Reproduction","3.5 ug/L","Macroinvertebrate","Arthropoda","Insecta","Reconstituted water","19-21oC","Chronic","7.8-8.2","N.A.","Stefani, F., M. Rusconi, S. Valsecchi and L. Marziali. 2014. Evolutionary ecotoxicology of perfluoralkyl substances (PFASs) inferred from multigenerational exposure: A case study with Chironomus riparius (Diptera, Chironomidae). Aquatic Toxicology 156: 41-51.","3043","Glass","\"Pure PFOS from Sigma-Aldrich\"","Measured conc (TWA was 3.5 ug/L although the nominal exposure was 10 ug/L)"]
["Freshwater/non-metal/non- plant","3043-2",68,0.74725274725274726,"","Chironomus riparius","Larvae F2","38 days","LOEC","Reproduction","3.5 ug/L","Macroinvertebrate","Arthropoda","Insecta","Reconstituted water","19-21oC","Chronic","7.8-8.2","N.A.","Stefani, F., M. Rusconi, S. Valsecchi and L. Marziali. 2014. Evolutionary ecotoxicology of perfluoralkyl substances (PFASs) inferred from multigenerational exposure: A case study with Chironomus riparius (Diptera, Chironomidae). Aquatic Toxicology 156: 41-51.","3043","Glass","\"Pure PFOS from Sigma-Aldrich\"","Measured conc (TWA was 3.5 ug/L although the nominal exposure was 10 ug/L)"]
["Freshwater/non-metal/non- plant","404-11",71,0.78021978021978022,"The highest possible grade for this datum is acceptable.","Daphnia magna","<24hr neonate","21 day","NOEC","Reproduction","1.25 mg/L","Microinvertebrate","Arthropoda","Branchiopoda","moderately hard reconstituted water",25,"Chronic","Not stated","N.A.","Ji, K., K. Younghee, S. Oh, B. Ahn, H. Jo and K. Choi. 2008. Toxicity of perfluorooctane sulfonic acid and perfluorooctanoic acid on freshwater macroinvertebrates (Daphnia magna and Moina macrocopa) and fish (Oryzias latipes). Environmental Toxicology and Chemistry 27: 2159-2168.","404","Not stated","PFOS acid form, purity not stated (PFOS C8HF17SO3: CAS RN 1763-23-1 from Wako Pure Chemicals (Osaka, Japan)","Nominal concs"]
["Freshwater/non-metal/non- plant","404-18",71,0.78021978021978022,"The highest possible grade for this datum is acceptable.","Moina macrocopa","<24hr neonate","7 days","NOEC","Reproduction","0.3125 mg/L","Microinvertebrate","Arthropoda","Branchiopoda","Moderately hard reconstituted water (USEPA guidelines)","25±1","Chronic","Not stated","N.A.","Ji, K., K. Younghee, S. Oh, B. Ahn, H. Jo and K. Choi. 2008. Toxicity of perfluorooctane sulfonic acid and perfluorooctanoic acid on freshwater macroinvertebrates (Daphnia magna and Moina macrocopa) and fish (Oryzias latipes). Environmental Toxicology and Chemistry 27: 2159-2168.","404","Not stated","PFOS acid form, purity not stated (PFOS C8HF17SO3: CAS RN 1763-23-1 from Wako Pure Chemicals (Osaka, Japan)","Nominal concs"]
["Freshwater/non-metal/non- plant","404-19",66,0.72527472527472525,"The highest possible grade for this datum is acceptable.","Oryzias latipes","Embryo","8 days","LOEC","Reproduction","0.01 mg/L","Fish","Chordata","Teleostei","Dechlorinated tap water","25±1","Chronic","Not stated","N.A.","Ji, K., K. Younghee, S. Oh, B. Ahn, H. Jo and K. Choi. 2008. Toxicity of perfluorooctane sulfonic acid and perfluorooctanoic acid on freshwater macroinvertebrates (Daphnia magna and Moina macrocopa) and fish (Oryzias latipes). Environmental Toxicology and Chemistry 27: 2159-2168.","404","Not stated","PFOS acid form, purity not stated (PFOS C8HF17SO3: CAS RN 1763-23-1 from Wako Pure Chemicals (Osaka, Japan)","Nominal concs"]
["Freshwater/non-metal/non- plant","409-1",63,0.69230769230769229,"The highest possible grade for this datum is acceptable.","Daphnia magna","Neonate","21 day","NOEC","Survival","25000 µg/L","Macroinvertebrate","Arthropoda","Branchiopoda","Moderately hard clean well water (°dH 8-12))","21±1","Chronic","Not stated","N.A.","Sanderson, H., T.M. Boudreau, S.A. Mabury and K.R. Solomon. 2004. Effects of perfluorooctane sulfonate and perfluorooctanoic acid on the zooplanktonic community. Ecotoxicology and Environmental Safety 58: 68-76","409","Polypropylene containers","PFOS-K, treatment concs based on PFOS anion (PFOS (CF3(CF2))7S(O)2O-K+ CAS RN 2795-39-3 donated from 3M).","Nominal concs"]
["Freshwater/non-metal/non- plant","409-2",63,0.69230769230769229,"The highest possible grade for this datum is acceptable.","Daphnia magna","Neonate","21 day","LOEC","Survival","50000 µg/L","Macroinvertebrate","Arthropoda","Branchiopoda","Moderately hard clean well water (°dH 8-12))","21±1","Chronic","Not stated","N.A.","Sanderson, H., T.M. Boudreau, S.A. Mabury and K.R. Solomon. 2004. Effects of perfluorooctane sulfonate and perfluorooctanoic acid on the zooplanktonic community. Ecotoxicology and Environmental Safety 58: 68-76","409","Polypropylene containers","PFOS-K, treatment concs based on PFOS anion (PFOS (CF3(CF2))7S(O)2O-K+ CAS RN 2795-39-3 donated from 3M).","Nominal concs"]
["Freshwater/non-metal/non- plant","409-3",63,0.69230769230769229,"The highest possible grade for this datum is acceptable.","Daphnia pulicaria","Neonate","21 day","NOEC","Survival","6000 µg/L","Macroinvertebrate","Arthropoda","Branchiopoda","Moderately hard clean well water (°dH 8-12))","21±1","Chronic","Not stated","N.A.","Sanderson, H., T.M. Boudreau, S.A. Mabury and K.R. Solomon. 2004. Effects of perfluorooctane sulfonate and perfluorooctanoic acid on the zooplanktonic community. Ecotoxicology and Environmental Safety 58: 68-76","409","Polypropylene containers","PFOS-K, treatment concs based on PFOS anion (PFOS (CF3(CF2))7S(O)2O-K+ CAS RN 2795-39-3 donated from 3M).","Nominal concs"]
["Freshwater/non-metal/non- plant","409-4",63,0.69230769230769229,"The highest possible grade for this datum is acceptable.","Daphnia pulicaria","Neonate","21 day","LOEC","Survival","13000 µg/L","Macroinvertebrate","Arthropoda","Branchiopoda","Moderately hard clean well water (°dH 8-12))","21±1","Chronic","Not stated","N.A.","Sanderson, H., T.M. Boudreau, S.A. Mabury and K.R. Solomon. 2004. Effects of perfluorooctane sulfonate and perfluorooctanoic acid on the zooplanktonic community. Ecotoxicology and Environmental Safety 58: 68-76","409","Polypropylene containers","PFOS-K, treatment concs based on PFOS anion (PFOS (CF3(CF2))7S(O)2O-K+ CAS RN 2795-39-3 donated from 3M).","Nominal concs"]
["Freshwater/non-metal/non- plant","412-1",62,0.68131868131868134,"The highest possible grade for this datum is acceptable.","Daphnia magna","Neonate","21 day","LC50","Survival","9.1 mg/L (7.3-11.5)","Macroinvertebrate","Arthropoda","Branchiopoda","ATSM hardwater","Not stated","Chronic","Not stated","N.A.","Li, M-H. 2010. Chronic effects of perfluorooctane sulfonate and ammonium perfluorooctanoate and biochemical parameters, survival and reproduction of Daphnia magna. Journal of Health Science 56: 104-111","412","Polypropylene culture tubes","PFOS-K, 98% purity from Fluka ","Nominal concs"]
["Freshwater/non-metal/non- plant","412-2",62,0.68131868131868134,"The highest possible grade for this datum is acceptable.","Daphnia magna","Neonate","21 day","NOEC","Survival","5000 µg/L","Macroinvertebrate","Arthropoda","Branchiopoda","ATSM hardwater","Not stated","Chronic","Not stated","N.A.","Li, M-H. 2010. Chronic effects of perfluorooctane sulfonate and ammonium perfluorooctanoate and biochemical parameters, survival and reproduction of Daphnia magna. Journal of Health Science 56: 104-111","412","Polypropylene culture tubes","PFOS-K, 98% purity from Fluka ","Nominal concs"]
["Freshwater/non-metal/non- plant","412-3",62,0.68131868131868134,"The highest possible grade for this datum is acceptable.","Daphnia magna","Neonate","21 day","NOEC","Reproduction","1000 µg/L","Macroinvertebrate","Arthropoda","Branchiopoda","ATSM hardwater","Not stated","Chronic","Not stated","N.A.","Li, M-H. 2010. Chronic effects of perfluorooctane sulfonate and ammonium perfluorooctanoate and biochemical parameters, survival and reproduction of Daphnia magna. Journal of Health Science 56: 104-111","412","Polypropylene culture tubes","PFOS-K, 98% purity from Fluka ","Nominal concs"]
["Freshwater/non-metal/plant","431-1",64,0.72727272727272729,"The highest possible grade for this datum is acceptable.","Chlorella vulgaris","Not stated","96 hrs","IC50","Growth inhibition","81.6 mg/L (69.6-98.6)","Microalga","Chlorophyta",null,"Bristol’s algal growing media in laboratory-grade distilled water","23±1","Chronic","Not stated","N.A.","Boudreau, T.M., P.K. Sibley, S.A. Mabury, D.G.C. Muir and K.R. Solomon. 2003. Laboratory evaluation of the toxicity of perfluorooctane sulfonate (PFOS) on Selenastrum capricornutum, Chlorella vulgaris, Lemna gibba, Daphnia magna, and Daphnia pulicaria. Archives of Environmental Contamination and Toxicology 44: 307-313.","431","Polypropylene or polyethylene","PFOS-K 95% from 3M. Treatment concs were PFOS anion","Nominal concs"]
["Freshwater/non-metal/non- plant","431-10",66,0.72527472527472525,"The highest possible grade for this datum is acceptable.","Daphnia magna","<24hr neonate","21 day","NOEC","Survival","5.3 mg/L (2.5-9.2)","Macroinvertebrate","Arthropoda","Branchiopoda","Bristols algal growing media",21,"Chronic","Not stated","N.A.","Boudreau, T.M., P.K. Sibley, S.A. Mabury, D.G.C. Muir and K.R. Solomon. 2003. Laboratory evaluation of the toxicity of perfluorooctane sulfonate (PFOS) on Selenastrum capricornutum, Chlorella vulgaris, Lemna gibba, Daphnia magna, and Daphnia pulicaria. Archives of Environmental Contamination and Toxicology 44: 307-313.","431","Polypropylene or polyethylene","PFOS-K 95% from 3M. Treatment concs were PFOS anion","Nominal concs"]
["Freshwater/non-metal/plant","431-15",64,0.72727272727272729,"The highest possible grade for this datum is acceptable.","Lemna gibba","Not stated","7 days","IC50","Frond number","59.1 mg/L (51.5-60.3)","plantae","Spermatophyta","Hunters growing media","Bristols algal growing media","25°C","Chronic","not stated","N.A.","Boudreau, T.M., P.K. Sibley, S.A. Mabury, D.G.C. Muir and K.R. Solomon. 2003. Laboratory evaluation of the toxicity of perfluorooctane sulfonate (PFOS) on Selenastrum capricornutum, Chlorella vulgaris, Lemna gibba, Daphnia magna, and Daphnia pulicaria. Archives of Environmental Contamination and Toxicology 44: 307-313.","431","Polypropylene or polyethylene","PFOS-K 95% from 3M. Treatment concs were PFOS anion","Nominal concs"]
["Freshwater/non-metal/plant","431-16",64,0.72727272727272729,"The highest possible grade for this datum is acceptable.","Lemna gibba","Not stated","7 days","NOEC","Frond number","29.2 mg/L (27.5-32.1)","plantae","Spermatophyta","Hunters growing media","Bristols algal growing media","25°C","Chronic","not stated","N.A.","Boudreau, T.M., P.K. Sibley, S.A. Mabury, D.G.C. Muir and K.R. Solomon. 2003. Laboratory evaluation of the toxicity of perfluorooctane sulfonate (PFOS) on Selenastrum capricornutum, Chlorella vulgaris, Lemna gibba, Daphnia magna, and Daphnia pulicaria. Archives of Environmental Contamination and Toxicology 44: 307-313.","431","Polypropylene or polyethylene","PFOS-K 95% from 3M. Treatment concs were PFOS anion","Nominal concs"]
["Freshwater/non-metal/plant","431-17",64,0.72727272727272729,"The highest possible grade for this datum is acceptable.","Lemna gibba","Not stated","7 days","IC50","Wet weight","31.1 mg/L (22.2-36.1)","plantae","Spermatophyta","Hunters growing media","25°C","25°C","Chronic","not stated","N.A.","Boudreau, T.M., P.K. Sibley, S.A. Mabury, D.G.C. Muir and K.R. Solomon. 2003. Laboratory evaluation of the toxicity of perfluorooctane sulfonate (PFOS) on Selenastrum capricornutum, Chlorella vulgaris, Lemna gibba, Daphnia magna, and Daphnia pulicaria. Archives of Environmental Contamination and Toxicology 44: 307-313.","431","Polypropylene or polyethylene","PFOS-K 95% from 3M. Treatment concs were PFOS anion","Nominal concs"]
["Freshwater/non-metal/plant","431-18",64,0.72727272727272729,"The highest possible grade for this datum is acceptable.","Lemna gibba","Not stated","7 days","NOEC","Wet weight","6.6 mg/L (4.5-13.6)","plantae","Spermatophyta","Hunters growing media","25°C","25°C","Chronic","not stated","N.A.","Boudreau, T.M., P.K. Sibley, S.A. Mabury, D.G.C. Muir and K.R. Solomon. 2003. Laboratory evaluation of the toxicity of perfluorooctane sulfonate (PFOS) on Selenastrum capricornutum, Chlorella vulgaris, Lemna gibba, Daphnia magna, and Daphnia pulicaria. Archives of Environmental Contamination and Toxicology 44: 307-313.","431","Polypropylene or polyethylene","PFOS-K 95% from 3M. Treatment concs were PFOS anion","Nominal concs"]
["Freshwater/non-metal/plant","431-19",64,0.72727272727272729,"The highest possible grade for this datum is acceptable.","Raphidocelis subcapitata","Not stated","96 hrs","IC50","Growth inhibition: cell count","48.2 mg/L (45.2-51.1)","Microalga","Chlorophyta",null,"Bristol’s algal growing media in laboratory-grade distilled water","23±1","Chronic","Not stated","Not stated","Boudreau, T.M., P.K. Sibley, S.A. Mabury, D.G.C. Muir and K.R. Solomon. 2003. Laboratory evaluation of the toxicity of perfluorooctane sulfonate (PFOS) on Selenastrum capricornutum, Chlorella vulgaris, Lemna gibba, Daphnia magna, and Daphnia pulicaria. Archives of Environmental Contamination and Toxicology 44: 307-313.","431","Polypropylene or polyethylene","PFOS-K 95% from 3M. Treatment concs were PFOS anion","Nominal concs"]
["Freshwater/non-metal/plant","431-2",64,0.72727272727272729,"The highest possible grade for this datum is acceptable.","Chlorella vulgaris","Not stated","96 hrs","NOEC","Growth inhibition: cell count","8.2 mg/L (6.4-13.0)","Microalga","Chlorophyta",null,"Bristol’s algal growing media in laboratory-grade distilled water","23±1","Chronic","Not stated","N.A.","Boudreau, T.M., P.K. Sibley, S.A. Mabury, D.G.C. Muir and K.R. Solomon. 2003. Laboratory evaluation of the toxicity of perfluorooctane sulfonate (PFOS) on Selenastrum capricornutum, Chlorella vulgaris, Lemna gibba, Daphnia magna, and Daphnia pulicaria. Archives of Environmental Contamination and Toxicology 44: 307-313.","431","Polypropylene or polyethylene","PFOS-K 95% from 3M. Treatment concs were PFOS anion","Nominal concs"]
["Freshwater/non-metal/plant","431-20",64,0.72727272727272729,"The highest possible grade for this datum is acceptable.","Raphidocelis subcapitata","Not stated","96 hrs","IC50","Chlorophyll a conc. ","59.2 mg/L (50.9-67.4)","Microalga","Chlorophyta",null,"Bristol’s algal growing media in laboratory-grade distilled water","23±1","Chronic","Not stated","Not stated","Boudreau, T.M., P.K. Sibley, S.A. Mabury, D.G.C. Muir and K.R. Solomon. 2003. Laboratory evaluation of the toxicity of perfluorooctane sulfonate (PFOS) on Selenastrum capricornutum, Chlorella vulgaris, Lemna gibba, Daphnia magna, and Daphnia pulicaria. Archives of Environmental Contamination and Toxicology 44: 307-313.","431","Polypropylene or polyethylene","PFOS-K 95% from 3M. Treatment concs were PFOS anion","Nominal concs"]
["Freshwater/non-metal/plant","431-21",64,0.72727272727272729,"The highest possible grade for this datum is acceptable.","Raphidocelis subcapitata","Not stated","96 hrs","NOEC","Growth inhibition: cell count","5.3 mg/L (4.6-6.8)","Microalga","Chlorophyta",null,"Bristol’s algal growing media in laboratory-grade distilled water","23±1","Chronic","Not stated","Not stated","Boudreau, T.M., P.K. Sibley, S.A. Mabury, D.G.C. Muir and K.R. Solomon. 2003. Laboratory evaluation of the toxicity of perfluorooctane sulfonate (PFOS) on Selenastrum capricornutum, Chlorella vulgaris, Lemna gibba, Daphnia magna, and Daphnia pulicaria. Archives of Environmental Contamination and Toxicology 44: 307-313.","431","Polypropylene or polyethylene","PFOS-K 95% from 3M. Treatment concs were PFOS anion","Nominal concs"]
["Freshwater/non-metal/plant","431-22",64,0.72727272727272729,"The highest possible grade for this datum is acceptable.","Raphidocelis subcapitata","Not stated","96 hrs","NOEC","Chlorophyll a conc. ","16.6 mg/L (8.5-28.1)","Microalga","Chlorophyta",null,"Bristol’s algal growing media in laboratory-grade distilled water","23±1","Chronic","Not stated","Not stated","Boudreau, T.M., P.K. Sibley, S.A. Mabury, D.G.C. Muir and K.R. Solomon. 2003. Laboratory evaluation of the toxicity of perfluorooctane sulfonate (PFOS) on Selenastrum capricornutum, Chlorella vulgaris, Lemna gibba, Daphnia magna, and Daphnia pulicaria. Archives of Environmental Contamination and Toxicology 44: 307-313.","431","Polypropylene or polyethylene","PFOS-K 95% from 3M. Treatment concs were PFOS anion","Nominal concs"]
["Freshwater/non-metal/plant","431-3",64,0.72727272727272729,"The highest possible grade for this datum is acceptable.","Chlorella vulgaris","Not stated","96 hrs","IC50","Chlorophyll a conc. ","88.1 mg/L (71.2-104)","Microalga","Chlorophyta",null,"Bristol’s algal growing media in laboratory-grade distilled water","23±1","Chronic","Not stated","N.A.","Boudreau, T.M., P.K. Sibley, S.A. Mabury, D.G.C. Muir and K.R. Solomon. 2003. Laboratory evaluation of the toxicity of perfluorooctane sulfonate (PFOS) on Selenastrum capricornutum, Chlorella vulgaris, Lemna gibba, Daphnia magna, and Daphnia pulicaria. Archives of Environmental Contamination and Toxicology 44: 307-313.","431","Polypropylene or polyethylene","PFOS-K 95% from 3M. Treatment concs were PFOS anion","Nominal concs"]
["Freshwater/non-metal/plant","431-4",64,0.72727272727272729,"The highest possible grade for this datum is acceptable.","Chlorella vulgaris","Not stated","96 hrs","NOEC","Chlorophyll a conc. ","9.6 mg/L (7.6-16.5)","Microalga","Chlorophyta",null,"Bristol’s algal growing media in laboratory-grade distilled water","23±1","Chronic","Not stated","N.A.","Boudreau, T.M., P.K. Sibley, S.A. Mabury, D.G.C. Muir and K.R. Solomon. 2003. Laboratory evaluation of the toxicity of perfluorooctane sulfonate (PFOS) on Selenastrum capricornutum, Chlorella vulgaris, Lemna gibba, Daphnia magna, and Daphnia pulicaria. Archives of Environmental Contamination and Toxicology 44: 307-313.","431","Polypropylene or polyethylene","PFOS-K 95% from 3M. Treatment concs were PFOS anion","Nominal concs"]
["Freshwater/non-metal/non- plant","431-9",66,0.72527472527472525,"The highest possible grade for this datum is acceptable.","Daphnia magna","<24hr neonate","21 day","LOEC","Survival","42.9 mg/L (31.7-56.4)","Macroinvertebrate","Arthropoda","Branchiopoda","Clean well water",21,"Chronic","Not stated","N.A.","Boudreau, T.M., P.K. Sibley, S.A. Mabury, D.G.C. Muir and K.R. Solomon. 2003. Laboratory evaluation of the toxicity of perfluorooctane sulfonate (PFOS) on Selenastrum capricornutum, Chlorella vulgaris, Lemna gibba, Daphnia magna, and Daphnia pulicaria. Archives of Environmental Contamination and Toxicology 44: 307-313.","431","Polypropylene or polyethylene","PFOS-K 95% from 3M. Treatment concs were PFOS anion","Nominal concs"]
["Freshwater/non-metal/plant","432-1",72,0.81818181818181823,"The highest possible grade for this datum is acceptable.","Tetradesmus obliquus (formerly Scenedesmus obliquus and Acutodesmus obliquus)","Exponential growth phase","3 days","IC10","Growth inhibition","102 mM = 51000 mg/L","Microalga","Chlorophyta",null,"Algal medium using deionized water","22±1oC","Chronic","7.5 ± 0.2","N.A.","Liu, W., S. Chen, X. Quan and Y-H. Jin. 2008. Toxic effect of serial perfluorosulfonic and perfluorocarboxylic acids on the membrane system of a freshwater alga measured by flow cytometry. Environmental Toxicology and Chemistry 27: 1597-1604.","432","Not stated","PFOS from Sigma-Aldrich. CAS RN: 1763-23-1. Form and purity not stated","Nominal concs"]
["Freshwater/non-metal/plant","432-2",68,0.77272727272727271,"The highest possible grade for this datum is acceptable.","Tetradesmus obliquus (formerly Scenedesmus obliquus and Acutodesmus obliquus)","Exponential growth phase","3 days","IC50","Growth inhibition","156 mM = 78000 mg/L","Microalga","Chlorophyta",null,"Algal medium","Not stated","Chronic","Not stated","N.A.","Liu, W., S. Chen, X. Quan and Y-H. Jin. 2008. Toxic effect of serial perfluorosulfonic and perfluorocarboxylic acids on the membrane system of a freshwater alga measured by flow cytometry. Environmental Toxicology and Chemistry 27: 1597-1604.","432","Not stated","PFOS from Sigma-Aldrich. CAS RN: 1763-23-1. Form and purity not stated","Nominal concs"]
["Freshwater/non-metal/plant","432-2",72,0.81818181818181823,"The highest possible grade for this datum is acceptable.","Tetradesmus obliquus (formerly Scenedesmus obliquus and Acutodesmus obliquus)","Exponential growth phase","3 days","IC50","Growth inhibition","156 mM = 78000 mg/L","Microalga","Chlorophyta",null,"Algal medium using deionized water","22±1oC","Chronic","7.5 ± 0.2","N.A.","Liu, W., S. Chen, X. Quan and Y-H. Jin. 2008. Toxic effect of serial perfluorosulfonic and perfluorocarboxylic acids on the membrane system of a freshwater alga measured by flow cytometry. Environmental Toxicology and Chemistry 27: 1597-1604.","432","Not stated","PFOS from Sigma-Aldrich. CAS RN: 1763-23-1. Form and purity not stated","Nominal concs"]
["Freshwater/non-metal/plant","432-3",68,0.77272727272727271,"The highest possible grade for this datum is acceptable.","Tetradesmus obliquus (formerly Scenedesmus obliquus and Acutodesmus obliquus)","Exponential growth phase","3 days","IC10","Growth inhibition","110 mM = 55000 mg/L","Microalga","Chlorophyta",null,"Algal medium","Not stated","Chronic","Not stated","N.A.","Liu, W., S. Chen, X. Quan and Y-H. Jin. 2008. Toxic effect of serial perfluorosulfonic and perfluorocarboxylic acids on the membrane system of a freshwater alga measured by flow cytometry. Environmental Toxicology and Chemistry 27: 1597-1604.","432","Not stated","PFOS from Sigma-Aldrich. CAS RN: 1763-23-1. Form and purity not stated","Nominal concs"]
["Freshwater/non-metal/plant","432-3",72,0.81818181818181823,"The highest possible grade for this datum is acceptable.","Tetradesmus obliquus (formerly Scenedesmus obliquus and Acutodesmus obliquus)","Exponential growth phase","3 days","IC10","Growth inhibition","110 mM = 55000 mg/L","Microalga","Chlorophyta",null,"Algal medium using deionized water","22±1oC","Chronic","7.5 ± 0.2","N.A.","Liu, W., S. Chen, X. Quan and Y-H. Jin. 2008. Toxic effect of serial perfluorosulfonic and perfluorocarboxylic acids on the membrane system of a freshwater alga measured by flow cytometry. Environmental Toxicology and Chemistry 27: 1597-1604.","432","Not stated","PFOS from Sigma-Aldrich. CAS RN: 1763-23-1. Form and purity not stated","Nominal concs"]
["Freshwater/non-metal/plant","432-4",68,0.77272727272727271,"The highest possible grade for this datum is acceptable.","Tetradesmus obliquus (formerly Scenedesmus obliquus and Acutodesmus obliquus)","Exponential growth phase","3 days","IC50","Growth inhibition","200 mM = 10000 mg/L","Microalga","Chlorophyta",null,"Algal medium","Not stated","Chronic","Not stated","N.A.","Liu, W., S. Chen, X. Quan and Y-H. Jin. 2008. Toxic effect of serial perfluorosulfonic and perfluorocarboxylic acids on the membrane system of a freshwater alga measured by flow cytometry. Environmental Toxicology and Chemistry 27: 1597-1604.","432","Not stated","PFOS from Sigma-Aldrich. CAS RN: 1763-23-1. Form and purity not stated","Nominal concs"]
["Freshwater/non-metal/plant","432-4",72,0.81818181818181823,"The highest possible grade for this datum is acceptable.","Tetradesmus obliquus (formerly Scenedesmus obliquus and Acutodesmus obliquus)","Exponential growth phase","3 days","IC50","Growth inhibition","200 mM = 10000 mg/L","Microalga","Chlorophyta",null,"Algal medium using deionized water","22±1oC","Chronic","7.5 ± 0.2","N.A.","Liu, W., S. Chen, X. Quan and Y-H. Jin. 2008. Toxic effect of serial perfluorosulfonic and perfluorocarboxylic acids on the membrane system of a freshwater alga measured by flow cytometry. Environmental Toxicology and Chemistry 27: 1597-1604.","432","Not stated","PFOS from Sigma-Aldrich. CAS RN: 1763-23-1. Form and purity not stated","Nominal concs"]
["Freshwater/non-metal/non- plant","434-1",57,0.62637362637362637,"The highest possible grade for this datum is acceptable.","Enallagma cyathigerum ","Eggs","14 days","NOEC","Reproduction","10 mg/L (7.95 mg/L PFOS anion)","Macroinvertebrate","Arthropoda","Insecta","Dechlorinated tap water",21,"Chronic","≥7.5","N.A.","Bots, J., L. De Bruyn, T. Snijkers, B. Van den Branden and H. Van Gossum. 2010. Exposure to perfluorooctane sulfonic acid (PFOS) adversely affects the life-cycle of the damselfly Enallagma cyathigerum. Environmental Pollution 158: 901-905.","434","Polypropylene","PFOS-tetraethyl ammonium salt, 98% purity from Sigma Aldrich","Nominal concs"]
["Freshwater/non-metal/non- plant","434-2",57,0.62637362637362637,"The highest possible grade for this datum is acceptable.","Enallagma cyathigerum ","Eggs","14 days","NOEC","Reproduction","10 mg/L (7.95 mg/L PFOS anion)","Macroinvertebrate","Arthropoda","Insecta","Dechlorinated tap water",21,"Chronic","≥7.5","N.A.","Bots, J., L. De Bruyn, T. Snijkers, B. Van den Branden and H. Van Gossum. 2010. Exposure to perfluorooctane sulfonic acid (PFOS) adversely affects the life-cycle of the damselfly Enallagma cyathigerum. Environmental Pollution 158: 901-905.","434","Polypropylene","PFOS-tetraethyl ammonium salt, 98% purity from Sigma Aldrich","Nominal concs"]
["Freshwater/non-metal/non- plant","434-3",63,0.69230769230769229,"The highest possible grade for this datum is acceptable.","Enallagma cyathigerum ","Larvae","120 days","NOEC","Survival","0.01 mg/L (7.95 ug/L PFOS anion)","Macroinvertebrate","Arthropoda","Insecta","Dechlorinated tap water",21,"Chronic","≥7.5","N.A.","Bots, J., L. De Bruyn, T. Snijkers, B. Van den Branden and H. Van Gossum. 2010. Exposure to perfluorooctane sulfonic acid (PFOS) adversely affects the life-cycle of the damselfly Enallagma cyathigerum. Environmental Pollution 158: 901-905.","434","Polypropylene","PFOS-tetraethyl ammonium salt, 98% purity from Sigma Aldrich","Nominal concs"]
["Freshwater/non-metal/non- plant","434-4",68,0.74725274725274726,"The highest possible grade for this datum is acceptable.","Enallagma cyathigerum ","Larvae","120 days","NOEC","Development","0.01 mg/L (7.95 ug/L PFOS anion)","Macroinvertebrate","Arthropoda","Insecta","Dechlorinated tap water",21,"Chronic","≥7.5","N.A.","Bots, J., L. De Bruyn, T. Snijkers, B. Van den Branden and H. Van Gossum. 2010. Exposure to perfluorooctane sulfonic acid (PFOS) adversely affects the life-cycle of the damselfly Enallagma cyathigerum. Environmental Pollution 158: 901-905.","434","Polypropylene","PFOS-tetraethyl ammonium salt, 98% purity from Sigma Aldrich","Nominal concs"]
["Freshwater/non-metal/non- plant","434-5",68,0.74725274725274726,"The highest possible grade for this datum is acceptable.","Enallagma cyathigerum ","Larvae","120 days","NOEC","Development","<0.01 mg/L (7.95 ug/L PFOS anion)","Macroinvertebrate","Arthropoda","Insecta","Dechlorinated tap water",21,"Chronic","≥7.5","N.A.","Bots, J., L. De Bruyn, T. Snijkers, B. Van den Branden and H. Van Gossum. 2010. Exposure to perfluorooctane sulfonic acid (PFOS) adversely affects the life-cycle of the damselfly Enallagma cyathigerum. Environmental Pollution 158: 901-905.","434","Polypropylene","PFOS-tetraethyl ammonium salt, 98% purity from Sigma Aldrich","Nominal concs"]
["Freshwater/non-metal/non- plant","599-1",71,0.78021978021978022,"","Lithobates pipiens","embryo","5 weeks","LC50","Survival","6.21 mg/L (5.12-7.52)","Amphibian","Chordata","Amphibia","Lake Superior Water",20,"Chronic","Not stated","N.A.","Ankley, G.T., D.W. Kuehl, M.D. Kahl, K.M. Jensen, B.C. Butterworth and J.W. Nichols. 2004. Partial life-cycle toxicity and bioconcentration modeling of perfluorooctanesulfonate in the northern leopard frog (Rana pipiens). Environmental Toxicology and Chemistry 23: 2745-2755.","599","Glass aquaria","PFOS, form not stated, 98% purity from Fluka Chemical ","Measured"]
["Freshwater/non-metal/non- plant","701-1",68,0.74725274725274726,"","Pimephales promelas","Adult","21 day","EC50","Fecundity","0.23 mg/L (0.19-0.25)","Fish","Chordata","Teleostei ","Lake Superior water","Not stated","Chronic",7.30,"CaCO3 46 mg/L","Ankley, G.T., D.W. Kuehl, M.D. Kahl, K.M. Jensen, A. Linnum, R.L. Leino and D.A. Villeneuve. 2005. Reproductive and developmental toxicity and bioconcentration of perfluorooctanesulfonate in a partial life-cycle test with fathead minnow (Pimephales promelas). Environmental Toxicology and Chemistry 24: 2316-2324","701","Glass aquaria / pyrex beakers","PFOS-K, 98% purity from Fluka Chemical","Measured"]
["Freshwater/non-metal/non- plant","701-2",68,0.74725274725274726,"","Pimephales promelas","Fry","21 day","NOEC","Survival","0.3 mg/L","Fish","Chordata","Teleostei ","Lake Superior water","Not stated","Chronic",7.30,"CaCO3 46 mg/L","Ankley, G.T., D.W. Kuehl, M.D. Kahl, K.M. Jensen, A. Linnum, R.L. Leino and D.A. Villeneuve. 2005. Reproductive and developmental toxicity and bioconcentration of perfluorooctanesulfonate in a partial life-cycle test with fathead minnow (Pimephales promelas). Environmental Toxicology and Chemistry 24: 2316-2324","701","Glass aquaria / pyrex beakers","PFOS-K, 98% purity from Fluka Chemical","Measured"]
["Freshwater/non-metal/non- plant","701-3",68,0.74725274725274726,"","Pimephales promelas","Fry","24 days","NOEC","Growth","0.3 mg/L","Fish","Chordata","Teleostei ","Lake Superior water","Not stated","Chronic",7.30,"CaCO3 46 mg/L","Ankley, G.T., D.W. Kuehl, M.D. Kahl, K.M. Jensen, A. Linnum, R.L. Leino and D.A. Villeneuve. 2005. Reproductive and developmental toxicity and bioconcentration of perfluorooctanesulfonate in a partial life-cycle test with fathead minnow (Pimephales promelas). Environmental Toxicology and Chemistry 24: 2316-2324","701","Glass aquaria / pyrex beakers","PFOS-K, 98% purity from Fluka Chemical","Measured"]
["Freshwater/non-metal/non- plant","702-10",62,0.68131868131868134,"","Chironomus tentans","larvae","20 days","EC50","Emergence","0.0945 mg/L","Macroinvertebrate","Arthropoda","Insecta","ATSM hardwater","21±2","Chronic","Not stated","N.A.","MacDonald, M.M., A.L. Warne, N.L. Stock, S.A. Mabury, K.R. Solomon and P.K. Sibley. 2004. Toxicity of perfluorooctane sulfonic acid and perfluorooctanoic acid to Chironomus tentans. Environmental Toxicology and Chemistry 23: 2116-2123","702","Petri dishes / beakers - material not stated","95% PFOS-K from 3M. Treatment cons were PFOS anion","Measured"]
["Freshwater/non-metal/non- plant","702-11",62,0.68131868131868134,"","Chironomus tentans","larvae","20 days","EC10","Emergence","0.0893 mg/L","Macroinvertebrate","Arthropoda","Insecta","ATSM hardwater","21±2","Chronic","Not stated","N.A.","MacDonald, M.M., A.L. Warne, N.L. Stock, S.A. Mabury, K.R. Solomon and P.K. Sibley. 2004. Toxicity of perfluorooctane sulfonic acid and perfluorooctanoic acid to Chironomus tentans. Environmental Toxicology and Chemistry 23: 2116-2123","702","Petri dishes / beakers - material not stated","95% PFOS-K from 3M. Treatment cons were PFOS anion","Measured"]
["Freshwater/non-metal/non- plant","702-12",62,0.68131868131868134,"","Chironomus tentans","larvae","20 days","NOEC","Emergence","0.0023 mg/L","Macroinvertebrate","Arthropoda","Insecta","ATSM hardwater","21±2","Chronic","Not stated","N.A.","MacDonald, M.M., A.L. Warne, N.L. Stock, S.A. Mabury, K.R. Solomon and P.K. Sibley. 2004. Toxicity of perfluorooctane sulfonic acid and perfluorooctanoic acid to Chironomus tentans. Environmental Toxicology and Chemistry 23: 2116-2123","702","Petri dishes / beakers - material not stated","95% PFOS-K from 3M. Treatment cons were PFOS anion","Measured"]
["Freshwater/non-metal/non- plant","702-4",62,0.68131868131868134,"","Chironomus tentans","larvae","20 days","EC50","Survival","0.0922 mg/L","Macroinvertebrate","Arthropoda","Insecta","ATSM hardwater","21±2","Chronic","Not stated","N.A.","MacDonald, M.M., A.L. Warne, N.L. Stock, S.A. Mabury, K.R. Solomon and P.K. Sibley. 2004. Toxicity of perfluorooctane sulfonic acid and perfluorooctanoic acid to Chironomus tentans. Environmental Toxicology and Chemistry 23: 2116-2123","702","Petri dishes / beakers - material not stated","95% PFOS-K from 3M. Treatment cons were PFOS anion","Measured"]
["Freshwater/non-metal/non- plant","702-5",62,0.68131868131868134,"","Chironomus tentans","larvae","20 days","EC10","Survival","0.0864 mg/L","Macroinvertebrate","Arthropoda","Insecta","ATSM hardwater","21±2","Chronic","Not stated","N.A.","MacDonald, M.M., A.L. Warne, N.L. Stock, S.A. Mabury, K.R. Solomon and P.K. Sibley. 2004. Toxicity of perfluorooctane sulfonic acid and perfluorooctanoic acid to Chironomus tentans. Environmental Toxicology and Chemistry 23: 2116-2123","702","Petri dishes / beakers - material not stated","95% PFOS-K from 3M. Treatment cons were PFOS anion","Measured"]
["Freshwater/non-metal/non- plant","702-6",62,0.68131868131868134,"","Chironomus tentans","larvae","20 days","NOEC","Survival","0.0949 mg/L","Macroinvertebrate","Arthropoda","Insecta","ATSM hardwater","21±2","Chronic","Not stated","N.A.","MacDonald, M.M., A.L. Warne, N.L. Stock, S.A. Mabury, K.R. Solomon and P.K. Sibley. 2004. Toxicity of perfluorooctane sulfonic acid and perfluorooctanoic acid to Chironomus tentans. Environmental Toxicology and Chemistry 23: 2116-2123","702","Petri dishes / beakers - material not stated","95% PFOS-K from 3M. Treatment cons were PFOS anion","Measured"]
["Freshwater/non-metal/non- plant","702-7",62,0.68131868131868134,"","Chironomus tentans","larvae","20 days","EC50","Survival","0.0938 mg/L","Macroinvertebrate","Arthropoda","Insecta","ATSM hardwater","21±2","Chronic","Not stated","N.A.","MacDonald, M.M., A.L. Warne, N.L. Stock, S.A. Mabury, K.R. Solomon and P.K. Sibley. 2004. Toxicity of perfluorooctane sulfonic acid and perfluorooctanoic acid to Chironomus tentans. Environmental Toxicology and Chemistry 23: 2116-2123","702","Petri dishes / beakers - material not stated","95% PFOS-K from 3M. Treatment cons were PFOS anion","Measured"]
["Freshwater/non-metal/non- plant","702-8",62,0.68131868131868134,"","Chironomus tentans","larvae","20 days","EC10","Growth","0.0882 mg/L","Macroinvertebrate","Arthropoda","Insecta","ATSM hardwater","21±2","Chronic","Not stated","N.A.","MacDonald, M.M., A.L. Warne, N.L. Stock, S.A. Mabury, K.R. Solomon and P.K. Sibley. 2004. Toxicity of perfluorooctane sulfonic acid and perfluorooctanoic acid to Chironomus tentans. Environmental Toxicology and Chemistry 23: 2116-2123","702","Petri dishes / beakers - material not stated","95% PFOS-K from 3M. Treatment cons were PFOS anion","Measured"]
["Freshwater/non-metal/non- plant","702-9",62,0.68131868131868134,"","Chironomus tentans","larvae","20 days","NOEC","Growth","0.0217 mg/L","Macroinvertebrate","Arthropoda","Insecta","ATSM hardwater","21±2","Chronic","Not stated","N.A.","MacDonald, M.M., A.L. Warne, N.L. Stock, S.A. Mabury, K.R. Solomon and P.K. Sibley. 2004. Toxicity of perfluorooctane sulfonic acid and perfluorooctanoic acid to Chironomus tentans. Environmental Toxicology and Chemistry 23: 2116-2123","702","Petri dishes / beakers - material not stated","95% PFOS-K from 3M. Treatment cons were PFOS anion","Measured"]
["Freshwater/non-metal/non- plant","704-1",71,0.78021978021978022,"","Pimephales promelas","Adult","28 days","LD50","Survival","7.2 mg/L (5.2-9.2)","Fish","Chordata","Teleostei","Pond water",18,"Chronic",9.1999999999999993,"N.A.","Oakes, K.D., P.K. Sibley, J.W. Martin, D.D. MacLean, K.R. Solomon, S.A. Mabury, G.J. Van der Kraak. 2005. Short-term exposures of fish to perfluorooctane sulfonate: Acute effects on fatty acly-coa oxidase activity, oxidative stress, and circulating sex steriods. Environmental Toxicology and Chemistry 24: 1172-1181.","704","Microcosms - steel panels lined with food grade polyvinyl chloride","PFOS-K, 86% purity, treatment concs were PFOS anion from 3M (Fluorad fluorochemical surfactant FC-95)","Measured"]
["Freshwater/non-metal/non- plant","704-2",71,0.78021978021978022,"","Pimephales promelas","Adult","28 days","LC10","Survival","3.5 mg/L (1.0-6.1)","Fish","Chordata","Teleostei","Pond water",18,"Chronic",9.1999999999999993,"N.A.","Oakes, K.D., P.K. Sibley, J.W. Martin, D.D. MacLean, K.R. Solomon, S.A. Mabury, G.J. Van der Kraak. 2005. Short-term exposures of fish to perfluorooctane sulfonate: Acute effects on fatty acly-coa oxidase activity, oxidative stress, and circulating sex steriods. Environmental Toxicology and Chemistry 24: 1172-1181.","704","Microcosms - steel panels lined with food grade polyvinyl chloride","PFOS-K, 86% purity, treatment concs were PFOS anion from 3M (Fluorad fluorochemical surfactant FC-95)","Measured"]
["Freshwater/non-metal/non- plant","704-3",72,0.79120879120879117,"","Pimephales promelas","Adult","28 days","NOEC","Growth","3000 ug/L","Fish","Chordata","Actinopterygii","Pond water","20.1-29.2oC","Chronic","7.8-8.2","N.A.","Oakes, K.D., P.K. Sibley, J.W. Martin, D.D. MacLean, K.R. Solomon, S.A. Mabury and G.J. van der Kraak. 2005. Short-term exposures of fish to perfluorooctane sulfonate: acute effects on fatty acyl-coa oxidase activity, oxidative stress, and circulating sex steroids. Environmental Toxicology and Chemistry 24: 1172-1181","704","Microcosms - steel panels lined with food grade polyvinyl chloride","PFOS-K, 86% purity, treatment concs were PFOS anion from 3M (Fluorad fluorochemical surfactant FC-95)","Measured"]
["Freshwater/non-metal/non- plant","704-4",72,0.79120879120879117,"","Oncorhynchus mykiss","Juvenile","12 days","NOEC","Growth","2900 ug/L","Fish","Chordata","Actinopterygii","Pond water","6-16.5oC","Acute ","7.8-8.2","N.A.","Oakes, K.D., P.K. Sibley, J.W. Martin, D.D. MacLean, K.R. Solomon, S.A. Mabury and G.J. van der Kraak. 2005. Short-term exposures of fish to perfluorooctane sulfonate: acute effects on fatty acyl-coa oxidase activity, oxidative stress, and circulating sex steroids. Environmental Toxicology and Chemistry 24: 1172-1181","704","Microcosms - steel panels lined with food grade polyvinyl chloride","PFOS-K, 86% purity, treatment concs were PFOS anion from 3M (Fluorad fluorochemical surfactant FC-95)","Measured"]
["Freshwater/non-metal/non- plant","704-5",64,0.70329670329670335,"","Oncorhynchus mykiss","Adult","14 days","NOEC","Growth","1000 ug/L","Fish","Chordata","Actinopterygii","Pond water","12oC","Acute ","7.8-8.2","N.A.","Oakes, K.D., P.K. Sibley, J.W. Martin, D.D. MacLean, K.R. Solomon, S.A. Mabury and G.J. van der Kraak. 2005. Short-term exposures of fish to perfluorooctane sulfonate: acute effects on fatty acyl-coa oxidase activity, oxidative stress, and circulating sex steroids. Environmental Toxicology and Chemistry 24: 1172-1181","704","Fibre glass tank ","PFOS-K, 86% purity, treatment concs were PFOS anion from 3M (Fluorad fluorochemical surfactant FC-95)","Measured"]
["Freshwater/non-metal/non- plant","704-6",66,0.72527472527472525,"","Semotilus antromaculatus","Adult","14 days","NOEC","Growth","2900 ug/L","Fish","Chordata","Actinopterygii","Pond water","6-16.5oC","Acute ","7.8-8.2","N.A.","Oakes, K.D., P.K. Sibley, J.W. Martin, D.D. MacLean, K.R. Solomon, S.A. Mabury and G.J. van der Kraak. 2005. Short-term exposures of fish to perfluorooctane sulfonate: acute effects on fatty acyl-coa oxidase activity, oxidative stress, and circulating sex steroids. Environmental Toxicology and Chemistry 24: 1172-1181","704","Microcosms - steel panels lined with food grade polyvinyl chloride","PFOS-K, 86% purity, treatment concs were PFOS anion from 3M (Fluorad fluorochemical surfactant FC-95)","Measured"]
["Freshwater/non-metal/non- plant","704-7",66,0.72527472527472525,"","Notropis hudsonius","Adult","14 days","NOEC","Growth","2900 ug/L","Fish","Chordata","Actinopterygii","Pond water","6-16.5oC","Acute ","7.8-8.2","N.A.","Oakes, K.D., P.K. Sibley, J.W. Martin, D.D. MacLean, K.R. Solomon, S.A. Mabury and G.J. van der Kraak. 2005. Short-term exposures of fish to perfluorooctane sulfonate: acute effects on fatty acyl-coa oxidase activity, oxidative stress, and circulating sex steroids. Environmental Toxicology and Chemistry 24: 1172-1181","704","Microcosms - steel panels lined with food grade polyvinyl chloride","PFOS-K, 86% purity, treatment concs were PFOS anion from 3M (Fluorad fluorochemical surfactant FC-95)","Measured"]
["Freshwater/non-metal/non- plant","704-8",66,0.72527472527472525,"","Catostomus commersoni","Adult","14 days","NOEC","Growth","2900 ug/L","Fish","Chordata","Actinopterygii","Pond water","6-16.5oC","Acute ","7.8-8.2","N.A.","Oakes, K.D., P.K. Sibley, J.W. Martin, D.D. MacLean, K.R. Solomon, S.A. Mabury and G.J. van der Kraak. 2005. Short-term exposures of fish to perfluorooctane sulfonate: acute effects on fatty acyl-coa oxidase activity, oxidative stress, and circulating sex steroids. Environmental Toxicology and Chemistry 24: 1172-1181","704","Microcosms - steel panels lined with food grade polyvinyl chloride","PFOS-K, 86% purity, treatment concs were PFOS anion from 3M (Fluorad fluorochemical surfactant FC-95)","Measured"]
["Freshwater/non-metal/plant","705-1",66,0.75,"","Anabaena flos-aquae","Not stated","96 hrs","NOEC","Growth inhibition","93.8 mg/L","Blue-green algae","Chlorophyta","Cyanophyceae ","Algae culture medium and purified well water","22.8 - 23.8oC","Chronic","7.4-7.6","N.A.","Hazard Assessment of Perfluorooctane sulfonate (PFOS) and its Salts. Organisation for Economic Co-operation and Development. 2002. ENV/JM/RD(2002)17/FINAL","705","Glass flasks","PFOS-K, 86.9% purity","Measured"]
["Freshwater/non-metal/non- plant","705-12",70,0.76923076923076927,"","Pimephales promelas","Embryo","42 day","NOEC","Mortality","0.3 mg/L","Fish","Chordata","Actinopterygii"," 0.45  µ m filtered well water","24.3-24.7","Chronic","8.0-8.4","N.A.","Hazard Assessment of Perfluorooctane sulfonate (PFOS) and its Salts. Organisation for Economic Co-operation and Development (OECD). 2002. ENV/JM/RD(2002)17/FINAL","705","Glass flasks","PFOS-K, 86.9% purity","Measured"]
["Freshwater/non-metal/plant","705-2",66,0.75,"","Anabaena flos-aquae","Not stated","96 hrs","EC10","Growth inhibition","82 mg/L","Blue-green algae","Chlorophyta","Cyanophyceae ","Algae culture medium and reverse osmosis-purified well water","22.8 - 23.8oC","Chronic",7.40,"N.A.","Hazard Assessment of Perfluorooctane sulfonate (PFOS) and its Salts. Organisation for Economic Co-operation and Development. 2002. ENV/JM/RD(2002)17/FINAL","705","Glass flasks","PFOS-K, 86.9% purity","Measured"]
["Freshwater/non-metal/plant","705-3",66,0.75,"","Anabaena flos-aquae","Not stated","96 hrs","EC50","Growth inhibition","131 mg/L","Blue-green algae","Chlorophyta","Cyanophyceae ","Algae culture medium and purified well water","22.8 - 23.8oC","Chronic","7.4-7.6","N.A.","Hazard Assessment of Perfluorooctane sulfonate (PFOS) and its Salts. Organisation for Economic Co-operation and Development. 2002. ENV/JM/RD(2002)17/FINAL","705","Glass flasks","PFOS-K, 86.9% purity","Measured"]
["Freshwater/non-metal/plant","705-4",66,0.75,"","Navicula pelliculosa","Not stated","96 hrs","NOEC","Growth inhibition","150 mg/L","Microalga","Chlorophyta","Bacillariophyceae","Algae culture medium and purified well water","22.8 - 23.8oC","Chronic","7.4-7.6","N.A.","Hazard Assessment of Perfluorooctane sulfonate (PFOS) and its Salts. Organisation for Economic Co-operation and Development. 2002. ENV/JM/RD(2002)17/FINAL","705","Glass flasks","PFOS-K, 86.9% purity","Measured"]
["Freshwater/non-metal/plant","705-5",66,0.75,"","Navicula pelliculosa","Not stated","96 hrs","EC50","Growth inhibition","263 mg/L","Microalga","Chlorophyta","Bacillariophyceae","Algae culture medium and purified well water","22.8 - 23.8oC","Chronic","7.4-7.6","N.A.","Hazard Assessment of Perfluorooctane sulfonate (PFOS) and its Salts. Organisation for Economic Co-operation and Development. 2002. ENV/JM/RD(2002)17/FINAL","705","Glass flasks","PFOS-K, 86.9% purity","Measured"]
["Freshwater/non-metal/plant","705-6",66,0.75,"","Navicula pelliculosa","Not stated","96 hrs","EC10","Growth inhibition","62.3 mg/L","Microalga","Chlorophyta","Bacillariophyceae","Algae culture medium and purified well water","22.8 - 23.8oC","Chronic","7.4-7.6","N.A.","Hazard Assessment of Perfluorooctane sulfonate (PFOS) and its Salts. Organisation for Economic Co-operation and Development. 2002. ENV/JM/RD(2002)17/FINAL","705","Glass flasks","PFOS-K, 86.9% purity","Measured"]
["Freshwater/non-metal/non- plant","706-1",75,0.82417582417582413,"The highest possible grade for this datum is acceptable.","Daphnia magna","Neonate","21 day","LOEC","Growth","0.008 mg/L ","Macroinvertebrate","Arthropoda","Branchiopoda","Daphnia culture medium","20 ± 1","Chronic","7.5±0.3","Not stated","Lu, G-h., J-c. Liu, L-s. Sun and L-j. Yuan. 2015. Toxicty of perfluoroononanoic acid and perfluorooctane sulfonate to Daphnia magna. Water Science and Engineering 8: 40-48.","706","Glass beakers","PFOS, form not stated, 98% purity from Matrix Scientific Co. ","Nominal concs"]
["Freshwater/non-metal/non- plant","706-2",75,0.82417582417582413,"The highest possible grade for this datum is acceptable.","Daphnia magna","Neonate","21 day","NOEC","Reproduction","0.008 mg/L ","Macroinvertebrate","Arthropoda","Branchiopoda","Daphnia culture medium","20 ± 1","Chronic","7.5±0.3","Not stated","Lu, G-h., J-c. Liu, L-s. Sun and L-j. Yuan. 2015. Toxicty of perfluoroononanoic acid and perfluorooctane sulfonate to Daphnia magna. Water Science and Engineering 8: 40-48.","706","Glass beakers","PFOS, form not stated, 98% purity from Matrix Scientific Co. ","Nominal concs"]
["Freshwater/non-metal/non- plant","706-3",64,0.70329670329670335,"The highest possible grade for this datum is acceptable.","Daphnia magna","Neonate","21 day","LOEC","Reproduction","40 ug/L","Macroinvertebrate","Arthropoda","Branchiopoda","Daphnia culture medium","20 ± 1","Chronic","7.5±0.3","Not stated","Lu, G-h., J-c. Liu, L-s. Sun and L-j. Yuan. 2015. Toxicty of perfluoroononanoic acid and perfluorooctane sulfonate to Daphnia magna. Water Science and Engineering 8: 40-48","706","Glass beakers","PFOS, form not stated, 98% purity from Matrix Scientific Co. ","Nominal concs"]
["Freshwater/non-metal/non- plant","706-4",64,0.70329670329670335,"The highest possible grade for this datum is acceptable.","Daphnia magna","Neonate","21 day","NOEC","Reproduction","200ug/L","Macroinvertebrate","Arthropoda","Branchiopoda","Daphnia culture medium","20 ± 1","Chronic","7.5±0.3","Not stated","Lu, G-h., J-c. Liu, L-s. Sun and L-j. Yuan. 2015. Toxicty of perfluoroononanoic acid and perfluorooctane sulfonate to Daphnia magna. Water Science and Engineering 8: 40-48","706","Glass beakers","PFOS, form not stated, 98% purity from Matrix Scientific Co. ","Nominal concs"]
["Freshwater/non-metal/non- plant","706-5",64,0.70329670329670335,"The highest possible grade for this datum is acceptable.","Daphnia magna","Neonate","21 day","LOEC","Reproduction","1000 ug/L","Macroinvertebrate","Arthropoda","Branchiopoda","Daphnia culture medium","20 ± 1","Chronic","7.5±0.3","Not stated","Lu, G-h., J-c. Liu, L-s. Sun and L-j. Yuan. 2015. Toxicty of perfluoroononanoic acid and perfluorooctane sulfonate to Daphnia magna. Water Science and Engineering 8: 40-48","706","Glass beakers","PFOS, form not stated, 98% purity from Matrix Scientific Co. ","Nominal concs"]
["Freshwater/non-metal/non- plant","707-1",75,0.72527472527472525,null,"Danio rerio","Eggs","90 days","LOEC","Growth","0.734 ug/L","Fish","Chordata","Actinopterygii","Tap water and deionized water","26±1oC","Chronic","8.25-8.75","600–750","Keiter, S., L. Baumann, H. Farber, H. Holbech, D. Skutlarek, M. Engwall and T. Braunbeck. 2012. Long-term effects of a binary mixture of perfluorooctane sulfonate (PFOS) and bisphenol A (BPA) in zebrafish (Danio rerio). Aquatic Toxicology 118-119: 116-129.","707","Glass dishes / glass aquaria","PFOS-K 98% from Sigma Aldrich CAS RN: 2795-39-7","Measured"]
["Freshwater/non-metal/non- plant","707-10",66,0.72527472527472525,"","Danio rerio","Eggs","90 days","LOEC","Growth","0.734 ug/L","Fish","Chordata","Actinopterygii","Tap water and deionized water","26±1oC","Chronic","8.25-8.75","600–750","Keiter, S., L. Baumann, H. Farber, H. Holbech, D. Skutlarek, M. Engwall and T. Braunbeck. 2012. Long-term effects of a binary mixture of perfluorooctane sulfonate (PFOS) and bisphenol A (BPA) in zebrafish (Danio rerio). Aquatic Toxicology 118-119: 116-129.","707","Glass dishes / glass aquaria","PFOS-K 98% from Sigma Aldrich CAS RN: 2795-39-7","Measured"]
["Freshwater/non-metal/non- plant","707-11",66,0.72527472527472525,"","Danio rerio","Eggs","180 days","LOEC","Growth","0.734 ug/L","Fish","Chordata","Actinopterygii","Tap water and deionized water","26±1oC","Chronic","8.25-8.75","600–750","Keiter, S., L. Baumann, H. Farber, H. Holbech, D. Skutlarek, M. Engwall and T. Braunbeck. 2012. Long-term effects of a binary mixture of perfluorooctane sulfonate (PFOS) and bisphenol A (BPA) in zebrafish (Danio rerio). Aquatic Toxicology 118-119: 116-129.","707","Glass dishes / glass aquaria","PFOS-K 98% from Sigma Aldrich CAS RN: 2795-39-7","Measured"]
["Freshwater/non-metal/non- plant","707-12",66,0.72527472527472525,"","Danio rerio","Eggs","180 days","NOEC","Growth","0.734 ug/L","Fish","Chordata","Actinopterygii","Tap water and deionized water","26±1oC","Chronic","8.25-8.75","600–750","Keiter, S., L. Baumann, H. Farber, H. Holbech, D. Skutlarek, M. Engwall and T. Braunbeck. 2012. Long-term effects of a binary mixture of perfluorooctane sulfonate (PFOS) and bisphenol A (BPA) in zebrafish (Danio rerio). Aquatic Toxicology 118-119: 116-129.","707","Glass dishes / glass aquaria","PFOS-K 98% from Sigma Aldrich CAS RN: 2795-39-7","Measured"]
["Freshwater/non-metal/non- plant","707-13",66,0.72527472527472525,"","Danio rerio","Eggs","180 days","LOEC","Growth","106.9 ug/L","Fish","Chordata","Actinopterygii","Tap water and deionized water","26±1oC","Chronic","8.25-8.75","600–750","Keiter, S., L. Baumann, H. Farber, H. Holbech, D. Skutlarek, M. Engwall and T. Braunbeck. 2012. Long-term effects of a binary mixture of perfluorooctane sulfonate (PFOS) and bisphenol A (BPA) in zebrafish (Danio rerio). Aquatic Toxicology 118-119: 116-129.","707","Glass dishes / glass aquaria","PFOS-K 98% from Sigma Aldrich CAS RN: 2795-39-7","Measured"]
["Freshwater/non-metal/non- plant","707-14",66,0.72527472527472525,"","Danio rerio","Eggs","30 days","LOEC","Growth","0.734 ug/L","Fish","Chordata","Actinopterygii","Tap water and deionized water","26±1oC","Chronic","8.25-8.75","600–750","Keiter, S., L. Baumann, H. Farber, H. Holbech, D. Skutlarek, M. Engwall and T. Braunbeck. 2012. Long-term effects of a binary mixture of perfluorooctane sulfonate (PFOS) and bisphenol A (BPA) in zebrafish (Danio rerio). Aquatic Toxicology 118-119: 116-129.","707","Glass dishes / glass aquaria","PFOS-K 98% from Sigma Aldrich CAS RN: 2795-39-7","Measured"]
["Freshwater/non-metal/non- plant","707-15",66,0.72527472527472525,"","Danio rerio","Eggs","90 days","LOEC","Growth","0.734 ug/L","Fish","Chordata","Actinopterygii","Tap water and deionized water","26±1oC","Chronic","8.25-8.75","600–750","Keiter, S., L. Baumann, H. Farber, H. Holbech, D. Skutlarek, M. Engwall and T. Braunbeck. 2012. Long-term effects of a binary mixture of perfluorooctane sulfonate (PFOS) and bisphenol A (BPA) in zebrafish (Danio rerio). Aquatic Toxicology 118-119: 116-129.","707","Glass dishes / glass aquaria","PFOS-K 98% from Sigma Aldrich CAS RN: 2795-39-7","Measured"]
["Freshwater/non-metal/non- plant","707-16",66,0.72527472527472525,"","Danio rerio","Eggs","180 days","NOEC","Growth","106.9 ug/L","Fish","Chordata","Actinopterygii","Tap water and deionized water","26±1oC","Chronic","8.25-8.75","600–750","Keiter, S., L. Baumann, H. Farber, H. Holbech, D. Skutlarek, M. Engwall and T. Braunbeck. 2012. Long-term effects of a binary mixture of perfluorooctane sulfonate (PFOS) and bisphenol A (BPA) in zebrafish (Danio rerio). Aquatic Toxicology 118-119: 116-129.","707","Glass dishes / glass aquaria","PFOS-K 98% from Sigma Aldrich CAS RN: 2795-39-7","Measured"]
["Freshwater/non-metal/non- plant","707-17",66,0.72527472527472525,"","Danio rerio","Eggs","180 days","LOEC","Growth","0.734 ug/L","Fish","Chordata","Actinopterygii","Tap water and deionized water","26±1oC","Chronic","8.25-8.75","600–750","Keiter, S., L. Baumann, H. Farber, H. Holbech, D. Skutlarek, M. Engwall and T. Braunbeck. 2012. Long-term effects of a binary mixture of perfluorooctane sulfonate (PFOS) and bisphenol A (BPA) in zebrafish (Danio rerio). Aquatic Toxicology 118-119: 116-129.","707","Glass dishes / glass aquaria","PFOS-K 98% from Sigma Aldrich CAS RN: 2795-39-7","Measured"]
["Freshwater/non-metal/non- plant","707-2",75,0.72527472527472525,"","Danio rerio","Eggs","180 days","LOEC","Growth","0.734 ug/L","Fish","Chordata","Actinopterygii","Tap water and deionized water","26±1oC","Chronic","8.25-8.75","600–750","Keiter, S., L. Baumann, H. Farber, H. Holbech, D. Skutlarek, M. Engwall and T. Braunbeck. 2012. Long-term effects of a binary mixture of perfluorooctane sulfonate (PFOS) and bisphenol A (BPA) in zebrafish (Danio rerio). Aquatic Toxicology 118-119: 116-129.","707","Glass dishes / glass aquaria","PFOS-K 98% from Sigma Aldrich CAS RN: 2795-39-7","Measured"]
["Freshwater/non-metal/non- plant","707-3",66,0.72527472527472525,"","Danio rerio","Eggs","90 days","LOEC","Growth","0.734 ug/L","Fish","Chordata","Actinopterygii","Tap water and deionized water","26±1oC","Chronic","8.25-8.75","600–750","Keiter, S., L. Baumann, H. Farber, H. Holbech, D. Skutlarek, M. Engwall and T. Braunbeck. 2012. Long-term effects of a binary mixture of perfluorooctane sulfonate (PFOS) and bisphenol A (BPA) in zebrafish (Danio rerio). Aquatic Toxicology 118-119: 116-129.","707","Glass dishes / glass aquaria","PFOS-K 98% from Sigma Aldrich CAS RN: 2795-39-7","Measured"]
["Freshwater/non-metal/non- plant","707-4",66,0.72527472527472525,"","Danio rerio","Eggs","180 days","NOEC","Growth","0.734 ug/L","Fish","Chordata","Actinopterygii","Tap water and deionized water","26±1oC","Chronic","8.25-8.75","600–750","Keiter, S., L. Baumann, H. Farber, H. Holbech, D. Skutlarek, M. Engwall and T. Braunbeck. 2012. Long-term effects of a binary mixture of perfluorooctane sulfonate (PFOS) and bisphenol A (BPA) in zebrafish (Danio rerio). Aquatic Toxicology 118-119: 116-129.","707","Glass dishes / glass aquaria","PFOS-K 98% from Sigma Aldrich CAS RN: 2795-39-7","Measured"]
["Freshwater/non-metal/non- plant","707-5",66,0.72527472527472525,"","Danio rerio","Eggs","180 days","LOEC","Growth","106.9 ug/L","Fish","Chordata","Actinopterygii","Tap water and deionized water","26±1oC","Chronic","8.25-8.75","600–750","Keiter, S., L. Baumann, H. Farber, H. Holbech, D. Skutlarek, M. Engwall and T. Braunbeck. 2012. Long-term effects of a binary mixture of perfluorooctane sulfonate (PFOS) and bisphenol A (BPA) in zebrafish (Danio rerio). Aquatic Toxicology 118-119: 116-129.","707","Glass dishes / glass aquaria","PFOS-K 98% from Sigma Aldrich CAS RN: 2795-39-7","Measured"]
["Freshwater/non-metal/non- plant","707-6",66,0.72527472527472525,"","Danio rerio","Eggs","180 days","NOEC","Growth","267.6 ug/L","Fish","Chordata","Actinopterygii","Tap water and deionized water","26±1oC","Chronic","8.25-8.75","600–750","Keiter, S., L. Baumann, H. Farber, H. Holbech, D. Skutlarek, M. Engwall and T. Braunbeck. 2012. Long-term effects of a binary mixture of perfluorooctane sulfonate (PFOS) and bisphenol A (BPA) in zebrafish (Danio rerio). Aquatic Toxicology 118-119: 116-129.","707","Glass dishes / glass aquaria","PFOS-K 98% from Sigma Aldrich CAS RN: 2795-39-7","Measured"]
["Freshwater/non-metal/non- plant","707-7",66,0.72527472527472525,"","Danio rerio","Eggs","90 days","NOEC","Growth","267.6 ug/L","Fish","Chordata","Actinopterygii","Tap water and deionized water","26±1oC","Chronic","8.25-8.75","600–750","Keiter, S., L. Baumann, H. Farber, H. Holbech, D. Skutlarek, M. Engwall and T. Braunbeck. 2012. Long-term effects of a binary mixture of perfluorooctane sulfonate (PFOS) and bisphenol A (BPA) in zebrafish (Danio rerio). Aquatic Toxicology 118-119: 116-129.","707","Glass dishes / glass aquaria","PFOS-K 98% from Sigma Aldrich CAS RN: 2795-39-7","Measured"]
["Freshwater/non-metal/non- plant","707-8",66,0.72527472527472525,"","Danio rerio","Eggs","180 days","LOEC","Growth","0.734 ug/L","Fish","Chordata","Actinopterygii","Tap water and deionized water","26±1oC","Chronic","8.25-8.75","600–750","Keiter, S., L. Baumann, H. Farber, H. Holbech, D. Skutlarek, M. Engwall and T. Braunbeck. 2012. Long-term effects of a binary mixture of perfluorooctane sulfonate (PFOS) and bisphenol A (BPA) in zebrafish (Danio rerio). Aquatic Toxicology 118-119: 116-129.","707","Glass dishes / glass aquaria","PFOS-K 98% from Sigma Aldrich CAS RN: 2795-39-7","Measured"]
["Freshwater/non-metal/non- plant","707-9",66,0.72527472527472525,"","Danio rerio","Eggs","30 days","LOEC","Growth","0.734 ug/L","Fish","Chordata","Actinopterygii","Tap water and deionized water","26±1oC","Chronic","8.25-8.75","600–750","Keiter, S., L. Baumann, H. Farber, H. Holbech, D. Skutlarek, M. Engwall and T. Braunbeck. 2012. Long-term effects of a binary mixture of perfluorooctane sulfonate (PFOS) and bisphenol A (BPA) in zebrafish (Danio rerio). Aquatic Toxicology 118-119: 116-129.","707","Glass dishes / glass aquaria","PFOS-K 98% from Sigma Aldrich CAS RN: 2795-39-7","Measured"]
["Freshwater/non-metal/non- plant","708-1",63,0.69230769230769229,"The highest possible grade for this datum is acceptable.","Xiphorus helleri","fry","90 days","LOEC","growth","100 ug/L","Fish","Chordata","Teleostei","Dechlorinated tap water",27,"Chronic","Not stated","N.A.","Han, J. and Z. Fang. 2010. Estrogenic effects, reproductive impairment and developmental toxicity in ovoviparous swordtail fish (Xiphophorus helleri) exposed to perfluorooctane sulfonate (PFOS). Aquatic Toxicology 99: 281-290","708","Tanks - material not stated","PFOS-K, 98% purity from Alfa Aesar","Nominal concs"]
["Freshwater/non-metal/non- plant","708-1",60,0.65934065934065933,"The highest possible grade for this datum is acceptable.","Xiphophorus helleri","Fry","90 days","NOEC","Growth","100 ug/L","Fish","Chordata","Actinopterygii","Dechlorinated tap water","27±1","Chronic","Not stated","Not stated","Han, J. and Z. Fang. 2010. Estrogenic effects, reproductive impairment and developmental toxicity in ovoviparous swordtail fish (Xiphophorus helleri) exposed to perfluorooctance sulfonate (PFOS). Aquatic Toxicology 99: 281-290","708","Tanks - material not stated","PFOS-K, 98% purity from Alfa Aesar","Nominal concs"]
["Freshwater/non-metal/non- plant","708-2",60,0.65934065934065933,"The highest possible grade for this datum is acceptable.","Xiphophorus helleri","Fry","90 days","LOEC","Growth","100 ug/L","Fish","Chordata","Actinopterygii","Dechlorinated tap water","27±1","Chronic","Not stated","Not stated","Han, J. and Z. Fang. 2010. Estrogenic effects, reproductive impairment and developmental toxicity in ovoviparous swordtail fish (Xiphophorus helleri) exposed to perfluorooctance sulfonate (PFOS). Aquatic Toxicology 99: 281-290","708","Tanks - material not stated","PFOS-K, 98% purity from Alfa Aesar","Nominal concs"]
["Freshwater/non-metal/non- plant","708-3",60,0.65934065934065933,"The highest possible grade for this datum is acceptable.","Xiphophorus helleri","Fry","90 days","NOEC","Growth","100 ug/L","Fish","Chordata","Actinopterygii","Dechlorinated tap water","27±1","Chronic","Not stated","Not stated","Han, J. and Z. Fang. 2010. Estrogenic effects, reproductive impairment and developmental toxicity in ovoviparous swordtail fish (Xiphophorus helleri) exposed to perfluorooctance sulfonate (PFOS). Aquatic Toxicology 99: 281-290","708","Tanks - material not stated","PFOS-K, 98% purity from Alfa Aesar","Nominal concs"]
["Freshwater/non-metal/non- plant","708-4",60,0.65934065934065933,"The highest possible grade for this datum is acceptable.","Xiphophorus helleri","fry","90 days","NOEC","Growth","100 ug/L","Fish","Chordata","Actinopterygii","Dechlorinated tap water","27±1","Chronic","Not stated","Not stated","Han, J. and Z. Fang. 2010. Estrogenic effects, reproductive impairment and developmental toxicity in ovoviparous swordtail fish (Xiphophorus helleri) exposed to perfluorooctance sulfonate (PFOS). Aquatic Toxicology 99: 281-290","708","Tanks - material not stated","PFOS-K, 98% purity from Alfa Aesar","Nominal concs"]
["Freshwater/non-metal/plant","709-1",65,0.73863636363636365,"","Myriophyllum sibiricum","Not stated","42 days","EC10","Growth","100 ug/L","Macrophyte","Tracheophyta","Irrigation pond water","Not stated","Not stated","Chronic","not stated","N.A.","Hanson, M.L., P.K. Sibley, R.A. Brain, S.A. Mabury and K.R. Solomon. 2005. Microcosm evaluation of the toxicity and risk to aquatic macrophytes from perfluorooctane sulfonic acid. Archives of Environmental Contamination and Toxicology 48: 329-337","709","Plastic tanks","PFOS-K, From 3M purity not stated","Measured"]
["Freshwater/non-metal/plant","709-10",63,0.71590909090909094,"","Myriophyllum spicatam","not stated","42 days","EC10","Growth","10000 ug/L","Macrophyte","Tracheophyta","Irrigation pond water","Not stated","Not stated","Chronic","not stated","N.A.","Hanson, M.L., P.K. Sibley, R.A. Brain, S.A. Mabury and K.R. Solomon. 2005. Microcosm evaluation of the toxicity and risk to aquatic macrophytes from perfluorooctane sulfonic acid. Archives of Environmental Contamination and Toxicology 48: 329-337","709","Plastic tanks","PFOS-K, From 3M purity not stated","Measured"]
["Freshwater/non-metal/plant","709-11",63,0.71590909090909094,"","Myriophyllum spicatam","not stated","28 days","EC10","Growth","4600 ug/L","Macrophyte","Tracheophyta","Irrigation pond water","Not stated","Not stated","Chronic","not stated","N.A.","Hanson, M.L., P.K. Sibley, R.A. Brain, S.A. Mabury and K.R. Solomon. 2005. Microcosm evaluation of the toxicity and risk to aquatic macrophytes from perfluorooctane sulfonic acid. Archives of Environmental Contamination and Toxicology 48: 329-337","709","Plastic tanks","PFOS-K, From 3M purity not stated","Measured"]
["Freshwater/non-metal/plant","709-12",63,0.71590909090909094,"","Myriophyllum spicatam","not stated","42 days","EC10","Growth","3500 ug/L","Macrophyte","Tracheophyta","Irrigation pond water","Not stated","Not stated","Chronic","not stated","N.A.","Hanson, M.L., P.K. Sibley, R.A. Brain, S.A. Mabury and K.R. Solomon. 2005. Microcosm evaluation of the toxicity and risk to aquatic macrophytes from perfluorooctane sulfonic acid. Archives of Environmental Contamination and Toxicology 48: 329-337","709","Plastic tanks","PFOS-K, From 3M purity not stated","Measured"]
["Freshwater/non-metal/plant","709-13",63,0.71590909090909094,"","Myriophyllum sibiricum","Not stated","42 days","NOEC","Growth","300 ug/L","Macrophyte","Tracheophyta","Irrigation pond water","Not stated","Not stated","Chronic","not stated","N.A.","Hanson, M.L., P.K. Sibley, R.A. Brain, S.A. Mabury and K.R. Solomon. 2005. Microcosm evaluation of the toxicity and risk to aquatic macrophytes from perfluorooctane sulfonic acid. Archives of Environmental Contamination and Toxicology 48: 329-337","709","Plastic tanks","PFOS-K, From 3M purity not stated","Measured"]
["Freshwater/non-metal/plant","709-14",63,0.71590909090909094,null,"Myriophyllum sibiricum","Not stated","42 days","EC50","Growth","2200 ug/L","Macrophyte","Tracheophyta","Irrigation pond water","Not stated","Not stated","Chronic","not stated","N.A.","Hanson, M.L., P.K. Sibley, R.A. Brain, S.A. Mabury and K.R. Solomon. 2005. Microcosm evaluation of the toxicity and risk to aquatic macrophytes from perfluorooctane sulfonic acid. Archives of Environmental Contamination and Toxicology 48: 329-337","709","Plastic tanks","PFOS-K, From 3M purity not stated","Measured"]
["Freshwater/non-metal/plant","709-15",63,0.71590909090909094,null,"Myriophyllum sibiricum","Not stated","42 days","NOEC","Growth","2900 ug/L","Macrophyte","Tracheophyta","Irrigation pond water","Not stated","Not stated","Chronic","not stated","N.A.","Hanson, M.L., P.K. Sibley, R.A. Brain, S.A. Mabury and K.R. Solomon. 2005. Microcosm evaluation of the toxicity and risk to aquatic macrophytes from perfluorooctane sulfonic acid. Archives of Environmental Contamination and Toxicology 48: 329-337","709","Plastic tanks","PFOS-K, From 3M purity not stated","Measured"]
["Freshwater/non-metal/plant","709-16",63,0.71590909090909094,null,"Myriophyllum sibiricum","Not stated","42 days","NOEC","Growth","2900 ug/L","Macrophyte","Tracheophyta","Irrigation pond water","Not stated","Not stated","Chronic","not stated","N.A.","Hanson, M.L., P.K. Sibley, R.A. Brain, S.A. Mabury and K.R. Solomon. 2005. Microcosm evaluation of the toxicity and risk to aquatic macrophytes from perfluorooctane sulfonic acid. Archives of Environmental Contamination and Toxicology 48: 329-337","709","Plastic tanks","PFOS-K, From 3M purity not stated","Measured"]
["Freshwater/non-metal/plant","709-17",63,0.71590909090909094,null,"Myriophyllum sibiricum","Not stated","42 days","EC50","Growth","3400 ug/L","Macrophyte","Tracheophyta","Irrigation pond water","Not stated","Not stated","Chronic","not stated","N.A.","Hanson, M.L., P.K. Sibley, R.A. Brain, S.A. Mabury and K.R. Solomon. 2005. Microcosm evaluation of the toxicity and risk to aquatic macrophytes from perfluorooctane sulfonic acid. Archives of Environmental Contamination and Toxicology 48: 329-337","709","Plastic tanks","PFOS-K, From 3M purity not stated","Measured"]
["Freshwater/non-metal/plant","709-18",63,0.71590909090909094,null,"Myriophyllum sibiricum","Not stated","42 days","EC50","Growth","6600 ug/L","Macrophyte","Tracheophyta","Irrigation pond water","Not stated","Not stated","Chronic","not stated","N.A.","Hanson, M.L., P.K. Sibley, R.A. Brain, S.A. Mabury and K.R. Solomon. 2005. Microcosm evaluation of the toxicity and risk to aquatic macrophytes from perfluorooctane sulfonic acid. Archives of Environmental Contamination and Toxicology 48: 329-337","709","Plastic tanks","PFOS-K, From 3M purity not stated","Measured"]
["Freshwater/non-metal/plant","709-19",63,0.71590909090909094,null,"Myriophyllum spicatam","not stated","42 days","EC10","Growth","4300 ug/L","Macrophyte","Tracheophyta","Irrigation pond water","Not stated","Not stated","Chronic","not stated","N.A.","Hanson, M.L., P.K. Sibley, R.A. Brain, S.A. Mabury and K.R. Solomon. 2005. Microcosm evaluation of the toxicity and risk to aquatic macrophytes from perfluorooctane sulfonic acid. Archives of Environmental Contamination and Toxicology 48: 329-337","709","Plastic tanks","PFOS-K, From 3M purity not stated","Measured"]
["Freshwater/non-metal/plant","709-2",65,0.73863636363636365,"","Myriophyllum spicatam","not stated","28 days","EC10","Growth: Length","3.3 mg/L","Macrophyte","Tracheophyta","Irrigation pond water","Not stated","Not stated","Chronic","not stated","N.A.","Hanson, M.L., P.K. Sibley, R.A. Brain, S.A. Mabury and K.R. Solomon. 2005. Microcosm evaluation of the toxicity and risk to aquatic macrophytes from perfluorooctane sulfonic acid. Archives of Environmental Contamination and Toxicology 48: 329-337","709","Plastic tanks","PFOS-K, From 3M purity not stated","Measured"]
["Freshwater/non-metal/plant","709-20",63,0.71590909090909094,null,"Myriophyllum spicatam","not stated","42 days","NOEC","Growth","11400 ug/L","Macrophyte","Tracheophyta","Irrigation pond water","Not stated","Not stated","Chronic","not stated","N.A.","Hanson, M.L., P.K. Sibley, R.A. Brain, S.A. Mabury and K.R. Solomon. 2005. Microcosm evaluation of the toxicity and risk to aquatic macrophytes from perfluorooctane sulfonic acid. Archives of Environmental Contamination and Toxicology 48: 329-337","709","Plastic tanks","PFOS-K, From 3M purity not stated","Measured"]
["Freshwater/non-metal/plant","709-21",63,0.71590909090909094,null,"Myriophyllum spicatam","not stated","42 days","NOEC","Growth","11400 ug/L","Macrophyte","Tracheophyta","Irrigation pond water","Not stated","Not stated","Chronic","not stated","N.A.","Hanson, M.L., P.K. Sibley, R.A. Brain, S.A. Mabury and K.R. Solomon. 2005. Microcosm evaluation of the toxicity and risk to aquatic macrophytes from perfluorooctane sulfonic acid. Archives of Environmental Contamination and Toxicology 48: 329-337","709","Plastic tanks","PFOS-K, From 3M purity not stated","Measured"]
["Freshwater/non-metal/plant","709-22",63,0.71590909090909094,"","Myriophyllum spicatam","not stated","28 days","NOEC","Growth","11400 ug/L","Macrophyte","Tracheophyta","Irrigation pond water","Not stated","Not stated","Chronic","not stated","N.A.","Hanson, M.L., P.K. Sibley, R.A. Brain, S.A. Mabury and K.R. Solomon. 2005. Microcosm evaluation of the toxicity and risk to aquatic macrophytes from perfluorooctane sulfonic acid. Archives of Environmental Contamination and Toxicology 48: 329-337","709","Plastic tanks","PFOS-K, From 3M purity not stated","Measured"]
["Freshwater/non-metal/plant","709-23",63,0.71590909090909094,"","Myriophyllum spicatam","not stated","42 days","NOEC","Growth","11400 ug/L","Macrophyte","Tracheophyta","Irrigation pond water","Not stated","Not stated","Chronic","not stated","N.A.","Hanson, M.L., P.K. Sibley, R.A. Brain, S.A. Mabury and K.R. Solomon. 2005. Microcosm evaluation of the toxicity and risk to aquatic macrophytes from perfluorooctane sulfonic acid. Archives of Environmental Contamination and Toxicology 48: 329-337","709","Plastic tanks","PFOS-K, From 3M purity not stated","Measured"]
["Freshwater/non-metal/plant","709-24",63,0.71590909090909094,"","Myriophyllum spicatam","not stated","42 days","EC50","Growth","12500 ug/L","Macrophyte","Tracheophyta","Irrigation pond water","Not stated","Not stated","Chronic","not stated","N.A.","Hanson, M.L., P.K. Sibley, R.A. Brain, S.A. Mabury and K.R. Solomon. 2005. Microcosm evaluation of the toxicity and risk to aquatic macrophytes from perfluorooctane sulfonic acid. Archives of Environmental Contamination and Toxicology 48: 329-337","709","Plastic tanks","PFOS-K, From 3M purity not stated","Measured"]
["Freshwater/non-metal/plant","709-25",63,0.71590909090909094,"","Myriophyllum spicatam","not stated","28 days","EC50","Growth","16600 ug/L","Macrophyte","Tracheophyta","Irrigation pond water","Not stated","Not stated","Chronic","not stated","N.A.","Hanson, M.L., P.K. Sibley, R.A. Brain, S.A. Mabury and K.R. Solomon. 2005. Microcosm evaluation of the toxicity and risk to aquatic macrophytes from perfluorooctane sulfonic acid. Archives of Environmental Contamination and Toxicology 48: 329-337","709","Plastic tanks","PFOS-K, From 3M purity not stated","Measured"]
["Freshwater/non-metal/plant","709-26",63,0.71590909090909094,"","Myriophyllum spicatam","not stated","42 days","EC50","Growth","17500 ug/L","Macrophyte","Tracheophyta","Irrigation pond water","Not stated","Not stated","Chronic","not stated","N.A.","Hanson, M.L., P.K. Sibley, R.A. Brain, S.A. Mabury and K.R. Solomon. 2005. Microcosm evaluation of the toxicity and risk to aquatic macrophytes from perfluorooctane sulfonic acid. Archives of Environmental Contamination and Toxicology 48: 329-337","709","Plastic tanks","PFOS-K, From 3M purity not stated","Measured"]
["Freshwater/non-metal/plant","709-27",63,0.71590909090909094,"","Myriophyllum spicatam","not stated","42 days","EC50","Growth","20400 ug/L","Macrophyte","Tracheophyta","Irrigation pond water","Not stated","Not stated","Chronic","not stated","N.A.","Hanson, M.L., P.K. Sibley, R.A. Brain, S.A. Mabury and K.R. Solomon. 2005. Microcosm evaluation of the toxicity and risk to aquatic macrophytes from perfluorooctane sulfonic acid. Archives of Environmental Contamination and Toxicology 48: 329-337","709","Plastic tanks","PFOS-K, From 3M purity not stated","Measured"]
["Freshwater/non-metal/plant","709-3",63,0.71590909090909094,"","Myriophyllum sibiricum","Not stated","42 days","EC10","Growth","1400 ug/L","Macrophyte","Tracheophyta","Irrigation pond water","Not stated","Not stated","Chronic","not stated","N.A.","Hanson, M.L., P.K. Sibley, R.A. Brain, S.A. Mabury and K.R. Solomon. 2005. Microcosm evaluation of the toxicity and risk to aquatic macrophytes from perfluorooctane sulfonic acid. Archives of Environmental Contamination and Toxicology 48: 329-337","709","Plastic tanks","PFOS-K, From 3M purity not stated","Measured"]
["Freshwater/non-metal/plant","709-4",63,0.71590909090909094,"","Myriophyllum sibiricum","Not stated","42 days","EC10","Growth","1200 ug/L","Macrophyte","Tracheophyta","Irrigation pond water","Not stated","Not stated","Chronic","not stated","N.A.","Hanson, M.L., P.K. Sibley, R.A. Brain, S.A. Mabury and K.R. Solomon. 2005. Microcosm evaluation of the toxicity and risk to aquatic macrophytes from perfluorooctane sulfonic acid. Archives of Environmental Contamination and Toxicology 48: 329-337","709","Plastic tanks","PFOS-K, From 3M purity not stated","Measured"]
["Freshwater/non-metal/plant","709-5",63,0.71590909090909094,"","Myriophyllum sibiricum","Not stated","42 days","EC10","Growth","700 ug/L","Macrophyte","Tracheophyta","Irrigation pond water","Not stated","Not stated","Chronic","not stated","N.A.","Hanson, M.L., P.K. Sibley, R.A. Brain, S.A. Mabury and K.R. Solomon. 2005. Microcosm evaluation of the toxicity and risk to aquatic macrophytes from perfluorooctane sulfonic acid. Archives of Environmental Contamination and Toxicology 48: 329-337","709","Plastic tanks","PFOS-K, From 3M purity not stated","Measured"]
["Freshwater/non-metal/plant","709-6",63,0.71590909090909094,"","Myriophyllum sibiricum","Not stated","42 days","EC10","Growth","600 ug/L","Macrophyte","Tracheophyta","Irrigation pond water","Not stated","Not stated","Chronic","not stated","N.A.","Hanson, M.L., P.K. Sibley, R.A. Brain, S.A. Mabury and K.R. Solomon. 2005. Microcosm evaluation of the toxicity and risk to aquatic macrophytes from perfluorooctane sulfonic acid. Archives of Environmental Contamination and Toxicology 48: 329-337","709","Plastic tanks","PFOS-K, From 3M purity not stated","Measured"]
["Freshwater/non-metal/plant","709-7",63,0.71590909090909094,"","Myriophyllum sibiricum","Not stated","42 days","EC10","Growth","1500 ug/L","Macrophyte","Tracheophyta","Irrigation pond water","Not stated","Not stated","Chronic","not stated","N.A.","Hanson, M.L., P.K. Sibley, R.A. Brain, S.A. Mabury and K.R. Solomon. 2005. Microcosm evaluation of the toxicity and risk to aquatic macrophytes from perfluorooctane sulfonic acid. Archives of Environmental Contamination and Toxicology 48: 329-337","709","Plastic tanks","PFOS-K, From 3M purity not stated","Measured"]
["Freshwater/non-metal/plant","709-8",63,0.71590909090909094,"","Myriophyllum spicatam","not stated","42 days","EC10","Growth","9900 ug/L","Macrophyte","Tracheophyta","Irrigation pond water","Not stated","Not stated","Chronic","not stated","N.A.","Hanson, M.L., P.K. Sibley, R.A. Brain, S.A. Mabury and K.R. Solomon. 2005. Microcosm evaluation of the toxicity and risk to aquatic macrophytes from perfluorooctane sulfonic acid. Archives of Environmental Contamination and Toxicology 48: 329-337","709","Plastic tanks","PFOS-K, From 3M purity not stated","Measured"]
["Freshwater/non-metal/plant","709-9",63,0.71590909090909094,"","Myriophyllum spicatam","not stated","28 days","EC10","Growth","4700 ug/L","Macrophyte","Tracheophyta","Irrigation pond water","Not stated","Not stated","Chronic","not stated","N.A.","Hanson, M.L., P.K. Sibley, R.A. Brain, S.A. Mabury and K.R. Solomon. 2005. Microcosm evaluation of the toxicity and risk to aquatic macrophytes from perfluorooctane sulfonic acid. Archives of Environmental Contamination and Toxicology 48: 329-337","709","Plastic tanks","PFOS-K, From 3M purity not stated","Measured"]
["Freshwater/non-metal/non- plant","717-1",62,0.68131868131868134,"The highest possible grade for this datum is acceptable.","Danio rerio","Fry","70 days","NOEC","Survival","10 ug/L","Chordata","Chordata","Teleostei","charcoal-filtered tap water",27,"Chronic","Not stated","N.A.","Du Y., X. Shi, C. Liu, K. Yu, B. Zhou. 2009. Chronic effects of water-bore PFOS exposure on growth, survivial and hepatotoxicity in zebrafish: A partial life-cycle test. Chemosphere 74: 723-729","717","Glass tanks","PFOS-K (.99%) from Tokyo Kasei Kogyo Co.","Nominal concs"]
["Freshwater/non-metal/non- plant","717-10",60,0.65934065934065933,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","70 days","LOEC","Growth","50 ug/L","Fish","Chordata","Actinopterygii","Dechlorinated tap water","26.5-27.5oC","Chronic","Not stated","N.A.","Du, Y., X. Shi, C. Liu, K. Yu and B. Zhou. 2009. Chronic effects of water-borne PFOS exposure on growth, survival and hepatotoxicity in zebrafish: A partial life-cycle test. Chemosphere 74: 723-729","717","Glass tanks","PFOS-K (.99%) from Tokyo Kasei Kogyo Co.","Nominal concs"]
["Freshwater/non-metal/non- plant","717-11",60,0.65934065934065933,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","40 days","NOEC","Growth","250 ug/L","Fish","Chordata","Actinopterygii","Dechlorinated tap water","26.5-27.5oC","Chronic","Not stated","N.A.","Du, Y., X. Shi, C. Liu, K. Yu and B. Zhou. 2009. Chronic effects of water-borne PFOS exposure on growth, survival and hepatotoxicity in zebrafish: A partial life-cycle test. Chemosphere 74: 723-729","717","Glass tanks","PFOS-K (.99%) from Tokyo Kasei Kogyo Co.","Nominal concs"]
["Freshwater/non-metal/non- plant","717-12",60,0.65934065934065933,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","70 days","NOEC","Growth","250 ug/L","Fish","Chordata","Actinopterygii","Dechlorinated tap water","26.5-27.5oC","Chronic","Not stated","N.A.","Du, Y., X. Shi, C. Liu, K. Yu and B. Zhou. 2009. Chronic effects of water-borne PFOS exposure on growth, survival and hepatotoxicity in zebrafish: A partial life-cycle test. Chemosphere 74: 723-729","717","Glass tanks","PFOS-K (.99%) from Tokyo Kasei Kogyo Co.","Nominal concs"]
["Freshwater/non-metal/non- plant","717-13",60,0.65934065934065933,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","40 days","NOEC","Growth","50 ug/L","Fish","Chordata","Actinopterygii","Dechlorinated tap water","26.5-27.5oC","Chronic","Not stated","N.A.","Du, Y., X. Shi, C. Liu, K. Yu and B. Zhou. 2009. Chronic effects of water-borne PFOS exposure on growth, survival and hepatotoxicity in zebrafish: A partial life-cycle test. Chemosphere 74: 723-729","717","Glass tanks","PFOS-K (.99%) from Tokyo Kasei Kogyo Co.","Nominal concs"]
["Freshwater/non-metal/non- plant","717-14",60,0.65934065934065933,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","40 days","LOEC","Growth","250 ug/L","Fish","Chordata","Actinopterygii","Dechlorinated tap water","26.5-27.5oC","Chronic","Not stated","N.A.","Du, Y., X. Shi, C. Liu, K. Yu and B. Zhou. 2009. Chronic effects of water-borne PFOS exposure on growth, survival and hepatotoxicity in zebrafish: A partial life-cycle test. Chemosphere 74: 723-729","717","Glass tanks","PFOS-K (.99%) from Tokyo Kasei Kogyo Co.","Nominal concs"]
["Freshwater/non-metal/non- plant","717-2",62,0.68131868131868134,"The highest possible grade for this datum is acceptable.","Danio rerio","14 days post fertilisation","40 days","NOEC","Growth","10 ug/L","Chordata","Chordata","Teleostei","charcoal-filtered tap water",27,"Chronic","Not stated","N.A.","Du Y., X. Shi, C. Liu, K. Yu, B. Zhou. 2009. Chronic effects of water-bore PFOS exposure on growth, survivial and hepatotoxicity in zebrafish: A partial life-cycle test. Chemosphere 74: 723-729","717","Glass tanks","PFOS-K (.99%) from Tokyo Kasei Kogyo Co.","Nominal concs"]
["Freshwater/non-metal/non- plant","717-3",60,0.65934065934065933,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","40 days","LOEC","Growth","50 ug/L","Fish","Chordata","Actinopterygii","Dechlorinated tap water","26.5-27.5oC","Chronic","Not stated","N.A.","Du, Y., X. Shi, C. Liu, K. Yu and B. Zhou. 2009. Chronic effects of water-borne PFOS exposure on growth, survival and hepatotoxicity in zebrafish: A partial life-cycle test. Chemosphere 74: 723-729","717","Glass tanks","PFOS-K (.99%) from Tokyo Kasei Kogyo Co.","Nominal concs"]
["Freshwater/non-metal/non- plant","717-4",60,0.65934065934065933,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","40 days","NOEC","Growth","250 ug/L","Fish","Chordata","Actinopterygii","Dechlorinated tap water","26.5-27.5oC","Chronic","Not stated","N.A.","Du, Y., X. Shi, C. Liu, K. Yu and B. Zhou. 2009. Chronic effects of water-borne PFOS exposure on growth, survival and hepatotoxicity in zebrafish: A partial life-cycle test. Chemosphere 74: 723-729","717","Glass tanks","PFOS-K (.99%) from Tokyo Kasei Kogyo Co.","Nominal concs"]
["Freshwater/non-metal/non- plant","717-5",60,0.65934065934065933,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","40 days","NOEC","Growth","50 ug/L","Fish","Chordata","Actinopterygii","Dechlorinated tap water","26.5-27.5oC","Chronic","Not stated","N.A.","Du, Y., X. Shi, C. Liu, K. Yu and B. Zhou. 2009. Chronic effects of water-borne PFOS exposure on growth, survival and hepatotoxicity in zebrafish: A partial life-cycle test. Chemosphere 74: 723-729","717","Glass tanks","PFOS-K (.99%) from Tokyo Kasei Kogyo Co.","Nominal concs"]
["Freshwater/non-metal/non- plant","717-6",60,0.65934065934065933,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","40 days","LOEC","Growth","250 ug/L","Fish","Chordata","Actinopterygii","Dechlorinated tap water","26.5-27.5oC","Chronic","Not stated","N.A.","Du, Y., X. Shi, C. Liu, K. Yu and B. Zhou. 2009. Chronic effects of water-borne PFOS exposure on growth, survival and hepatotoxicity in zebrafish: A partial life-cycle test. Chemosphere 74: 723-729","717","Glass tanks","PFOS-K (.99%) from Tokyo Kasei Kogyo Co.","Nominal concs"]
["Freshwater/non-metal/non- plant","717-7",60,0.65934065934065933,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","70 days","NOEC","Growth","50 ug/L","Fish","Chordata","Actinopterygii","Dechlorinated tap water","26.5-27.5oC","Chronic","Not stated","N.A.","Du, Y., X. Shi, C. Liu, K. Yu and B. Zhou. 2009. Chronic effects of water-borne PFOS exposure on growth, survival and hepatotoxicity in zebrafish: A partial life-cycle test. Chemosphere 74: 723-729","717","Glass tanks","PFOS-K (.99%) from Tokyo Kasei Kogyo Co.","Nominal concs"]
["Freshwater/non-metal/non- plant","717-8",60,0.65934065934065933,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","70 days","LOEC","Growth","250 ug/L","Fish","Chordata","Actinopterygii","Dechlorinated tap water","26.5-27.5oC","Chronic","Not stated","N.A.","Du, Y., X. Shi, C. Liu, K. Yu and B. Zhou. 2009. Chronic effects of water-borne PFOS exposure on growth, survival and hepatotoxicity in zebrafish: A partial life-cycle test. Chemosphere 74: 723-729","717","Glass tanks","PFOS-K (.99%) from Tokyo Kasei Kogyo Co.","Nominal concs"]
["Freshwater/non-metal/non- plant","717-9",60,0.65934065934065933,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","70 days","NOEC","Growth","10 ug/L","Fish","Chordata","Actinopterygii","Dechlorinated tap water","26.5-27.5oC","Chronic","Not stated","N.A.","Du, Y., X. Shi, C. Liu, K. Yu and B. Zhou. 2009. Chronic effects of water-borne PFOS exposure on growth, survival and hepatotoxicity in zebrafish: A partial life-cycle test. Chemosphere 74: 723-729","717","Glass tanks","PFOS-K (.99%) from Tokyo Kasei Kogyo Co.","Nominal concs"]
["Freshwater/non-metal/non- plant","718-1",57,0.62637362637362637,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","8 days","NOEC","Mortality","5 µg/L","Chordata","Chordata","Teleostei","Water filtered by reverse osmosis with \"Instant Ocean\" salt added",28,"Chronic","7.0-7.5","N.A.","Wang M., J. Chen, K. Lin, Y. Chen, W. Hu, R. L. Tanguay, C. Huang, and Q. Dong. 2011. Chronic Zebrafish PFOS Exposure Alters Sex Ratio and Maternal Related Effects in F1 Offspring. Environemtnal Toxicology and Chemistry Vol 30: 2073-2080. ","718","Petri dishes / tanks - material not stated","PFOS purity >96% (CAS RN 1763-23-1) from Sigma Aldrich","Nominal concs"]
["Freshwater/non-metal/non- plant","718-2",57,0.62637362637362637,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","150 days post fertilisation","NOEC","Growth","5 µg/L","Chordata","Chordata","Teleostei","Water filtered by reverse osmosis with \"Instant Ocean\" salt added",28,"Chronic","7.0-7.5","N.A.","Wang M., J. Chen, K. Lin, Y. Chen, W. Hu, R. L. Tanguay, C. Huang, and Q. Dong. 2011. Chronic Zebrafish PFOS Exposure Alters Sex Ratio and Maternal Related Effects in F1 Offspring. Environemtnal Toxicology and Chemistry Vol 30: 2073-2080. ","718","Petri dishes / tanks - material not stated","PFOS purity >96% (CAS RN 1763-23-1) from Sigma Aldrich","Nominal concs"]
["Freshwater/non-metal/non- plant","718-3",56,0.61538461538461542,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","8 days","LOEC","Mortality","50 ug/L","Fish","Chordata","Actinopterygii","Reverse Osmosis water with salt added","28oC","Chronic","Not stated","N.A.","Wang M., J. Chen, K. Lin, Y. Chen, W. Hu, R. L. Tanguay, C. Huang, and Q. Dong. 2011. Chronic Zebrafish PFOS Exposure Alters Sex Ratio and Maternal Related Effects in F1 Offspring. Environemtnal Toxicology and Chemistry Vol 30: 2073-2080. ","718","Petri dishes / tanks - material not stated","PFOS purity >96% (CAS RN 1763-23-1) from Sigma Aldrich","Nominal concs"]
["Freshwater/non-metal/non- plant","718-4",56,0.61538461538461542,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","150 days post fertilisation","LOEC","Growth","50 ug/L","Fish","Chordata","Actinopterygii","Reverse Osmosis water with salt added","28oC","Chronic","Not stated","N.A.","Wang M., J. Chen, K. Lin, Y. Chen, W. Hu, R. L. Tanguay, C. Huang, and Q. Dong. 2011. Chronic Zebrafish PFOS Exposure Alters Sex Ratio and Maternal Related Effects in F1 Offspring. Environemtnal Toxicology and Chemistry Vol 30: 2073-2080. ","718","Petri dishes / tanks - material not stated","PFOS purity >96% (CAS RN 1763-23-1) from Sigma Aldrich","Nominal concs"]
["Freshwater/non-metal/non- plant","718-5",56,0.61538461538461542,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","150 days post fertilisation","NOEC","Growth","50 ug/L","Fish","Chordata","Actinopterygii","Reverse Osmosis water with salt added","28oC","Chronic","Not stated","N.A.","Wang M., J. Chen, K. Lin, Y. Chen, W. Hu, R. L. Tanguay, C. Huang, and Q. Dong. 2011. Chronic Zebrafish PFOS Exposure Alters Sex Ratio and Maternal Related Effects in F1 Offspring. Environemtnal Toxicology and Chemistry Vol 30: 2073-2080. ","718","Petri dishes / tanks - material not stated","PFOS purity >96% (CAS RN 1763-23-1) from Sigma Aldrich","Nominal concs"]
["Freshwater/non-metal/non- plant","718-6",56,0.61538461538461542,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","150 days post fertilisation","LOEC","Growth","250 ug/L","Fish","Chordata","Actinopterygii","Reverse Osmosis water with salt added","28oC","Chronic","Not stated","N.A.","Wang M., J. Chen, K. Lin, Y. Chen, W. Hu, R. L. Tanguay, C. Huang, and Q. Dong. 2011. Chronic Zebrafish PFOS Exposure Alters Sex Ratio and Maternal Related Effects in F1 Offspring. Environemtnal Toxicology and Chemistry Vol 30: 2073-2080. ","718","Petri dishes / tanks - material not stated","PFOS purity >96% (CAS RN 1763-23-1) from Sigma Aldrich","Nominal concs"]
["Freshwater/non-metal/non- plant","718-7",56,0.61538461538461542,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","150 days post fertilisation","NOEC","Growth","50 ug/L","Fish","Chordata","Actinopterygii","Reverse Osmosis water with salt added","28oC","Chronic","Not stated","N.A.","Wang M., J. Chen, K. Lin, Y. Chen, W. Hu, R. L. Tanguay, C. Huang, and Q. Dong. 2011. Chronic Zebrafish PFOS Exposure Alters Sex Ratio and Maternal Related Effects in F1 Offspring. Environemtnal Toxicology and Chemistry Vol 30: 2073-2080. ","718","Petri dishes / tanks - material not stated","PFOS purity >96% (CAS RN 1763-23-1) from Sigma Aldrich","Nominal concs"]
["Freshwater/non-metal/non- plant","718-8",56,0.61538461538461542,"The highest possible grade for this datum is acceptable.","Danio rerio","Embryo","150 days post fertilisation","LOEC","Growth","250 ug/L","Fish","Chordata","Actinopterygii","Reverse Osmosis water with salt added","28oC","Chronic","Not stated","N.A.","Wang M., J. Chen, K. Lin, Y. Chen, W. Hu, R. L. Tanguay, C. Huang, and Q. Dong. 2011. Chronic Zebrafish PFOS Exposure Alters Sex Ratio and Maternal Related Effects in F1 Offspring. Environemtnal Toxicology and Chemistry Vol 30: 2073-2080. ","718","Petri dishes / tanks - material not stated","PFOS purity >96% (CAS RN 1763-23-1) from Sigma Aldrich","Nominal concs"]
["Freshwater/non-metal/plant","3044-1",60,0.68181818181818177,"","Lemna gibba","Not stated","42 days","IC50","Growth","19100 ug/L","Macrophyte","Tracheophyta","Irrigation pond water","Not stated","15.9-20.5","Chronic","8.3-8.8","CaCO3 292.1-300.0 mg/L","Boudreau, T.M., C.J. Wilson, W.J. Cheong, P.K. Sibley, S.A. Mabury, P.C.G. Muir and K.R. Solomon. 2003. Response of the zooplankton community and environmental fate of perfluorooctane sulfonic acid in aquatic microcosms. Environmental Toxicology and Chemistry 22: 2739-2745.","3044","Plastic tanks","PFOS-K purity 86% from 3M (Fluorad)","Measured"]
["Freshwater/non-metal/plant","3044-2",60,0.68181818181818177,"","Lemna gibba","Not stated","42 days","NOEC","Growth","300 ug/L","Macrophyte","Tracheophyta","Irrigation pond water","Not stated","15.9-20.5","Chronic","8.3-8.8","CaCO3 292.1-300.0 mg/L","Boudreau, T.M., C.J. Wilson, W.J. Cheong, P.K. Sibley, S.A. Mabury, P.C.G. Muir and K.R. Solomon. 2003. Response of the zooplankton community and environmental fate of perfluorooctane sulfonic acid in aquatic microcosms. Environmental Toxicology and Chemistry 22: 2739-2745.","3044","Plastic tanks","PFOS-K purity 86% from 3M (Fluorad)","Measured"]
["Freshwater/non-metal/non- plant","404-29",49,0.53846153846153844,"The highest possible grade for this datum is acceptable.","Oryzias latipes","embryo","14 days","LOEC","Growth","10 ug/L","Fish","Chordata","Actinopterygii","Dechlorinated tap water","25°C","Chronic","Not stated","N.A.","Du,J., S. Wang, H. You, and Z. Liu. 2016. Effects of ZnO Nanoparticles on Perfluorooctane Sulfonate Induced Thyroid-Disrupting on Zebrafish Larvae. J. Environ. Sci.47:153-164","404","Not stated","PFOS acid form, purity not stated (PFOS C8HF17SO3: CAS RN 1763-23-1 from Wako Pure Chemicals (Osaka, Japan)","Nominal concs"]
["Freshwater/non-metal/non- plant","404-27",49,0.53846153846153844,"The highest possible grade for this datum is acceptable.","Oryzias latipes","Adult","14 days","NOEC","Mortality","1000 ug/L","Fish","Chordata","Actinopterygii","Dechlorinated tap water","25°C","Chronic","Not stated","N.A.","Du,J., S. Wang, H. You, and Z. Liu. 2016. Effects of ZnO Nanoparticles on Perfluorooctane Sulfonate Induced Thyroid-Disrupting on Zebrafish Larvae. J. Environ. Sci.47:153-164","404","Not stated","PFOS acid form, purity not stated (PFOS C8HF17SO3: CAS RN 1763-23-1 from Wako Pure Chemicals (Osaka, Japan)","Nominal concs"]
["Freshwater/non-metal/non- plant","404-28",49,0.53846153846153844,"The highest possible grade for this datum is acceptable.","Oryzias latipes","Adult","14 days","NOEC","Growth","1000 ug/L","Fish","Chordata","Actinopterygii","Dechlorinated tap water","25°C","Chronic","Not stated","N.A.","Du,J., S. Wang, H. You, and Z. Liu. 2016. Effects of ZnO Nanoparticles on Perfluorooctane Sulfonate Induced Thyroid-Disrupting on Zebrafish Larvae. J. Environ. Sci.47:153-164","404","Not stated","PFOS acid form, purity not stated (PFOS C8HF17SO3: CAS RN 1763-23-1 from Wako Pure Chemicals (Osaka, Japan)","Nominal concs"]
["Freshwater/non-metal/non- plant","404-23",60,0.65934065934065933,"The highest possible grade for this datum is acceptable.","Moina macrocopa","Neonate","7 days","LOEC","Reproduction","312.5 ug/L","Microinvertebrate","Arthropoda","Branchiopoda","moderately hard water","24-26","Chronic","Not stated","N.A.","Du,J., S. Wang, H. You, and Z. Liu. 2016. Effects of ZnO Nanoparticles on Perfluorooctane Sulfonate Induced Thyroid-Disrupting on Zebrafish Larvae. J. Environ. Sci.47:153-164","404","Not stated","PFOS acid form, purity not stated (PFOS C8HF17SO3: CAS RN 1763-23-1 from Wako Pure Chemicals (Osaka, Japan)","Nominal concs"]
["Freshwater/non-metal/non- plant","404-24",60,0.65934065934065933,"The highest possible grade for this datum is acceptable.","Moina macrocopa","Neonate","7 days","LOEC","Reproduction","5000 ug/L","Microinvertebrate","Arthropoda","Branchiopoda","moderately hard water","24-26","Chronic","Not stated","N.A.","Du,J., S. Wang, H. You, and Z. Liu. 2016. Effects of ZnO Nanoparticles on Perfluorooctane Sulfonate Induced Thyroid-Disrupting on Zebrafish Larvae. J. Environ. Sci.47:153-164","404","Not stated","PFOS acid form, purity not stated (PFOS C8HF17SO3: CAS RN 1763-23-1 from Wako Pure Chemicals (Osaka, Japan)","Nominal concs"]
["Freshwater/non-metal/non- plant","404-25",60,0.65934065934065933,"The highest possible grade for this datum is acceptable.","Moina macrocopa","Neonate","7 days","NOEC","Mortality","1250 ug/L","Microinvertebrate","Arthropoda","Branchiopoda","moderately hard water","24-26","Chronic","Not stated","N.A.","Du,J., S. Wang, H. You, and Z. Liu. 2016. Effects of ZnO Nanoparticles on Perfluorooctane Sulfonate Induced Thyroid-Disrupting on Zebrafish Larvae. J. Environ. Sci.47:153-164","404","Not stated","PFOS acid form, purity not stated (PFOS C8HF17SO3: CAS RN 1763-23-1 from Wako Pure Chemicals (Osaka, Japan)","Nominal concs"]
["Freshwater/non-metal/non- plant","404-26",60,0.65934065934065933,"The highest possible grade for this datum is acceptable.","Moina macrocopa","Neonate","7 days","LOEC","Mortality","2500 ug/L","Microinvertebrate","Arthropoda","Branchiopoda","moderately hard water","24-26","Chronic","Not stated","N.A.","Du,J., S. Wang, H. You, and Z. Liu. 2016. Effects of ZnO Nanoparticles on Perfluorooctane Sulfonate Induced Thyroid-Disrupting on Zebrafish Larvae. J. Environ. Sci.47:153-164","404","Not stated","PFOS acid form, purity not stated (PFOS C8HF17SO3: CAS RN 1763-23-1 from Wako Pure Chemicals (Osaka, Japan)","Nominal concs"]
["Freshwater/non-metal/non- plant","404-20",60,0.65934065934065933,"The highest possible grade for this datum is acceptable.","Daphnia magna","Neonate","21 day","LOEC","Reproduction","2500 ug/L","Macroinvertebrate","Arthropoda","Branchiopoda","moderately hard water","20-22","Chronic","Not stated","N.A.","Du,J., S. Wang, H. You, and Z. Liu. 2016. Effects of ZnO Nanoparticles on Perfluorooctane Sulfonate Induced Thyroid-Disrupting on Zebrafish Larvae. J. Environ. Sci.47:153-164","404","Not stated","PFOS acid form, purity not stated (PFOS C8HF17SO3: CAS RN 1763-23-1 from Wako Pure Chemicals (Osaka, Japan)","Nominal concs"]
["Freshwater/non-metal/non- plant","404-21",60,0.65934065934065933,"The highest possible grade for this datum is acceptable.","Daphnia magna","Neonate","21 day","NOEC","Growth","5000 ug/L","Macroinvertebrate","Arthropoda","Branchiopoda","moderately hard water","20-22","Chronic","Not stated","N.A.","Du,J., S. Wang, H. You, and Z. Liu. 2016. Effects of ZnO Nanoparticles on Perfluorooctane Sulfonate Induced Thyroid-Disrupting on Zebrafish Larvae. J. Environ. Sci.47:153-164","404","Not stated","PFOS acid form, purity not stated (PFOS C8HF17SO3: CAS RN 1763-23-1 from Wako Pure Chemicals (Osaka, Japan)","Nominal concs"]
["Freshwater/non-metal/non- plant","404-22",60,0.65934065934065933,"The highest possible grade for this datum is acceptable.","Daphnia magna","Neonate","21 day","NOEC","Mortality","5000 ug/L","Macroinvertebrate","Arthropoda","Branchiopoda","moderately hard water","20-22","Chronic","Not stated","N.A.","Du,J., S. Wang, H. You, and Z. Liu. 2016. Effects of ZnO Nanoparticles on Perfluorooctane Sulfonate Induced Thyroid-Disrupting on Zebrafish Larvae. J. Environ. Sci.47:153-164","404","Not stated","PFOS acid form, purity not stated (PFOS C8HF17SO3: CAS RN 1763-23-1 from Wako Pure Chemicals (Osaka, Japan)","Nominal concs"]
["Freshwater/non-metal/non- plant","412-4",56,0.61538461538461542,"The highest possible grade for this datum is acceptable.","Daphnia magna","Neonate","21 day","LOEC","Reproduction","5000 ug/L","Macroinvertebrate","Arthropoda","Branchiopoda","ATSM hardwater","Not stated","Chronic","Not stated","N.A.","Li, M-H. 2010. Chronic effects of perfluorooctane sulfonate and ammonium perfluorooctanoate and biochemical parameters, survival and reproduction of Daphnia magna. Journal of Health Science 56: 104-111","412","Polypropylene culture tubes","PFOS-K, 98% purity from Fluka ","Nominal concs"]
["Freshwater/non-metal/non- plant","431-23",57,0.62637362637362637,"The highest possible grade for this datum is acceptable.","Daphnia magna","Neonate","21 day","NOEC","Reproduction","25000 ug/L","Macroinvertebrate","Arthropoda","Branchiopoda","Lab distilled water","20-22","Chronic","Not stated","N.A.","Boudreau, T.M., P.K. Sibley, S.A. Mabury, D.G.C. Muir and K.R. Solomon. 2003. Laboratory evaluation of the toxicity of perfluorooctane sulfonate (PFOS) on Selenastrum capricornutum, Chlorella vulgaris, Lemna gibba, Daphnia magna, and Daphnia pulicaria. Archives of Environmental Contamination and Toxicology 44: 307-313.","431","Polypropylene or polyethylene","PFOS-K 95% from 3M. Treatment concs were PFOS anion","Nominal concs"]
["Freshwater/non-metal/non- plant","431-24",57,0.62637362637362637,"The highest possible grade for this datum is acceptable.","Daphnia magna","Neonate","21 day","LOEC","Reproduction","50000 ug/L","Macroinvertebrate","Arthropoda","Branchiopoda","Lab distilled water","20-22","Chronic","Not stated","N.A.","Boudreau, T.M., P.K. Sibley, S.A. Mabury, D.G.C. Muir and K.R. Solomon. 2003. Laboratory evaluation of the toxicity of perfluorooctane sulfonate (PFOS) on Selenastrum capricornutum, Chlorella vulgaris, Lemna gibba, Daphnia magna, and Daphnia pulicaria. Archives of Environmental Contamination and Toxicology 44: 307-313.","431","Polypropylene or polyethylene","PFOS-K 95% from 3M. Treatment concs were PFOS anion","Nominal concs"]
["Freshwater/non-metal/non- plant","435-9",58,0.63736263736263732,"","Lampsilis siliquoidea","Neonate","36 days","LOEC","Mortality","4.5 ug/L","Mollusc","Mollusca","Bivalvia","Pond water","20oC","Chronic","Not stated","N.A.","Hazelton, P.D., W.G. Cope, T.J. Pandolfo, S. Mosher, M.J. Strynar, M.C. Barnhart and R.B. Bringholf. 2012. Partial life-cycle and acute toxicity of perfluoroalkyl acids to freshwater mussels. Environmental Toxicology and Chemistry 31: 1611-1620.","435","Glass jars/beakers","PFOS, form not stated, >98% purity from Fisher Scientific or Sigma Aldrich","Measured"]
["Freshwater/non-metal/non- plant","434-6",73,0.80219780219780223,"The highest possible grade for this datum is acceptable.","Enallagma cyathigerum","larvae","120 days","LOEC","Development","7950 ug/L PFOS anion (10,000 ug/L nominal)","Macroinvertebrate","Arthropoda","Insecta","Dechlorinated tap water","21oC","Chronic","7.3-7.7","N.A.","Bots, J., L. De Bruyn, T. Snijkers, B. Van den Branden and H. Van Gossum. 2010. Exposure to perfluorooctane sulfonic acid (PFOS) adversely affects the life-cycle of the damselfly Enallagma cyathigerum. Environmental Pollution 158: 901-905.","434","Polypropylene","PFOS-tetraethyl ammonium salt, 98% purity from Sigma Aldrich","Nominal concs"]
["Freshwater/non-metal/non- plant","598-1",67,0.73626373626373631,"","Brachionus calyciflorus","Neonate","28 days","LOEC","Reproduction","250 ug/L","Microinvertebrate","Rotifera","Monogononta","USEPA medium","20oC","Chronic","Not stated","N.A.","Zhang, L., J. Niu, Y. Li, Y. Wang and D. Sun. 2013. Evaluating the sub-lethal toxicity of PFOS and PFOA using rotifer Brachionus calyciflorus. Environmental Pollution 180: 34-40.","598","100ml plastic vessel","PFOS, form not stated, 98% purity from Sigma Aldrich","Measured"]
["Freshwater/non-metal/non- plant","598-2",59,0.64835164835164838,"","Brachionus calyciflorus","Neonate","5 day","LOEC","Reproduction","250 ug/L","Microinvertebrate","Rotifera","Monogononta","USEPA medium","20oC","Chronic","Not stated","N.A.","Zhang, L., J. Niu, Y. Li, Y. Wang and D. Sun. 2013. Evaluating the sub-lethal toxicity of PFOS and PFOA using rotifer Brachionus calyciflorus. Environmental Pollution 180: 34-40.","598","24 well culture plates","PFOS, form not stated, 98% purity from Sigma Aldrich","Measured"]
["Freshwater/non-metal/non- plant","598-3",59,0.64835164835164838,"","Brachionus calyciflorus","Neonate","5 day","NOEC","Mortality","1000 ug/L","Microinvertebrate","Rotifera","Monogononta","USEPA medium","20oC","Chronic","Not stated","N.A.","Zhang, L., J. Niu, Y. Li, Y. Wang and D. Sun. 2013. Evaluating the sub-lethal toxicity of PFOS and PFOA using rotifer Brachionus calyciflorus. Environmental Pollution 180: 34-40.","598","24 well culture plates","PFOS, form not stated, 98% purity from Sigma Aldrich","Measured"]
["Freshwater/non-metal/non- plant","598-4",59,0.64835164835164838,"","Brachionus calyciflorus","Neonate","5 day","LOEC","Mortality","2000 ug/L","Microinvertebrate","Rotifera","Monogononta","USEPA medium","20oC","Chronic","Not stated","N.A.","Zhang, L., J. Niu, Y. Li, Y. Wang and D. Sun. 2013. Evaluating the sub-lethal toxicity of PFOS and PFOA using rotifer Brachionus calyciflorus. Environmental Pollution 180: 34-40.","598","24 well culture plates","PFOS, form not stated, 98% purity from Sigma Aldrich","Measured"]
["Freshwater/non-metal/non- plant","599-2",49,0.53846153846153844,"","Lithobates pipiens","embryo","60 day","NOEC","Development","1000 ug/L","Amphibian","Chordata","Amphibia","Lake Superior Water","20oC","Chronic","Not stated","N.A.","Zhang, L., J. Niu, Y. Li, Y. Wang and D. Sun. 2013. Evaluating the sub-lethal toxicity of PFOS and PFOA using rotifer Brachionus calyciflorus. Environmental Pollution 180: 34-40.","599","Glass aquaria","PFOS, form not stated, 98% purity from Fluka Chemical ","Measured"]
["Freshwater/non-metal/non- plant","599-3",49,0.53846153846153844,"","Lithobates pipiens","embryo","60 day","LOEC","Development","3000 ug/L","Amphibian","Chordata","Amphibia","Lake Superior Water","20oC","Chronic","Not stated","N.A.","Zhang, L., J. Niu, Y. Li, Y. Wang and D. Sun. 2013. Evaluating the sub-lethal toxicity of PFOS and PFOA using rotifer Brachionus calyciflorus. Environmental Pollution 180: 34-40.","599","Glass aquaria","PFOS, form not stated, 98% purity from Fluka Chemical ","Measured"]
["Freshwater/non-metal/plant","3044-3",60,0.68181818181818177,"","Lemna gibba","not stated","42 days","LOEC","Growth","3000 ug/L","Macrophyte","Tracheophyta","Irrigation pond water","15.9-20.5","15.9-20.5","Chronic","8.3-8.8","N.A.","Boudreau, T.M., C.J. Wilson, W.J. Cheong, P.K. Sibley, S.A. Mabury, P.C.G. Muir and K.R. Solomon. 2003. Response of the zooplankton community and environmental fate of perfluorooctane sulfonic acid in aquatic microcosms. Environmental Toxicology and Chemistry 22: 2739-2745.","3044","Plastic tanks","PFOS-K purity 86% from 3M (Fluorad)","Measured"]
["Freshwater/non-metal/non- plant","3045-1",47,0.51648351648351654,"The highest possible grade for this datum is acceptable.","Xenopus laevis","embryo","45 days","NOEC","Mortality","100 ug/L","Amphibian","Chordata","Amphibia","Dechlorinated tap water","20-24oC","Chronic","Not stated","N.A.","Cheng, Y., Y. Cui, H-M. Chen and W-P. Xie. 2011. Thyroid disruption effects of environmental level perfluorooctane sulfaontes (PFOS) in Xenopus laevis. Ecotoxicology 20: 2069-2078.","3045"]

{"sheet":"Sheet1","index":4,"n_rows":70,"n_cols":29,"rows_kept":70,"cut":false,"hidden":true,"merged":[]}
[]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["Answers",{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}}]
[]
[]
[]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},null,{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}}]
[]
[]
[]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}}]
[]
[]
[]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}}]
[{"$f":"'FW nonmetal plant'!B11","v":"No."},{"$f":"'FW nonmetal plant'!B13","v":1},{"$f":"'FW nonmetal plant'!B16","v":2},{"$f":"'FW nonmetal plant'!B19","v":3},{"$f":"'FW nonmetal plant'!B21","v":4},{"$f":"'FW nonmetal plant'!B23","v":5},{"$f":"'FW nonmetal plant'!B26","v":6},{"$f":"'FW nonmetal plant'!B29","v":7},{"$f":"'FW nonmetal plant'!B32","v":8},{"$f":"'FW nonmetal plant'!B35","v":9},{"$f":"'FW nonmetal plant'!B39","v":10},{"$f":"'FW nonmetal plant'!B42","v":11},{"$f":"'FW nonmetal plant'!B45","v":12},{"$f":"'FW nonmetal plant'!B48","v":13},{"$f":"'FW nonmetal plant'!B51","v":14},{"$f":"'FW nonmetal plant'!B53","v":15},{"$f":"'FW nonmetal plant'!B58","v":16.10},{"$f":"'FW nonmetal plant'!B62","v":17},{"$f":"'FW nonmetal plant'!B65","v":18},{"$f":"'FW nonmetal plant'!C70","v":"Total score"},{"$f":"'FW nonmetal plant'!C72","v":"Quality Score"}]
[{"$f":"'FW nonmetal plant'!C2","v":"Category"},{"$f":"'FW nonmetal plant'!E2","v":"Freshwater/non-metal/plant"},{"$f":"'FW nonmetal plant'!C3","v":"Paper and data unique identifier(eg. 1-1,10-150)"},{"$f":"'FW nonmetal plant'!E3","v":"3044-3"}]
[{"$f":"'FW nonmetal plant'!G11","v":"Scores"},{"$f":"'FW nonmetal plant'!G12","v":10},{"$f":"'FW nonmetal plant'!G15","v":5},{"$f":"'FW nonmetal plant'!G18","v":5},{"$f":"'FW nonmetal plant'!G21","v":0},{"$f":"'FW nonmetal plant'!G23","v":5},{"$f":"'FW nonmetal plant'!G26","v":5},{"$f":"'FW nonmetal plant'!G29","v":0},{"$f":"'FW nonmetal plant'!G32","v":0},{"$f":"'FW nonmetal plant'!G35","v":5},{"$f":"'FW nonmetal plant'!G38","v":0},{"$f":"'FW nonmetal plant'!G41","v":4},{"$f":"'FW nonmetal plant'!G44","v":0},{"$f":"'FW nonmetal plant'!G47","v":4},{"$f":"'FW nonmetal plant'!G50","v":4},{"$f":"'FW nonmetal plant'!G53","v":4},{"$f":"'FW nonmetal plant'!G57","v":3},{"$f":"'FW nonmetal plant'!G61","v":3},{"$f":"'FW nonmetal plant'!G64","v":3},{"$f":"'FW nonmetal plant'!G70","v":60},{"$f":"'FW nonmetal plant'!G72","v":0.68181818181818177},{"$f":"'FW nonmetal plant'!H72","v":""}]
[{"$f":"'FW nonmetal plant'!H11","v":"Answers"},{"$f":"IF('FW nonmetal plant'!H12=\"\",\"\",'FW nonmetal plant'!H12)","v":"42 days"},{"$f":"IF('FW nonmetal plant'!H15=\"\",\"\",'FW nonmetal plant'!H15)","v":"Growth - frond number"},{"$f":"IF('FW nonmetal plant'!H18=\"\",\"\",'FW nonmetal plant'!H18)","v":"LOEC"},{"$f":"IF('FW nonmetal plant'!H21=\"\",\"\",'FW nonmetal plant'!H21)","v":"LOEC"},{"$f":"IF('FW nonmetal plant'!H23=\"\",\"\",'FW nonmetal plant'!H23)","v":"Yes"},{"$f":"IF('FW nonmetal plant'!H26=\"\",\"\",'FW nonmetal plant'!H26)","v":"Triplicate"},{"$f":"IF('FW nonmetal plant'!H29=\"\",\"\",'FW nonmetal plant'!H29)","v":"Not stated"},{"$f":"IF('FW nonmetal plant'!H32=\"\",\"\",'FW nonmetal plant'!H32)","v":"Small plants"},{"$f":"IF('FW nonmetal plant'!H35=\"\",\"\",'FW nonmetal plant'!H35)","v":"Irrigation pond water"},{"$f":"IF('FW nonmetal plant'!H38=\"\",\"\",'FW nonmetal plant'!H38)","v":"Not stated"},{"$f":"IF('FW nonmetal plant'!H41=\"\",\"\",'FW nonmetal plant'!H41)","v":"Measured"},{"$f":"IF('FW nonmetal plant'!H44=\"\",\"\",'FW nonmetal plant'!H44)","v":"Not stated"},{"$f":"IF('FW nonmetal plant'!H47=\"\",\"\",'FW nonmetal plant'!H47)","v":"Figure 6"},{"$f":"IF('FW nonmetal plant'!H53=\"\",\"\",'FW nonmetal plant'!H53)","v":"Yes"},{"$f":"IF('FW nonmetal plant'!H53=\"\",\"\",'FW nonmetal plant'!H53)","v":"Yes"},{"$f":"IF('FW nonmetal plant'!H57=\"\",\"\",'FW nonmetal plant'!H57)","v":"8.3-8.3"},{"$f":"IF('FW nonmetal plant'!H61=\"\",\"\",'FW nonmetal plant'!H61)","v":"15.9 - 20.5oC"},{"$f":"IF('FW nonmetal plant'!H64=\"\",\"\",'FW nonmetal plant'!H64)","v":"PFOS-K 86% from 3 M (Fluorad fluorochemical surfactant FC-95)"}]
[{"$f":"'FW nonmetal plant'!G3","v":"Species (Scientific name)"},{"$f":"'FW nonmetal plant'!G4","v":"Lifestage"},{"$f":"'FW nonmetal plant'!G5","v":"Exposure duration"},{"$f":"'FW nonmetal plant'!G6","v":"Measure of toxicity"},{"$f":"'FW nonmetal plant'!G7","v":"Toxicity endpoint"},{"$f":"'FW nonmetal plant'!G8","v":"Toxicity value"},{"$f":"'FW nonmetal plant'!J2","v":"Taxonomic group"},{"$f":"'FW nonmetal plant'!J3","v":"Phylum"},{"$f":"'FW nonmetal plant'!J4","v":"Class"},{"$f":"'FW nonmetal plant'!J5","v":"Media"},{"$f":"'FW nonmetal plant'!J6","v":"Temperature "},{"$f":"'FW nonmetal plant'!J7","v":"Acute Or Chronic "},{"$f":"'FW nonmetal plant'!J8","v":"PH"},{"$f":"'FW nonmetal plant'!J9","v":"Salinity/Conductivity"},{"$f":"'FW nonmetal plant'!C4","v":"Citation"},{"$f":"'FW nonmetal plant'!G2","v":"Citation No."}]
[{"$f":"'FW nonmetal plant'!Q3","v":"Lemna gibba"},{"$f":"'FW nonmetal plant'!T3","v":"not stated"},{"$f":"'FW nonmetal plant'!W3","v":"42 days"},{"$f":"'FW nonmetal plant'!Z3","v":"LOEC"},{"$f":"'FW nonmetal plant'!AC3","v":"Growth"},{"$f":"IF('FW nonmetal plant'!H8=\"\",\"\",'FW nonmetal plant'!H8)","v":"3000 ug/L"},{"$f":"'FW nonmetal plant'!AF3","v":"Macrophyte"},{"$f":"'FW nonmetal plant'!AI3","v":"Tracheophyta"},{"$f":"'FW nonmetal plant'!AO3","v":"Irrigation pond water"},{"$f":"'FW nonmetal plant'!AR3","v":"15.9-20.5"},{"$f":"'FW nonmetal plant'!AR3","v":"15.9-20.5"},{"$f":"'FW nonmetal plant'!AU3","v":"Chronic"},{"$f":"'FW nonmetal plant'!AX3","v":"8.3-8.8"},{"$f":"'FW nonmetal plant'!BA3","v":"N.A."},{"$f":"IF('FW nonmetal plant'!E4=\"\",\"\",'FW nonmetal plant'!E4)","v":"Boudreau, T.M., C.J. Wilson, W.J. Cheong, P.K. Sibley, S.A. Mabury, P.C.G. Muir and K.R. Solomon. 2003. Response of the zooplankton community and environmental fate of perfluorooctane sulfonic acid in aquatic microcosms. Environmental Toxicology and Chemistry 22: 2739-2745."},{"$f":"IF('FW nonmetal plant'!H2=\"\",\"\",'FW nonmetal plant'!H2)","v":"3044"}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}}]
[{"$f":"'FW nonmetal nonplant'!B11","v":"No."},{"$f":"'FW nonmetal nonplant'!B13","v":1},{"$f":"'FW nonmetal nonplant'!B16","v":2},{"$f":"'FW nonmetal nonplant'!B19","v":3},{"$f":"'FW nonmetal nonplant'!B21","v":4},{"$f":"'FW nonmetal nonplant'!B23","v":5},{"$f":"'FW nonmetal nonplant'!B26","v":6},{"$f":"'FW nonmetal nonplant'!B29","v":7},{"$f":"'FW nonmetal nonplant'!B32","v":8},{"$f":"'FW nonmetal nonplant'!B35","v":9},{"$f":"'FW nonmetal nonplant'!B39","v":10},{"$f":"'FW nonmetal nonplant'!B42","v":11},{"$f":"'FW nonmetal nonplant'!B45","v":12},{"$f":"'FW nonmetal nonplant'!B48","v":13},{"$f":"'FW nonmetal nonplant'!B51","v":14},{"$f":"'FW nonmetal nonplant'!B53","v":15},{"$f":"'FW nonmetal nonplant'!B58","v":16.10},{"$f":"'FW nonmetal nonplant'!B61","v":16.20},{"$f":"'FW nonmetal nonplant'!B64","v":17},{"$f":"'FW nonmetal nonplant'!B67","v":18},{"$f":"'FW nonmetal nonplant'!C72","v":"Total score"},{"$f":"'FW nonmetal nonplant'!C74","v":"Quality Score"}]
[{"$f":"'FW nonmetal nonplant'!C2","v":"Category"},{"$f":"'FW nonmetal nonplant'!E2","v":"Freshwater/non-metal/non- plant"},{"$f":"'FW nonmetal nonplant'!C3","v":"Paper and data unique identifier(eg. 1-1,10-150)"},{"$f":"'FW nonmetal nonplant'!E3","v":"3045-1"}]
[{"$f":"'FW nonmetal nonplant'!G11","v":"Scores"},{"$f":"'FW nonmetal nonplant'!G12","v":10},{"$f":"'FW nonmetal nonplant'!G15","v":5},{"$f":"'FW nonmetal nonplant'!G18","v":0},{"$f":"'FW nonmetal nonplant'!G21","v":0},{"$f":"'FW nonmetal nonplant'!G23","v":5},{"$f":"'FW nonmetal nonplant'!G26","v":5},{"$f":"'FW nonmetal nonplant'!G29","v":0},{"$f":"'FW nonmetal nonplant'!G32","v":5},{"$f":"'FW nonmetal nonplant'!G35","v":5},{"$f":"'FW nonmetal nonplant'!G38","v":0},{"$f":"'FW nonmetal nonplant'!G41","v":0},{"$f":"'FW nonmetal nonplant'!G44","v":0},{"$f":"'FW nonmetal nonplant'!G47","v":0},{"$f":"'FW nonmetal nonplant'!G50","v":4},{"$f":"'FW nonmetal nonplant'!G53","v":4},{"$f":"'FW nonmetal nonplant'!G57","v":0},{"$f":"'FW nonmetal nonplant'!G60","v":0},{"$f":"'FW nonmetal nonplant'!G63","v":1},{"$f":"'FW nonmetal nonplant'!G66","v":3},{"$f":"'FW nonmetal nonplant'!G72","v":47},{"$f":"'FW nonmetal nonplant'!G74","v":0.51648351648351654},null,{"$f":"'FW nonmetal nonplant'!H74","v":"The highest possible grade for this datum is acceptable."}]
[{"$f":"'FW nonmetal nonplant'!H11","v":"Answers"},{"$f":"IF('FW nonmetal nonplant'!H12=\"\",\"\",'FW nonmetal nonplant'!H12)","v":"45 days between NF stages 46/47 and NF stage 62"},{"$f":"IF('FW nonmetal nonplant'!H15=\"\",\"\",'FW nonmetal nonplant'!H15)","v":"Survival"},{"$f":"IF('FW nonmetal nonplant'!H18=\"\",\"\",'FW nonmetal nonplant'!H18)","v":"NOEC"},{"$f":"IF('FW nonmetal nonplant'!H21=\"\",\"\",'FW nonmetal nonplant'!H21)","v":"NOEC"},{"$f":"IF('FW nonmetal nonplant'!H23=\"\",\"\",'FW nonmetal nonplant'!H23)","v":"Yes"},{"$f":"IF('FW nonmetal nonplant'!H26=\"\",\"\",'FW nonmetal nonplant'!H26)","v":"Duplicate tanks"},{"$f":"IF('FW nonmetal nonplant'!H29=\"\",\"\",'FW nonmetal nonplant'!H29)","v":"Not stated"},{"$f":"IF('FW nonmetal nonplant'!H32=\"\",\"\",'FW nonmetal nonplant'!H32)","v":"6 dpf (NF State 46/47)"},{"$f":"IF('FW nonmetal nonplant'!H35=\"\",\"\",'FW nonmetal nonplant'!H35)","v":"Dechlorinated tap water"},{"$f":"IF('FW nonmetal nonplant'!H38=\"\",\"\",'FW nonmetal nonplant'!H38)","v":"Static renewal - changed twice a week"},{"$f":"IF('FW nonmetal nonplant'!H41=\"\",\"\",'FW nonmetal nonplant'!H41)","v":"Not stated"},{"$f":"IF('FW nonmetal nonplant'!H44=\"\",\"\",'FW nonmetal nonplant'!H44)","v":"Not stated"},{"$f":"IF('FW nonmetal nonplant'!H47=\"\",\"\",'FW nonmetal nonplant'!H47)","v":"Figure 2"},{"$f":"IF('FW nonmetal nonplant'!H50=\"\",\"\",'FW nonmetal nonplant'!H50)","v":"Yes"},{"$f":"IF('FW nonmetal nonplant'!H53=\"\",\"\",'FW nonmetal nonplant'!H53)","v":"p < 0.05"},{"$f":"IF('FW nonmetal nonplant'!H57=\"\",\"\",'FW nonmetal nonplant'!H57)","v":"Not stated"},{"$f":"IF('FW nonmetal nonplant'!H60=\"\",\"\",'FW nonmetal nonplant'!H60)","v":"Not stated"},{"$f":"IF('FW nonmetal nonplant'!H63=\"\",\"\",'FW nonmetal nonplant'!H63)","v":"20-24oC"},{"$f":"IF('FW nonmetal nonplant'!H66=\"\",\"\",'FW nonmetal nonplant'!H66)","v":"PFOS > 96% from Fluka "}]
[{"$f":"'FW nonmetal nonplant'!G3","v":"Species (Scientific name)"},{"$f":"'FW nonmetal nonplant'!G4","v":"Lifestage"},{"$f":"'FW nonmetal nonplant'!G5","v":"Exposure duration"},{"$f":"'FW nonmetal nonplant'!G6","v":"Measure of toxicity"},{"$f":"'FW nonmetal nonplant'!G7","v":"Toxicity endpoint"},{"$f":"'FW nonmetal nonplant'!G8","v":"Toxicity value"},{"$f":"'FW nonmetal nonplant'!J2","v":"Taxonomic group"},{"$f":"'FW nonmetal nonplant'!J3","v":"Phylum"},{"$f":"'FW nonmetal nonplant'!J4","v":"Class"},{"$f":"'FW nonmetal nonplant'!J5","v":"Media"},{"$f":"'FW nonmetal nonplant'!J6","v":"Temperature "},{"$f":"'FW nonmetal nonplant'!J7","v":"Acute Or Chronic "},{"$f":"'FW nonmetal nonplant'!J8","v":"PH"},{"$f":"'FW nonmetal nonplant'!J9","v":"Salinity/Conductivity"},{"$f":"'FW nonmetal nonplant'!C4","v":"Citation"},{"$f":"'FW nonmetal nonplant'!G2","v":"Citation No."}]
[{"$f":"'FW nonmetal nonplant'!Q3","v":{"$error":"#REF!"}},{"$f":"'FW nonmetal nonplant'!T3","v":"embryo"},{"$f":"'FW nonmetal nonplant'!W3","v":"45 days"},{"$f":"'FW nonmetal nonplant'!Z3","v":"NOEC"},{"$f":"'FW nonmetal nonplant'!AC3","v":"Mortality"},{"$f":"IF('FW nonmetal nonplant'!H8=\"\",\"\",'FW nonmetal nonplant'!H8)","v":"100 ug/L"},{"$f":"'FW nonmetal nonplant'!AF3","v":"Amphibian"},{"$f":"'FW nonmetal nonplant'!AI3","v":"Chordata"},{"$f":"'FW nonmetal nonplant'!AL3","v":"Amphibia"},{"$f":"'FW nonmetal nonplant'!AO3","v":"Dechlorinated tap water"},{"$f":"'FW nonmetal nonplant'!AR3","v":"20-24oC"},{"$f":"'FW nonmetal nonplant'!AU3","v":"Chronic"},{"$f":"'FW nonmetal nonplant'!AX3","v":"Not stated"},{"$f":"'FW nonmetal nonplant'!BA3","v":"N.A."},{"$f":"IF('FW nonmetal nonplant'!E4=\"\",\"\",'FW nonmetal nonplant'!E4)","v":"Cheng, Y., Y. Cui, H-M. Chen and W-P. Xie. 2011. Thyroid disruption effects of environmental level perfluorooctane sulfaontes (PFOS) in Xenopus laevis. Ecotoxicology 20: 2069-2078."},{"$f":"IF('FW nonmetal nonplant'!H2=\"\",\"\",'FW nonmetal nonplant'!H2)","v":"3045"}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=\"\",\"\",#REF!)","v":{"$error":"#REF!"}}]

{"sheet":"FW nonmetal nonplant","index":5,"n_rows":128,"n_cols":53,"rows_kept":128,"cut":false,"hidden":false,"merged":[[3,4,7,4],[9,2,9,4],[11,2,13,2],[11,7,13,7],[14,2,16,2],[14,7,16,7],[17,2,19,2],[17,7,19,7],[20,2,21,2],[20,7,21,7],[22,2,24,2],[22,7,24,7],[25,2,27,2],[25,7,27,7],[28,2,30,2],[28,7,30,7],[31,2,33,2],[31,7,33,7],[34,2,36,2],[34,7,36,7],[37,2,39,2],[37,7,39,7],[40,2,42,2],[40,7,42,7],[43,2,45,2],[43,7,45,7],[46,2,48,2],[46,7,48,7],[49,2,51,2],[49,7,51,7],[65,2,68,2],[65,7,68,7],[59,7,61,7],[52,2,54,2],[52,7,54,7],[56,7,58,7],[62,2,64,2],[62,7,64,7]]}
[null,1,"Fill in the blank cells below, based on information provided in the paper being assessed. You can either pick an option from the dropdown list or add the appropriate detail using the 'Add to list' button. ",null,null,null,null,null,null,null,null,null,null,null,"* All the text in RED are used for drop down list ,make changes with caution."]
[null,null,"Category",{"$f":"IF(AF3=\"\",0,1)","v":1},"Freshwater/non-metal/non- plant",{"$f":"IF(E3=\"\",0,1)","v":1},"Citation No.",{"$f":"IF(ISERROR(FIND(\"-\",E3)),E3,LEFT(E3,FIND(\"-\",E3)-1))","v":"3045"},null,"Taxonomic group",null,null,null,null,"Species",null,null,"Lifestage",null,null,"Exposure duration",null,null,"Measure of toxicity",null,null,"Toxicity endpoint",null,null,"Taxonomic group",null,null,"Phylum",null,null,"Class",null,null,"Media",null,null,"Temperature ",null,null,"Acute Or Chronic",null,null,"PH",null,null,"Salinity/Comdictivity"]
[null,null,"Paper and data unique identifier(eg. 1-1,10-150)",{"$f":"IF(AI3=\"\",0,1)","v":1},"3045-1",{"$f":"IF(E4=\"\",0,1)","v":1},"Species (Scientific name)",null,null,"Phylum",null,null,null,null,"Acanthocyclops robustus",126,{"$f":"IF(P3=0,\"\",INDEX(O3:O102,P3))","v":{"$error":"#REF!"}},"<120 days post h atch",27,{"$f":"IF(S3=0,\"\",INDEX(R3:R102,S3))","v":"embryo"},"10 day",88,{"$f":"IF(V3=0,\"\",INDEX(U3:U102,V3))","v":"45 days"},"EC10",18,{"$f":"IF(Y3=0,\"\",INDEX(X3:X102,Y3))","v":"NOEC"},"ability to cling",36,{"$f":"IF(AB3=0,\"\",INDEX(AA3:AA102,AB3))","v":"Mortality"},"Amphibian",1,{"$f":"IF(AE3=0,\"\",INDEX(AD3:AD102,AE3))","v":"Amphibian"},"\tChytridiomycota",9,{"$f":"IF(AH3=0,\"\",INDEX(AG3:AG102,AH3))","v":"Chordata"},"\tOstracoda",4,{"$f":"IF(AK3=0,\"\",INDEX(AJ3:AJ102,AK3))","v":"Amphibia"}," 0.45  µ m filtered well water",19,{"$f":"IF(AN3=0,\"\",INDEX(AM3:AM102,AN3))","v":"Dechlorinated tap water"},8,84,{"$f":"IF(AQ3=0,\"\",INDEX(AP3:AP102,AQ3))","v":"20-24oC"},"7.378-8.33",4,{"$f":"IF(AT3=0,\"\",INDEX(AS3:AS102,AT3))","v":"Chronic"},7,39,{"$f":"IF(AW3=0,\"\",INDEX(AV3:AV102,AW3))","v":"Not stated"},null,null,"N.A."]
[null,null,"Citation",{"$f":"IF(AL3=\"\",0,1)","v":1},"Cheng, Y., Y. Cui, H-M. Chen and W-P. Xie. 2011. Thyroid disruption effects of environmental level perfluorooctane sulfaontes (PFOS) in Xenopus laevis. Ecotoxicology 20: 2069-2078.",{"$f":"IF(H8=\"\",0,1)","v":1},"Lifestage",null,null,"Class",null,null,null,null,"Acutodesmus obliquus",null,null,"<24h neonate f2 ",null,null,"11 hour",null,null,"EC50",null,null,"ability to swim",null,null,"Bacteria",null,null,"\tOomycota",null,null,"\tSordariomycetes",null,null,"50 mL AA/8 supplemented with nitrate (5 mM) in 125 ml Erlenmeyer ?asks and 10 mg/mL of neomycin sulphate (Nm)",null,null,10,null,null,"7.78-8.33",null,null,7.20]
[null,null,null,{"$f":"IF(AO3=\"\",0,1)","v":1},null,{"$f":"IF(W3=\"\",0,1)","v":1},"Exposure duration",null,null,"Media",null,null,null,null,"Aedes aegypti",null,null,"<24hr neonate",null,null,"1-2 weeks",null,null,"EC50",null,null,"ability to thrash when prodded",null,null,"Chordata",null,null,"\tRotifera",null,null,"Actinopterygii",null,null,"Activated carbon-dechlorinated tap water ",null,null,12,null,null,"Acute ",null,null,7.30]
[null,null,null,{"$f":"IF(AR3=\"\",0,1)","v":1},null,{"$f":"IF(Q3=\"\",0,1)","v":{"$error":"#REF!"}},"Measure of toxicity",null,null,"Temperature ",null,null,null,null,"Aedes albopictus",null,null,">23 days",null,null,"120 days",null,null,"hatchability",null,null,"ability to walk/crawl",null,null,"Chromista",null,null,"Actinopterygii",null,null,"Amphibia",null,null,"Aerated synthetic fresh water",null,null,12,null,null,"Chronic",null,null,7.50]
[null,null,null,{"$f":"IF(AU3=\"\",0,1)","v":1},null,{"$f":"IF(T3=\"\",0,1)","v":1},"Toxicity endpoint",null,null,"Acute Or Chronic ",null,null,null,null,"Aedes albopictus",null,null,">6 month ",null,null,"120hpf",null,null,"IC25",null,null,"activity",null,null,"Fish",null,null,"Arthropoda",null,null,"Bivalvia",null,null,"Aerated tap water with dimethyl sulfoxide",null,null,12,null,null,"N.A.",null,null,7.50]
[null,null,null,null,null,{"$f":"IF(W3=\"\",0,1)","v":1},"Toxicity value","100 ug/L",null,"PH",null,null,null,null,"Aedes albopictus HAmAal strain",null,null,"1 month",null,null,"13 days",null,null,"LC10",null,null,"Bioluminescence",null,null,"Fish",null,null,"Ascomycota",null,null,"Bivalvia",null,null,"algal medium prepared with  deionized water",null,null,13,null,null,null,null,null,7.66]
[null,2,"Select the appropriate answer option to each question. Comments can be added to the cells in column H.",null,null,{"$f":"IF(Z3=\"\",0,1)","v":1},null,null,null,"Salinity/Conductivity","N.A.",null,null,null,"Aedes albopictus Ikaken strain",null,null,"1 year old",null,null,"14 days",null,null,"LC100",null,null,"Body length",null,null,"Flagellate",null,null,"Basidiomycota",null,null,"Branchiopoda",null,null,"algaltoxkit",null,null,13,null,null,null,null,null,7.67]
[null,"*","If the selected answer option does not work try clicking on any other cell first and then click back on the answer option again.",null,null,{"$f":"IF(AC3=\"\",0,1)","v":1},null,null,null,null,null,null,null,null,"Aedes albopictus MAmAal strain",null,null,"10-12 mm length",null,null,"15 days",null,null,"LC50",null,null,"Body weight",null,null,"Fungi",null,null,"Chlorophyta",null,null,"Chlorophyceae  ",null,null,"artificial system water",null,null,13,null,null,null,null,null,7.80]
[null,"No.","Question","Marks Awarded","Answer Options","Option References","Scores","Answers",null,null,null,null,null,null,"Aedes albopictus SFmAal strain",null,null,"14 days post fertilisation",null,null,"15 days ",null,null,"LC50",null,null,"Brood size",null,null,"Insect",null,null,"Chordata",null,null,"Chytridiomycetes",null,null,"ATSM hardwater",null,null,14,null,null,null,null,null,8.10]
[null,null,"Was the duration of the exposure stated (e.g. 48 or 96 h)?",10,null,1,{"$f":"IF(F12=0,0,INDEX($D12:$D13,F12,1))","v":10},"45 days between NF stages 46/47 and NF stage 62",null,null,null,null,null,null,"Aedes albopictus VBFmAal strain",null,null,"1st instar larvae",null,null,"150 days post fertilisation",null,null,"LC90",null,null,"brood survival",null,null,"Macroinvertebrate",null,null,"Chordata",null,null,"Cryptophyceae",null,null,"Bore water",null,null,16,null,null,null,null,null,9.1999999999999993]
[null,1,null,0,null,null,null,null,null,null,null,null,null,null,"Aedes taeniorhynchus",null,null,"3rd brood",null,null,"150 days post fertilisation ",null,null,"LC90",null,null,"Cell viability",null,null,"Macroinvertebrate",null,null,"Ciliophora",null,null,"Cyanophyceae",null,null,"CBS culture collection",null,null,16,null,null,null,null,null,"6.5-7"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Anabaena flos-aquae",null,null,"3rd brood neonate",null,null,"180 days",null,null,"LC95",null,null,"Colour change",null,null,"Microalga",null,null,"Cryptophyta",null,null,"Eurotatoria",null,null,"charcoal-filtered tap water",null,null,17,null,null,null,null,null,"6.5-7.4"]
[null,null,"Was the biological endpoint (e.g. immobilization or population growth) stated and defined (10 marks)? Award 5 marks if the biological endpoint is only stated.",10,null,2,{"$f":"IF(F15=0,0,INDEX($D15:$D17,F15,1))","v":5},"Survival",null,null,null,null,null,null,"AnopheIes quadrimaculatus",null,null,"3rd brood neonate <24hr",null,null,"19 days",null,null,"LD50",null,null,"development",null,null,"Microinvertebrate",null,null,"Cyanobacteria",null,null,"Gammaproteobacteria",null,null,"Clean river water",null,null,18,null,null,null,null,null,"6.6-7.2"]
[null,2,null,5,null,null,null,null,null,null,null,null,null,null,"Australian Bass",null,null,"4-5th instar larvae",null,null,"20 days",null,null,"LOEC",null,null,"Development",null,null,"N.A.",null,null,"Mollusca",null,null,"Gastropoda",null,null,"Clean river watrer",null,null,18,null,null,null,null,null,"6.8-7.5"]
[null,null,null,0,null,null,null,null,null,null,null,null,null,null,"Baetis tricaudatus",null,null,"4th instar larvae",null,null,"21 day",null,null,"LOEC",null,null,"Developmental",null,null,"Rotifer",null,null,"N.A.",null,null,"Insecta",null,null,"Clean well water",null,null,19,null,null,null,null,null,"7.0-7.5"]
[null,null,"Was the biological effect stated (e.g. LC or NOEC)?",5,null,2,{"$f":"IF(F18=0,0,INDEX($D18:$D19,F18,1))","v":0},"NOEC",null,null,null,null,null,null,"Batrachochytrium dendrobatidis",null,null,"5-7d adult",null,null,"21 day",null,null,"LOEC",null,null,"Developmental",null,null,"Snail",null,null,"Platyhelminthes",null,null,"Insecta",null,null,"Control water - water chem provided",null,null,20,null,null,null,null,null,"7.1 ± 0.5"]
[null,3,null,0,null,null,null,null,null,null,null,null,null,null,"Batrachochytrium dendrobatidis",null,null,"5th instar larvae",null,null,"24 days",null,null,"N.A.",null,null,"Emergence",null,null,"Microorganism",null,null,"Proteobacteria",null,null,"Malacostraca",null,null,"Daphnia culture medium",null,null,20,null,null,null,null,null,"7.3 ± 0.2"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Bufo gargarizans",null,null,"6-11 g",null,null,"24 hrs",null,null,"NOEC",null,null,"Fecundity",null,null,"Mollusc",null,null,"Tracheophyta",null,null,"Maxillopoda",null,null,"Daphtoxkit",null,null,20,null,null,null,null,null,"7.35-7.6"]
[null,4,"Was the biological effect quantified (e.g. 50% effect, 25% effect)? \nNote: The effect for NOEC and LOEC data must be quantified.",5,null,2,{"$f":"IF(F21=0,0,INDEX($D21:$D22,F21,1))","v":0},"NOEC",null,null,null,null,null,null,"Ceriodaphnia dubia",null,null,"6-9cm length",null,null,"24h",null,null,"NOEC",null,null,"Feed assimilation",null,null,null,null,null,"Zygomycota",null,null,"N.A.",null,null,"Dechlorinated tap water",null,null,20,null,null,null,null,null,"7.3-8.0"]
[null,null,null,0,null,null,null,null,null,null,null,null,null,null,"Chaoborus crystallinus",null,null,"7-11g",null,null,"24hr",null,null,"NOEC",null,null,"Foraging success",null,null,null,null,null,"Nematoda",null,null,"Not assigned",null,null,"dechlorinated water",null,null,20,null,null,null,null,null,"7.51 ± 0.19"]
[null,5,"Were appropriate controls (e.g. a no-toxicant control and/or solvent control) used?",5,null,1,{"$f":"IF(F23=0,0,INDEX($D23:$D24,F23,1))","v":5},"Yes",null,null,null,null,null,null,"Chironomus crassicaudatus",null,null,"adult",null,null,"24hr",null,null,"NOEL",null,null,"Gonad mass",null,null,null,null,null,"Rotifera",null,null,"Prostomatea",null,null,"deinonised reconstituted water",null,null,21,null,null,null,null,null,"7.6-7.75"]
[null,null,null,0,null,null,null,null,null,null,null,null,null,null,"Chironomus dilutus",null,null,"Adult",null,null,"25 days",null,null,"NOEL",null,null,"Gonadosomatic index",null,null,null,null,null,null,null,null,"Teleostei",null,null,"deionised sterile water",null,null,22,null,null,null,null,null,"7.6-8.2"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Chironomus tentans",null,null,"Adult (7.1-10.5cm length)",null,null,"25hr",null,null,null,null,null,"granulocyte count",null,null,null,null,null,null,null,null,"Tremellomycetes",null,null,"Deionised water",null,null,23,null,null,null,null,null,"7.78-8.33"]
[null,6,"Was each control and contaminant concentration at least duplicated?",5,null,1,{"$f":"IF(F26=0,0,INDEX($D26:$D27,F26,1))","v":5},"Duplicate tanks",null,null,null,null,null,null,"Colubotelson chiltoni minor",null,null,"adult female",null,null,"26 days",null,null,null,null,null,"Growth",null,null,null,null,null,null,null,null,"Trepaxonemata",null,null,"Deionised water with added salts",null,null,23,null,null,null,null,null,"7.8 -+ 0.2"]
[null,null,null,0,null,null,null,null,null,null,null,null,null,null,"Cryptococcus flavescens",null,null,"Eggs",null,null,"28 day",null,null,null,null,null,"growth",null,null,null,null,null,null,null,null,"Secernentea",null,null,"essential medium",null,null,23,null,null,null,null,null,"7.8-8.1"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Cryptomonas sp.",null,null,"embryo",null,null,"28 days",null,null,null,null,null,"growth inhibition",null,null,null,null,null,null,null,null,"Sarcopterygii",null,null,"Filtered natural lake water",null,null,23,null,null,null,null,null,"7-7.2"]
[null,7,"Were test acceptability criteria stated (e.g. mortality in controls must not exceed a certain percentage) (5 marks)?\nOR Were test acceptability criteria inferred (e.g. test method used [USEPA, OECD, ASTM etc.]) (award 2 marks). \nNote: Data that fail the acceptability criteria are automatically deemed to be of unacceptable quality and must not be used. ",5,null,3,{"$f":"IF(F29=0,0,INDEX($D29:$D31,F29,1))","v":0},"Not stated",null,null,null,null,null,null,"Culex nigripalpus",null,null,"embryo",null,null,"28 days",null,null,null,null,null,"growth: length",null,null,null,null,null,null,null,null,"Bivalvia",null,null,"Freshwater",null,null,23,null,null,null,null,null,"8 ± 0.2"]
[null,null,null,2,null,null,null,null,null,null,null,null,null,null,"Culex quinqefasciatus",null,null,"Embryo 1-2 hpf; 8-64 cell stage",null,null,"28 dyas",null,null,null,null,null,"hatchability",null,null,null,null,null,null,null,null,"Monogononta",null,null,"grown on tadpoles in freshwater",null,null,24,null,null,null,null,null,"8.0-8.2"]
[null,null,null,0,null,null,null,null,null,null,null,null,null,null,"Culex quinqefasciatus HAmCq strain",null,null,"embryo to juvenile",null,null,"3 days",null,null,null,null,null,"hatching time",null,null,null,null,null,null,null,null,null,null,null,"growth culture",null,null,25,null,null,null,null,null,"8.0-8.4"]
[null,8,"Were the characteristics of the test organism (e.g. length, mass, age) stated?",5,null,1,{"$f":"IF(F32=0,0,INDEX($D32:$D34,F32,1))","v":5},"6 dpf (NF State 46/47)",null,null,null,null,null,null,"Culex quinqefasciatus S-Lab strain",null,null,"embryop",null,null,"30 days",null,null,null,null,null,"Immobilisation",null,null,null,null,null,null,null,null,null,null,null,"Lab water",null,null,25,null,null,null,null,null,"8.16-8.36"]
[null,null,null,0,null,null,null,null,null,null,null,null,null,null,"Culex quinqefasciatus VBFmCq strain",null,null,"fry",null,null,"32 day",null,null,null,null,null,"lymphocyte count",null,null,null,null,null,null,null,null,null,null,null,"Lake Superior Water",null,null,25,null,null,null,null,null,"8.32-8.61"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Culex quinquefasciatus MAmCq strain",null,null,"glochidia",null,null,"35 day",null,null,null,null,null,"Malformations - skeletal deformaties, F1",null,null,null,null,null,null,null,null,null,null,null,"Lake Superior water",null,null,26,null,null,null,null,null,"8.32-8.61"]
[null,9,"Was the type of test media used stated?",5,null,1,{"$f":"IF(F35=0,0,INDEX($D35:$D37,F35,1))","v":5},"Dechlorinated tap water",null,null,null,null,null,null,"Cyclops diaptomus",null,null,"glochidia",null,null,"4 day",null,null,null,null,null,"Mass",null,null,null,null,null,null,null,null,null,null,null,"M4 culture medium ",null,null,26,null,null,null,null,null,"N.A."]
[null,null,null,0,null,null,null,null,null,null,null,null,null,null,"Cyprinus carpio",null,null,"Glochidia",null,null,"40 days",null,null,null,null,null,"Mobility",null,null,null,null,null,null,null,null,null,null,null,"malt extract broth",null,null,27,null,null,null,null,null,"N/A"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Danio rerio",null,null,"juvenile",null,null,"42 day",null,null,null,null,null,"mobility: swim speed",null,null,null,null,null,null,null,null,null,null,null,"Marinewater",null,null,28,null,null,null,null,null,"N/A"]
[null,null,"Was the type of exposure (e.g. static, flow through) stated? ",4,null,2,{"$f":"IF(F38=0,0,INDEX($D38:$D40,F38,1))","v":0},"Static renewal - changed twice a week",null,null,null,null,null,null,"Daphnia magna",null,null,"juvenile",null,null,"45 days",null,null,null,null,null,"Mortality",null,null,null,null,null,null,null,null,null,null,null,"Martins rearing solution",null,null,28.50,null,null,null,null,null,"not stated"]
[null,10,null,0,null,null,null,null,null,null,null,null,null,null,"Daphnia pulex",null,null,"juvenile",null,null,"48 hr",null,null,null,null,null,"Mortality",null,null,null,null,null,null,null,null,null,null,null,"Milli-Q water",null,null,"2016-12-15",null,null,null,null,null,"Not stated"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Daphnia pulicaria",null,null,"juvenile",null,null,"48 hrs",null,null,null,null,null,"Mortality: disease susceptibility L. anguillarum",null,null,null,null,null,null,null,null,null,null,null,"minimal medium",null,null,"12 to 15",null,null,null,null,null,"Not stated"]
[null,null,"Were the contaminant concentrations measured at the beginning and end of the exposure (4 marks)? Award 2 marks if they were measured only once during the test.\nNote: If the concentrations were not measured then automatically the data cannot be high quality. ",4,null,3,{"$f":"IF(F41=0,0,INDEX($D41:$D43,F41,1))","v":0},"Not stated",null,null,null,null,null,null,"Diaptomus castor",null,null,"Juvenile",null,null,"48hr",null,null,null,null,null,"N.A.",null,null,null,null,null,null,null,null,null,null,null,"moderate hard synthetic water",null,null,"12.5-15.5",null,null,null,null,null,"Not stated"]
[null,11,null,2,null,null,null,null,null,null,null,null,null,null,"Diphetor hageni",null,null,"Juvenile",null,null,"5 day",null,null,null,null,null,"number of broods",null,null,null,null,null,null,null,null,null,null,null,"moderately hard reconstituted water",null,null,"12.6±0.03",null,null,null,null,null,"Not stated"]
[null,null,null,0,null,null,null,null,null,null,null,null,null,null,"Dreissena polymorpha",null,null,"Juvenile",null,null,"5 months",null,null,null,null,null,"number of broods",null,null,null,null,null,null,null,null,null,null,null,"Moderately hard water",null,null,"15°C",null,null,null,null,null,"Not stated"]
[null,null,"Were parallel reference toxicant toxicity tests conducted?",4,null,2,{"$f":"IF(F44=0,0,INDEX($D44:$D46,F44,1))","v":0},"Not stated",null,null,null,null,null,null,"Dugesia japonica",null,null,"larvae",null,null,"5 weeks",null,null,null,null,null,"number of broods",null,null,null,null,null,null,null,null,null,null,null,"moderately hard water",null,null,"18-22",null,null,null,null,null,"PH11"]
[null,12,null,0,null,null,null,null,null,null,null,null,null,null,"Elliptio complananta",null,null,"larvae",null,null,"6 days",null,null,null,null,null,"Nutrient assimilation",null,null,null,null,null,null,null,null,null,null,null,"moderately hard water",null,null,"19.6-23.1",null,null,null,null,null,"PH7.0"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Elliptio complanata",null,null,"Larvae (96 hours post fertilisation)",null,null,"60 day",null,null,null,null,null,"phagocytic cell count",null,null,null,null,null,null,null,null,null,null,null,"moderately hard water",null,null,"20 ± 1 ",null,null,null,null,null,"7-7.4"]
[null,null,"Was there a concentration–response relationship either observable or stated?",4,null,2,{"$f":"IF(F47=0,0,INDEX($D47:$D49,F47,1))","v":0},"Figure 2",null,null,null,null,null,null,"Elliptio complanata",null,null,"Larval",null,null,"7 day",null,null,null,null,null,"Reproduction",null,null,null,null,null,null,null,null,null,null,null,"N.A.",null,null,"20 ± 2",null,null,null,null,null,"7.9-8.2"]
[null,13,null,0,null,null,null,null,null,null,null,null,null,null,"Enallagma cyathigerum",null,null,"larval (7-d post hatch)",null,null,"7 day",null,null,null,null,null,"reproduction impairment",null,null,null,null,null,null,null,null,null,null,null,"Natural pond water",null,null,"20.1-21.9",null,null,null,null,null,"7-7.5"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Ephemeralla excrucians",null,null,"lochidia",null,null,"7 day",null,null,null,null,null,"respiratory burst",null,null,null,null,null,null,null,null,null,null,null,"Not stated",null,null,"20.1-21.9",null,null,null,null,null,"6.5-7.0"]
[null,null,"Was an appropriate statistical method or model used to determine the toxicity?\nNote: They should be accepted by a recognised national or international regulatory body (e.g. USEPA, OECD, ASTM). ",4,null,1,{"$f":"IF(F50=0,0,INDEX($D50:$D52,F50,1))","v":4},"Yes",null,null,null,null,null,null,"Eucypris virens",null,null,"N.A.",null,null,"7 days",null,null,null,null,null,"Secondary sexual characteristics",null,null,null,null,null,null,null,null,null,null,null,"Pond water",null,null,"20.2 ± 0.1",null,null,null,null,null,"7-7.6"]
[null,14,null,0,null,null,null,null,null,null,null,null,null,null,"Fallceon quilleri",null,null,"Neonate",null,null,"7 days",null,null,null,null,null,"serum lysozyme activity",null,null,null,null,null,null,null,null,null,null,null,"potato dextrose agar",null,null,"20-22",null,null,null,null,null,"7.8-8.2"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Fusarium sporotrichioides",null,null,"neonate",null,null,"7 dyas",null,null,null,null,null,"sex ratio",null,null,null,null,null,null,null,null,null,null,null,"reconstituted hard water",null,null,"21-24",null,null,null,null,null,"6.9-7.5"]
[null,15,"For LC/EC/BEC data was an estimate of variability provided? \nOR \nFor NO EC/LOEC data was the significance level 0.05 or less?  \n\n",4,null,1,{"$f":"IF(F53=0,0,INDEX($D53:$D55,F53,1))","v":4},"p < 0.05",null,null,null,null,null,null,"Galaxias auratus",null,null,"neonate fed",null,null,"70 days",null,null,null,null,null,"Survival",null,null,null,null,null,null,null,null,null,null,null,"reconstituted hard water",null,null,"22.0-22.4",null,null,null,null,null,"8-8.2"]
[null,null,null,0,null,null,null,null,null,null,null,null,null,null,"Galaxias maculatus",null,null,"neonate unfed",null,null,"7-14 days",null,null,null,null,null,"Swim ability",null,null,null,null,null,null,null,null,null,null,null,"reconstituted water",null,null,"22-23",null,null,null,null,null,"7.3-7.7"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Galaxias maculatus",null,null,"Not stated",null,null,"72 hrs",null,null,null,null,null,"time taken to release brood",null,null,null,null,null,null,null,null,null,null,null,"reoncstituted water",null,null,"22-24"]
[null,16,"Were the following parameters measured and stated? (3 marks if measured and stated, 1 mark if just measured).",null,null,null,null,null,null,null,null,null,null,null,"Galaxias truttaceus ",null,null,"Not stated",null,null,"7-8 days",null,null,null,null,null,"time until brood release",null,null,null,null,null,null,null,null,null,null,null,"Seawater",null,null,"23 ± 0.3"]
[null,null,null,3,null,3,{"$f":"IF(F57=0,0,INDEX($D57:$D59,F57,1))","v":0},"Not stated",null,null,null,null,null,null,"Glyptotendipes paripes",null,null,"Not stated",null,null,"8 days",null,null,null,null,null,"viability",null,null,null,null,null,null,null,null,null,null,null,"standard reference water",null,null,"23.1 ± 0.3"]
[null,16.10,"pH",1,null,null,null,null,null,null,null,null,null,null,"Helicopsyche sp. ",null,null,"Not stated",null,null,"8 days",null,null,null,null,null,"viability",null,null,null,null,null,null,null,null,null,null,null,"system water",null,null,"23.2 ± 0.4°C"]
[null,null,null,0,null,null,null,null,null,null,null,null,null,null,"Hexagenia sp.",null,null,"Not stated",null,null,"8 days",null,null,null,null,null,"viability",null,null,null,null,null,null,null,null,null,null,null,"tannic acid aqueous solution",null,null,"23-25"]
[null,null,null,3,null,3,{"$f":"IF(F60=0,0,INDEX($D60:$D62,F60,1))","v":0},"Not stated",null,null,null,null,null,null,"Hyalella azteca",null,null,"tadpole",null,null,"90 days",null,null,null,null,null,"Viability: ability to attach to host",null,null,null,null,null,null,null,null,null,null,null,"Tap water",null,null,"24.3-24.7"]
[null,16.20,"Dissolved Oxygen",1,null,null,null,null,null,null,null,null,null,null,"Hydropsyche sp. ",null,null,"tadpole",null,null,"90 days",null,null,null,null,null,"Viability: ability to attach to host",null,null,null,null,null,null,null,null,null,null,null,"Tap water",null,null,"24-26"]
[null,null,null,0,null,null,null,null,null,null,null,null,null,null,"Hyla cinerea",null,null,"Tadpole",null,null,"96 hour",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Tap water",null,null,"24-26"]
[null,null,"Was the temperature measured and stated (3 marks)? Award 1 mark if the temperature was measured but not stated or if only the temperature settings of the room or chamber are stated.",3,null,2,{"$f":"IF(F63=0,0,INDEX(D63:D65,F63,1))","v":1},"20-24oC",null,null,null,null,null,null,"Hyla squirella",null,null,"Tadpoles",null,null,"96 hrs",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"tap water",null,null,"25 ± 1"]
[null,17,null,1,null,null,null,null,null,null,null,null,null,null,"Ictalurus punctatus",null,null,"Tadpoles",null,null,"96hr",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Tap water and deionized water",null,null,"25.8–28.2"]
[null,null,null,0,null,null,null,null,null,null,null,null,null,null,"Isoperla quinquepunctata",null,null,"Fragment",null,null,"N.A.",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"unfiltered river water",null,null,"25±1"]
[null,null,"Were test solutions, blanks and/or controls tested for contamination OR were analytical reagent grade chemicals used or the highest possible purity chemicals used for the experiment? (3 marks).",3,null,1,{"$f":"IF(F66=0,0,INDEX($D66:$D67,F66,1))","v":3},"PFOS > 96% from Fluka ",null,null,null,null,null,null,"Lampsilis fasciola",null,null,null,null,null,"NOEL",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"UV irradiated well water",null,null,"25°C"]
[null,18,null,0,null,null,null,null,null,null,null,null,null,null,"Lampsilis siliquoidea",null,null,null,null,null,"Not stated (test went until 120 hours post fertilisation)",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Water (chemical properties provided)",null,null,"26 ± 2"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Lampsilis siliquoidea",null,null,null,null,null,"72 days",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Water filtered by reverse osmosis with \"Instant Ocean\" salt added",null,null,"26±1oC"]
[null,null,null,null,null,null,null,null,{"$f":"(COUNTIF(F12:F67,\"=0\"))+COUNTIF(F2:F10,\"=0\")+COUNTIF(D2:D7,\"=0\")","v":0},null,null,null,null,null,"Lymnaea stagnalis",null,null,null,null,null,"72 d",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Nematode Growth Medium",null,null,"28 + 3"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Moina macrocopa",null,null,null,null,null,"58 days",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Filtered well water",null,null,"28 ± 1"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Mucor hiemalis",null,null,null,null,null,"150 days post metamorphosis",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Dechlorinated tap water",null,null,"28-30"]
[null,null,"Total score",null,null,null,{"$f":"IF(SUM(G12:G66)=0,\"\",SUM(G12:G66))","v":47},null,null,null,null,null,null,null,"Myriophyllum sibiricum",null,null,null,null,null,"44 days",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Fish culture water",null,null,"N.A."]
[null,null,"Total Max. possible score for the various types of data and contaminants ",null,{"$f":"D12+D15+D18+D21+D23+D26+D29+D32+D35+D38+D41+D44+D47+D50+D53+D57+D60+D63+D66","v":91},null,null,null,null,null,null,null,null,null,"N.A.",null,null,null,null,null,"28 days",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Reconstituted water",null,null,"N/A"]
[null,null,"Quality Score",null,{"$f":"\"= [Total score / Total possible score] * 100 = \"","v":"= [Total score / Total possible score] * 100 = "},null,{"$f":"IF(ISERROR(G72/E73),#N/A,G72/E73)","v":0.51648351648351654},{"$f":"IF(F41=3,\"The highest possible grade for this datum is acceptable.\",\"\")","v":"The highest possible grade for this datum is acceptable."},null,null,null,null,null,null,"Nectopsyche sp.",null,null,null,null,null,"44 days",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Daphnia culture media",null,null,"Not stated"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Neoniphargus sp.",null,null,null,null,null,"22 days",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Culture medium",null,null,"20oC"]
[null,null,"H = high quality                           Quality score ≥ 80%      ",null,null,null,null,null,null,null,null,null,null,null,"Oncorhynchus mykiss",null,null,null,null,null,"38 days",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Danieaus medium",null,null,"21oC"]
[null,null,"A = acceptable quality         > 50% Quality score < 80%        ",null,null,null,null,null,null,null,null,null,null,null,"Oryzias latipes",null,null,null,null,null,"12 days",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"RO water",null,null,"25.5-26.5oC"]
[null,null,"U = unacceptable quality              Quality score ≤ 50%  ",null,null,null,null,null,null,null,null,null,null,null,"Osteopilus septentrionalis",null,null,null,null,null,"90 days",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Charcoal filtered tap water",null,null,"27-29oC"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Pacifastacus leniusculus",null,null,null,null,null,"90 days",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Spring water",null,null,"19-21oC"]
[3,null,"Click the 'Save & Update' button to save and export the answers to the 'All results' worksheet. ",null,null,null,null,null,null,null,null,null,null,null,"Palaemonetes pugio",null,null,null,null,null,"90 days",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Carbon-filtered tap water",null,null,"18.7 and 21.2oC"]
[null,null,"Select the 'Reset Answers' button if you wish to clear all answers.",null,null,null,null,null,null,null,null,null,null,null,"Parutya austruliensis",null,null,null,null,null,"90 days",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Reverse Osmosis water with salt added",null,null,"19-21oC"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Philodina acuticornis odiosa",null,null,null,null,null,"70 days",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Lab distilled water",null,null,"28oC"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Pimephales promelas",null,null,null,null,null,"70 days",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"USEPA medium",null,null,"24-26oC"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Pimephales promelas",null,null,null,null,null,"8 days",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"18-22oC"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Polypedilum nubiferum",null,null,null,null,null,"58 days",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"27.5-28.5oC"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Procambarus clarkii",null,null,null,null,null,"120 days",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"20-24oC"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Procambarus zonangulus",null,null,null,null,null,"36 days",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"22oC"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Pseudaphritis urvillir",null,null,null,null,null,"120 days",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"21-25oC"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Pseudorasbora parva",null,null,null,null,null,"90 days",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"19-21oC"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Pythium spp",null,null,null,null,null,"45 days",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"20.1-29.2oC"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rana pipiens",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"6-16.5oC"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rana sphenocephala",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"12oC"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Raphidocelis subcapitata",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"19-21oC"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Salmo gairdneri",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"25-27oC"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Selenastrum capricornutum",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"26-28oC"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Serratella micheneri",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"26.5-27.5oC"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Simocephalus elizabethae"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Simulium vittatum"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Simulium vittatum IS-7"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Spea multiplicata"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Taenionema sp."]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Trichoderma hamatum"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Tricorythodes sp. "]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Unio elongatulus"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Urotricha furcata"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Villosa constricta"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Villosa delumbis"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Xenopus laevis"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Xiphophorus helleri"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Caenorhabditis elegans"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rana catesbiana"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Silurana tropicalis"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Chironomus riparius"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Physa pomilia"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Procambarus fallax f. virginalis"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Anguilla anguilla"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Xenopus laevis"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Chironomus riparius"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Semotilus antromaculatus"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Notropis hudsonius"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Catostomus commersoni"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Xiphophorus helleri"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Xenopus tropicalis"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Chironomus riparius"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Brachionus calyciflorus"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Lithobates pipiens"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Xiphorus helleri"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Xenopus laevis"]

{"sheet":"FW nonmetal nonplant_WS","index":6,"n_rows":633,"n_cols":24,"rows_kept":633,"cut":false,"hidden":false,"merged":[]}
[]
["Question No.",1,2,3,4,5,6,7,8,9,10,11,12,13,14,15,16.10,16.60,17,18,"Total Score","Quality Score",null,"Comment "]
["Short Questions","Duration of the exposure ","Biological endpoint","Biological effect stated or not","Biological effect quantified or not","Appropriate controls","Control & contaminant concentration","Test acceptability criteria","Characteristics of the test organism"," Type of test media","Type of exposure","Contaminant concentrations","Parallel reference toxicant toxicity tests","Concentration–response relationship","Determine the toxicity","NOEC/LOEC or LC/EC/BEC","pH","Dissolved oxygen","Temperature","Grade or purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3011-8"]
["Scores",10,10,0,0,5,0,0,5,5,4,0,0,4,4,4,0,0,1,0,52,0.5714285714285714,null,"The highest possible grade for this datum is acceptable."]
["Answers","Presented in figure V-1 - 40 + days","Mortality - \"individuals which did not respond to stimuli\"","LOEC not stated, inferred from results write up","","No-toxicant control used - moderately hard laboratory water. ","Not stated.","","Age - 1st instar larvae","Moderately hard laboratory water","Static renewal - water changed every 72 hours.","","","Presented in figure V-1 ","Kaplan-Meier Estimator Test using program R","p=0.05","","","Stated - 25oC",""]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3011-9"]
["Scores",10,5,0,0,5,0,0,5,5,4,0,0,4,4,4,0,0,1,0,47,0.51648351648351654,null,"The highest possible grade for this datum is acceptable."]
["Answers","Presented in figure V-3: 20 days","average time to emergence ","LOEC not stated, inferred from results write up","","No-toxicant control used - moderately hard laboratory water. ","Not stated.","","Age - 1st instar larvae","Moderately hard laboratory water","Static renewal - water changed every 72 hours.","","","Presented in figure V-3","ANOVA and ANCOVA tests using program R","p=0.05","","","Stated - 25oC",""]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3011-10"]
["Scores",10,5,0,0,5,0,0,5,5,4,0,0,4,4,4,0,0,1,0,47,0.51648351648351654,null,"The highest possible grade for this datum is acceptable."]
["Answers","Presented in figure V-3: 20 days","average time to emergence ","NOEC not stated, inferred from results write up","","No-toxicant control used - moderately hard laboratory water. ","Not stated.","","Age - 1st instar larvae","Moderately hard laboratory water","Static renewal - water changed every 72 hours.","","","Presented in figure V-3","ANOVA and ANCOVA tests using program R","p=0.05","","","Stated - 25oC",""]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3001-2"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,4,1,0,1,3,61,0.67032967032967028,null,"The highest possible grade for this datum is acceptable."]
["Answers","21 days","Reproduction defined as 'days to first brood'","Biological effect inferred. ","","no-toxicant control ","10 replicates","","Neonates","M4 medium (stated in acute tests but inferred for chronic tests)","static renewal (twice daily)","","","Detailed in Table 1","Student's t-test and analyis of variance (ANOVA) using program SPSS 13.0. ","p<0.01","D. magna was maintained in artificial medium M4 at 20oC with pH 7 in the labortory. ","","D. magna was maintained in artificial medium M4 at 20oC with pH 7 in the labortory. ","The highest possible purity chemicals were used for the experiment: ≥98%"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3001-3"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,4,1,0,1,3,61,0.67032967032967028,null,"The highest possible grade for this datum is acceptable."]
["Answers","21 days","Reproduction defined as 'days to first brood'","Biological effect inferred. ","","no-toxicant control ","10 replicates","","Neonates","M4 medium (stated in acute tests but inferred for chronic tests)","static renewal (twice daily)","","","Detailed in Table 1","Student's t-test and analyis of variance (ANOVA) using program SPSS 13.0. ","p<0.01","D. magna was maintained in artificial medium M4 at 20oC with pH 7 in the labortory. ","","D. magna was maintained in artificial medium M4 at 20oC with pH 7 in the labortory. ","The highest possible purity chemicals were used for the experiment: ≥98%"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3001-4"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,4,1,0,1,3,61,0.67032967032967028,null,"The highest possible grade for this datum is acceptable."]
["Answers","21 days","Reproduction defined as quantity of brood","Biological effect inferred. ","","no-toxicant control ","10 replicates","","Neonates","M4 medium (stated in acute tests but inferred for chronic tests)","static renewal (twice daily)","","","Detailed in Table 1","Student's t-test and analyis of variance (ANOVA) using program SPSS 13.0. ","p<0.01","D. magna was maintained in artificial medium M4 at 20oC with pH 7 in the labortory. ","","D. magna was maintained in artificial medium M4 at 20oC with pH 7 in the labortory. ","The highest possible purity chemicals were used for the experiment: ≥98%"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3001-5"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,4,1,0,1,3,61,0.67032967032967028,null,"The highest possible grade for this datum is acceptable."]
["Answers","21 days","Reproduction defined as quantity of brood","Biological effect inferred. ","","no-toxicant control ","10 replicates","","Neonates","M4 medium (stated in acute tests but inferred for chronic tests)","static renewal (twice daily)","","","Detailed in Table 1","Student's t-test and analyis of variance (ANOVA) using program SPSS 13.0. ","p<0.01","D. magna was maintained in artificial medium M4 at 20oC with pH 7 in the labortory. ","","D. magna was maintained in artificial medium M4 at 20oC with pH 7 in the labortory. ","The highest possible purity chemicals were used for the experiment: ≥98%"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3004-2"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,1,3,60,0.65934065934065933,null,"The highest possible grade for this datum is acceptable."]
["Answers","10 days (Section 2.3)","Reproduction - the regeneration of planarians with a pair of well-formed auricles from a piece of amputated tail fragment. ","LOEC inferred from avaliable data. ","","No-toxicant control ","Three replicates","","10-12 mm at the start of the experiment","Aerated tap water and dimethyl sulfoxide (DMSO)","Static renewal - changed daily. ","","","Figure 2B","One-way ANOVA followed by the Tukey's post-hoc test using SPSS 16.0 software.","p<0.05","","","Planarians were cultivated in tanks with aerated tap water at 20oC (Section 2.1)","Highest possible purity chemical used for the experiment >99% obtained from Sigma-Aldrich (St. Louis, USA). "]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3011-3"]
["Scores",10,5,5,5,5,5,0,5,5,4,4,0,4,4,4,0,0,1,3,69,0.75824175824175821,null,""]
["Answers","21 days","Mortality","NOEC","Mortality data quantified. ","Lab water (aerated synthetic lab water)","Duplicated. ","","Age >12 weeks","Aerated synthetic lab water","Static renewal - water changed every 3.5 days.","Yes - initially and 3, then 7 days into the experiment","","Figure IV-1 ","Kaplan-Meier estimator was used from the \"survival\" libaray avalaible for the program R.","P<0.01","","","Room temp 19-21oC","PFOS concentrations were analysed at the beginning and during the experiment"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3011-4"]
["Scores",10,5,5,5,5,5,0,5,5,4,4,0,4,4,4,0,0,1,3,69,0.75824175824175821,null,""]
["Answers","21 days","Mortality","LOEC (Table IV-1)","Mortality data quantified. ","Lab water (aerated synthetic lab water)","Duplicated. ","","Age >12 weeks","Aerated synthetic lab water","Static renewal - water changed every 3.5 days.","Yes - initially and 3, then 7 days into the experiment","","Figure IV-1 ","Kaplan-Meier estimator was used from the \"survival\" libaray avalaible for the program R.","P<0.01","","","Room temp 19-21oC","PFOS concentrations were analysed at the beginning and during the experiment"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3011-5"]
["Scores",10,5,5,5,5,5,0,5,5,4,4,0,4,4,4,0,0,1,3,69,0.75824175824175821,null,""]
["Answers","21 days","Growth (mass and length)","NOEC (Table IV-1)","Length and mass quantified. ","Lab water (aerated synthetic lab water)","Duplicated. ","","Age 3-6 weeks","Aerated synthetic lab water","Static renewal - water changed every 3.5 days.","Yes - initially and 3, then 7 days into the experiment","","Figure IV-3","One-way ANOVA using the program R.","P<0.006","","","Room temp 19-21oC","PFOS concentrations were analysed at the beginning and during the experiment"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3011-6"]
["Scores",10,5,5,5,5,5,0,5,5,4,4,0,4,4,4,0,0,1,3,69,0.75824175824175821,null,""]
["Answers","21 days","Growth (mass and length)","LOEC (Table IV-1)","Length and mass quantified. ","Lab water (aerated synthetic lab water)","Duplicated. ","","Age 3-6 weeks","Aerated synthetic lab water","Static renewal - water changed every 3.5 days.","Yes - initially and 3, then 7 days into the experiment","","Figure IV-3","One-way ANOVA using the program R.","P<0.006","","","Room temp 19-21oC","PFOS concentrations were analysed at the beginning and during the experiment"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3003-1"]
["Scores",10,10,0,0,5,5,0,5,5,4,4,0,4,4,4,0,0,1,3,64,0.70329670329670335,null,""]
["Answers","40 days","Development measured using the Gosner stages","Endpoint inferred. ","","No-toxicant control","2 replicates","","Gosner stage 26 tadpoles","UV irradiated well water","Static renewal with the water changed every 4 days","A water sample (~ 5 mL) was taken immediately pior to and after each water change to monitor concentrations of test chemicals i.e. every four days over the forty day experiment.","","Figure 3","Repeated measures analysis of variance (rm-ANOVA) was used for changes over monitoring duration, and on-way ANOVAs were used for comparson between groups. ","p < 0.05","","","Animas were maintained at 20 ±2 oC","Highest possible purity chemical (≥98%)"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3003-2"]
["Scores",10,10,0,0,5,5,0,5,5,4,4,0,4,4,4,0,0,1,3,64,0.70329670329670335,null,""]
["Answers","40 days","Development measured using the Gosner stages","Endpoint inferred. ","","No-toxicant control","2 replicates","","Gosner stage 26 tadpoles","UV irradiated well water","Static renewal with the water changed every 4 days","A water sample (~ 5 mL) was taken immediately pior to and after each water change to monitor concentrations of test chemicals i.e. every four days over the forty day experiment.","","Figure 3","Repeated measures analysis of variance (rm-ANOVA) was used for changes over monitoring duration, and on-way ANOVAs were used for comparson between groups. ","p < 0.05","","","Animas were maintained at 20 ±2 oC","Highest possible purity chemical (≥98%)"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3018-10"]
["Scores",10,5,5,5,5,5,0,5,5,4,2,0,0,4,4,3,3,3,3,71,0.78021978021978022,null,""]
["Answers","30 days","Longevity (survival)","EC10","Table 4, 10%","No-toxicant control","Three replicates","","average length of 4.0 ± 0.5 cm and average weight 4.0 ± 0.8 g. ","Activated carbon-dechlorinated tap water","Semi-static with water renewed at 48 hour intervals. ","'Concentrations of PFOS and PFOA were monitored throughout the experiment' however it is unclear how frequently they were monitored. ","","","","p>0.01","Measured once a week for chronic tests - pH 7.0 ± 0.5","Measured once a day for acute tests and once a week for chronic tests - DO 7.0  ± 0.5 mg/L","Measured once a day for acute tests and once a week for chronic tests - 22 ± 2oC","Highest possible purity chemicals - 99% pure Shultz Company (Shanghai, China)"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3018-11"]
["Scores",10,5,5,5,5,5,0,5,5,4,2,0,0,4,4,3,3,3,3,71,0.78021978021978022,null,""]
["Answers","30 days","Longevity (survival)","EC10","Table 4, 10%","No-toxicant control","Three replicates","","Tadpoles with an average weight 0.048± 0.005 g and body length of 1.8 ± 0.2 cm","Activated carbon-dechlorinated tap water","Semi-static with water renewed at 48 hour intervals. ","'Concentrations of PFOS and PFOA were monitored throughout the experiment' however it is unclear how frequently they were monitored. ","","","","p>0.01","Measured once a week for chronic tests - pH 7.0 ± 0.5","Measured once a day for acute tests and once a week for chronic tests - DO 7.0  ± 0.5 mg/L","Measured once a day for acute tests and once a week for chronic tests - 22 ± 2oC","Highest possible purity chemicals - 99% pure Shultz Company (Shanghai, China)"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3018-12"]
["Scores",10,5,5,5,5,5,0,5,5,4,2,0,0,4,4,3,3,3,3,71,0.78021978021978022,null,""]
["Answers","21 days","Longevity (survival)","EC10","Table 4, 10%","No-toxicant control","Three replicates","","Neonates <24 hours old","Activated carbon-dechlorinated tap water","Semi-static with water renewed at 48 hour intervals. ","'Concentrations of PFOS and PFOA were monitored throughout the experiment' however it is unclear how frequently they were monitored. ","","","","p>0.01","Measured once a week for chronic tests - pH 7.0 ± 0.5","Measured once a day for acute tests and once a week for chronic tests - DO 7.0  ± 0.5 mg/L","Measured once a day for acute tests and once a week for chronic tests - 22 ± 2oC","Highest possible purity chemicals - 99% pure Shultz Company (Shanghai, China)"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3018-13"]
["Scores",10,5,5,5,5,5,0,5,5,4,2,0,0,4,4,3,3,3,3,71,0.78021978021978022,null,""]
["Answers","21 days","Reproduction - total number of spawning fish","EC10","Table 4, 10%","No-toxicant control","Three replicates","","Neonates <24 hours old","Activated carbon-dechlorinated tap water","Semi-static with water renewed at 48 hour intervals. ","'Concentrations of PFOS and PFOA were monitored throughout the experiment' however it is unclear how frequently they were monitored. ","","","","p>0.01","Measured once a week for chronic tests - pH 7.0 ± 0.5","Measured once a day for acute tests and once a week for chronic tests - DO 7.0  ± 0.5 mg/L","Measured once a day for acute tests and once a week for chronic tests - 22 ± 2oC","Highest possible purity chemicals - 99% pure Shultz Company (Shanghai, China)"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3006-1"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,0,3,59,0.64835164835164838,null,"The highest possible grade for this datum is acceptable."]
["Answers","25 days","Rate of offspring relative to the control in the F0 generation. ","Inferred from Figure 2","","No-toxicant control","10 replicants","","<24 hour ol neonates","Reconstituted hard water","Static, changed daily","","","Figure 2","One-way ANOVA with Tukey's post-hoc test using SPSS 18.0 ","p < 0.05 ","","","","highest possible purity chemical used for the experiment (99%) "]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3006-2"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,4,0,4,4,0,0,0,3,59,0.64835164835164838,null,"The highest possible grade for this datum is acceptable."]
["Answers","25 days","Rate of offspring relative to the control in the F0 generation. ","Inferred from Figure 2","","No-toxicant control","10 replicants","","<24 hour ol neonates","Reconstituted hard water","Static, changed daily","","","Figure 2","One-way ANOVA with Tukey's post-hoc test using SPSS 18.0 ","p < 0.05 ","","","","highest possible purity chemical used for the experiment (99%) "]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3006-3"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,4,0,4,4,0,0,0,3,59,0.64835164835164838,null,"The highest possible grade for this datum is acceptable."]
["Answers","25 days","Time to first brood for the F0 generation","Inferred from Figure 2","","No-toxicant control","10 replicants","","<24 hour ol neonates","Reconstituted hard water","Static, changed daily","","","Figure 2","One-way ANOVA with Tukey's post-hoc test using SPSS 18.0 ","p < 0.05 ","","","","highest possible purity chemical used for the experiment (99%) "]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3006-4"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,4,0,4,4,0,0,0,3,59,0.64835164835164838,null,"The highest possible grade for this datum is acceptable."]
["Answers","25 days","Time to first brood for the F0 generation","Inferred from Figure 2","","No-toxicant control","10 replicants","","<24 hour ol neonates","Reconstituted hard water","Static, changed daily","","","Figure 2","One-way ANOVA with Tukey's post-hoc test using SPSS 18.0 ","p < 0.05 ","","","","highest possible purity chemical used for the experiment (99%) "]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3020-1"]
["Scores",10,5,0,0,5,5,0,0,5,0,4,0,4,4,4,0,0,1,3,50,0.5494505494505495,null,""]
["Answers","35 days ","Survival / abundance (p<0.05)","Concentration were there was a significant affect was stated (LOEC)","","No-toxicant control","Five replicates for each treatment concentation (1-, 10-, and 30-mg PFOS/L nominal concentrations). ","","","Natural pond water","","Measured 3 times; day 1, day 8 and day 35","","Figure 2","t-test one way analysis of variation (ANOVA) using Excel 2000 and SigmaStat","Three levels of significance were accepted in the paper, p<0.1, p<0.05 and p<0.01. ","","","18oC ","anaytical reagent grade PFOS CAS 2795-39-3 received from the Centre for Toxicology, University of Guelph, ON, Canada (donated by 3M)"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3020-2"]
["Scores",10,5,0,0,5,5,0,0,5,0,4,0,4,4,4,0,0,1,3,50,0.5494505494505495,null,""]
["Answers","35 days ","Survival / abundance (p<0.05)","Concentration were there was a significant affect was stated (LOEC)","","No-toxicant control","Five replicates for each treatment concentation (1-, 10-, and 30-mg PFOS/L nominal concentrations). ","","","Natural pond water","","Measured 3 times; day 1, day 8 and day 35","","Figure 2","t-test one way analysis of variation (ANOVA) using Excel 2000 and SigmaStat","Three levels of significance were accepted in the paper, p<0.1, p<0.05 and p<0.01. ","","","18oC ","anaytical reagent grade PFOS CAS 2795-39-3 received from the Centre for Toxicology, University of Guelph, ON, Canada (donated by 3M)"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3023-1"]
["Scores",10,10,0,0,5,5,0,5,0,4,0,0,4,4,4,0,0,0,3,54,0.59340659340659341,null,"The highest possible grade for this datum is acceptable."]
["Answers","15 days post-fertilization (dpf)","Body weight and length of each fry along the body axis from the anterior-most part of the head to the tp of the tail was measured form these digital images using Imge Pro Plus Software (Media Cybernetics, Bethesda, MS, USA). ","Inferred from Section 3.1","","no-toxicant and solvent (DSMO) control used","Three replicates","","Embryos at the blastula stage","","Static with 50% of the exposure solution renewed daily","","","Figure 1c","One-way anlaysis of ariance (ANOVA) followed by Tukey's test using SPSS 13.0","P<0.05","","","","Highest possible purity chemicals used for the experiment (>99%) "]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3023-2"]
["Scores",10,10,0,0,5,5,0,5,0,4,0,0,4,4,4,0,0,0,3,54,0.59340659340659341,null,"The highest possible grade for this datum is acceptable."]
["Answers","15 days post-fertilization (dpf)","Body weight and length of each fry along the body axis from the anterior-most part of the head to the tp of the tail was measured form these digital images using Imge Pro Plus Software (Media Cybernetics, Bethesda, MS, USA). ","Inferred from Section 3.1","","no-toxicant and solvent (DSMO) control used","Three replicates","","Embryos at the blastula stage","","Static with 50% of the exposure solution renewed daily","","","Figure 1c","One-way anlaysis of ariance (ANOVA) followed by Tukey's test using SPSS 13.0","P<0.05","","","","Highest possible purity chemicals used for the experiment (>99%) "]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","404-18"]
["Scores",10,5,5,5,5,5,2,5,5,4,0,4,4,4,4,1,0,3,0,71,0.78021978021978022,null,"The highest possible grade for this datum is acceptable."]
["Answers","7 days ","Reproduction ","NOEC","NOEC","","","Based on USEPA Guidelines","neonates < 24h old","Moderately hard reconstituted water","Static","","NaCl - monthly acute tests","Table 3","","","Stated that it was measured, no result presented. ","","25±1oC",""]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","404-11"]
["Scores",10,5,5,5,5,5,2,5,5,4,0,4,4,4,4,1,0,3,0,71,0.78021978021978022,null,"The highest possible grade for this datum is acceptable."]
["Answers","21 days","Reproduction ","NOEC","NOEC","","","Based on USEPA Guidelines","neonates < 24h old","Moderately hard reconstituted water","Static","","NaCl - monthly acute tests","Table 2","","","Stated that it was measured, no result presented. ","","25±1oC",""]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","404-19"]
["Scores",10,5,5,5,5,5,0,5,5,4,0,4,4,4,4,0,0,1,0,66,0.72527472527472525,null,"The highest possible grade for this datum is acceptable."]
["Answers","8 days","Reproduction - hatchability defined as disruption of the chorion","LOEC","Displayed graphically (Figure 2)","","","","embroys < 12 hours post fertilization","Dechlorinated tap water","Static","","NaCl - monthly acute tests","Table 2","Probit analyses with ToxStat","","","","25oC",""]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","409-1"]
["Scores",10,10,5,5,5,5,0,5,5,4,0,0,0,4,4,0,1,0,0,63,0.69230769230769229,null,"The highest possible grade for this datum is acceptable."]
["Answers","21 day","Survival ","NOEC","","","","","neonates < 24h old","mod-hard clean well water","static - weekly water change","","","","","","","","",""]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","409-2"]
["Scores",10,10,5,5,5,5,0,5,5,4,0,0,0,4,4,0,1,0,0,63,0.69230769230769229,null,"The highest possible grade for this datum is acceptable."]
["Answers","21 day","Survival ","LOEC","LOEC","","","","neonates < 24h old","mod-hard clean well water","static - weekly water change","","","","","","","","",""]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","409-3"]
["Scores",10,10,5,5,5,5,0,5,5,4,0,0,0,4,4,0,1,0,0,63,0.69230769230769229,null,"The highest possible grade for this datum is acceptable."]
["Answers","21 day","Survival ","NOEC","NOEC","","","","neonates < 24h old","mod-hard clean well water","static - weekly water change","","","","","","","","",""]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","409-4"]
["Scores",10,10,5,5,5,5,0,5,5,4,0,0,0,4,4,0,1,0,0,63,0.69230769230769229,null,"The highest possible grade for this datum is acceptable."]
["Answers","21 day","Survival ","LOEC","LOEC","","","","neonates < 24h old","mod-hard clean well water","static - weekly water change","","","","","","","","",""]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","412-1"]
["Scores",10,5,5,5,5,5,2,5,5,4,0,0,0,4,4,0,0,0,3,62,0.68131868131868134,null,"The highest possible grade for this datum is acceptable."]
["Answers","21 days","Survival ","LC50","LC50","","","Based on OECD guidelines","neonates < 24h old","ASTM test medium","Static - 3 renewals a week","","","","","","","","",""]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","412-2"]
["Scores",10,5,5,5,5,5,2,5,5,4,0,0,0,4,4,0,0,0,3,62,0.68131868131868134,null,"The highest possible grade for this datum is acceptable."]
["Answers","21 days","Survival ","NOEC","NOEC","","","Based on OECD guidelines","neonates < 24h old","ASTM test medium","Static - 3 renewals a week","","","","","","","","",""]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","412-3"]
["Scores",10,5,5,5,5,5,2,5,5,4,0,0,0,4,4,0,0,0,3,62,0.68131868131868134,null,"The highest possible grade for this datum is acceptable."]
["Answers","21 days","Reproduction","NOEC","NOEC","","","Based on OECD guidelines","neonates < 24h old","ASTM test medium","Static - 3 renewals a week","","","","","","","","",""]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","431-10"]
["Scores",10,5,5,5,5,5,2,5,5,4,0,0,0,4,4,1,0,3,3,66,0.72527472527472525,null,"The highest possible grade for this datum is acceptable."]
["Answers","21 days","Survival ","NOEC","NOEC","","","Based on methodology","<24 hours old neonates","Clean well water","Static - based on methodology","","","","","","","","21oC","highest possible purity chemicals (95%)"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","431-9"]
["Scores",10,5,5,5,5,5,2,5,5,4,0,0,0,4,4,1,0,3,3,66,0.72527472527472525,null,"The highest possible grade for this datum is acceptable."]
["Answers","21 days","Survival ","LC50","LC50","","","Based on methodology","<24 hours old neonates","Clean well water","Static - based on methodology","","","","","","","","21oC","highest possible purity chemicals (95%)"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","434-1"]
["Scores",10,5,5,5,5,5,0,5,5,0,0,0,0,4,4,0,0,1,3,57,0.62637362637362637,null,"The highest possible grade for this datum is acceptable."]
["Answers","14 days","Egg hatching success","NOEC","NOEC  - egg hatching success (proportion of eggs that hatched)","Yes - 5 duplicate test chambers (petri dishes) per concentration","","","2 day old eggs","Dechlorinated tap water","Static - petri dishes","","","","","For each endpoint in the results section","","","21oC","Highest possible purity chemicals (98%) perfluoro-1-octanesulfonic acid tetraethyl ammonium salt"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","434-2"]
["Scores",10,5,5,5,5,5,0,5,5,0,0,0,0,4,4,0,0,1,3,57,0.62637362637362637,null,"The highest possible grade for this datum is acceptable."]
["Answers","14 days","Egg hatching time","NOEC","NOEC  - egg hatching time (egg development time)","Yes - 5 duplicate test chambers (petri dishes) per concentration","","","2 day old eggs","Dechlorinated tap water","Static - petri dishes","","","","","For each endpoint in the results section","","","21oC","Highest possible purity perfluoro-1-octanesulfonic acid tetraethyl ammonium salt (98%) Tox enpoint converted to anion"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","434-3"]
["Scores",10,5,5,5,5,5,0,5,5,0,0,0,4,4,4,1,1,1,3,63,0.69230769230769229,null,"The highest possible grade for this datum is acceptable."]
["Answers","120 days","Larval Survival","NOEC","NOEC - larval survival","Yes - 5 duplicate test chambers (petri dishes) per concentration","","","Larvae from the egg hatching test","Dechlorinated tap water","Static - cups","","","Figure 2. ","","For each endpoint in the results section","","","21oC","Highest possible purity perfluoro-1-octanesulfonic acid tetraethyl ammonium salt (98%) Tox enpoint converted to anion"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","434-4"]
["Scores",10,10,5,5,5,5,0,5,5,0,0,0,4,4,4,1,1,1,3,68,0.74725274725274726,null,"The highest possible grade for this datum is acceptable."]
["Answers","120 days","Larval development time - calculated as the number of days between egg hatching and metamorphosis","NOEC","NOEC - larval development time","","","","Larvae from the egg hatching test","Dechlorinated tap water","Static - cups","","","","","For each endpoint in the results section","","","21oC","Highest possible purity perfluoro-1-octanesulfonic acid tetraethyl ammonium salt (98%) Tox enpoint converted to anion"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","434-5"]
["Scores",10,10,5,5,5,5,0,5,5,0,0,0,4,4,4,1,1,1,3,68,0.74725274725274726,null,"The highest possible grade for this datum is acceptable."]
["Answers","120 days","Metamorphosis success - complete emergence","NOEC","Metamorphosis success - complete emergence","","","","Larvae from the egg hatching test","Dechlorinated tap water","Static - cups","","","","","For each endpoint in the results section","","","21oC","Highest possible purity perfluoro-1-octanesulfonic acid tetraethyl ammonium salt (98%) Tox enpoint converted to anion"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","599-1"]
["Scores",10,5,5,5,5,5,2,5,5,4,2,0,4,4,4,0,0,3,3,71,0.78021978021978022,null,""]
["Answers","5 weeks - mortality was measured every week for 5 weeks. At 6 weeks there was unexplained mortality in all treatments so couldn’t continue. ","Survival ","LC50","LC50","","Duplicate tanks for each PFOS concentration and four replicate control tanks.","Control survival was greater than 90% but no recommended % provided so inferred. ","Stage 8/9 embryos used to initiate the tests.","Lake Superior Water","Flow rate discussed. ","Yes - LC/EC/MS","","Figure 1. ","","Yes p </= 0.05","","","20oC","Yes - 98%."]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","701-1"]
["Scores",10,5,5,5,5,5,0,5,5,4,2,0,4,4,4,1,1,0,3,68,0.74725274725274726,null,""]
["Answers","21 days","Fecundity ","EC50","EC50","","","","Age","Control water - water chem provided","Flow through","LC/EC/MS","","Figure 1. ","","Yes p </= 0.05","Only measured in the control water","Only measured in the control water","","Yes - 98%."]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","701-2"]
["Scores",10,5,5,5,5,5,0,5,5,4,2,0,4,4,4,1,1,0,3,68,0.74725274725274726,null,""]
["Answers","24 days","Survival","NOEC","NOEC","","","","Age","Control water - water chem provided","Flow through","LC/EC/MS","","Figure 1. ","","Yes p </= 0.05","Only measured in the control water","Only measured in the control water","","Yes - 98%."]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","701-3"]
["Scores",10,5,5,5,5,5,0,5,5,4,2,0,4,4,4,1,1,0,3,68,0.74725274725274726,null,""]
["Answers","24 days","Growth","NOEC","NOEC","","","","Age","Control water - water chem provided","Flow through","LC/EC/MS","","Figure 1. ","","Yes p </= 0.05","Only measured in the control water","Only measured in the control water","","Yes - 98%."]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","702-10"]
["Scores",10,5,5,5,5,5,2,5,5,4,2,0,0,4,0,0,1,1,3,62,0.68131868131868134,null,""]
["Answers","20 days","Emergence","EC50","EC50","","","","Age","ASTM Hard Water","Static-renewal","In some samples","","","","","","\"DO concentrations remained consistently greater than 5 mg/L\"","23oC",""]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","702-11"]
["Scores",10,5,5,5,5,5,2,5,5,4,2,0,0,4,0,0,1,1,3,62,0.68131868131868134,null,""]
["Answers","20 days","Emergence","EC10","EC10","","","","Age","ASTM Hard Water","Static-renewal","In some samples","","","","","","\"DO concentrations remained consistently greater than 5 mg/L\"","23oC",""]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","702-12"]
["Scores",10,5,5,5,5,5,2,5,5,4,2,0,0,4,0,0,1,1,3,62,0.68131868131868134,null,""]
["Answers","20 days","Emergence","NOEC","NOEC","","","","Age","ASTM Hard Water","Static-renewal","In some samples","","","","","","\"DO concentrations remained consistently greater than 5 mg/L\"","23oC",""]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","702-4"]
["Scores",10,5,5,5,5,5,2,5,5,4,2,0,0,4,0,0,1,1,3,62,0.68131868131868134,null,""]
["Answers","20 days","Survival","EC50","EC50","","","","Age","ASTM Hard Water","Static-renewal","In some samples","","","","","","\"DO concentrations remained consistently greater than 5 mg/L\"","23oC",""]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","702-5"]
["Scores",10,5,5,5,5,5,2,5,5,4,2,0,0,4,0,0,1,1,3,62,0.68131868131868134,null,""]
["Answers","20 days","Survival","EC10","EC10","","","","Age","ASTM Hard Water","Static-renewal","In some samples","","","","","","\"DO concentrations remained consistently greater than 5 mg/L\"","23oC",""]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","702-6"]
["Scores",10,5,5,5,5,5,2,5,5,4,2,0,0,4,0,0,1,1,3,62,0.68131868131868134,null,""]
["Answers","20 days","Survival","NOEC","NOEC","","","","Age","ASTM Hard Water","Static-renewal","In some samples","","","","","","\"DO concentrations remained consistently greater than 5 mg/L\"","23oC",""]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","702-7"]
["Scores",10,5,5,5,5,5,2,5,5,4,2,0,0,4,0,0,1,1,3,62,0.68131868131868134,null,""]
["Answers","20 days","Growth","EC50","EC50","","","","Age","ASTM Hard Water","Static-renewal","In some samples","","","","","","\"DO concentrations remained consistently greater than 5 mg/L\"","23oC",""]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","702-8"]
["Scores",10,5,5,5,5,5,2,5,5,4,2,0,0,4,0,0,1,1,3,62,0.68131868131868134,null,""]
["Answers","20 days","Growth","EC10","EC10","","","","Age","ASTM Hard Water","Static-renewal","In some samples","","","","","","\"DO concentrations remained consistently greater than 5 mg/L\"","23oC",""]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","702-9"]
["Scores",10,5,5,5,5,5,2,5,5,4,2,0,0,4,0,0,1,1,3,62,0.68131868131868134,null,""]
["Answers","20 days","Growth","NOEC","NOEC","","","","Age","ASTM Hard Water","Static-renewal","In some samples","","","","","","\"DO concentrations remained consistently greater than 5 mg/L\"","23oC",""]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","704-1"]
["Scores",10,5,5,5,5,5,0,5,5,4,2,0,0,4,4,3,3,3,3,71,0.78021978021978022,null,""]
["Answers","28 days","Survival","LC50","LC50","","","","Length ","Pond water","","","","","","","9.2±0.05","8.7 ± 0.3 mg/L","22.7 ±0.3oC",""]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","704-2"]
["Scores",10,5,5,5,5,5,0,5,5,4,2,0,0,4,4,3,3,3,3,71,0.78021978021978022,null,""]
["Answers","28 days","Survival","LC10","LC10","","","","Length ","Pond water","","","","","","","9.2±0.05","8.7 ± 0.3 mg/L","22.7 ±0.3oC",""]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","706-1"]
["Scores",10,5,5,5,5,5,2,5,5,4,0,0,4,4,4,3,3,3,3,75,0.82417582417582413,null,"The highest possible grade for this datum is acceptable."]
["Answers","21 days","Body length - growth","LOEC","LOEC","","","OECD guidelines","Age","Daphnia culture medium","Static renewal","","","Table 1 - results","","","7.2 ± 0.3","6.5 ± 0.5 mg/L","20 ± 1 oC",""]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","706-2"]
["Scores",10,5,5,5,5,5,2,5,5,4,0,0,4,4,4,3,3,3,3,75,0.82417582417582413,null,"The highest possible grade for this datum is acceptable."]
["Answers","21 days","Reproduction ","NOEC","NOEC","","","OECD guidelines","Age","Daphnia culture medium","Static renewal","","","Table 1 - results","","","7.2 ± 0.3","6.5 ± 0.5 mg/L","20 ± 1 oC",""]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","707-1"]
["Scores",10,5,5,5,5,5,0,5,5,4,2,0,4,4,4,3,3,3,3,75,0.82417582417582413,null,""]
["Answers","90 days","Body length and weight - male fish","LOEC","LOEC","","","","Age","Tap water and deionized water","Static to begin and then flow-through","","","Graph of results presented","","","8.0-8.2","6.45-10.97 mg/L","26±1oC",""]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","707-2"]
["Scores",10,5,5,5,5,5,0,5,5,4,2,0,4,4,4,3,3,3,3,75,0.82417582417582413,null,""]
["Answers","180 days","Body length and weight - female fish","LOEC","LOEC","","","","Age","Tap water and deionized water","Static to begin and then flow-through","","","Graph of results presented","","","8.0-8.2","6.45-10.97 mg/L","26±1oC",""]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","708-1"]
["Scores",10,5,5,5,5,5,0,5,5,4,0,0,0,4,4,0,0,3,3,63,0.69230769230769229,null,"The highest possible grade for this datum is acceptable."]
["Answers","90 days","Body length and weight ","LOEC","LOEC","","","","Age","Dechlorinated tap water","Static renewal","","","Table of results presented","","","","","27±1 ◦C",""]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","717-1"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,3,3,62,0.68131868131868134,null,"The highest possible grade for this datum is acceptable."]
["Answers","Female D. rerio were exposed for 70 days, removed to clean water for 30 days and paired with unexposed male zebrafish. ","Endpoint was malformation of the F1 generation. In particualr skeletal deformities with cirved spines. ","Inferred.","Inferred. ","Non-toxicant control used","Three replicates per treatment ","","Fry from 14 days post-fertilisation were subject to treatment. ","\"charcoal-filtered, recalclating, aerated tap water\"","Semi-static system and the water was half-renewed every other day. ","Nominal concentrations used. ","","stated in-text","chi squared test","p<0.05","","","27±0.5oC","Reagent grade chemical used: heptadecafluorooctanesulfonic acid potassium salt (PFOS >99%)"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","717-2"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,3,3,62,0.68131868131868134,null,"The highest possible grade for this datum is acceptable."]
["Answers","14 day post fertilisation D. rerio were subject to treatment for 70 days with 30 days recovery. Sampling occurred at 40 days, and 70 days and 100 days. ","Endpoint was the weight of fish after 100 days of exposure","Inferred.","Inferred. ","Non-toxicant control used","Three replicates per treatment ","","Fry from 14 days post-fertilisation were subject to treatment. ","\"charcoal-filtered, recalclating, aerated tap water\"","Semi-static system and the water was half-renewed every other day. ","Nominal concentrations used. ","","stated in-text","chi squared test","p<0.05","","","27±0.5oC","Reagent grade chemical used: heptadecafluorooctanesulfonic acid potassium salt (PFOS >99%)"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","718-1"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,0,1,0,1,3,57,0.62637362637362637,null,"The highest possible grade for this datum is acceptable."]
["Answers","F0 were exposed for 150 days post fertilisation. F1 were not exposed to PFOS. ","Mortality of F0 offspring (F1) at 7 days post fertilisation ","Inferred","Figure 3","No-toxicant controls used","Three replicates","","Embroys ","Water supplied to the system was filtered by reverse osmosis and Instant Ocean sat was added. ","Fish were kept in a static system with 50% of the water renewed with freshly prepared soutions even 5 days. ","","","Figure 3","one-way analysis of variance and Tukey's multiple range tests ","Significance level not stated. May be inferred from confidence intervals in Figure 3. ","7.0-7.5","","28oC","analytical reagent grade chemical used: Perfluorooctanesulphonic acid purity >96%)"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","718-2"]
["Scores",10,5,0,5,5,5,0,5,5,4,0,0,4,4,0,1,0,1,3,57,0.62637362637362637,null,"The highest possible grade for this datum is acceptable."]
["Answers","F0 were exposed for 150 days post fertilisation.","Length of males in the F0 generation","Inferred","Table 1","Non-toxicant controls used. ","Three replicates","","Embroys ","Water supplied to the system was filtered by reverse osmosis and Instant Ocean sat was added. ","Fish were kept in a static system with 50% of the water renewed with freshly prepared soutions even 5 days. ","","","Figure 3","one-way analysis of variance and Tukey's multiple range tests ","Significance level not stated. May be inferred from confidence intervals in Figure 3. ","7.0-7.5","","28oC","analytical reagent grade chemical used: Perfluorooctanesulphonic acid purity >96%)"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","705-12"]
["Scores",10,5,5,0,5,5,2,5,5,4,4,0,4,4,0,3,3,3,3,70,0.76923076923076927,null,""]
["Answers","42d NOEC","Percent survival. All fish surviving to test termination appeared normal with no overt signs of sublethal toxicity. Fish which did not survive generally appeared to be swimming erratically prior to death.","NOEC","","Negative control","Four replicates","Method:  OECD 210, OPPTS 850.1400","Test fish age: eggs < 24-hours old at test initiation. Growth, survival and hatchability measures were reported","Test Conditions\nDilution water: 0.45  µ m filtered well water\nDilution water chemistry (during the 4-week period immediately preceding the test):\nHardness: 126 (124-128) mg/L as CaCO 3\nAlkalinity:  172 (170-172) mg/L as CaCO 3\npH: 8.2   (8.2-8.3)\nTOC: < 1.0 mg/L\nConductivity: 321 (315-330)  µ mhos/cm","Flow-through chronic. Flow through rate: Approximately six volume additions of test water every 24-hours"," PFOS measured on days 0, 4, 7, 14, 21, 28, 35, 42, and 47","","Observed from tabulated data","Discrete-variable  data  were  analyzed  using  2  x  2  contingency  tables  to  identify treatment groups that showed a statistically significant difference (p<0.05) from the negative control group. All continuous-variable data were evaluated for normality using Shapiro-Wilk’s test and for homogeneity of variance using Bartlett’s test.  Analysis of variance and Dunnett’s test were used to evaluate differences between treatment and control means.","","pH range (0 – 47 days):\n8.0 – 8.4  (control exposure)\n8.0 – 8.4  (1.2 mg/L exposure)","Dissolved oxygen range (0 – 47 days):\n7.6 – 8.2 mg/L (control exposure)\n7.6 – 8.2 mg/L  (1.2 mg/L exposure)","Test temperature range (0 – 47 days):\n24.4 – 24.7oC  (control exposure)\n24.3 – 24.7oC (1.2 mg/L exposure)","Potassium  perfluorooctanesulfonate;  may  also  be  referred  to  as  PFOS  or  FC-95.    (1-Octanesulfonic acid, 1,1,2,2,3,3,4,4,5,5,6,6,7,7,8,8,8-heptadecafluoro-, potassium salt, CAS # 2795-39-3). Purity determined to be 90.49% by LC/MS, 1H-HMR, 19F-NMR and elemental analyses techniques"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3026-1"]
["Scores",10,5,5,5,0,0,0,5,5,0,0,0,4,4,4,0,0,1,3,51,0.56000000000000005,null,"The highest possible grade for this datum is acceptable."]
["Answers","24 hours","Lethality","LC50","LC50","Not stated","Not stated","Not stated","Stage L4","Nematode Growth Media","Not stated","Not stated","Not stated","Figure 1","Yes","p = .05","Not stated","Not stated","20oC","From Sigma Aldrich "]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3026-2"]
["Scores",10,10,0,0,5,5,0,5,5,0,0,0,0,4,4,0,0,1,3,52,0.5714285714285714,null,"The highest possible grade for this datum is acceptable."]
["Answers","5 days","Reproduction - # of eggs","LOEC","LOEC","Figure 1d","At least 30 worms were applied to each group","Not stated","Stage L4","Nematode Growth Media","Not stated","Not stated","Not stated","Not stated - only one exposure concentration","Yes","p = .05","Not stated","Not stated","20oC","From Sigma Aldrich "]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3027-1"]
["Scores",10,5,5,5,0,5,2,5,0,4,0,0,0,4,4,0,0,1,3,53,0.58241758241758246,null,"The highest possible grade for this datum is acceptable."]
["Answers","96 hour","Lethality","LC50","LC50","Not stated","10 embryos per concentration ","OECD guideline","Embryos","Not stated","Semi-static","Not stated","Not stated","Not stated","Yes","p < 0.05","Not stated","Not stated","Not stated",">98% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3028-1"]
["Scores",10,5,5,5,5,5,0,5,0,0,0,0,4,4,4,0,0,1,3,56,0.61538461538461542,null,"The highest possible grade for this datum is acceptable."]
["Answers","96 hour","Lethality","LC50","LC50","Yes, control and 8 concentrations","10 replicates","Not stated","Tadpoles - Gosner stage 25","Not stated","Not stated","Not stated","Not stated","Figure 1","Yes","p = 0.05","Not stated","Not stated","21oC","PFOS from Sigma Aldrich (#77282-10G)"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3028-2"]
["Scores",10,5,5,5,5,5,0,5,0,0,0,0,4,4,4,0,0,1,3,56,0.61538461538461542,null,"The highest possible grade for this datum is acceptable."]
["Answers","72 days","Growth (mass)","LOEC","LOEC","Yes","4 replicates","Not stated","Tadpoles - Gosner stage 25","Filtered well water","Static renewal - water changed every 3-4 days","Not stated","Not stated","Not stated - 1 exposure concentration","Yes","p = 0.05","Not stated","Not stated","21oC","PFOS from Sigma Aldrich (#77282-10G)"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3029-1"]
["Scores",10,5,0,0,5,5,0,5,5,4,4,0,4,4,4,0,0,1,3,59,0.64835164835164838,null,""]
["Answers","72 days","Growth (mass and snout vent length)","NOEC","NOEC","Yes","4 replicates","Not stated","Tadpoles - Nieuwkpp and Faber (NF) Stage 10","Dechlorinated tap water","Flow through ","At initiation and completion ","Not stated","Table 1","Yes","alpha = 0.05","Not stated","Not stated","25.5-26.5oC","PFOS >/= 98% pure from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3029-2"]
["Scores",10,5,0,0,5,5,0,5,5,4,4,0,4,4,4,0,0,1,3,59,0.64835164835164838,null,""]
["Answers","72 days","Growth (mass and snout vent length)","LOEC","LOEC","Yes","4 replicates","Not stated","Tadpoles - Nieuwkpp and Faber (NF) Stage 10","Dechlorinated tap water","Flow through ","At initiation and completion ","Not stated","Table 1","Yes","alpha = 0.05","Not stated","Not stated","25.5-26.5oC","PFOS >/= 98% pure from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3029-3"]
["Scores",10,5,0,0,5,5,0,5,5,4,4,0,4,4,4,0,0,1,3,59,0.64835164835164838,null,""]
["Answers","72 days","Survival ","NOEC","NOEC","Yes","4 replicates","Not stated","Tadpoles - Nieuwkpp and Faber (NF) Stage 10","Dechlorinated tap water","Flow through ","At initiation and completion ","Not stated","Table 1","Yes","alpha = 0.05","Not stated","Not stated","25.5-26.5oC","PFOS >/= 98% pure from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3029-4"]
["Scores",10,5,0,0,5,5,0,5,5,4,4,0,4,4,4,0,0,1,3,59,0.64835164835164838,null,""]
["Answers","150 days post metamorphosis","Survival ","NOEC","NOEC","Yes","4 replicates","Not stated","Tadpoles - Nieuwkpp and Faber (NF) Stage 10","Dechlorinated tap water","Flow through ","At initiation and completion ","Not stated","Table 2","Yes","alpha = 0.05","Not stated","Not stated","25.5-26.5oC","PFOS >/= 98% pure from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3029-5"]
["Scores",10,5,0,0,5,5,0,5,5,4,4,0,4,4,4,0,0,1,3,59,0.64835164835164838,null,""]
["Answers","150 days post metamorphosis","Growth (mean weight in males and females)","NOEC","NOEC","Yes","4 replicates","Not stated","Tadpoles - Nieuwkpp and Faber (NF) Stage 10","Dechlorinated tap water","Flow through ","At initiation and completion ","Not stated","Table 2","Yes","alpha = 0.05","Not stated","Not stated","25.5-26.5oC","PFOS >/= 98% pure from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3029-6"]
["Scores",10,5,0,0,5,5,0,5,5,4,4,0,4,4,4,0,0,1,3,59,0.64835164835164838,null,""]
["Answers","150 days post metamorphosis","Reproduction (mean oocyte count)","NOEC","NOEC","Yes","4 replicates","Not stated","Tadpoles - Nieuwkpp and Faber (NF) Stage 10","Dechlorinated tap water","Flow through ","At initiation and completion ","Not stated","Table 2","Yes","alpha = 0.05","Not stated","Not stated","25.5-26.5oC","PFOS >/= 98% pure from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3029-7"]
["Scores",10,5,0,0,5,5,0,5,5,4,4,0,4,4,4,0,0,1,3,59,0.64835164835164838,null,""]
["Answers","150 days post metamorphosis","Reproduction (mean oocyte count)","LOEC","LOEC","Yes","4 replicates","Not stated","Tadpoles - Nieuwkpp and Faber (NF) Stage 10","Dechlorinated tap water","Flow through ","At initiation and completion ","Not stated","Table 2","Yes","alpha = 0.05","Not stated","Not stated","25.5-26.5oC","PFOS >/= 98% pure from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3030-1"]
["Scores",10,5,0,0,5,5,2,5,5,4,0,0,0,4,4,0,0,1,3,53,0.58241758241758246,null,"The highest possible grade for this datum is acceptable."]
["Answers","21 days","Reproduction (# eggs)","LOEC","LOEC","Yes","Eggs from 8 females ","Modified OECD test methodology","Adults 14-18 weeks old, 0.32-0.44 g weight","Fish culture water","Static renewal - replaced twice a week","Not stated","Not stated","Only one exposure concentration ","Yes","p < 0.05","Not stated","Not stated","25oC","PFOS >/= 98% pure from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3030-2"]
["Scores",10,5,0,0,5,5,2,5,5,4,0,0,0,4,4,0,0,1,3,53,0.58241758241758246,null,"The highest possible grade for this datum is acceptable."]
["Answers","21 days","Reproduction (# eggs)","LOEC","LOEC","Yes","Eggs from 8 females ","Modified OECD test methodology","Adults 14-18 weeks old, 0.32-0.44 g weight","Fish culture water","Static renewal - replaced twice a week","Not stated","Not stated","Only one exposure concentration ","Yes","p < 0.05","Not stated","Not stated","25oC","PFOS >/= 98% pure from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3030-3"]
["Scores",10,5,0,0,5,5,2,5,5,4,0,0,0,4,4,0,0,1,3,53,0.58241758241758246,null,"The highest possible grade for this datum is acceptable."]
["Answers","21 days","Reproduction (# eggs)","LOEC","LOEC","Yes","Eggs from 8 females ","Modified OECD test methodology","Adults 14-18 weeks old, 0.32-0.44 g weight","Fish culture water","Static renewal - replaced twice a week","Not stated","Not stated","Only one exposure concentration ","Yes","p < 0.05","Not stated","Not stated","25oC","PFOS >/= 98% pure from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3031-1"]
["Scores",10,5,0,0,5,5,5,5,5,4,4,0,0,4,4,3,3,3,3,68,0.74725274725274726,null,""]
["Answers","150 days","Development time","LOEC","LOEC","Yes","Ten replicates","OECD test guideine 218 and 233 with slight variations. Each generational test was considered valid if emergence in the control was >/= 70% in at least 6/10 replicates","1st instar larvae","Reconstituted water","Static renewal - replaced twice a week","Measured during the test","Not stated","Only one exposure concentration ","Yes","p < 0.05","Measured during the test. Between 7.9 and 8.2","Measured during the test > 55%","Measured during the test. Between 18.7 and 21.2 oC","Pure compounds"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3031-2"]
["Scores",10,5,0,0,5,5,5,5,5,4,4,0,0,4,4,3,3,3,3,68,0.74725274725274726,null,""]
["Answers","25 days","Weight and length","LOEC","LOEC","Yes","Ten replicates","OECD test guideine 218 and 233 with slight variations. Each generational test was considered valid if emergence in the control was >/= 70% in at least 6/10 replicates","1st instar larvae","Reconstituted water","Static renewal - replaced twice a week","Measured during the test","Not stated","Only one exposure concentration ","Yes","p < 0.05","Measured during the test. Between 7.9 and 8.2","Measured during the test > 55%","Measured during the test. Between 18.7 and 21.2 oC","Pure compounds"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3031-3"]
["Scores",10,5,0,0,5,5,5,5,5,4,4,0,0,4,4,3,3,3,3,68,0.74725274725274726,null,""]
["Answers","50 days","Reproduction - # eggs per rope","LOEC","LOEC","Yes","Ten replicates","OECD test guideine 218 and 233 with slight variations. Each generational test was considered valid if emergence in the control was >/= 70% in at least 6/10 replicates","1st instar larvae","Re","Static renewal - replaced twice a week","Measured during the test","Not stated","Only one exposure concentration ","Yes","p < 0.05","Measured during the test. Between 7.9 and 8.2","Measured during the test > 55%","Measured during the test. Between 18.7 and 21.2 oC","Pure compounds"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3032-1"]
["Scores",10,5,0,0,5,5,5,5,5,4,0,4,4,4,4,1,1,3,3,68,0.74725274725274726,null,"The highest possible grade for this datum is acceptable."]
["Answers","21 days","Reproduction - # offspring","LOEC","LOEC","Yes","Ten replicates","OECD test guideline 211, no morality in the control","Neonates","Daphnia culture water","Static renewal - renewed every 72 hours","Not stated","For acute tests with potassium dichromate","Figure 3","Yes","p < 0.05","Measured during the test","Measured during the test","Measured during the test 19-21oC","98% pure from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3032-2"]
["Scores",10,5,0,0,5,5,5,5,5,4,0,4,4,4,4,1,1,3,3,68,0.74725274725274726,null,"The highest possible grade for this datum is acceptable."]
["Answers","21 days","Growth - body length","NOEC","NOEC","Yes","Ten replicates","OECD test guideline 211, no morality in the control","Neonates","Daphnia culture water","Static renewal - renewed every 72 hours","Not stated","For acute tests with potassium dichromate","Figure 3","Yes","p < 0.05","Measured during the test","Measured during the test","Measured during the test 19-21oC","98% pure from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3032-3"]
["Scores",10,5,0,0,5,5,5,5,5,4,0,4,4,4,4,1,1,3,3,68,0.74725274725274726,null,"The highest possible grade for this datum is acceptable."]
["Answers","21 days","Growth - body length","LOEC","LOEC","Yes","Ten replicates","OECD test guideline 211, no morality in the control","Neonates","Daphnia culture water","Static renewal - renewed every 72 hours","Not stated","For acute tests with potassium dichromate","Figure 3","Yes","p < 0.05","Measured during the test","Measured during the test","Measured during the test 19-21oC","98% pure from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3033-1"]
["Scores",10,5,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,1,3,55,0.60439560439560436,null,"The highest possible grade for this datum is acceptable."]
["Answers","120 days","Reproduction - number of embryos each day per fish","NOEC","NOEC","Yes, normal control and solvent control","Three replicates","Not stated","Embryos","Culture medium","Static renewal - daily","Not stated","Not stated","Figure 3","Yes","p < 0.05","Not stated","Not stated","28oC","98% pure from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3033-2"]
["Scores",10,5,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,1,3,55,0.60439560439560436,null,"The highest possible grade for this datum is acceptable."]
["Answers","120 days","Reproduction - number of embryos each day per fish","LOEC","LOEC","Yes, normal control and solvent control","Three replicates","Not stated","Embryos","Culture medium","Static renewal - daily","Not stated","Not stated","Figure 3","Yes","p < 0.05","Not stated","Not stated","28oC","98% pure from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3033-3"]
["Scores",10,5,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,1,3,55,0.60439560439560436,null,"The highest possible grade for this datum is acceptable."]
["Answers","120 days","Survival","NOEC","NOEC","Yes, normal control and solvent control","Three replicates","Not stated","Embryos","Culture medium","Static renewal - daily","Not stated","Not stated","Figure 2","Yes","p < 0.05","Not stated","Not stated","28oC","98% pure from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3033-4"]
["Scores",10,5,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,1,3,55,0.60439560439560436,null,"The highest possible grade for this datum is acceptable."]
["Answers","120 days","Survival","LOEC","LOEC","Yes, normal control and solvent control","Three replicates","Not stated","Embryos","Culture medium","Static renewal - daily","Not stated","Not stated","Figure 2","Yes","p < 0.05","Not stated","Not stated","28oC","98% pure from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3033-5"]
["Scores",10,5,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,1,3,55,0.60439560439560436,null,"The highest possible grade for this datum is acceptable."]
["Answers","120 days","Growth - body weight","NOEC","NOEC","Yes, normal control and solvent control","Three replicates","Not stated","Embryos","Culture medium","Static renewal - daily","Not stated","Not stated","Table 2","Yes","p < 0.05","Not stated","Not stated","28oC","98% pure from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3033-6"]
["Scores",10,5,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,1,3,55,0.60439560439560436,null,"The highest possible grade for this datum is acceptable."]
["Answers","120 days","Growth - length","NOEC","NOEC","Yes, normal control and solvent control","Three replicates","Not stated","Embryos","Culture medium","Static renewal - daily","Not stated","Not stated","Table 2","Yes","p < 0.05","Not stated","Not stated","28oC","98% pure from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3033-7"]
["Scores",10,5,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,1,3,55,0.60439560439560436,null,"The highest possible grade for this datum is acceptable."]
["Answers","120 days","Growth - length","LOEC","LOEC","Yes, normal control and solvent control","Three replicates","Not stated","Embryos","Culture medium","Static renewal - daily","Not stated","Not stated","Table 2","Yes","p < 0.05","Not stated","Not stated","28oC","98% pure from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3033-8"]
["Scores",10,5,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,1,3,55,0.60439560439560436,null,"The highest possible grade for this datum is acceptable."]
["Answers","120 days","Survival - F1 offspring of exposed parents","NOEC","NOEC","Yes, normal control and solvent control","Three replicates","Not stated","Embryos","Culture medium","Static renewal - daily","Not stated","Not stated","Figure 9","Yes","p < 0.05","Not stated","Not stated","28oC","98% pure from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3033-9"]
["Scores",10,5,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,1,3,55,0.60439560439560436,null,"The highest possible grade for this datum is acceptable."]
["Answers","120 days","Reproduction - F1 hatching rate from exposed parents","NOEC","NOEC","Yes, normal control and solvent control","Three replicates","Not stated","Embryos","Culture medium","Static renewal - daily","Not stated","Not stated","Figure 8","Yes","p < 0.05","Not stated","Not stated","28oC","98% pure from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3033-10"]
["Scores",10,5,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,1,3,55,0.60439560439560436,null,"The highest possible grade for this datum is acceptable."]
["Answers","120 days","Body length in F1 offspring from exposed parents","NOEC","NOEC","Yes, normal control and solvent control","Three replicates","Not stated","Embryos","Culture medium","Static renewal - daily","Not stated","Not stated","Figure 8","Yes","p < 0.05","Not stated","Not stated","28oC","98% pure from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3034-1"]
["Scores",10,5,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,0,3,54,0.59340659340659341,null,"The highest possible grade for this datum is acceptable."]
["Answers","7 days","Fish length","NOEC","NOEC","Yes (DMSO control)","Three to four times","Not stated","Embryos 3 hours post fertilization","Danieau's medium","Static renewal - daily","Not stated","Not stated","Figure S1","Yes","alpha = 0.05","Not stated","Not stated","Not stated","Heptadecafluorooctanesulfonic acid (PFOS) from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3034-2"]
["Scores",10,5,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,0,3,54,0.59340659340659341,null,"The highest possible grade for this datum is acceptable."]
["Answers","7 days","Fish length","LOEC","LOEC","Yes (DMSO control)","Three to four times","Not stated","Embryos 3 hours post fertilization","Danieau's medium","Static renewal - daily","Not stated","Not stated","Figure S1","Yes","alpha = 0.05","Not stated","Not stated","Not stated","Heptadecafluorooctanesulfonic acid (PFOS) from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3035-1"]
["Scores",10,5,0,0,5,5,0,5,5,4,2,0,4,4,4,0,0,0,3,56,0.61538461538461542,null,""]
["Answers","14 days","Survival","NOEC","NOEC","Yes (DMSO control)","Three repllicates per exposure concentration","Not stated","Embryos","Culture medium + DMSO","Static renewal - daily","Measured after 24 hours","Not stated","Table 2","Yes","p < 0.05","Not stated","Not stated","Not stated","PFOS >/= 98% purity from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3035-2"]
["Scores",10,5,0,0,5,5,0,5,5,4,2,0,4,4,4,0,0,0,3,56,0.61538461538461542,null,""]
["Answers","14 days","Survival","LOEC","LOEC","Yes (DMSO control)","Three repllicates per exposure concentration","Not stated","Embryos","Culture medium + DMSO","Static renewal - daily","Measured after 24 hours","Not stated","Table 2","Yes","p < 0.05","Not stated","Not stated","Not stated","PFOS >/= 98% purity from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3035-3"]
["Scores",10,5,0,0,5,5,0,5,5,4,2,0,4,4,4,0,0,0,3,56,0.61538461538461542,null,""]
["Answers","14 days","Growth - body length","NOEC","NOEC","Yes (DMSO control)","Three repllicates per exposure concentration","Not stated","Embryos","Culture medium + DMSO","Static renewal - daily","Measured after 24 hours","Not stated","Table 2","Yes","p < 0.05","Not stated","Not stated","Not stated","PFOS >/= 98% purity from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3035-4"]
["Scores",10,5,0,0,5,5,0,5,5,4,2,0,4,4,4,0,0,0,3,56,0.61538461538461542,null,""]
["Answers","14 days","Growth - body length","LOEC","LOEC","Yes (DMSO control)","Three repllicates per exposure concentration","Not stated","Embryos","Culture medium + DMSO","Static renewal - daily","Measured after 24 hours","Not stated","Table 2","Yes","p < 0.05","Not stated","Not stated","Not stated","PFOS >/= 98% purity from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3035-4"]
["Scores",10,5,0,0,5,5,0,5,5,4,2,0,4,4,4,0,0,0,3,56,0.61538461538461542,null,""]
["Answers","14 days","Growth - weight","NOEC","NOEC","Yes (DMSO control)","Three repllicates per exposure concentration","Not stated","Embryos","Culture medium + DMSO","Static renewal - daily","Measured after 24 hours","Not stated","Table 2","Yes","p < 0.05","Not stated","Not stated","Not stated","PFOS >/= 98% purity from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3036-1"]
["Scores",10,5,5,5,5,5,0,5,5,4,4,0,4,4,4,0,0,0,3,68,0.74725274725274726,null,""]
["Answers","14 days","Survival","LC50","LC50","Yes","Four replicates per concentration","Not stated","6 month old adults","Moderately hard water","Semi static - water changed twice a week","Measured random set of exposure containers until the first water change at 4 days","Not stated","Yes Figure 2.3","Yes","p < 0.05","Not stated","Not stated","Not stated","PFOS >/= 98% purity from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3036-2"]
["Scores",10,5,0,0,5,5,0,5,5,4,4,0,4,4,4,0,0,0,3,58,0.63700000000000001,null,""]
["Answers","14 days","Survival","NOEC","NOEC","Yes","Four replicates per concentration","Not stated","6 month old adults","Moderately hard water","Semi static - water changed twice a week","Measured random set of exposure containers until the first water change at 4 days","Not stated","Yes Figure 2.3","Yes","alpha = 0l05","Not stated","Not stated","Not stated","PFOS >/= 98% purity from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3036-3"]
["Scores",10,5,0,0,5,5,0,5,5,4,4,0,4,4,4,0,0,0,3,58,0.63736263736263732,null,""]
["Answers","14 days","Survival","LOEC","LOEC","Yes","Four replicates per concentration","Not stated","6 month old adults","Moderately hard water","Semi static - water changed twice a week","Measured random set of exposure containers until the first water change at 4 days","Not stated","Yes Figure 2.3","Yes","alpha = 0l05","Not stated","Not stated","Not stated","PFOS >/= 98% purity from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3036-4"]
["Scores",10,5,0,0,5,5,0,5,5,4,4,0,4,4,4,0,0,0,3,58,0.63736263736263732,null,""]
["Answers","44 days","Survival","LC50","LC50","Yes","Two replicates (egg masses) per concentration","Not stated","Eggs ","Moderately hard water","Semi static - water changed twice a week","Measured random set of exposure containers until the first water change at 4 days","Not stated","Figure 2.5","Yes","alpha = 0.05","Not stated","Not stated","Not stated","PFOS >/= 98% purity from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3036-5"]
["Scores",10,5,0,0,5,5,0,5,5,4,4,0,4,4,4,0,0,0,3,58,0.63736263736263732,null,""]
["Answers","28 day","Growth - length","NOEC","NOEC","Yes","Two replicates (egg masses) per concentration","Not stated","Eggs ","Moderately hard water","Semi static - water changed twice a week","Measured random set of exposure containers until the first water change at 4 days","Not stated","Figure 2.6","Yes","alpha = 0.05","Not stated","Not stated","Not stated","PFOS >/= 98% purity from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3036-6"]
["Scores",10,5,0,0,5,5,0,5,5,4,4,0,4,4,4,0,0,0,3,58,0.63736263736263732,null,""]
["Answers","28 day","Growth - length","LOEC","LOEC","Yes","Two replicates (egg masses) per concentration","Not stated","Eggs ","Moderately hard water","Semi static - water changed twice a week","Measured random set of exposure containers until the first water change at 4 days","Not stated","Figure 2.6","Yes","alpha = 0.05","Not stated","Not stated","Not stated","PFOS >/= 98% purity from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3036-7"]
["Scores",10,5,0,0,5,5,0,5,5,4,4,0,4,4,4,0,0,0,3,58,0.63736263736263732,null,""]
["Answers","44 days","Reproduction - clutch size (averate number of eggs per egg mass)","NOEC","NOEC","Yes","Two replicates (egg masses) per concentration","Not stated","Eggs ","Moderately hard water","Semi static - water changed twice a week","Measured random set of exposure containers until the first water change at 4 days","Not stated","Figure 2.7","Yes","alpha = 0.05","Not stated","Not stated","Not stated","PFOS >/= 98% purity from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3036-8"]
["Scores",10,5,0,0,5,5,0,5,5,4,4,0,4,4,4,0,0,0,3,58,0.63736263736263732,null,""]
["Answers","44 days","Reproduction - clutch size (averate number of eggs per egg mass)","LOEC","LOEC","Yes","Two replicates (egg masses) per concentration","Not stated","Eggs ","Moderately hard water","Semi static - water changed twice a week","Measured random set of exposure containers until the first water change at 4 days","Not stated","Figure 2.7","Yes","alpha = 0.05","Not stated","Not stated","Not stated","PFOS >/= 98% purity from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3036-9"]
["Scores",10,5,5,5,5,5,0,5,5,4,4,0,4,4,4,0,0,0,3,68,0.747,null,""]
["Answers","28 days","Mortality - gentle prodding with a paintbrush","LC50","LC50","Yes","Eight replicates per concentration","Not stated","Juvenile F4-F6","Moderately hard water","Semi static - water changed every 5 days","Measured random set of exposure containers until the first water change at 4 days","Not stated","Figure 3.2","Yes","alpha = 0.05","Not stated","Not stated","Not stated","PFOS >/= 98% purity from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3036-10"]
["Scores",10,5,0,0,5,5,0,5,5,4,4,0,4,4,4,0,0,0,3,58,0.63736263736263732,null,""]
["Answers","28 days","Mortality - gentle prodding with a paintbrush","NOEC","NOEC","Yes","Eight replicates per concentration","Not stated","Juvenile F4-F6","Moderately hard water","Semi static - water changed every 5 days","Measured random set of exposure containers until the first water change at 4 days","Not stated","Figure 3.2","Yes","alpha = 0.05","Not stated","Not stated","Not stated","PFOS >/= 98% purity from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3036-12"]
["Scores",10,5,0,0,5,5,0,5,5,4,4,0,4,4,4,0,0,0,3,58,0.63736263736263732,null,""]
["Answers","28 days","Mortality - gentle prodding with a paintbrush","LOEC","LOEC","Yes","Eight replicates per concentration","Not stated","Juvenile F4-F6","Moderately hard water","Semi static - water changed every 5 days","Measured random set of exposure containers until the first water change at 4 days","Not stated","Figure 3.2","Yes","alpha = 0.05","Not stated","Not stated","Not stated","PFOS >/= 98% purity from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3037-1"]
["Scores",10,5,0,0,5,5,0,5,5,4,4,0,0,4,4,0,0,1,3,55,0.60439560439560436,null,""]
["Answers","28 days","Mortality - gentle prodding with a paintbrush","NOEC","NOEC","Yes","Six replicates tanks with 9 fish per tank","Not stated","Adults mean body weight 138.3 +/- 33.9 g. ","Moderately hard water","Semi static - one third of water renewed every 72 hours","Concentrations sampled at days 0,7, 14 and 28","Not stated","Not stated","Yes","alpha = 0.05","Not stated","Not stated","18-22oC","PFOS >/= 98% purity from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3037-2"]
["Scores",10,5,0,0,5,5,0,5,5,4,4,0,0,4,4,0,0,1,3,55,0.60439560439560436,null,""]
["Answers","28 days","Growth - mean weight","NOEC","NOEC","Yes","Six replicates tanks with 9 fish per tank","Not stated","Adults mean body weight 138.3 +/- 33.9 g. ","Moderately hard water","Semi static - one third of water renewed every 72 hours","Concentrations sampled at days 0,7, 14 and 28","Not stated","Not stated","Yes","alpha = 0.05","Not stated","Not stated","18-22oC","PFOS >/= 98% purity from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3038-1"]
["Scores",10,5,0,0,5,5,0,5,5,4,4,0,0,4,4,3,0,1,3,58,0.63736263736263732,null,""]
["Answers","120 days adult exposure (F0) and then 7 days embryo survival in clean water (F1)","Survival ","LOEC","LOEC","Control + DMSO (solvent)","100 embryos per treeatment","Not stated","Embryos 8 hours post fertilization (F0)","Reverse osmosis water with instant ocean added to raise the conductivity","Static renewal - daily for first 4 days and then every 3 days","Concentrations sampled at days 0,7, 14 and 28","Not stated","Not stated","Yes","alpha = 0.05","7-7.5","Not stated","27.5-28.5oC","PFOS > 96% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3038-2"]
["Scores",10,5,0,0,5,5,0,5,5,4,4,0,0,4,4,3,0,1,3,58,0.63736263736263732,null,""]
["Answers","120 days adult exposure (F0) and then 7 days embryo survival in clean water (F1)","Development - uninflated swim bladder ","LOEC","LOEC","Control + DMSO (solvent)","100 embryos per treeatment","Not stated","Embryos 8 hours post fertilization (F0)","Reverse osmosis water with instant ocean added to raise the conductivity","Static renewal - daily for first 4 days and then every 3 days","Concentrations sampled at days 0,7, 14 and 28","Not stated","Not stated","Yes","alpha = 0.05","7-7.5","Not stated","27.5-28.5oC","PFOS > 96% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3039-1"]
["Scores",10,5,0,0,5,5,0,5,5,4,4,0,0,4,4,1,1,1,3,57,0.62637362637362637,null,""]
["Answers","120 days (4 months)","Survival","NOEC","NOEC","Control + DMSO (solvent)","Three replicates","Not stated","5 dpf (NF stage 46/47","Charcoal filtered tap water","Static renewal - renewed every other day","Sampled at test intiation, days 61-63 and test termination","Not stated","Not stated","Yes"," p < 0.05","6.5-7.0","> 5 mg/L","20-24oC","PFOS 98% (Matrix Scientific Inc)"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3039-2"]
["Scores",10,5,0,0,5,5,0,5,5,4,4,0,0,4,4,1,1,1,3,57,0.62637362637362637,null,""]
["Answers","120 days (4 months)","Growth - body weight","NOEC","NOEC","Control + DMSO (solvent)","Three replicates","Not stated","5 dpf (NF stage 46/47","Charcoal filtered tap water","Static renewal - renewed every other day","Sampled at test intiation, days 61-63 and test termination","Not stated","Not stated","Yes"," p < 0.05","6.5-7.0","> 5 mg/L","20-24oC","PFOS 98% (Matrix Scientific Inc)"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3041-1"]
["Scores",10,5,0,0,5,5,0,5,5,4,0,0,0,4,4,0,0,1,3,51,0.56043956043956045,null,"The highest possible grade for this datum is acceptable."]
["Answers","22 days","Eye spot development (% compared to the control)","LOEC","LOEC","Control + DMSO (solvent)","Three replicates","Not stated","Tail fragment","Spring water","Static renewal - renewed ddaily","Not stated","Not stated","Figure 3 shows treatment time changes but only one exposure concentration","Yes"," p < 0.05","Not stated","Not stated","22oC","PFOS 99%"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3041-2"]
["Scores",10,5,0,0,5,5,0,5,5,4,0,0,0,4,4,0,0,1,3,51,0.56043956043956045,null,"The highest possible grade for this datum is acceptable."]
["Answers","22 days","Auricle development (% compared to the controls)","LOEC","LOEC","Control + DMSO (solvent)","Three replicates","Not stated","Tail fragment","Spring water","Static renewal - renewed ddaily","Not stated","Not stated","Figure 3 shows treatment time changes but only one exposure concentration","Yes"," p < 0.05","Not stated","Not stated","22oC","PFOS 99%"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3042-1"]
["Scores",10,5,0,0,5,5,0,5,5,4,4,0,0,4,4,1,1,1,3,57,0.62637362637362637,null,""]
["Answers","28 days","Survival","LOEC","LOEC","Control","Three replicates","Not stated","Adults - four months old","Carbon filtered tapwater","Static renewal - renewed daily","Measured at the beginning and end of experiments","Not stated","Only one exposure concentration","Yes"," p < 0.05","7-7.6","6.9-7.5 mg/L","21-25oC","PFOS 98% Agros Organics"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3042-2"]
["Scores",10,5,0,0,5,5,0,5,5,4,4,0,0,4,4,1,1,1,3,57,0.62637362637362637,null,""]
["Answers","28 days","Growth - length","LOEC","LOEC","Control","Three replicates","Not stated","Adults - four months old","Carbon filtered tapwater","Static renewal - renewed daily","Measured at the beginning and end of experiments","Not stated","Only one exposure concentration","Yes"," p < 0.05","7-7.6","6.9-7.5 mg/L","21-25oC","PFOS 98% Agros Organics"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3042-3"]
["Scores",10,5,0,0,5,5,0,5,5,4,4,0,0,4,4,1,1,1,3,57,0.62637362637362637,null,""]
["Answers","28 days","Growth - weight","LOEC","LOEC","Control","Three replicates","Not stated","Adults - four months old","Carbon filtered tapwater","Static renewal - renewed daily","Measured at the beginning and end of experiments","Not stated","Only one exposure concentration","Yes"," p < 0.05","7-7.6","6.9-7.5 mg/L","21-25oC","PFOS 98% Agros Organics"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3043-1"]
["Scores",10,5,0,0,5,5,5,5,5,4,4,0,0,4,4,3,3,3,3,68,0.74725274725274726,null,""]
["Answers","38 days","Emergence","NOEC","NOEC","Control","Five replicates","OECD guideline 218. Control emergence was at least 70%","L1 larvae (F0) then L4 larvae (F1)","Carbon filtered tapwater","Static renewal - renewed daily","Measured during the test","Not stated","Only one exposure concentration","Yes"," p < 0.05","Measured every 3-5 days 7.8-8.2","Measured every 3-5 days > 66%","Measured every 3-5 days 19-21oC","Pure PFOS from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3043-2"]
["Scores",10,5,0,0,5,5,5,5,5,4,4,0,0,4,4,3,3,3,3,68,0.74725274725274726,null,""]
["Answers","38 days","Mean number of eggs per rope generation 2, 3 and 6","NOEC","NOEC","Control","Five replicates","OECD guideline 218. Control emergence was at least 70%","L1 larvae (F0) then L4 larvae (F1)","Carbon filtered tapwater","Static renewal - renewed daily","Measured during the test","Not stated","Only one exposure concentration","Yes"," p < 0.05","Measured every 3-5 days 7.8-8.2","Measured every 3-5 days > 66%","Measured every 3-5 days 19-21oC","Pure PFOS from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","704-3"]
["Scores",10,10,0,0,5,5,0,5,5,4,4,0,4,4,4,3,3,3,3,72,0.79120879120879117,null,""]
["Answers","28 days","Growth - condition factor = weight/length","NOEC","NOEC","Control","Triplicate","Not stated","Adults mean length 6.1cm, weight 2 g","Irrigation pond water","Flow through","Meausred at 1h and 1, 2, 4, 7, 14 and 21 days","Not stated","Table 2","Yes"," p < 0.05","Measured 8.9-10.9","Measured 6.3-12.4 mg/L","Measured 20.1-29.2oC","PFOS 86% from 3M"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","704-4"]
["Scores",10,10,0,0,5,5,0,5,5,4,4,0,4,4,4,3,3,3,3,72,0.79120879120879117,null,""]
["Answers","12 days","Growth - condition factor = weight/length","NOEC","NOEC","Control","Triplicate","Not stated","Sexually immature fish 16.4cm x 22.7 g","Irrigation pond water","Flow through","Meausred at 1h and 1, 2, 4, 7, 14 and 21 days","Not stated","Table 2","Yes"," p < 0.05","Measured 8.9-10.9","Measured 5.6-16 mg/L","Measured 6-16.5oC","PFOS 86% from 3M"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","704-5"]
["Scores",10,10,0,0,5,5,0,5,5,4,4,0,0,4,4,1,1,3,3,64,0.70329670329670335,null,""]
["Answers","14 days","Growth - condition factor = weight/length","NOEC","NOEC","Control","Triplicate","Not stated","Adults 34.8 cm and 511.1 g","Irrigation pond water","Flow through","Meausred at 1h and 1, 2, 4, 7, 14 and 21 days","Not stated","Table 2. Only one exposure concentration","Yes"," p < 0.05","Data collected but not available","Data collected but not available","Measured 10oC","PFOS 86% from 3M"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","704-6"]
["Scores",10,10,0,0,5,5,0,5,5,4,4,0,0,4,4,1,3,3,3,66,0.72527472527472525,null,""]
["Answers","14 days","Growth - condition factor = weight/length","NOEC","NOEC","Control","Duplicate","Not stated","Adults 11.8 cm and 16.3 g","Irrigation pond water","Flow through","Meausred at 1h and 1, 2, 4, 7, 14 and 21 days","Not stated","Table 2. Only one exposure concentration","Yes"," p < 0.05","Measured 8.9-10.9","Measured 5.6-16 mg/L","Measured 6-16.5oC","PFOS 86% from 3M"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","704-7"]
["Scores",10,10,0,0,5,5,0,5,5,4,4,0,0,4,4,1,3,3,3,66,0.72527472527472525,null,""]
["Answers","14 days","Growth - condition factor = weight/length","NOEC","NOEC","Control","Duplicate","Not stated","Adults 8.9 cm and 6.7 g","Irrigation pond water","Flow through","Meausred at 1h and 1, 2, 4, 7, 14 and 21 days","Not stated","Table 2. Only one exposure concentration","Yes"," p < 0.05","Measured 8.9-10.9","Measured 5.6-16 mg/L","Measured 6-16.5oC","PFOS 86% from 3M"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","704-8"]
["Scores",10,10,0,0,5,5,0,5,5,4,4,0,0,4,4,1,3,3,3,66,0.72527472527472525,null,""]
["Answers","14 days","Growth - condition factor = weight/length","NOEC","NOEC","Control","Duplicate","Not stated","Adults 22.7 cm and 114.5 g","Irrigation pond water","Flow through","Meausred at 1h and 1, 2, 4, 7, 14 and 21 days","Not stated","Table 2. Only one exposure concentration","Yes"," p < 0.05","Measured 8.9-10.9","Measured 5.6-16 mg/L","Measured 6-16.5oC","PFOS 86% from 3M"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","706-3"]
["Scores",10,10,0,0,5,5,2,5,5,4,0,0,0,4,4,1,3,3,3,64,0.70329670329670335,null,"The highest possible grade for this datum is acceptable."]
["Answers","21 days","Reproduction - number of offspring per female","LOEC","LOEC","Control","Triplicate","OECD guidelines","Neonates < 24 h old","Daphnia culture water","Static renewal - renewed every 48 hours","Not stated","Not stated","Table 1","Yes"," p < 0.05","Measured 6.9-7.5","Measured 6-7 mg/L","Measured 19-21oC","PFOS 98% purity from Matrix Scientific"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","706-4"]
["Scores",10,10,0,0,5,5,2,5,5,4,0,0,0,4,4,1,3,3,3,64,0.70329670329670335,null,"The highest possible grade for this datum is acceptable."]
["Answers","21 days","Reproduction - time to first brood","NOEC","NOEC","Control","Triplicate","OECD guidelines","Neonates < 24 h old","Daphnia culture water","Static renewal - renewed every 48 hours","Not stated","Not stated","Table 1","Yes"," p < 0.05","Measured 6.9-7.5","Measured 6-7 mg/L","Measured 19-21oC","PFOS 98% purity from Matrix Scientific"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","706-5"]
["Scores",10,10,0,0,5,5,2,5,5,4,0,0,0,4,4,1,3,3,3,64,0.70329670329670335,null,"The highest possible grade for this datum is acceptable."]
["Answers","21 days","Reproduction - time to first brood","LOEC","LOEC","Control","Triplicate","OECD guidelines","Neonates < 24 h old","Daphnia culture water","Static renewal - renewed every 48 hours","Not stated","Not stated","Table 1","Yes"," p < 0.05","Measured 6.9-7.5","Measured 6-7 mg/L","Measured 19-21oC","PFOS 98% purity from Matrix Scientific"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","707-3"]
["Scores",10,10,0,0,5,5,0,5,5,4,4,0,0,4,4,1,3,3,3,66,0.72527472527472525,null,""]
["Answers","90 days","Growth - length and weight in F1 males","LOEC","LOEC","Control","Duplicate","Not stated","Fertilized eggs","Tap water and deionised water","Static to begin and then flow-through","Measured","Not stated","Figure 3","Yes"," p < 0.05, p < 0.01 and p < 0.001","Measured 8-8,2","Measured 6.45-10.97 mg/L","Measured 25-27oC","PFOS >/= 98% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","707-4"]
["Scores",10,10,0,0,5,5,0,5,5,4,4,0,0,4,4,1,3,3,3,66,0.72527472527472525,null,""]
["Answers","180 days","Growth - length F1 males","NOEC","NOEC","Control","Duplicate","Not stated","Fertilized eggs","Tap water and deionised water","Static to begin and then flow-through","Measured","Not stated","Figure 3","Yes"," p < 0.05, p < 0.01 and p < 0.001","Measured 8-8,2","Measured 6.45-10.97 mg/L","Measured 25-27oC","PFOS >/= 98% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","707-5"]
["Scores",10,10,0,0,5,5,0,5,5,4,4,0,0,4,4,1,3,3,3,66,0.72527472527472525,null,""]
["Answers","180 days","Growth - length F1 males","LOEC","LOEC","Control","Duplicate","Not stated","Fertilized eggs","Tap water and deionised water","Static to begin and then flow-through","Measured","Not stated","Figure 3","Yes"," p < 0.05, p < 0.01 and p < 0.001","Measured 8-8,2","Measured 6.45-10.97 mg/L","Measured 25-27oC","PFOS >/= 98% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","707-6"]
["Scores",10,10,0,0,5,5,0,5,5,4,4,0,0,4,4,1,3,3,3,66,0.72527472527472525,null,""]
["Answers","180 days","Growth - weight F1 males","NOEC","NOEC","Control","Duplicate","Not stated","Fertilized eggs","Tap water and deionised water","Static to begin and then flow-through","Measured","Not stated","Figure 3","Yes"," p < 0.05, p < 0.01 and p < 0.001","Measured 8-8,2","Measured 6.45-10.97 mg/L","Measured 25-27oC","PFOS >/= 98% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","707-7"]
["Scores",10,10,0,0,5,5,0,5,5,4,4,0,0,4,4,1,3,3,3,66,0.72527472527472525,null,""]
["Answers","90 days","Growth - length and weight F1 females","NOEC","NOEC","Control","Duplicate","Not stated","Fertilized eggs","Tap water and deionised water","Static to begin and then flow-through","Measured","Not stated","Figure 3","Yes"," p < 0.05, p < 0.01 and p < 0.001","Measured 8-8,2","Measured 6.45-10.97 mg/L","Measured 25-27oC","PFOS >/= 98% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","707-8"]
["Scores",10,10,0,0,5,5,0,5,5,4,4,0,0,4,4,1,3,3,3,66,0.72527472527472525,null,""]
["Answers","180 days","Length and weight - females F1","LOEC","LOEC","Control","Duplicate","Not stated","Fertilized eggs","Tap water and deionised water","Static to begin and then flow-through","Measured","Not stated","Figure 3","Yes"," p < 0.05, p < 0.01 and p < 0.001","Measured 8-8,2","Measured 6.45-10.97 mg/L","Measured 25-27oC","PFOS >/= 98% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","707-9"]
["Scores",10,10,0,0,5,5,0,5,5,4,4,0,0,4,4,1,3,3,3,66,0.72527472527472525,null,""]
["Answers","30 days","Length and weight - females F2","LOEC","LOEC","Control","Duplicate","Not stated","Fertilized eggs","Tap water and deionised water","Static to begin and then flow-through","Measured","Not stated","Figure 3","Yes"," p < 0.05, p < 0.01 and p < 0.001","Measured 8-8,2","Measured 6.45-10.97 mg/L","Measured 25-27oC","PFOS >/= 98% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","707-10"]
["Scores",10,10,0,0,5,5,0,5,5,4,4,0,0,4,4,1,3,3,3,66,0.72527472527472525,null,""]
["Answers","90 days","Length and weight - females F2","LOEC","LOEC","Control","Duplicate","Not stated","Fertilized eggs","Tap water and deionised water","Static to begin and then flow-through","Measured","Not stated","Figure 3","Yes"," p < 0.05, p < 0.01 and p < 0.001","Measured 8-8,2","Measured 6.45-10.97 mg/L","Measured 25-27oC","PFOS >/= 98% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","707-11"]
["Scores",10,10,0,0,5,5,0,5,5,4,4,0,0,4,4,1,3,3,3,66,0.72527472527472525,null,""]
["Answers","180 days","Length  - females F2","LOEC","LOEC","Control","Duplicate","Not stated","Fertilized eggs","Tap water and deionised water","Static to begin and then flow-through","Measured","Not stated","Figure 3","Yes"," p < 0.05, p < 0.01 and p < 0.001","Measured 8-8,2","Measured 6.45-10.97 mg/L","Measured 25-27oC","PFOS >/= 98% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","707-12"]
["Scores",10,10,0,0,5,5,0,5,5,4,4,0,0,4,4,1,3,3,3,66,0.72527472527472525,null,""]
["Answers","180 days","Weight  - females F2","NOEC","NOEC","Control","Duplicate","Not stated","Fertilized eggs","Tap water and deionised water","Static to begin and then flow-through","Measured","Not stated","Figure 3","Yes"," p < 0.05, p < 0.01 and p < 0.001","Measured 8-8,2","Measured 6.45-10.97 mg/L","Measured 25-27oC","PFOS >/= 98% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","707-13"]
["Scores",10,10,0,0,5,5,0,5,5,4,4,0,0,4,4,1,3,3,3,66,0.72527472527472525,null,""]
["Answers","180 days","Weight  - females F2","LOEC","LOEC","Control","Duplicate","Not stated","Fertilized eggs","Tap water and deionised water","Static to begin and then flow-through","Measured","Not stated","Figure 3","Yes"," p < 0.05, p < 0.01 and p < 0.001","Measured 8-8,2","Measured 6.45-10.97 mg/L","Measured 25-27oC","PFOS >/= 98% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","707-14"]
["Scores",10,10,0,0,5,5,0,5,5,4,4,0,0,4,4,1,3,3,3,66,0.72527472527472525,null,""]
["Answers","30 days","Length and weight - males F2","LOEC","LOEC","Control","Duplicate","Not stated","Fertilized eggs","Tap water and deionised water","Static to begin and then flow-through","Measured","Not stated","Figure 3","Yes"," p < 0.05, p < 0.01 and p < 0.001","Measured 8-8,2","Measured 6.45-10.97 mg/L","Measured 25-27oC","PFOS >/= 98% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","707-15"]
["Scores",10,10,0,0,5,5,0,5,5,4,4,0,0,4,4,1,3,3,3,66,0.72527472527472525,null,""]
["Answers","90 days","Length and weight - males F2","LOEC","LOEC","Control","Duplicate","Not stated","Fertilized eggs","Tap water and deionised water","Static to begin and then flow-through","Measured","Not stated","Figure 3","Yes"," p < 0.05, p < 0.01 and p < 0.001","Measured 8-8,2","Measured 6.45-10.97 mg/L","Measured 25-27oC","PFOS >/= 98% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","707-16"]
["Scores",10,10,0,0,5,5,0,5,5,4,4,0,0,4,4,1,3,3,3,66,0.72527472527472525,null,""]
["Answers","180 days","Length and weight - males F2","NOEC","NOEC","Control","Duplicate","Not stated","Fertilized eggs","Tap water and deionised water","Static to begin and then flow-through","Measured","Not stated","Figure 3","Yes"," p < 0.05, p < 0.01 and p < 0.001","Measured 8-8,2","Measured 6.45-10.97 mg/L","Measured 25-27oC","PFOS >/= 98% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","707-17"]
["Scores",10,10,0,0,5,5,0,5,5,4,4,0,0,4,4,1,3,3,3,66,0.72527472527472525,null,""]
["Answers","180 days","Length and weight - males F2","LOEC","LOEC","Control","Duplicate","Not stated","Fertilized eggs","Tap water and deionised water","Static to begin and then flow-through","Measured","Not stated","Figure 3","Yes"," p < 0.05, p < 0.01 and p < 0.001","Measured 8-8,2","Measured 6.45-10.97 mg/L","Measured 25-27oC","PFOS >/= 98% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","708-1"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,1,3,60,0.65934065934065933,null,"The highest possible grade for this datum is acceptable."]
["Answers","90 days","Length and weight males","NOEC","NOEC","Control","Triplicate","Not stated","Adult male fish","Dechlorinated tap water","Static renewal - renewed every day","Not measured","Not stated","Table 2","Yes"," p < 0.01 ","Not stated","Not stated","26-28oC","PFOS > 98% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","708-2"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,1,3,60,0.65934065934065933,null,"The highest possible grade for this datum is acceptable."]
["Answers","90 days","Length and weight females","LOEC","LOEC","Control","Triplicate","Not stated","Adult male fish","Dechlorinated tap water","Static renewal - renewed every day","Not measured","Not stated","Table 2","Yes"," p < 0.01 ","Not stated","Not stated","26-28oC","PFOS > 98% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","708-3"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,1,3,60,0.65934065934065933,null,"The highest possible grade for this datum is acceptable."]
["Answers","90 days","Condition factor males","NOEC","NOEC","Control","Triplicate","Not stated","Adult male fish","Dechlorinated tap water","Static renewal - renewed every day","Not measured","Not stated","Table 2","Yes"," p < 0.01 ","Not stated","Not stated","26-28oC","PFOS > 98% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","708-4"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,1,3,60,0.65934065934065933,null,"The highest possible grade for this datum is acceptable."]
["Answers","90 days","Condition factor females","NOEC","NOEC","Control","Triplicate","Not stated","Adult male fish","Dechlorinated tap water","Static renewal - renewed every day","Not measured","Not stated","Table 2","Yes"," p < 0.01 ","Not stated","Not stated","26-28oC","PFOS > 98% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","717-3"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,1,3,60,0.65934065934065933,null,"The highest possible grade for this datum is acceptable."]
["Answers","40 days","Weight - F0 males","LOEC","LOEC","Control","Triplicate","Not stated","Adult male fish","Fry 14dpf","Static renewal - 1/2 volume renewed per day","Not measured","Not stated","Table 1","Yes"," p < 0.05","Not stated","Not stated","26.5-27.5oC","PFOS > 99% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","717-4"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,1,3,60,0.65934065934065933,null,"The highest possible grade for this datum is acceptable."]
["Answers","40 days","Length - F0 males","NOEC","NOEC","Control","Triplicate","Not stated","Adult male fish","Fry 14dpf","Static renewal - 1/2 volume renewed per day","Not measured","Not stated","Table 1","Yes"," p < 0.05","Not stated","Not stated","26.5-27.5oC","PFOS > 99% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","717-5"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,1,3,60,0.65934065934065933,null,"The highest possible grade for this datum is acceptable."]
["Answers","40 days","Condition factor - F0 males","NOEC","NOEC","Control","Triplicate","Not stated","Adult male fish","Fry 14dpf","Static renewal - 1/2 volume renewed per day","Not measured","Not stated","Table 1","Yes"," p < 0.05","Not stated","Not stated","26.5-27.5oC","PFOS > 99% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","717-6"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,1,3,60,0.65934065934065933,null,"The highest possible grade for this datum is acceptable."]
["Answers","40 days","Condition factor - F0 males","LOEC","LOEC","Control","Triplicate","Not stated","Adult male fish","Fry 14dpf","Static renewal - 1/2 volume renewed per day","Not measured","Not stated","Table 1","Yes"," p < 0.05","Not stated","Not stated","26.5-27.5oC","PFOS > 99% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","717-7"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,1,3,60,0.65934065934065933,null,"The highest possible grade for this datum is acceptable."]
["Answers","70 days","Length and weight - F0 males","NOEC","NOEC","Control","Triplicate","Not stated","Adult male fish","Fry 14dpf","Static renewal - 1/2 volume renewed per day","Not measured","Not stated","Table 1","Yes"," p < 0.05","Not stated","Not stated","26.5-27.5oC","PFOS > 99% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","717-8"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,1,3,60,0.65934065934065933,null,"The highest possible grade for this datum is acceptable."]
["Answers","70 days","Length and weight - F0 males","LOEC","LOEC","Control","Triplicate","Not stated","Adult male fish","Fry 14dpf","Static renewal - 1/2 volume renewed per day","Not measured","Not stated","Table 1","Yes"," p < 0.05","Not stated","Not stated","26.5-27.5oC","PFOS > 99% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","717-9"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,1,3,60,0.65934065934065933,null,"The highest possible grade for this datum is acceptable."]
["Answers","70 days","Condition factor - F0 males","NOEC","NOEC","Control","Triplicate","Not stated","Adult male fish","Fry 14dpf","Static renewal - 1/2 volume renewed per day","Not measured","Not stated","Table 1","Yes"," p < 0.05","Not stated","Not stated","26.5-27.5oC","PFOS > 99% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","717-10"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,1,3,60,0.65934065934065933,null,"The highest possible grade for this datum is acceptable."]
["Answers","70 days","Condition factor - F0 males","LOEC","LOEC","Control","Triplicate","Not stated","Adult male fish","Fry 14dpf","Static renewal - 1/2 volume renewed per day","Not measured","Not stated","Table 1","Yes"," p < 0.05","Not stated","Not stated","26.5-27.5oC","PFOS > 99% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","717-11"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,1,3,60,0.65934065934065933,null,"The highest possible grade for this datum is acceptable."]
["Answers","40 days","Length and weight - F0 females","NOEC","NOEC","Control","Triplicate","Not stated","Adult male fish","Fry 14dpf","Static renewal - 1/2 volume renewed per day","Not measured","Not stated","Table 1","Yes"," p < 0.05","Not stated","Not stated","26.5-27.5oC","PFOS > 99% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","717-12"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,1,3,60,0.65934065934065933,null,"The highest possible grade for this datum is acceptable."]
["Answers","70 days","Length and weight - F0 females","NOEC","NOEC","Control","Triplicate","Not stated","Adult male fish","Fry 14dpf","Static renewal - 1/2 volume renewed per day","Not measured","Not stated","Table 1","Yes"," p < 0.05","Not stated","Not stated","26.5-27.5oC","PFOS > 99% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","717-13"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,1,3,60,0.65934065934065933,null,"The highest possible grade for this datum is acceptable."]
["Answers","40 days","Condition factor - F0 females ","NOEC","NOEC","Control","Triplicate","Not stated","Adult male fish","Fry 14dpf","Static renewal - 1/2 volume renewed per day","Not measured","Not stated","Table 1","Yes"," p < 0.05","Not stated","Not stated","26.5-27.5oC","PFOS > 99% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","717-14"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,1,3,60,0.65934065934065933,null,"The highest possible grade for this datum is acceptable."]
["Answers","40 days","Condition factor - F0 females ","LOEC","LOEC","Control","Triplicate","Not stated","Adult male fish","Fry 14dpf","Static renewal - 1/2 volume renewed per day","Not measured","Not stated","Table 1","Yes"," p < 0.05","Not stated","Not stated","26.5-27.5oC","PFOS > 99% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","718-3"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,0,0,0,1,3,56,0.61538461538461542,null,"The highest possible grade for this datum is acceptable."]
["Answers","8 days","Survival - F1 generation","LOEC","LOEC","Control","Triplicate","Not stated","Embryos 8 hpf","RO water with instant ocean added","Static renewal ","Not measured","Not stated","Figure 3","Yes","Not stated","Not stated","Not stated","28oC","PFOS > 96% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","718-4"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,0,0,0,1,3,56,0.61538461538461542,null,"The highest possible grade for this datum is acceptable."]
["Answers","150 days","Length and weight FO male","LOEC","LOEC","Control","Triplicate","Not stated","Adults","RO water with instant ocean added","Static renewal ","Not measured","Not stated","Table 1","Yes","Not stated","Not stated","Not stated","28oC","PFOS > 96% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","718-5"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,0,0,0,1,3,56,0.61538461538461542,null,"The highest possible grade for this datum is acceptable."]
["Answers","150 days","Condition factor - F0 male","NOEC","NOEC","Control","Triplicate","Not stated","Adults","RO water with instant ocean added","Static renewal ","Not measured","Not stated","Table 1","Yes","Not stated","Not stated","Not stated","28oC","PFOS > 96% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","718-6"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,0,0,0,1,3,56,0.61538461538461542,null,"The highest possible grade for this datum is acceptable."]
["Answers","150 days","Condition factor - F0 male","LOEC","LOEC","Control","Triplicate","Not stated","Adults","RO water with instant ocean added","Static renewal ","Not measured","Not stated","Table 1","Yes","Not stated","Not stated","Not stated","28oC","PFOS > 96% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","718-7"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,0,0,0,1,3,56,0.61538461538461542,null,"The highest possible grade for this datum is acceptable."]
["Answers","150 days","Length, weight and condition factor F0 female ","NOEC","NOEC","Control","Triplicate","Not stated","Adults","RO water with instant ocean added","Static renewal ","Not measured","Not stated","Table 1","Yes","Not stated","Not stated","Not stated","28oC","PFOS > 96% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","718-8"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,0,0,0,1,3,56,0.61538461538461542,null,"The highest possible grade for this datum is acceptable."]
["Answers","150 days","Length and weight  F0 female ","LOEC","LOEC","Control","Triplicate","Not stated","Adults","RO water with instant ocean added","Static renewal ","Not measured","Not stated","Table 1","Yes","Not stated","Not stated","Not stated","28oC","PFOS > 96% purity"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3029-8"]
["Scores",10,10,0,0,5,5,0,5,5,4,4,0,4,4,4,0,0,1,3,64,0.70329670329670335,null,""]
["Answers","58 days","Growth - snout-vent length (mm)","NOEC","NOEC","Control","4 replicates","Not stated","Tadpoles Niewkop and Faber (NF) Stage 10","Dechlorinated tap water","Flow-through","At initiation and completion","Not stated","Table 1","Yes","alpha = 0.05","Not stated","Not stated","25.5-26.5oC","PFOS > /=98% purity from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3029-9"]
["Scores",10,10,0,0,5,5,0,5,5,4,4,0,4,4,4,0,0,1,3,64,0.70329670329670335,null,""]
["Answers","58 days","Growth - snout-vent length (mm)","LOEC","LOEC","Control","4 replicates","Not stated","Tadpoles Niewkop and Faber (NF) Stage 10","Dechlorinated tap water","Flow-through","At initiation and completion","Not stated","Table 1","Yes","alpha = 0.05","Not stated","Not stated","25.5-26.5oC","PFOS > /=98% purity from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3031-4"]
["Scores",10,10,0,0,5,5,0,5,5,4,4,0,0,4,4,1,1,1,3,62,0.68131868131868134,null,""]
["Answers","150 days","Growth - time to emergence","LOEC","LOEC","Yes","10 replictes","OECD test guideine 218 and 233 with slight variations. Each generational test was considered valid if emergence in the control was >/= 70% in at least 6/10 replicates","1st instar larvae","Reconstituted water","Static renewal - replaced twice aweek","Measured during the test","Not stated","Only one exposure concentration","Yes","p < 0.05","Measured during the test","Measured during the test","Measured during the test 18.7-21.2oC","Pure compounds"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3032-4"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,4,4,4,4,1,1,1,3,66,0.72527472527472525,null,"The highest possible grade for this datum is acceptable."]
["Answers","21 days","Reproduction - days to first brood","LOEC","LOEC","Yes","10 replictes","OECD test guideline 211, no morality in the control","Neonates","Daphnia culture media","Static renewal - renewed every 72 hours","Not stated","For acute tests with potassium dichromate","Figure 3","Yes","p < 0.05","Measured during the test","Measured during the test","Measured during the test 19-21oC","98% pure from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3032-5"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,4,4,4,4,1,1,1,3,66,0.72527472527472525,null,"The highest possible grade for this datum is acceptable."]
["Answers","21 days","Reproduction - days to first pregnancy","LOEC","LOEC","Yes","10 replictes","OECD test guideline 211, no morality in the control","Neonates","Daphnia culture media","Static renewal - renewed every 72 hours","Not stated","For acute tests with potassium dichromate","Figure 3","Yes","p < 0.05","Measured during the test","Measured during the test","Measured during the test 19-21oC","98% pure from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3033-11"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,1,3,60,0.65934065934065933,null,"The highest possible grade for this datum is acceptable."]
["Answers","120 days","Growth - body length males","NOEC","NOEC","Yes normal control and solvent control","Three replicates","Not stated","Embryos","Culture media","Static renewal","Not stated","Not stated","Table 2","Yes","p < 0.05","Not stated","Not stated","280C","98% pure from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3033-12"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,1,3,60,0.65934065934065933,null,"The highest possible grade for this datum is acceptable."]
["Answers","120 days","Growth - body weight, males","NOEC","NOEC","Yes normal control and solvent control","Three replicates","Not stated","Embryos","Culture media","Static renewal","Not stated","Not stated","Table 2","Yes","p < 0.05","Not stated","Not stated","280C","98% pure from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3033-13"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,1,3,60,0.65934065934065933,null,"The highest possible grade for this datum is acceptable."]
["Answers","120 days","Growth - body length, females","NOEC","NOEC","Yes normal control and solvent control","Three replicates","Not stated","Embryos","Culture media","Static renewal","Not stated","Not stated","Table 2","Yes","p < 0.05","Not stated","Not stated","280C","98% pure from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3033-14"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,1,3,60,0.65934065934065933,null,"The highest possible grade for this datum is acceptable."]
["Answers","120 days","Fertilization - Fertilisation rate of 12hpf F1 embryos of exposed parents (F0)","NOEC","NOEC","Yes normal control and solvent control","Three replicates","Not stated","Embryos","Culture media","Static renewal","Not stated","Not stated","Figure 7","Yes","p < 0.05","Not stated","Not stated","280C","98% pure from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3033-15"]
["Scores",10,10,0,0,5,5,0,5,5,4,0,0,4,4,4,0,0,1,3,60,0.65934065934065933,null,"The highest possible grade for this datum is acceptable."]
["Answers","120 days","Malformation rate of 96hpf F1 embryos of exposed parents (F0)","NOEC","NOEC","Yes normal control and solvent control","Three replicates","Not stated","Embryos","Culture media","Static renewal","Not stated","Not stated","Figure 11","Yes","p < 0.05","Not stated","Not stated","280C","98% pure from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3035-6"]
["Scores",10,10,0,0,5,5,0,5,5,4,2,0,4,4,4,0,0,0,3,61,0.67032967032967028,null,""]
["Answers","14 days","Development - malformations","NOEC","NOEC","Yes (DMSO controls)","Three replicates","Not stated","Embryos","Culture media","Static renewal","Measured after 24 hours","Not stated","Table 2","Yes","p < 0.05","Not stated","Not stated","Not stated",">/=98% pure from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3035-7"]
["Scores",10,10,0,0,5,5,0,5,5,4,2,0,4,4,4,0,0,0,3,61,0.67032967032967028,null,""]
["Answers","14 days","Development - malformations","LOEC","LOEC","Yes (DMSO controls)","Three replicates","Not stated","Embryos","Culture media","Static renewal","Measured after 24 hours","Not stated","Table 2","Yes","p < 0.05","Not stated","Not stated","Not stated",">/=98% pure from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","404-29"]
["Scores",10,5,0,0,5,0,0,5,5,4,0,0,4,4,4,0,0,0,3,49,0.53846153846153844,null,"The highest possible grade for this datum is acceptable."]
["Answers","14 days","Growth - length and weight","LOEC","LOEC","Yes","Not stated","Not stated","Embryos","Dechlorinated tap water","Static renewal - renewed 3 x a week","Nominal","Not stated","Table 5","Yes","p < 0.05","Not stated","Not stated","25oC","Wako chemicals CAS RN 1763-23-1"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","404-27"]
["Scores",10,5,0,0,5,0,0,5,5,4,0,0,4,4,4,0,0,0,3,49,0.53846153846153844,null,"The highest possible grade for this datum is acceptable."]
["Answers","14 days","Survival","NOEC","NOEC","Yes","Not stated","Not stated","Breeding age ","Dechlorinated tap water","Static renewal - renewed 3 x a week","Nominal","Not stated","Table 5","Yes","p < 0.05","Not stated","Not stated","25oC","Wako chemicals CAS RN 1763-23-1"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","404-28"]
["Scores",10,5,0,0,5,0,0,5,5,4,0,0,4,4,4,0,0,0,3,49,0.53846153846153844,null,"The highest possible grade for this datum is acceptable."]
["Answers","14 days","Growth - condition factor (weight/length)","NOEC","NOEC","Yes","Not stated","Not stated","Breeding age ","Dechlorinated tap water","Static renewal - renewed 3 x a week","Nominal","Not stated","Table 5","Yes","p < 0.05","Not stated","Not stated","25oC","Wako chemicals CAS RN 1763-23-1"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","404-23"]
["Scores",10,5,0,0,5,5,0,5,5,4,0,4,4,4,4,1,1,0,3,60,0.65934065934065933,null,"The highest possible grade for this datum is acceptable."]
["Answers","7 days","Reproduction - # young per adult","LOEC","LOEC","Yes","10 replicates","Not stated","Neonates < 24 hours old","Moderately hard water","Static renewal - renewed 3 x a week","Nominal","Monthly NaCl tests","Table 3","Yes","p < 0.05","Stated it was undertaken at water changes. ","Stated it was undertaken at water changes. ","24-26oC","Wako chemicals CAS RN 1763-23-1"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","404-24"]
["Scores",10,5,0,0,5,5,0,5,5,4,0,4,4,4,4,1,1,0,3,60,0.65934065934065933,null,"The highest possible grade for this datum is acceptable."]
["Answers","7 days","Reproduction - days to first brood","LOEC","LOEC","Yes","10 replicates","Not stated","Neonates < 24 hours old","Moderately hard water","Static renewal - renewed 3 x a week","Nominal","Monthly NaCl tests","Table 3","Yes","p < 0.05","Stated it was undertaken at water changes. ","Stated it was undertaken at water changes. ","24-26oC","Wako chemicals CAS RN 1763-23-1"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","404-25"]
["Scores",10,5,0,0,5,5,0,5,5,4,0,4,4,4,4,1,1,0,3,60,0.65934065934065933,null,"The highest possible grade for this datum is acceptable."]
["Answers","7 days","Survival","NOEC","NOEC","Yes","10 replicates","Not stated","Neonates < 24 hours old","Moderately hard water","Static renewal - renewed 3 x a week","Nominal","Monthly NaCl tests","Table 3","Yes","p < 0.05","Stated it was undertaken at water changes. ","Stated it was undertaken at water changes. ","24-26oC","Wako chemicals CAS RN 1763-23-1"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","404-26"]
["Scores",10,5,0,0,5,5,0,5,5,4,0,4,4,4,4,1,1,0,3,60,0.65934065934065933,null,"The highest possible grade for this datum is acceptable."]
["Answers","7 days","Survival","LOEC","LOEC","Yes","10 replicates","Not stated","Neonates < 24 hours old","Moderately hard water","Static renewal - renewed 3 x a week","Nominal","Monthly NaCl tests","Table 3","Yes","p < 0.05","Stated it was undertaken at water changes. ","Stated it was undertaken at water changes. ","24-26oC","Wako chemicals CAS RN 1763-23-1"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","404-20"]
["Scores",10,5,0,0,5,5,0,5,5,4,0,4,4,4,4,1,1,0,3,60,0.65934065934065933,null,"The highest possible grade for this datum is acceptable."]
["Answers","21 days","Reproduction - # offspring per female / days to first brood / # young per brood","LOEC","LOEC","Yes","10 replicates","Not stated","Neonates < 24 hours old","Moderately hard water","Static renewal - renewed 3 x a week","Nominal","Monthly NaCl tests","Table 3","Yes","p < 0.05","Stated it was undertaken at water changes. ","Stated it was undertaken at water changes. ","20-22oC","Wako chemicals CAS RN 1763-23-1"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","404-21"]
["Scores",10,5,0,0,5,5,0,5,5,4,0,4,4,4,4,1,1,0,3,60,0.65934065934065933,null,"The highest possible grade for this datum is acceptable."]
["Answers","21 days","Growth (mm)","NOEC","NOEC","Yes","10 replicates","Not stated","Neonates < 24 hours old","Moderately hard water","Static renewal - renewed 3 x a week","Nominal","Monthly NaCl tests","Table 3","Yes","p < 0.05","Stated it was undertaken at water changes. ","Stated it was undertaken at water changes. ","20-22oC","Wako chemicals CAS RN 1763-23-1"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","404-22"]
["Scores",10,5,0,0,5,5,0,5,5,4,0,4,4,4,4,1,1,0,3,60,0.65934065934065933,null,"The highest possible grade for this datum is acceptable."]
["Answers","21 days","Survival","NOEC","NOEC","Yes","10 replicates","Not stated","Neonates < 24 hours old","Moderately hard water","Static renewal - renewed 3 x a week","Nominal","Monthly NaCl tests","Table 3","Yes","p < 0.05","Stated it was undertaken at water changes. ","Stated it was undertaken at water changes. ","20-22oC","Wako chemicals CAS RN 1763-23-1"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","412-4"]
["Scores",10,5,0,0,5,5,2,5,5,4,0,0,4,4,4,0,0,0,3,56,0.61538461538461542,null,"The highest possible grade for this datum is acceptable."]
["Answers","21 days","Reproduction - # offspring per female","LOEC","LOEC","Yes","10 replicates","OECD guidelines","Neonates < 24 hours old","ASTM hardwater","Static renewal - renewed 3 x a week","Nominal","Not stated","Table 2","Yes","p < 0.05","Not stated","Not stated","Not stated",">98% from Fluka"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","431-23"]
["Scores",10,5,0,0,5,5,2,5,5,4,0,0,4,4,4,0,0,1,3,57,0.62637362637362637,null,"The highest possible grade for this datum is acceptable."]
["Answers","21 days","Reproduction -Days to first brood/# young per adult/# young per brood","NOEC","NOEC","Yes","Three replicates","ASTM guidelines","Neonates < 24 hours old","Lab dechlorinated water","Static renewal - once per week ","Nominal","Not stated","Table 2","Yes","p < 0.05","Not stated","Not stated","20-22oC","PFOS-K purity 95% from 3M"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","431-24"]
["Scores",10,5,0,0,5,5,2,5,5,4,0,0,4,4,4,0,0,1,3,57,0.62637362637362637,null,"The highest possible grade for this datum is acceptable."]
["Answers","21 days","Reproduction -Days to first brood/# young per adult/# young per brood","LOEC","LOEC","Yes","Three replicates","ASTM guidelines","Neonates < 24 hours old","Lab dechlorinated water","Static renewal - once per week ","Nominal","Not stated","Table 2","Yes","p < 0.05","Not stated","Not stated","20-22oC","PFOS-K purity 95% from 3M"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","435-9"]
["Scores",10,10,0,0,5,5,0,5,5,0,2,0,4,4,4,0,0,1,3,58,0.63736263736263732,null,""]
["Answers","36 days","Survival - viablility following removal from adults at days 3, 5 and 7","LOEC","LOEC","Yes","Five replicates","Not stated","Glochidia removed from adults, surival assessed at days 1, 3, 5 and 7","Pond water ","Not stated","Measured on days 10 and 11 of the 36-d marsupia exposure","Not stated","Figure 2","Yes","p < 0.0005","Not stated","Not stated","20oC","PFOS > 98% purity from Fisher Scientific"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","434-6"]
["Scores",10,10,5,5,5,5,2,5,5,4,0,0,4,4,4,1,0,1,3,73,0.80219780219780223,null,"The highest possible grade for this datum is acceptable."]
["Answers","120 days","Development - larval development time. Calculated as the number of days between egg hatching and metamorphosis","LOEC","LOEC - larval development time","Yes","Triplicate","OECD guidelines","Larvae from the egg hatching test","Dechlorinated tap water","Static - cups","Not stated","Not stated","Figure 2","Yes","p < 0.05","7.3-7.7","Not stated","21oC","Highest possible purity perfluoro-1-octanesulfonic acid tetraethyl ammonium salt (98%) Tox enpoint converted to anion"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","598-1"]
["Scores",10,5,5,5,5,5,0,5,5,4,2,0,4,4,4,0,0,1,3,67,0.73626373626373631,null,""]
["Answers","28 days","Reproduction - population density","LOEC","LOEC","Yes","30 individuals","Not stated","Neonates < 2 hours old","USEPA medium","Static renewal - daily","Measured","Not stated","Table 1","Yes","CI","Not stated","Not stated","20oC","PFOS 98% from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","598-2"]
["Scores",10,5,5,5,5,5,0,5,5,0,2,0,0,4,4,0,0,1,3,59,0.64835164835164838,null,""]
["Answers","5 days ","Reproduction - net reproductive rate","LOEC","LOEC","Yes","10 neonates","Not stated","Neonates < 2 hours old","USEPA medium","Not stated","Measured","Not stated","Not stated","Yes","CI","Not stated","Not stated","20oC","PFOS 98% from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","598-3"]
["Scores",10,5,5,5,5,5,0,5,5,0,2,0,0,4,4,0,0,1,3,59,0.64835164835164838,null,""]
["Answers","5 days","Survival","NOEC","NOEC","Yes","10 neonates","Not stated","Neonates < 2 hours old","USEPA medium","Not stated","Measured","Not stated","Not stated","Yes","CI","Not stated","Not stated","20oC","PFOS 98% from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","598-4"]
["Scores",10,5,5,5,5,5,0,5,5,0,2,0,0,4,4,0,0,1,3,59,0.64835164835164838,null,""]
["Answers","5 days","Survival","LOEC","LOEC","Yes","10 neonates","Not stated","Neonates < 2 hours old","USEPA medium","Not stated","Measured","Not stated","Not stated","Yes","CI","Not stated","Not stated","20oC","PFOS 98% from Sigma Aldrich"]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","599-2"]
["Scores",10,5,0,0,5,5,0,5,5,0,2,0,0,4,4,0,0,1,3,49,0.53846153846153844,null,""]
["Answers","60 days","Development - metamorphosis","NOEC","NOEC","Yes","Duplicate tanks","Not stated","Stage 8/9 embryos","Lake Superior water","Flow through","Measured","Not stated","Figure 2","Yes","CI","Not stated","Not stated","20oC","PFOS 98% from Fluka chemicals "]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","599-3"]
["Scores",10,5,0,0,5,5,0,5,5,0,2,0,0,4,4,0,0,1,3,49,0.53846153846153844,null,""]
["Answers","60 days","Development - metamorphosis","LOEC","LOEC","Yes","Duplicate tanks","Not stated","Stage 8/9 embryos","Lake Superior water","Flow through","Measured","Not stated","Figure 2","Yes","CI","Not stated","Not stated","20oC","PFOS 98% from Fluka chemicals "]
["Category","Freshwater/non-metal/non- plant","Paper and data unique identifier(eg. 1-1,10-150)","3045-1"]
["Scores",10,5,0,0,5,5,0,5,5,0,0,0,0,4,4,0,0,1,3,47,0.51648351648351654,null,"The highest possible grade for this datum is acceptable."]
["Answers","45 days between NF stages 46/47 and NF stage 62","Survival","NOEC","NOEC","Yes","Duplicate tanks","Not stated","6 dpf (NF State 46/47)","Dechlorinated tap water","Static renewal - changed twice a week","Not stated","Not stated","Figure 2","Yes","p < 0.05","Not stated","Not stated","20-24oC","PFOS > 96% from Fluka "]

{"sheet":"FW nonmetal plant","index":7,"n_rows":79,"n_cols":53,"rows_kept":79,"cut":false,"hidden":false,"merged":[[3,4,7,4],[9,2,9,4],[11,2,13,2],[11,7,13,7],[14,2,16,2],[14,7,16,7],[17,2,19,2],[17,7,19,7],[20,2,21,2],[20,7,21,7],[22,2,24,2],[22,7,24,7],[25,2,27,2],[25,7,27,7],[28,2,30,2],[28,7,30,7],[31,2,33,2],[31,7,33,7],[34,2,36,2],[34,7,36,7],[37,2,39,2],[37,7,39,7],[40,2,42,2],[40,7,42,7],[43,2,45,2],[43,7,45,7],[46,2,48,2],[46,7,48,7],[49,2,51,2],[49,7,51,7],[60,2,62,2],[60,7,62,7],[63,2,66,2],[63,7,66,7],[52,2,54,2],[52,7,54,7],[56,2,59,2],[56,7,59,7]]}
[null,1,"Fill in the blank cells below, based on information provided in the paper being assessed. You can either pick an option from the dropdown list or add the appropriate detail using the 'Add to list' button. ",null,null,null,null,null,null,null,null,null,null,null,"* All the text in RED are used for drop down list ,make changes with caution."]
[null,null,"Category",{"$f":"IF(AF3=\"\",0,1)","v":1},"Freshwater/non-metal/plant",{"$f":"IF(E3=\"\",0,1)","v":1},"Citation No.",{"$f":"IF(ISERROR(FIND(\"-\",E3)),E3,LEFT(E3,FIND(\"-\",E3)-1))","v":"3044"},null,"Taxonomic group",null,null,null,null,"Species",null,null,"Lifestage",null,null,"Exposure duration",null,null,"Measure of toxicity",null,null,"Toxicity endpoint",null,null,"Taxonomic group",null,null,"Phylum",null,null,"Class",null,null,"Media",null,null,"Temperature ",null,null,"Acute Or Chronic",null,null,"PH",null,null,"Salinity/Conductivity"]
[null,null,"Paper and data unique identifier(eg. 1-1,10-150)",{"$f":"IF(AI3=\"\",0,1)","v":1},"3044-3",{"$f":"IF(E4=\"\",0,1)","v":1},"Species (Scientific name)",null,null,"Phylum",null,null,null,null,"Acutodesmus obliquus",11,{"$f":"IF(P3=0,\"\",INDEX(O3:O100,P3))","v":"Lemna gibba"},"1 month",9,{"$f":"IF(S3=0,\"\",INDEX(R3:R100,S3))","v":"not stated"},"11 hours",5,{"$f":"IF(V3=0,\"\",INDEX(U3:U100,V3))","v":"42 days"},"EC1",11,{"$f":"IF(Y3=0,\"\",INDEX(X3:X100,Y3))","v":"LOEC"},"Bioluminescence",20,{"$f":"IF(AB3=0,\"\",INDEX(AA3:AA100,AB3))","v":"Growth"},"Blue-green algae",4,{"$f":"IF(AE3=0,\"\",INDEX(AD3:AD100,AE3))","v":"Macrophyte"},"Chlorophyta",6,{"$f":"IF(AH3=0,\"\",INDEX(AG3:AG100,AH3))","v":"Tracheophyta"},"Bacillariophyceae",7,{"$f":"IF(AK3=0,\"\",INDEX(AJ3:AJ102,AK3))","v":"Liliopsida"},"50 mL AA/8 supplemented with nitrate (5 mM) in 125 ml Erlenmeyer ?asks and 10 mg/mL of neomycin sulphate (Nm)",13,{"$f":"IF(AN3=0,\"\",INDEX(AM3:AM100,AN3))","v":"Irrigation pond water"},20,20,{"$f":"IF(AQ3=0,\"\",INDEX(AP3:AP100,AQ3))","v":"15.9-20.5"},"Acute ",3,{"$f":"IF(AT3=0,\"\",INDEX(AS3:AS100,AT3))","v":"Chronic"},5.50,17,{"$f":"IF(AW3=0,\"\",INDEX(AV3:AV100,AW3))","v":"8.3-8.8"},"30 ppt",null,"N.A."]
[null,null,"Citation",{"$f":"IF(AL3=\"\",0,1)","v":1},"Boudreau, T.M., C.J. Wilson, W.J. Cheong, P.K. Sibley, S.A. Mabury, P.C.G. Muir and K.R. Solomon. 2003. Response of the zooplankton community and environmental fate of perfluorooctane sulfonic acid in aquatic microcosms. Environmental Toxicology and Chemistry 22: 2739-2745.",{"$f":"IF(AX3=\"\",0,1)","v":1},"Lifestage",null,null,"Class",null,null,null,null,"Aedes albopictus",null,null,"1 year old",null,null,"13 days ",null,null,"EC10",null,null,"cartenoid conc. ",null,null,"Cyano",null,null,"Cyanobacteria",null,null,"Branchiopoda",null,null,"AAP",null,null,21,null,null,"Chronic",null,null,6.70,null,null,"150 uS/cm"]
[null,null,null,{"$f":"IF(AO3=\"\",0,1)","v":1},null,{"$f":"IF(H8=\"\",0,1)","v":1},"Exposure duration",null,null,"Media",null,null,null,null,"Anabaena CPB4337",null,null,"28 days",null,null,"24 hr",null,null,"EC10",null,null,"Chlorophyll a conc. ",null,null,"Fish",null,null,"N.A.",null,null,"Chlorophyceae",null,null,"Algae culture medium and purified well water",null,null,22,null,null,"Chronic",null,null,6.90,null,null,"N.A."]
[null,null,null,{"$f":"IF(AR3=\"\",0,1)","v":1},null,{"$f":"IF(Q3=\"\",0,1)","v":1},"Measure of toxicity",null,null,"Temperature ",null,null,null,null,"Anabaena flos-aquae",null,null,"Exponential growth phase",null,null,"3 days",null,null,"EC20",null,null,"Chlorophyll b conc. ",null,null,"Macrophyte",null,null,"Spermatophyta",null,null,"Chlorophyceae",null,null,"Algal medium",null,null,28,null,null,"N.A.",null,null,7.50]
[null,null,null,{"$f":"IF(AU3=\"\",0,1)","v":1},null,{"$f":"IF(T3=\"\",0,1)","v":1},"Toxicity endpoint",null,null,"Acute Or Chronic ",null,null,null,null,"Australian Bass",null,null,"Exponential growth phase",null,null,"42 days",null,null,"EC50",null,null,"Frond number",null,null,"Microalga",null,null,"Tracheophyta",null,null,"Cyanophyceae",null,null,"Algal medium using deionized water",null,null,"15°C",null,null,null,null,null,7.70]
[null,null,null,null,null,{"$f":"IF(W3=\"\",0,1)","v":1},"Toxicity value","3000 ug/L",null,"PH",null,null,null,null,"Chlorella pyrenoidosa",null,null,"logarithmic growth phase",null,null,"6 days",null,null,"EC80",null,null,"Growth inhibition",null,null,"N.A.",null,null,"Tracheophyta",null,null,"Cyanophyceae",null,null,"algaltoxkit",null,null,"18-22",null,null,null,null,null,7.80]
[null,2,"Select the appropriate answer option to each question. Comments can be added to the cells in column H.",null,null,{"$f":"IF(Z3=\"\",0,1)","v":1},null,null,null,"Salinity/Conductivity","N.A.",null,null,null,"Chlorella pyrenoidosa",null,null,"N.A.",null,null,"7 days",null,null,"IC10",null,null,"Growth Inhibition: Algal Biomass (cell counts)",null,null,"plantae",null,null,null,null,null,"Liliopsida",null,null,"Bristols algal growing media",null,null,"20 ± 1°C",null,null,null,null,null,"7.4-7.6"]
[null,"*","If the selected answer option does not work try clicking on any other cell first and then click back on the answer option again.",null,null,{"$f":"IF(AC3=\"\",0,1)","v":1},null,null,null,null,null,null,null,null,"Chlorella vulgaris",null,null,"not stated",null,null,"72 hour",null,null,"IC50",null,null,"Growth inhibition: AUC",null,null,null,null,null,null,null,null,"Magnoliopsida",null,null,"Bristols algal growing media",null,null,"21-24",null,null,null,null,null,"7.5 - 8.3"]
[null,"No.","Question","Marks Awarded","Answer Options","Option References","Scores","Answers",null,null,null,null,null,null,"Chlorella vulgaris",null,null,"not stated",null,null,"96 hrs",null,null,"IC90",null,null,"Growth inhibition: cell count",null,null,null,null,null,null,null,null,"Magnoliopsida",null,null,"Freshwater",null,null,"21-24 ± 2",null,null,null,null,null,"7.5 ± 0.2"]
[null,null,"Was the duration of the exposure stated (e.g. 48 or 96 h)?",10,null,1,{"$f":"IF(F15=0,0,INDEX($D12:$D13,F12,1))","v":10},"42 days",null,null,null,null,null,null,"Dunaliella tertiolecta",null,null,null,null,null,"N.A.",null,null,"LC50",null,null,"Growth inhibition: growth rate",null,null,null,null,null,null,null,null,"N.A.",null,null,"HB4",null,null,"22 ± 1°C",null,null,null,null,null,"7.7-7.9"]
[null,1,null,0,null,null,null,null,null,null,null,null,null,null,"Lemna gibba",null,null,null,null,null,"28 days",null,null,"LOEC",null,null,"Mortality",null,null,null,null,null,null,null,null,"Trebouxiophyceae",null,null,"HGZ media",null,null,"22.8 - 23.8oC",null,null,null,null,null,"N.A."]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Lemna minor",null,null,null,null,null,"28 days",null,null,"N.A.",null,null,"N.A.",null,null,null,null,null,null,null,null,"Trebouxiophyceae",null,null,"Hunters growing media",null,null,"22±1oC",null,null,null,null,null,"N.A."]
[null,null,"Was the biological endpoint (e.g., immobilization or population growth) stated and defined (10 marks)? Award 5 marks if the biological endpoint is only stated.",10,null,2,{"$f":"IF(F15=0,0,INDEX($D15:$D17,F15,1))","v":5},"Growth - frond number",null,null,null,null,null,null,"Mirocystis aeruginosa",null,null,null,null,null,null,null,null,"NOEC",null,null,"population growth",null,null,null,null,null,null,null,null,"Trebouxiophyceae",null,null,"Irrigation pond water",null,null,"23oC",null,null,null,null,null,"not stated"]
[null,2,null,5,null,null,null,null,null,null,null,null,null,null,"Mycrocystis flos-aquae",null,null,null,null,null,null,null,null,"Population: Growth Rate: Frond count",null,null,"Population: Abundance: Biomass (Chl-a)",null,null,null,null,null,null,null,null,null,null,null,"M4",null,null,"23oC",null,null,null,null,null,"not stated"]
[null,null,null,0,null,null,null,null,null,null,null,null,null,null,"Myriophyllum sibiricum",null,null,null,null,null,null,null,null,null,null,null,"Population: Growth Rate: Front count",null,null,null,null,null,null,null,null,null,null,null,"Marinewater",null,null,"25 ± 2°C",null,null,null,null,null,"PH11"]
[null,null,"Was the biological effect stated (e.g. LC or NOEC)?",5,null,1,{"$f":"IF(F18=0,0,INDEX($D18:$D19,F18,1))","v":5},"LOEC",null,null,null,null,null,null,"N.A.",null,null,null,null,null,null,null,null,null,null,null,"Reproduction",null,null,null,null,null,null,null,null,null,null,null,"Moderately hard standard water",null,null,"25°C",null,null,null,null,null,"PH7.0"]
[null,3,null,0,null,null,null,null,null,null,null,null,null,null,"Navicula pelliculosa",null,null,null,null,null,null,null,null,null,null,null,"Wet weight",null,null,null,null,null,null,null,null,null,null,null,"N.A.",null,null,"N.A.",null,null,null,null,null,"8.3-8.8"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Pseudokirchneriella subcapitata",null,null,null,null,null,null,null,null,null,null,null,"Biomass",null,null,null,null,null,null,null,null,null,null,null,"not stated",null,null,"Not stated"]
[null,4,"Was the biological effect quantified (e.g. 50% effect, 25% effect)? \nNote: The effect for NOEC and LOEC data must be quantified.",5,null,2,{"$f":"IF(F21=0,0,INDEX($D21:$D22,F21,1))","v":0},"LOEC",null,null,null,null,null,null,"raphidocelis subcapitata",null,null,null,null,null,null,null,null,null,null,null,"Growth: Length",null,null,null,null,null,null,null,null,null,null,null,"Steinberg medium",null,null,"24oC"]
[null,null,null,0,null,null,null,null,null,null,null,null,null,null,"Raphidocelis subcapitata",null,null,null,null,null,null,null,null,null,null,null,"Growth",null,null,null,null,null,null,null,null,null,null,null,"Sterilised and filtered offshore marine water",null,null,"15.9-20.5"]
[null,5,"Were appropriate controls (e.g. a no-toxicant control and/or solvent control) used?",5,null,1,{"$f":"IF(F23=0,0,INDEX($D23:$D24,F23,1))","v":5},"Yes",null,null,null,null,null,null,"Raphidocelis subcapitata",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sterilised culture medium"]
[null,null,null,0,null,null,null,null,null,null,null,null,null,null,"Raphidocelis subcapitata"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Scendesmus quadricauda"]
[null,6,"Was each control and contaminant concentration at least duplicated?",5,null,1,{"$f":"IF(F26=0,0,INDEX($D26:$D27,F26,1))","v":5},"Triplicate",null,null,null,null,null,null,"Scenedesmus obliguus"]
[null,null,null,0,null,null,null,null,null,null,null,null,null,null,"Scenedesmus obliquus"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Scenedesmus obliquus"]
[null,7,"Were test acceptability criteria stated (e.g. mortality in controls must not exceed a certain percentage) (5 marks)?\nOR Were test acceptability criteria inferred (e.g. test method used [USEPA, OECD, ASTM etc.]) (award 2 marks). \nNote: Data that fail the acceptability criteria are automatically deemed to be of unacceptable quality and must not be used. ",5,null,3,{"$f":"IF(F29=0,0,INDEX($D29:$D31,F29,1))","v":0},"Not stated",null,null,null,null,null,null,"Scenedesmus quadricauda"]
[null,null,null,2,null,null,null,null,null,null,null,null,null,null,"Scenedesmus quadricauda"]
[null,null,null,0,null,null,null,null,null,null,null,null,null,null,"Scenedesmus vacuolatus"]
[null,8,"Were the characteristics of the test organism (e.g. length, mass, age) stated?",5,null,2,{"$f":"IF(F32=0,0,INDEX($D32:$D34,F32,1))","v":0},"Small plants",null,null,null,null,null,null,"Selenastrum capricornutum"]
[null,null,null,0,null,null,null,null,null,null,null,null,null,null,"Selenastrum capricornutum"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Myriophyllum spicatam"]
[null,9,"Was the type of test media used stated?",5,null,1,{"$f":"IF(F35=0,0,INDEX($D35:$D37,F35,1))","v":5},"Irrigation pond water",null,null,null,null,null,null,"Myriophyllum spicatam"]
[null,null,null,0]
[]
[null,null,"Was the type of exposure (e.g. static, flow through) stated? ",4,null,2,{"$f":"IF(F38=0,0,INDEX($D38:$D40,F38,1))","v":0},"Not stated"]
[null,10,null,0]
[]
[null,null,"Were the contaminant concentrations measured at the beginning and end of the exposure (4 marks)? Award 2 marks if they were measured only once during the test.\nNote: If the concentrations were not measured then automatically the data cannot be high quality. ",4,null,1,{"$f":"IF(F41=0,0,INDEX($D41:$D43,F41,1))","v":4},"Measured"]
[null,11,null,2]
[null,null,null,0]
[null,null,"Were parallel reference toxicant toxicity tests conducted?",4,null,2,{"$f":"IF(F44=0,0,INDEX($D44:$D46,F44,1))","v":0},"Not stated"]
[null,12,null,0]
[]
[null,null,"Was there a concentration–response relationship either observable or stated?",4,null,1,{"$f":"IF(F47=0,0,INDEX($D47:$D49,F47,1))","v":4},"Figure 6"]
[null,13,null,0]
[]
[null,null,"Was an appropriate statistical method or model used to determine the toxicity?\nNote: They should be accepted by a recognised national or international regulatory body (e.g. USEPA, OECD, ASTM). ",4,null,1,{"$f":"IF(F50=0,0,INDEX($D50:$D52,F50,1))","v":4},"Yes"]
[null,14,null,0]
[]
[null,15,"For LC/EC/BEC data was an estimate of variability provided? \nOR \nFor NO EC/LOEC data was the significance level 0.05 or less?  \n\n",4,null,1,{"$f":"IF(F53=0,0,INDEX($D53:$D55,F53,1))","v":4},"Yes"]
[null,null,null,0]
[]
[null,16,"Were the following parameters measured and stated? (3 marks if measured and stated, 1 mark if just measured)."]
[null,null,"pH",3,null,1,{"$f":"IF(F57=0,0,INDEX($D57:$D59,F57,1))","v":3},"8.3-8.3"]
[null,16.10,null,1]
[null,null,null,0]
[]
[null,null,"Was the temperature measured and stated (3 marks)? Award 1 mark if the temperature was measured but not stated or if only the temperature settings of the room or chamber are stated.",3,null,1,{"$f":"IF(F61=0,0,INDEX($D61:$D63,F61,1))","v":3},"15.9 - 20.5oC"]
[null,17,null,1]
[null,null,null,0]
[null,null,"Were test solutions, blanks and/or controls tested for contamination OR were analytical reagent grade chemicals used or the highest possible purity chemicals used for the experiment? (3 marks).",3,null,1,{"$f":"IF(F64=0,0,INDEX($D64:$D65,F64,1))","v":3},"PFOS-K 86% from 3 M (Fluorad fluorochemical surfactant FC-95)"]
[null,18,null,0]
[]
[null,null,null,null,null,null,null,null,{"$f":"COUNTIF(D2:D7,\"=0\")+COUNTIF(F2:F10,\"=0\")+COUNTIF(F12:F64,\"=0\")","v":0}]
[]
[]
[null,null,"Total score",null,null,null,{"$f":"IF(SUM(G12:G67)=0,\"\",SUM(G12:G67))","v":60}]
[null,null,"Total Max. possible score for the various types of data and contaminants ",null,{"$f":"D12+D15+D18+D21+D23+D26+D29+D32+D35+D38+D41+D44+D47+D50+D53+D57+D61+D64","v":88}]
[null,null,"Quality Score",null,{"$f":"\"= [Total score / Total possible score] * 100 = \"","v":"= [Total score / Total possible score] * 100 = "},null,{"$f":"IF(ISERROR(G70/E71),#N/A,G70/E71)","v":0.68181818181818177},{"$f":"IF(F41=3,\"The highest possible grade for this datum is acceptable.\",\"\")","v":""}]
[]
[null,null,"H = high quality                           Quality score ≥ 80%  "]
[null,null,"A = acceptable quality         > 50% Quality score < 80%     "]
[null,null,"U = unacceptable quality              Quality score ≤ 50%"]
[]
[3,null,"Click the 'Save & Update' button to save and export the answers to the 'All results' worksheet. "]
[null,null,"Select the 'Reset Answers' button if you wish to clear all answers."]

{"sheet":"FW nonmetal plant_WS","index":8,"n_rows":198,"n_cols":22,"rows_kept":198,"cut":false,"hidden":false,"merged":[]}
[]
["Question No.",1,2,3,4,5,6,7,8,9,10,11,12,13,14,15,16.10,17,18,"Total Score","Quality Score","Comment "]
["Short Questions","Duration of the exposure ","Biological endpoint","Biological effect stated or not","Biological effect quantified or not","Appropriate controls","Control & contaminant concentration","Test acceptability criteria","Characteristics of the test organism"," Type of test media","Type of exposure","Contaminant concentrations","Parallel reference toxicant toxicity tests","Concentration–response relationship","Determine the toxicity","NOEC/LOEC or LC/EC/BEC","pH","Temperature","Grade or purity"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","3018-9"]
["Scores",10,5,5,5,5,5,0,5,5,4,2,0,0,4,4,3,3,3,68,0.77272727272727271,""]
["Answers","96 hours","Growth inhibition ","LC50","","blank controls","Three replicates","","Logarithmic growth phase","M4 medium","Static with renewal at 48 hour intervals ","Measured using HPLC-MS. It doesn’t state how many times the solutions were measured. ","","","p<0.01","p<0.01","7 ± 0.5 measured once a day ","Measured once a day 22 ± 2 oC","Highest possible purity chemicals used - 99% pure"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","431-1"]
["Scores",10,5,5,5,5,5,0,5,5,4,0,0,0,4,4,1,3,3,64,0.72727272727272729,"The highest possible grade for this datum is acceptable."]
["Answers","96 hours","Cell density","IC50","IC50","","","","No but assumed based on methodology ","Bristols algal growing media","Static - based on methodology","","","","p ≤ 0.05","p ≤ 0.05","","23oC","Highest possible purity (95%)"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","431-20"]
["Scores",10,5,5,5,5,5,0,5,5,4,0,0,0,4,4,1,3,3,64,0.72727272727272729,"The highest possible grade for this datum is acceptable."]
["Answers","96 hours","Chlorophyll a","IC50","IC50","","","","No but assumed based on methodology ","Bristols algal growing media","Static - based on methodology","","","","p ≤ 0.05","p ≤ 0.05","","23oC","Highest possible purity (95%)"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","431-22"]
["Scores",10,5,5,5,5,5,0,5,5,4,0,0,0,4,4,1,3,3,64,0.72727272727272729,"The highest possible grade for this datum is acceptable."]
["Answers","96 hours","Chlorophyll a","NOEC","NOEC","","","","No but assumed based on methodology ","Bristols algal growing media","Static - based on methodology","","","","p ≤ 0.05","p ≤ 0.05","","23oC","Highest possible purity (95%)"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","431-16"]
["Scores",10,5,5,5,5,5,0,5,5,4,0,0,0,4,4,1,3,3,64,0.72727272727272729,"The highest possible grade for this datum is acceptable."]
["Answers","7 days","Frond number","NOEC","NOEC","","","","No but assumed based on methodology ","Hunters growing media","Static - based on methodology","","","","p ≤ 0.05","p ≤ 0.05","","25oC","Highest possible purity (95%)"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","431-17"]
["Scores",10,5,5,5,5,5,0,5,5,4,0,0,0,4,4,1,3,3,64,0.72727272727272729,"The highest possible grade for this datum is acceptable."]
["Answers","7 days","Wet weight","IC50","IC50","","","","No but assumed based on methodology ","Hunters growing media","Static - based on methodology","","","","p ≤ 0.05","p ≤ 0.05","","25oC","Highest possible purity (95%)"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","431-15"]
["Scores",10,5,5,5,5,5,0,5,5,4,0,0,0,4,4,1,3,3,64,0.72727272727272729,"The highest possible grade for this datum is acceptable."]
["Answers","7 days","Frond number","IC50","IC50","","","","No but assumed based on methodology ","Hunters growing media","Static - based on methodology","","","","p ≤ 0.05","p ≤ 0.05","","25oC","Highest possible purity (95%)"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","431-18"]
["Scores",10,5,5,5,5,5,0,5,5,4,0,0,0,4,4,1,3,3,64,0.72727272727272729,"The highest possible grade for this datum is acceptable."]
["Answers","7 days","Frond number","NOEC","NOEC","","","","No but assumed based on methodology ","Hunters growing media","Static - based on methodology","","","","p ≤ 0.05","p ≤ 0.05","","25oC","Highest possible purity (95%)"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","431-2"]
["Scores",10,5,5,5,5,5,0,5,5,4,0,0,0,4,4,1,3,3,64,0.72727272727272729,"The highest possible grade for this datum is acceptable."]
["Answers","95 hours","Cell density ","NOEC","NOEC","","","","No but assumed based on methodology ","Bristols algal growing media","Static - based on methodology","","","","p ≤ 0.05","p ≤ 0.05","","23oC","Highest possible purity (95%)"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","431-3"]
["Scores",10,5,5,5,5,5,0,5,5,4,0,0,0,4,4,1,3,3,64,0.72727272727272729,"The highest possible grade for this datum is acceptable."]
["Answers","95 hours","Chlorophyll (a)","IC50","IC50","","","","No but assumed based on methodology ","Bristols algal growing media","Static - based on methodology","","","","p ≤ 0.05","p ≤ 0.05","","23oC","Highest possible purity (95%)"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","431-4"]
["Scores",10,5,5,5,5,5,0,5,5,4,0,0,0,4,4,1,3,3,64,0.72727272727272729,"The highest possible grade for this datum is acceptable."]
["Answers","95 hours","Chlorophyll (a)","IC50","IC50","","","","No but assumed based on methodology ","Bristols algal growing media","Static - based on methodology","","","","p ≤ 0.05","p ≤ 0.05","","23oC","Highest possible purity (95%)"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","431-21"]
["Scores",10,5,5,5,5,5,0,5,5,4,0,0,0,4,4,1,3,3,64,0.72727272727272729,"The highest possible grade for this datum is acceptable."]
["Answers","95 hours","Cell density ","NOEC","NOEC","","","","No but assumed based on methodology ","Bristols algal growing media","Static - based on methodology","","","","p ≤ 0.05","p ≤ 0.05","","23oC","Highest possible purity (95%)"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","431-19"]
["Scores",10,5,5,5,5,5,0,5,5,4,0,0,0,4,4,1,3,3,64,0.72727272727272729,"The highest possible grade for this datum is acceptable."]
["Answers","95 hours","Cell density ","IC50","IC50","","","","No but assumed based on methodology ","Bristols algal growing media","Static - based on methodology","","","","p ≤ 0.05","p ≤ 0.05","","23oC","Highest possible purity (95%)"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","432-1"]
["Scores",10,10,5,5,5,5,0,5,5,4,0,0,4,4,4,1,1,0,68,0.77272727272727271,"The highest possible grade for this datum is acceptable."]
["Answers","72 hours","Growth Rate","IC10","IC10","","","OECD guidelines","","Algal medium","Static","","","Figure 1","","","","",""]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","432-2"]
["Scores",10,10,5,5,5,5,0,5,5,4,0,0,4,4,4,1,1,0,68,0.77272727272727271,"The highest possible grade for this datum is acceptable."]
["Answers","72 hours","Growth Rate","IC50","IC50","","","OECD guidelines","","Algal medium","Static","","","Figure 1","","","","",""]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","432-3"]
["Scores",10,10,5,5,5,5,0,5,5,4,0,0,4,4,4,1,1,0,68,0.77272727272727271,"The highest possible grade for this datum is acceptable."]
["Answers","72 hours","Growth Rate","IC10","IC10","","","OECD guidelines","","Algal medium","Static","","","Figure 1","","","","",""]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","432-4"]
["Scores",10,10,5,5,5,5,0,5,5,4,0,0,4,4,4,1,1,0,68,0.77272727272727271,"The highest possible grade for this datum is acceptable."]
["Answers","72 hours","Growth Rate","IC50","IC50","","","OECD guidelines","","Algal medium","Static","","","Figure 1","","","","",""]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","705-1"]
["Scores",10,5,5,5,5,5,2,5,5,0,2,0,0,4,4,3,3,3,66,0.75,""]
["Answers","96 hours","Growth ","NOEC","NOEC","","","Method presented","","Algae culture medium and purified well water","","","","","","","7.4-7.6","22.8 to 23.8oC","Sample from 3M production lot number 217. The test substance is a white powder. Purity\ndetermined to be 86.9% by LC/MS, 1H-HMR, 19F-NMR and elemental analyses techniques."]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","705-2"]
["Scores",10,5,5,5,5,5,2,5,5,0,2,0,0,4,4,3,3,3,66,0.75,""]
["Answers","96 hours","Cell density ","EC10","EC10","","","Method presented","","Algae culture medium and purified well water","","","","","","","7.4-7.6","22.8 to 23.8oC","Sample from 3M production lot number 217. The test substance is a white powder. Purity\ndetermined to be 86.9% by LC/MS, 1H-HMR, 19F-NMR and elemental analyses techniques."]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","705-3"]
["Scores",10,5,5,5,5,5,2,5,5,0,2,0,0,4,4,3,3,3,66,0.75,""]
["Answers","96 hours","Cell density ","EC50","EC50","","","Method presented","","Algae culture medium and purified well water","","","","","","","7.4-7.6","22.8 to 23.8oC","Sample from 3M production lot number 217. The test substance is a white powder. Purity\ndetermined to be 86.9% by LC/MS, 1H-HMR, 19F-NMR and elemental analyses techniques."]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","705-4"]
["Scores",10,5,5,5,5,5,2,5,5,0,2,0,0,4,4,3,3,3,66,0.75,""]
["Answers","96 hours","Cell density ","NOEC","NOEC","","","Method presented","","Algae culture medium and purified well water","","","","","","","7.4-7.6","22.8 to 23.8oC","Sample from 3M production lot number 217. The test substance is a white powder. Purity\ndetermined to be 86.9% by LC/MS, 1H-HMR, 19F-NMR and elemental analyses techniques."]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","705-5"]
["Scores",10,5,5,5,5,5,2,5,5,0,2,0,0,4,4,3,3,3,66,0.75,""]
["Answers","96 hours","Cell density ","EC50","EC50","","","Method presented","","Algae culture medium and purified well water","","","","","","","7.4-7.6","22.8 to 23.8oC","Sample from 3M production lot number 217. The test substance is a white powder. Purity\ndetermined to be 86.9% by LC/MS, 1H-HMR, 19F-NMR and elemental analyses techniques."]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","705-6"]
["Scores",10,5,5,5,5,5,2,5,5,0,2,0,0,4,4,3,3,3,66,0.75,""]
["Answers","96 hours","Cell density ","EC10","EC10","","","Method presented","","Algae culture medium and purified well water","","","","","","","7.4-7.6","22.8 to 23.8oC","Sample from 3M production lot number 217. The test substance is a white powder. Purity\ndetermined to be 86.9% by LC/MS, 1H-HMR, 19F-NMR and elemental analyses techniques."]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","710-1"]
["Scores",10,5,5,5,0,0,0,0,5,4,0,4,0,4,4,0,1,3,50,0.56818181818181823,"The highest possible grade for this datum is acceptable."]
["Answers","96 hours, 4 days","Inhibition of constitutive luminescence","EC50 presented in Table 1","50% effect","","number of replicates not specified. ","","","50 mL AA/8 supplemented with nitrate (5mM) in 125 mL Erlenmeyer flasks and 10 mg/mL of neomycin sulphate (Nm). ","Static ","","Antibacterial agent triclosan assessed","","95% Confidence Intervals calculated. ","95% Confidence Intervals calculated. ","","Stated: 28oC","Analytical reagent grade chemicals used (PFOS potassium salt at 98% purchased from Fluka) "]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","432-1"]
["Scores",10,5,5,5,5,5,2,5,5,4,0,0,4,4,4,3,3,3,72,0.81818181818181823,"The highest possible grade for this datum is acceptable."]
["Answers","72 hours","Growth rate","IC10",0.10,"","","OECD guidelines","","Algal medium was prepared using deionized water ","Static","","","Figure 1","","","","","Analytical reagent grade chemicals used (Sigma-Aldrich)"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","432-2"]
["Scores",10,5,5,5,5,5,2,5,5,4,0,0,4,4,4,3,3,3,72,0.81818181818181823,"The highest possible grade for this datum is acceptable."]
["Answers","72 hours","Growth rate","IC50",50,"","","OECD guidelines","","Algal medium was prepared using deionized water ","Static","","","Figure 1","","","","","Analytical reagent grade chemicals used (Sigma-Aldrich)"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","432-3"]
["Scores",10,5,5,5,5,5,2,5,5,4,0,0,4,4,4,3,3,3,72,0.81818181818181823,"The highest possible grade for this datum is acceptable."]
["Answers","72 hours","Growth rate - optical denisty","IC10",10,"","","OECD guidelines","","Algal medium was prepared using deionized water ","Static","","","Figure 1","","","","","Analytical reagent grade chemicals used (Sigma-Aldrich)"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","432-4"]
["Scores",10,5,5,5,5,5,2,5,5,4,0,0,4,4,4,3,3,3,72,0.81818181818181823,"The highest possible grade for this datum is acceptable."]
["Answers","72 hours","Growth rate - optical denisty","IC50",50,"","","OECD guidelines","","Algal medium was prepared using deionized water ","Static","","","Figure 1","","","","","Analytical reagent grade chemicals used (Sigma-Aldrich)"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","709-1"]
["Scores",10,5,5,5,5,5,2,5,5,4,4,0,0,4,4,1,1,0,65,0.73863636363636365,""]
["Answers","42 days","Growth - root length","EC10","EC10","","","ASTM guidelines","Apical shoots of a certain length","Irrigation pond water","Static","","","","","","","",""]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","709-2"]
["Scores",10,5,5,5,5,5,2,5,5,4,4,0,0,4,4,1,1,0,65,0.73863636363636365,""]
["Answers","28 days","Length","EC10","EC10","","","ASTM guidelines","Apical shoots of a certain length","Irrigation pond water","Static","","","","","","","",""]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","3040-1"]
["Scores",10,5,5,5,5,5,0,5,5,0,0,0,4,4,0,0,1,3,57,0.64772727272727271,"The highest possible grade for this datum is acceptable."]
["Answers","96 hours","Proliferation inhibition","EC50","EC50","Yes","Triplicate","Not stated","Logarithmic growth phase, initial concentration approximately 7 x 1000000 cells/ml","HB4 culture medium","Not stated","Not stated","Not stated","Described in results","Not stated","Not stated","Not stated","24oC","PFOS (hepadecafluorooctanesulfonic acid potasium salt) analytical purity"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","3040-2"]
["Scores",10,5,0,0,5,5,0,5,5,0,0,0,4,4,0,0,1,3,47,0.53409090909090906,"The highest possible grade for this datum is acceptable."]
["Answers","96 hours","Proliferation inhibition","NOEC","NOEC","Yes","Triplicate","Not stated","Logarithmic growth phase, initial concentration approximately 7 x 1000000 cells/ml","HB4 culture medium","Not stated","Not stated","Not stated","Described in results","Not stated","Not stated","Not stated","24oC","PFOS (hepadecafluorooctanesulfonic acid potasium salt) analytical purity"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","3040-3"]
["Scores",10,5,0,0,5,5,0,5,5,0,0,0,4,4,0,0,1,3,47,0.53409090909090906,"The highest possible grade for this datum is acceptable."]
["Answers","96 hours","Proliferation inhibition","LOEC","LOEC","Yes","Triplicate","Not stated","Logarithmic growth phase, initial concentration approximately 7 x 1000000 cells/ml","HB4 culture medium","Not stated","Not stated","Not stated","Described in results","Not stated","Not stated","Not stated","24oC","PFOS (hepadecafluorooctanesulfonic acid potasium salt) analytical purity"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","709-3"]
["Scores",10,5,5,0,5,5,2,5,5,0,4,0,4,4,4,1,1,3,63,0.71590909090909094,""]
["Answers","42 days","Growth - plant length","EC10","EC10","Yes","Triplicate","ASTM 1999 guidelines","Apical shoots 5cm","Irrigation pond water","Not stated","Measured","Not stated","Table 3","p < 0.05","p < 0.05","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","PFOS from 3M - purity not stated"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","709-4"]
["Scores",10,5,5,0,5,5,2,5,5,0,4,0,4,4,4,1,1,3,63,0.71590909090909094,""]
["Answers","42 days","Growth - root number","EC10","EC10","Yes","Triplicate","ASTM 1999 guidelines","Apical shoots 5cm","Irrigation pond water","Not stated","Measured","Not stated","Table 3","p < 0.05","p < 0.05","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","PFOS from 3M - purity not stated"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","709-5"]
["Scores",10,5,5,0,5,5,2,5,5,0,4,0,4,4,4,1,1,3,63,0.71590909090909094,""]
["Answers","42 days","Growth - root length","EC10","EC10","Yes","Triplicate","ASTM 1999 guidelines","Apical shoots 5cm","Irrigation pond water","Not stated","Measured","Not stated","Table 3","p < 0.05","p < 0.05","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","PFOS from 3M - purity not stated"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","709-6"]
["Scores",10,5,5,0,5,5,2,5,5,0,4,0,4,4,4,1,1,3,63,0.71590909090909094,""]
["Answers","42 days","Growth - wet mass","EC10","EC10","Yes","Triplicate","ASTM 1999 guidelines","Apical shoots 5cm","Irrigation pond water","Not stated","Measured","Not stated","Table 3","p < 0.05","p < 0.05","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","PFOS from 3M - purity not stated"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","709-7"]
["Scores",10,5,5,0,5,5,2,5,5,0,4,0,4,4,4,1,1,3,63,0.71590909090909094,""]
["Answers","42 days","Growth - dry mass","EC10","EC10","Yes","Triplicate","ASTM 1999 guidelines","Apical shoots 5cm","Irrigation pond water","Not stated","Measured","Not stated","Table 3","p < 0.05","p < 0.05","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","PFOS from 3M - purity not stated"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","709-8"]
["Scores",10,5,5,0,5,5,2,5,5,0,4,0,4,4,4,1,1,3,63,0.71590909090909094,""]
["Answers","42 days","Growth - plant length","EC10","EC10","Yes","Triplicate","ASTM 1999 guidelines","Apical shoots 5cm","Irrigation pond water","Not stated","Measured","Not stated","Table 2","p < 0.05","p < 0.05","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","PFOS from 3M - purity not stated"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","709-9"]
["Scores",10,5,5,0,5,5,2,5,5,0,4,0,4,4,4,1,1,3,63,0.71590909090909094,""]
["Answers","28 days","Growth - root number","EC10","EC10","Yes","Triplicate","ASTM 1999 guidelines","Apical shoots 5cm","Irrigation pond water","Not stated","Measured","Not stated","Table 2","p < 0.05","p < 0.05","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","PFOS from 3M - purity not stated"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","709-10"]
["Scores",10,5,5,0,5,5,2,5,5,0,4,0,4,4,4,1,1,3,63,0.71590909090909094,""]
["Answers","42 days","Growth - root length","EC10","EC10","Yes","Triplicate","ASTM 1999 guidelines","Apical shoots 5cm","Irrigation pond water","Not stated","Measured","Not stated","Table 2","p < 0.05","p < 0.05","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","PFOS from 3M - purity not stated"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","709-11"]
["Scores",10,5,5,0,5,5,2,5,5,0,4,0,4,4,4,1,1,3,63,0.71590909090909094,""]
["Answers","28 days","Growth - root length (longest root)","EC10","EC10","Yes","Triplicate","ASTM 1999 guidelines","Apical shoots 5cm","Irrigation pond water","Not stated","Measured","Not stated","Table 2","p < 0.05","p < 0.05","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","PFOS from 3M - purity not stated"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","709-12"]
["Scores",10,5,5,0,5,5,2,5,5,0,4,0,4,4,4,1,1,3,63,0.71590909090909094,""]
["Answers","42 days","Growth - wet mass","EC10","EC10","Yes","Triplicate","ASTM 1999 guidelines","Apical shoots 5cm","Irrigation pond water","Not stated","Measured","Not stated","Table 2","p < 0.05","p < 0.05","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","PFOS from 3M - purity not stated"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","709-13"]
["Scores",10,5,5,0,5,5,2,5,5,0,4,0,4,4,4,1,1,3,63,0.71590909090909094,""]
["Answers","42 days","Growth - plant length","NOEC","NOEC","Yes","Triplicate","ASTM 1999 guidelines","Apical shoots 5cm","Irrigation pond water","Not stated","Measured","Not stated","Table 2","p < 0.05","Stated","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","PFOS from 3M - purity not stated"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","709-14"]
["Scores",10,5,5,0,5,5,2,5,5,0,4,0,4,4,4,1,1,3,63,0.71590909090909094,""]
["Answers","42 days","Growth - wet mass","EC50","EC50","Yes","Triplicate","ASTM 1999 guidelines","Apical shoots 5cm","Irrigation pond water","Not stated","Measured","Not stated","Table 2","p < 0.05","p < 0.05","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","PFOS from 3M - purity not stated"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","709-15"]
["Scores",10,5,5,0,5,5,2,5,5,0,4,0,4,4,4,1,1,3,63,0.71590909090909094,""]
["Answers","42 days","Growth - wet mass","NOEC","NOEC","Yes","Triplicate","ASTM 1999 guidelines","Apical shoots 5cm","Irrigation pond water","Not stated","Measured","Not stated","Table 2","p < 0.05","p < 0.05","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","PFOS from 3M - purity not stated"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","709-16"]
["Scores",10,5,5,0,5,5,2,5,5,0,4,0,4,4,4,1,1,3,63,0.71590909090909094,""]
["Answers","42 days","Growth -dry mass","NOEC","NOEC","Yes","Triplicate","ASTM 1999 guidelines","Apical shoots 5cm","Irrigation pond water","Not stated","Measured","Not stated","Table 2","p < 0.05","p < 0.05","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","PFOS from 3M - purity not stated"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","709-17"]
["Scores",10,5,5,0,5,5,2,5,5,0,4,0,4,4,4,1,1,3,63,0.71590909090909094,""]
["Answers","42 days","Growth -dry mass","EC50","EC50","Yes","Triplicate","ASTM 1999 guidelines","Apical shoots 5cm","Irrigation pond water","Not stated","Measured","Not stated","Table 2","p < 0.05","p < 0.05","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","PFOS from 3M - purity not stated"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","709-17"]
["Scores",10,5,5,0,5,5,2,5,5,0,4,0,4,4,4,1,1,3,63,0.71590909090909094,""]
["Answers","42 days","Growth -dry mass","EC50","EC50","Yes","Triplicate","ASTM 1999 guidelines","Apical shoots 5cm","Irrigation pond water","Not stated","Measured","Not stated","Table 2","p < 0.05","p < 0.05","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","PFOS from 3M - purity not stated"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","709-16"]
["Scores",10,5,5,0,5,5,2,5,5,0,4,0,4,4,4,1,1,3,63,0.71590909090909094,""]
["Answers","42 days","Growth -dry mass","NOEC","NOEC","Yes","Triplicate","ASTM 1999 guidelines","Apical shoots 5cm","Irrigation pond water","Not stated","Measured","Not stated","Table 2","p < 0.05","p < 0.05","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","PFOS from 3M - purity not stated"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","709-15"]
["Scores",10,5,5,0,5,5,2,5,5,0,4,0,4,4,4,1,1,3,63,0.71590909090909094,""]
["Answers","42 days","Growth -wet mass","NOEC","NOEC","Yes","Triplicate","ASTM 1999 guidelines","Apical shoots 5cm","Irrigation pond water","Not stated","Measured","Not stated","Table 2","p < 0.05","p < 0.05","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","PFOS from 3M - purity not stated"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","709-14"]
["Scores",10,5,5,0,5,5,2,5,5,0,4,0,4,4,4,1,1,3,63,0.71590909090909094,""]
["Answers","42 days","Growth -wet mass","EC50","EC50","Yes","Triplicate","ASTM 1999 guidelines","Apical shoots 5cm","Irrigation pond water","Not stated","Measured","Not stated","Table 2","p < 0.05","p < 0.05","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","PFOS from 3M - purity not stated"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","709-18"]
["Scores",10,5,5,0,5,5,2,5,5,0,4,0,4,4,4,1,1,3,63,0.71590909090909094,""]
["Answers","42 days","Growth -plant length","EC50","EC50","Yes","Triplicate","ASTM 1999 guidelines","Apical shoots 5cm","Irrigation pond water","Not stated","Measured","Not stated","Table 2","p < 0.05","p < 0.05","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","PFOS from 3M - purity not stated"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","709-19"]
["Scores",10,5,5,0,5,5,2,5,5,0,4,0,4,4,4,1,1,3,63,0.71590909090909094,""]
["Answers","42 days","Growth -dry mass","EC10","EC10","Yes","Triplicate","ASTM 1999 guidelines","Apical shoots 5cm","Irrigation pond water","Not stated","Measured","Not stated","Table 2","p < 0.05","p < 0.05","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","PFOS from 3M - purity not stated"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","709-20"]
["Scores",10,5,5,0,5,5,2,5,5,0,4,0,4,4,4,1,1,3,63,0.71590909090909094,""]
["Answers","42 days","Growth -plant length","NOEC","NOEC","Yes","Triplicate","ASTM 1999 guidelines","Apical shoots 5cm","Irrigation pond water","Not stated","Measured","Not stated","Table 2","p < 0.05","p < 0.05","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","PFOS from 3M - purity not stated"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","709-21"]
["Scores",10,5,5,0,5,5,2,5,5,0,4,0,4,4,4,1,1,3,63,0.71590909090909094,""]
["Answers","42 days","Growth -wet mass","NOEC","NOEC","Yes","Triplicate","ASTM 1999 guidelines","Apical shoots 5cm","Irrigation pond water","Not stated","Measured","Not stated","Table 2","p < 0.05","p < 0.05","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","PFOS from 3M - purity not stated"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","709-22"]
["Scores",10,5,5,0,5,5,2,5,5,0,4,0,4,4,4,1,1,3,63,0.71590909090909094,""]
["Answers","28 days","Growth -dry mass","NOEC","NOEC","Yes","Triplicate","ASTM 1999 guidelines","Apical shoots 5cm","Irrigation pond water","Not stated","Measured","Not stated","Table 2","p < 0.05","p < 0.05","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","PFOS from 3M - purity not stated"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","709-23"]
["Scores",10,5,5,0,5,5,2,5,5,0,4,0,4,4,4,1,1,3,63,0.71590909090909094,""]
["Answers","42 days","Growth -dry mass","NOEC","NOEC","Yes","Triplicate","ASTM 1999 guidelines","Apical shoots 5cm","Irrigation pond water","Not stated","Measured","Not stated","Table 2","p < 0.05","p < 0.05","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","PFOS from 3M - purity not stated"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","709-24"]
["Scores",10,5,5,0,5,5,2,5,5,0,4,0,4,4,4,1,1,3,63,0.71590909090909094,""]
["Answers","42 days","Growth -dry mass","EC50","EC50","Yes","Triplicate","ASTM 1999 guidelines","Apical shoots 5cm","Irrigation pond water","Not stated","Measured","Not stated","Table 2","p < 0.05","p < 0.05","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","PFOS from 3M - purity not stated"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","709-25"]
["Scores",10,5,5,0,5,5,2,5,5,0,4,0,4,4,4,1,1,3,63,0.71590909090909094,""]
["Answers","28 days","Growth -dry mass","EC50","EC50","Yes","Triplicate","ASTM 1999 guidelines","Apical shoots 5cm","Irrigation pond water","Not stated","Measured","Not stated","Table 2","p < 0.05","p < 0.05","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","PFOS from 3M - purity not stated"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","709-26"]
["Scores",10,5,5,0,5,5,2,5,5,0,4,0,4,4,4,1,1,3,63,0.71590909090909094,""]
["Answers","42 days","Growth - wet mass","EC50","EC50","Yes","Triplicate","ASTM 1999 guidelines","Apical shoots 5cm","Irrigation pond water","Not stated","Measured","Not stated","Table 2","p < 0.05","p < 0.05","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","PFOS from 3M - purity not stated"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","709-27"]
["Scores",10,5,5,0,5,5,2,5,5,0,4,0,4,4,4,1,1,3,63,0.71590909090909094,""]
["Answers","42 days","Growth - plant length","EC50","EC50","Yes","Triplicate","ASTM 1999 guidelines","Apical shoots 5cm","Irrigation pond water","Not stated","Measured","Not stated","Table 2","p < 0.05","p < 0.05","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","Stated measured at 1 hour and 2,4,7,14,21,28,35 and 42 days ","PFOS from 3M - purity not stated"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","3044-1"]
["Scores",10,5,5,0,5,5,0,0,5,0,4,0,4,4,4,3,3,3,60,0.68181818181818177,""]
["Answers","42 days","Growth - frond number","IC50","IC50","Yes","Triplicate","Not stated","Small plants","Irrigation pond water","Not stated","Measured","Not stated","Figure 6","Yes","Yes","8.3-8.3","15.9 - 20.5oC","PFOS-K 86% from 3 M (Fluorad fluorochemical surfactant FC-95)"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","3044-2"]
["Scores",10,5,5,0,5,5,0,0,5,0,4,0,4,4,4,3,3,3,60,0.68181818181818177,""]
["Answers","42 days","Growth - frond number","NOEC","NOEC","Yes","Triplicate","Not stated","Small plants","Irrigation pond water","Not stated","Measured","Not stated","Figure 6","Yes","Yes","8.3-8.3","15.9 - 20.5oC","PFOS-K 86% from 3 M (Fluorad fluorochemical surfactant FC-95)"]
["Category","Freshwater/non-metal/plant","Paper and data unique identifier(eg. 1-1,10-150)","3044-3"]
["Scores",10,5,5,0,5,5,0,0,5,0,4,0,4,4,4,3,3,3,60,0.68181818181818177,""]
["Answers","42 days","Growth - frond number","LOEC","LOEC","Yes","Triplicate","Not stated","Small plants","Irrigation pond water","Not stated","Measured","Not stated","Figure 6","Yes","Yes","8.3-8.3","15.9 - 20.5oC","PFOS-K 86% from 3 M (Fluorad fluorochemical surfactant FC-95)"]