{"text_format":"1","workbook":"xlsx","n_sheets":38,"sheets":["Copyright","Cover","All Result","Sheet3","Sheet4","Sheet5","Sheet6","Sheet7","Sheet8","Sheet9","Sheet10","Sheet11","Sheet12","Sheet13","Sheet14","Sheet15","Sheet16","Sheet17","Instruction","Sheet1","FW metal nonplant","FW metal nonplant_WS","FW nonmetal nonplant","FW nonmetal nonplant_WS","FW metal plant","FW metal plant_WS","Sheet18","FW nonmetal plant","FW nonmetal plant_WS","MEW nonplant","MEW nonplant_WS","MEW plant","MEW plant_WS","Terrestrial Data QA","Terrestrial Quality","Sediment Data QA","Sediment Quality","Sheet2"],"not_rendered":{"charts":0,"images":0,"macros":1,"external_links":0,"defined_names":9,"comments":11,"pivot_tables":0},"unopened":[],"bounds":{"document_bytes":16777216,"sheet_cells":100000,"rows_first":2000,"rows_last":500,"rows_between":2000,"halvings":0,"cell_chars":16384,"cell_head_chars":4096},"cells_cut":0,"cells_raw":0,"read":"whole","date_system":"1900"}

{"sheet":"Copyright","index":0,"n_rows":0,"n_cols":0,"rows_kept":0,"cut":false,"hidden":false,"merged":[]}

{"sheet":"Cover","index":1,"n_rows":20,"n_cols":7,"rows_kept":20,"cut":false,"hidden":false,"merged":[[18,6,18,8],[14,6,14,8],[13,6,13,8],[4,4,4,10],[9,6,9,8],[12,6,12,8],[5,5,6,9]]}
[]
[]
[]
[]
[null,null,null,null,"Ecotoxicity Data Quality Assessment Method V2"]
[null,null,null,null,null,"To be used to assess the quality of data used for the Australian and New Zealand Guidelines for Fresh and Marine Water Quality (including sediment) and the Australian National Environment Protection (Assessment of Site Contamination) Measure"]
[]
[]
[]
[null,null,null,null,null,null,"Developed by "]
[]
[]
[null,null,null,null,null,null,"Zoe Zhang"]
[null,null,null,null,null,null,"   Dr. Michael Warne"]
[null,null,null,null,null,null,"Alison Vieritz "]
[]
[]
[]
[null,null,null,null,null,null,"Water Quality & Investigations "]
[null,null,null,null,null,"                 Department of Science,Information Technology and Innovation"]

{"sheet":"All Result","index":2,"n_rows":51,"n_cols":22,"rows_kept":51,"cut":false,"hidden":false,"merged":[]}
["Chemical","Chlorine in marine water"]
[{"$f":"'FW nonmetal plant'!C2","v":"Category"},{"$f":"'FW nonmetal plant'!C3","v":"Paper and data unique identifier(eg. 1-1,10-150)"},{"$f":"'FW nonmetal plant'!C70","v":"Total score"},{"$f":"'FW nonmetal plant'!C72","v":"Quality Score"},"Comment ",{"$f":"'FW nonmetal plant'!G3","v":"Species (Scientific name)"},{"$f":"'FW nonmetal plant'!G4","v":"Lifestage"},{"$f":"'FW nonmetal plant'!G5","v":"Exposure duration"},{"$f":"'FW nonmetal plant'!G6","v":"Measure of toxicity"},{"$f":"'FW nonmetal plant'!G7","v":"Toxicity endpoint"},{"$f":"'FW nonmetal plant'!G8","v":"Toxicity value"},{"$f":"'FW nonmetal plant'!J2","v":"Taxonomic group"},{"$f":"'FW nonmetal plant'!J3","v":"Phylum"},{"$f":"'FW nonmetal plant'!J4","v":"Class"},{"$f":"'FW nonmetal plant'!J5","v":"Media"},{"$f":"'FW nonmetal plant'!J6","v":"Temperature "},{"$f":"'FW nonmetal plant'!J7","v":"Acute Or Chronic "},{"$f":"'FW nonmetal plant'!J8","v":"PH"},{"$f":"'FW metal plant'!J9","v":"Salinity/Conductivity"},{"$f":"'FW metal plant'!C4","v":"Citation"},{"$f":"'FW metal plant'!G2","v":"Citation No."}]
["MEW_nonplant","1-1",64,0.68085106382978722,"","Brachionus plicatilis)","0.5 h old","24 h","LC50","Mortality","586 µg/L","Rotifer","?","?","Synthetic seawater","20oC","Acute",8,"20‰","Lopez-Galindo et al 2010","1"]
["MEW_nonplant","2-1",50,0.53191489361702127,"","Crassostrea virginica",0,"0.5 h","LC50","Mortality","80 µg/L","Bivalve","?","?","Seawater","20oC","Acute",8,"28‰","Capuzzo et al 1979","2"]
["MEW_nonplant","2-2",50,0.53191489361702127,"","Acartia tonsa",0,"0.5 h","LC50","Mortality","820 µg/L","Copepod","?","?","Seawater","20oC","Acute",8,"28‰","Capuzzo et al 1979","2"]
["MEW_nonplant","2-3",50,0.53191489361702127,"","Brachionus plicatilis",0,"0.5 h","LC50","Mortality","90 µg/L","Rotifer","?","?","Seawater","20oC","Acute",8,"28‰","Capuzzo et al 1979","2"]
["MEW_nonplant","3-1",79,0.84042553191489366,"","Hyale barbicornis","Juveniles","24 h","LC50","Mortality",1050,"Amphipod","?","?","Seawater","20oC","Acute",7.5,"33.7‰","Anasco et al 2008","3"]
["MEW_nonplant","3-2",79,0.84042553191489366,"","Hyale barbicornis","Juveniles","96 h","EC50","Body length",524,"Amphipod","?","?","Seawater","20oC","Acute",7.5,"33.7‰","Anasco et al 2008","3"]
["MEW_nonplant","4-1",67,0.71276595744680848,"","Pandalus danae","Juveniles and adults","96 h","LC50","Mortality","178 µg/L","Shrimp","?","?","Seawater","20oC","Acute",8,"28‰","Thatcher, 1978","4"]
["MEW_nonplant","5-1",56,0.5957446808510638,"","Strongylocentrotus droebachiensis","Sperm","5 min exp 15 min incubation","EC50","Mortality","<5, <6 µg/L","Sea urchin","?","?","Seawater",0,"Acute",8,"28‰","Dinnel et al., 1981","5"]
["MEW_nonplant","5-2",56,0.5957446808510638,"","Dendraster excentricus","Sperm","5 min exp 15 min incubation","EC50","Mortality","6.4 µg/L","Sand dollar","?","?","Seawater",0,"Acute",8,"28‰","Dinnel et al., 1981","5","6.4 ug/L value is the geomean of 3 EC50s from 1 min reaction time (0.002, <0.010 & 0.013 mg/L - see Table 2 of paper)"]
["MEW_nonplant","2-6",66,0.7021276595744681,"","Homarus americanus","Larvae","48 h","LC50","Mortality","2890 µg/L","Lobster","?","?","Seawater","20-22oC","Acute","7.9-8.1","30-31‰","Capuzzo et al., 1976","2"]
["MEW_nonplant","4-2",58,0.61702127659574468,"","Neomysis sp","Adult","96 h","LC50","Mortality","162 µg/L","Mysid","?","?","Seawater","25oC","Acute",8,"28‰","Thatcher, 1978","4"]
["MEW_nonplant","4-3",58,0.61702127659574468,"","Pontogeneia sp","Adult","96 h","LC50","Mortality","687 µg/L","Amphipod","?","?","Seawater","15oC","Acute",8,"28‰","Thatcher, 1978","4"]
["MEW_nonplant","4-4",58,0.61702127659574468,"","Anonyx sp","Adult","96 h","LC50","Mortality","145 µg/L","Amphipod","?","?","Seawater","15oC","Acute",8,"28‰","Thatcher, 1978","4"]
["MEW_nonplant","4-5",58,0.61702127659574468,"","Pandalus goniurus","Adult","96 h","LC50","Mortality","90 µg/L","Shrimp","?","?","Seawater","15oC","Acute",8,"28‰","Thatcher, 1978","4"]
["MEW_nonplant","4-6",58,0.61702127659574468,"","Crangon nigricorda","Adult","96 h","LC50","Mortality","134 µg/L","Shrimp","?","?","Seawater","15oC","Acute",8,"28‰","Thatcher, 1978","4"]
["MEW_nonplant","4-7",58,0.61702127659574468,"","Hemigrapsus nudus","Adult","96 h","LC50","Mortality","1418 µg/L","Crab","?","?","Seawater","15oC","Acute",8,"28‰","Thatcher, 1978","4"]
["MEW_nonplant","4-8",58,0.61702127659574468,"","Hemigrapsus oregonensis","Adult and juvenile","96 h","LC50","Mortality","1418 µg/L","Crab","?","?","Seawater","15oC","Acute",8,"28‰","Thatcher, 1978","4"]
["MEW_nonplant","4-9",58,0.61702127659574468,"","Onchorhynchus kisutch","Juvenile","96 h","LC50","Mortality","32 µg/L","Fish","?","?","Seawater","15oC","Acute",8,"28‰","Thatcher, 1978","4"]
["MEW_nonplant","4-10",58,0.61702127659574468,"","Clupea harengus pailasi","Juvenile","96 h","LC50","Mortality","65 µg/L","Fish","?","?","Seawater","15oC","Acute",8,"28‰","Thatcher, 1978","4"]
["MEW_nonplant","4-11",58,0.61702127659574468,"","Gasterosteus aculaetus","Juvenile plus adult","96 h","LC50","Mortality","167 µg/L","Fish","?","?","Seawater","15oC","Acute",8,"28‰","Thatcher, 1978","4"]
["MEW_nonplant","4-12",58,0.61702127659574468,"","Cymatogaster aggregata","Juvenile plus adult","96 h","LC50","Mortality","71 µg/L","Fish","?","?","Seawater","15oC","Acute",8,"28‰","Thatcher, 1978","4"]
["MEW_nonplant","4-13",58,0.61702127659574468,"","Ammodytes hexapterus","Juvenile plus adult","96 h","LC50","Mortality","82 µg/L","Fish","?","?","Seawater","15oC","Acute",8,"28‰","Thatcher, 1978","4"]
["MEW_nonplant","4-14",58,0.61702127659574468,"","Parophrys vetulus","Juvenile","96 h","LC50","Mortality","73 µg/L","Fish","?","?","Seawater","15oC","Acute",8,"28‰","Thatcher, 1978","4"]
["MEW_nonplant","6-1",64,0.68085106382978722,"","Menidia peninsulae","Fry","96 h","LC50","Mortality","54 µg/L","Fish","?","?","Seawater 22-27‰","25oC","Acute","7.9-8.0","28‰","Goodman et al., 1983","6"]
["MEW_nonplant","6-2",64,0.68085106382978722,"","Menidia peninsulae","Fry","96 h","NOEC","Mortality","40 µg/L","Fish","?","?","Seawater 22-27‰","25oC","Acute","7.9-8.0","28‰","Goodman et al., 1983","6"]
["MEW_nonplant","3-3",64,0.68085106382978722,"","Orizias javanicus","Eggs","96 h","LC50","Mortality","91 µg/L","Fish","?","?","Seawater","26oC","Acute",7.5,"33.7‰","Anasco et al 2008","3"]
["MEW_nonplant","3-4",64,0.68085106382978722,"","Orizias javanicus","Eggs","24 h","LC50","Mortality","152 µg/L","Fish","?","?","Seawater","26oC","Acute",7.5,"33.7‰","Anasco et al 2008","3"]
["MEW_nonplant","7-1",56,0.5957446808510638,"","Pleuronectes platessa","Larvae","24 h","LC50","Mortality","24 µg/L","Fish","?","?","Seawater","8oC","Acute",8,"35‰","Alderson et al., 1972","7"]
["MEW_nonplant","7-2",56,0.5957446808510638,"","Pleuronectes platessa","Larvae","8 d","LC50","Mortality","24 µg/L","Fish","?","?","Seawater","8oC","Chronic",8,"35‰","Alderson et al., 1972","7"]
["MEW_plant","8-1",48,0.52747252747252749,"","Isochrysis galbana","-","96 h","EC10","Growth",172,"Algae","?","?","Seawater","20oC","Chronic","?","35‰?","Lopez-Galinda et al., 2008","8"]
["MEW_plant","8-2",48,0.52747252747252749,"","Dunaliella salina","-","96 h","EC10","Growth",481,"Algae","?","?","Seawater","20oC","Chronic","?","35‰?","Lopez-Galinda et al., 2008","8"]
["MEW_nonplant","9-1",63,0.69230769230769229,"","Crassostrea virginica","Larvae","96 h","LC50","Mortality",26,"Oyster","?","?","Seawater","19-28oC","Chronic","?","19-28‰","Roberts and Gleeson 1978","9"]
["MEW_nonplant","9-2",63,0.69230769230769229,"","Acartia tonsa",0,"96 h","LC50","Mortality",29,"Copepod","?","?","Seawater","19-28oC","Chronic","?","19-28‰","Roberts and Gleeson 1978","9"]
["MEW_nonplant","9-3",63,0.69230769230769229,"","Palaemonetes pugio",0,"96 h","LC50","Mortality",220,"Shrimp","?","?","Seawater","19-28oC","Acute","?","20‰","Roberts and Gleeson 1978","9"]
["MEW_nonplant","9-4",63,0.69230769230769229,"","Menidia menidia","Juvenile","96 h","LC50","Mortality",37,"Fish","?","?","Seawater","19-28oC","Acute","?","15‰","Roberts and Gleeson 1978","9"]
["MEW_nonplant","10-1",55,0.58510638297872342,"","Crassostrea virginica","Larvae","96 h","LC50","Mortality","23 µg/L","Oyster","?","?","Seawater","19-28oC","Acute",8,"20‰","Roberts et al., 1975","10"]
["MEW_nonplant","10-2",55,0.58510638297872342,"","Synnathus focus","Juvenile","96 h","LC50","Mortality","270 µg/L","Fish","?","?","Seawater","19-28oC","Acute",8,"20‰","Roberts et al., 1975","10"]
["MEW_nonplant","10-3",55,0.58510638297872342,"","Gobiosoma bosci","Juvenile","96 h","LC50","Mortality","80 µg/L","Fish","?","?","Seawater","19-28oC","Acute",8,"20‰","Roberts et al., 1975","10"]
["MEW_nonplant","11-1",55,0.58510638297872342,"","Mysidopsis bahia","Juvenile","96 h","LC50","Mortality","73 µg/L","Mysid","?","?","Seawater","20oC","Acute",8,"20‰","Fisher et al., 1994","11"]
["MEW_nonplant","11-2",55,0.58510638297872342,"","Menidia beryllina","Juvenile","96 h","LC50","Mortality","128 µg/L","Fish","?","?","Seawater","20oC","Acute",8,"20‰","Fisher et al., 1999","11"]
["MEW_nonplant","12-1",55,0.58510638297872342,"","Mysidopsis bahia","Juvenile","96 h","LC50","Mortality","62 µg/L","Mysid","?","?","Seawater","20oC","Acute",8,"20‰","Fisher et al., 1999","12"]
["MEW_nonplant","12-2",55,0.58510638297872342,"","Menidia beryllina","Juvenile","96 h","LC50","Mortality","143 µg/L","Fish","?","?","Seawater","20oC","Acute",8,"20‰","Fisher et al., 1999","12"]
["MEW_nonplant","13-1",56,0.5957446808510638,"","Menidia menidia","Eggs","48 h","LC50","Mortality","300 µg/L","Fish","?","?","Seawater","8-12oC","Acute",8,"15‰","Morgan and Prince 1977","13"]
["MEW_nonplant","13-2",56,0.5957446808510638,"","Menidia beryllina","Eggs","96 h","LC50","Mortality","210 µg/L","Fish","?","?","Seawater","8-12oC","Acute",8,"15‰","Morgan and Prince 1977","13"]
["MEW_nonplant","13-3",56,0.5957446808510638,"","Morone americana","Eggs","76 h","LC50","Mortality","270 µg/L","Fish","?","?","Seawater","8-12oC","Acute",8,"15‰","Morgan and Prince 1977","13"]
["MEW_nonplant","13-4",56,0.5957446808510638,"","Morone saxitilis","Eggs","76 h","LC50","Mortality","200 µg/L","Fish","?","?","Seawater","8-12oC","Acute",8,"15‰","Morgan and Prince 1977","13"]
["MEW_nonplant","13-5",56,0.5957446808510638,"","Alosa aetvalis","Eggs","48 h","LC50","Mortality","240 µg/L","Fish","?","?","Seawater","8-12oC","Acute",8,"15‰","Morgan and Prince 1977","13"]
["MEW_nonplant","14-1",57,0.6063829787234043,"","Amphiporeia virgiana",0,"48 h","LC50","Mortality","626 µg/L","Amphipod","?","?","Seawater","10oC","Acute",7.5,"21‰","Wan et al., 2000","14"]
["MEW_nonplant","14-2",57,0.6063829787234043,"","Eohaustorius washingtoianus",0,"48 h","LC50","Mortality","567 µg/L","Amphipod","?","?","Seawater","15oC","Acute",7.5,"21‰","Wan et al., 2000","14"]

{"sheet":"Sheet3","index":3,"n_rows":0,"n_cols":0,"rows_kept":0,"cut":false,"hidden":true,"merged":[]}

{"sheet":"Sheet4","index":4,"n_rows":0,"n_cols":0,"rows_kept":0,"cut":false,"hidden":true,"merged":[]}

{"sheet":"Sheet5","index":5,"n_rows":0,"n_cols":0,"rows_kept":0,"cut":false,"hidden":true,"merged":[]}

{"sheet":"Sheet6","index":6,"n_rows":0,"n_cols":0,"rows_kept":0,"cut":false,"hidden":true,"merged":[]}

{"sheet":"Sheet7","index":7,"n_rows":0,"n_cols":0,"rows_kept":0,"cut":false,"hidden":true,"merged":[]}

{"sheet":"Sheet8","index":8,"n_rows":0,"n_cols":0,"rows_kept":0,"cut":false,"hidden":true,"merged":[]}

{"sheet":"Sheet9","index":9,"n_rows":0,"n_cols":0,"rows_kept":0,"cut":false,"hidden":true,"merged":[]}

{"sheet":"Sheet10","index":10,"n_rows":0,"n_cols":0,"rows_kept":0,"cut":false,"hidden":true,"merged":[]}

{"sheet":"Sheet11","index":11,"n_rows":0,"n_cols":0,"rows_kept":0,"cut":false,"hidden":true,"merged":[]}

{"sheet":"Sheet12","index":12,"n_rows":0,"n_cols":0,"rows_kept":0,"cut":false,"hidden":true,"merged":[]}

{"sheet":"Sheet13","index":13,"n_rows":0,"n_cols":0,"rows_kept":0,"cut":false,"hidden":true,"merged":[]}

{"sheet":"Sheet14","index":14,"n_rows":0,"n_cols":0,"rows_kept":0,"cut":false,"hidden":true,"merged":[]}

{"sheet":"Sheet15","index":15,"n_rows":0,"n_cols":0,"rows_kept":0,"cut":false,"hidden":true,"merged":[]}

{"sheet":"Sheet16","index":16,"n_rows":0,"n_cols":0,"rows_kept":0,"cut":false,"hidden":true,"merged":[]}

{"sheet":"Sheet17","index":17,"n_rows":0,"n_cols":0,"rows_kept":0,"cut":false,"hidden":true,"merged":[]}

{"sheet":"Instruction","index":18,"n_rows":21,"n_cols":10,"rows_kept":21,"cut":false,"hidden":false,"merged":[[27,6,27,16],[14,6,14,7],[5,4,5,7]]}
[]
[]
[null,"Click here to see \"All Result\" -->","All Result"]
[]
[]
[null,null,null,null,"Freshwater "]
[]
[null,"Tabs contain questionaries -->           ","Freshwater/metal/nonplant",null,"Freshwater/non-metal/non-plant ",null,null,"Freshwater/metal/plant",null,"Freshwater/non-metal/plant"]
[]
[]
[]
[null,"Tabs contain score of paper and short answers to questions -->","Freshwater/metal/nonplant Worksheet",null,"Freshwater/non-metal/non-plant Worksheet",null,null,"Freshwater/metal/plant Worksheet",null,"Freshwater/non-metal/plant/ Worksheet"]
[]
[]
[null,null,"Marine ",null,null,null,"Terrestrial",null,null,"Sediment "]
[]
[null,"Tab contain questionaries -->","Marine or estuarine/non-plant",null,"Marine or estuarine/Plant",null,null,"Terrestrial Data QA",null,"Sediment Data QA"]
[]
[]
[]
[null,"Tab Contains all scores of paper --> ","Marine or estuarine/non-Plant Worksheet",null,"Marine or estuarine/Plant_Worksheet",null,null,"Terrestrial Quality",null,"Sediment Quality"]

{"sheet":"Sheet1","index":19,"n_rows":70,"n_cols":29,"rows_kept":70,"cut":false,"hidden":true,"merged":[]}
[]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["Answers",{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}}]
[]
[]
[]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},null,{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}},{"$f":"IF(#REF!=0,\"\",#REF!)","v":{"$error":"#REF!"}}]
[]
[]
[]
[{"$f":"'Terrestrial Data QA'!B11","v":"No."},{"$f":"'Terrestrial Data QA'!B13","v":1},{"$f":"'Terrestrial Data QA'!B16","v":2},{"$f":"'Terrestrial Data QA'!B19","v":3},{"$f":"'Terrestrial Data QA'!B21","v":4},{"$f":"'Terrestrial Data QA'!B23","v":5},{"$f":"'Terrestrial Data QA'!B26","v":6},{"$f":"'Terrestrial Data QA'!B29","v":7},{"$f":"'Terrestrial Data QA'!B32","v":8},{"$f":"'Terrestrial Data QA'!B35","v":9},{"$f":"'Terrestrial Data QA'!B39","v":10},{"$f":"'Terrestrial Data QA'!B42","v":11},{"$f":"'Terrestrial Data QA'!B45","v":12},{"$f":"'Terrestrial Data QA'!B48","v":13},{"$f":"'Terrestrial Data QA'!B50","v":14},{"$f":"'Terrestrial Data QA'!B55","v":15.1},{"$f":"'Terrestrial Data QA'!B59","v":15.2},{"$f":"'Terrestrial Data QA'!B63","v":15.3},{"$f":"'Terrestrial Data QA'!B67","v":15.4},{"$f":"'Terrestrial Data QA'!B71","v":16},{"$f":"'Terrestrial Data QA'!B74","v":17},{"$f":"'Terrestrial Data QA'!B78","v":18},{"$f":"'Terrestrial Data QA'!B82","v":19},{"$f":"'Terrestrial Data QA'!B85","v":20},{"$f":"'Terrestrial Data QA'!C90","v":"Total Score"},{"$f":"'Terrestrial Data QA'!C92","v":"Quality Score"}]
[{"$f":"'Terrestrial Data QA'!C2","v":"Category"},{"$f":"'Terrestrial Data QA'!E2","v":"Terrestrial Quality"},{"$f":"'Terrestrial Data QA'!C3","v":"Paper and data unique identifier(eg. 1-1,10-150)"},{"$f":"'Terrestrial Data QA'!E3","v":0}]
[{"$f":"'Terrestrial Data QA'!G11","v":"Scores"},{"$f":"'Terrestrial Data QA'!G12","v":0},{"$f":"'Terrestrial Data QA'!G15","v":0},{"$f":"'Terrestrial Data QA'!G18","v":0},{"$f":"'Terrestrial Data QA'!G21","v":0},{"$f":"'Terrestrial Data QA'!G23","v":0},{"$f":"'Terrestrial Data QA'!G26","v":0},{"$f":"'Terrestrial Data QA'!G29","v":0},{"$f":"'Terrestrial Data QA'!G32","v":0},{"$f":"'Terrestrial Data QA'!G35","v":0},{"$f":"'Terrestrial Data QA'!G38","v":0},{"$f":"'Terrestrial Data QA'!G41","v":0},{"$f":"'Terrestrial Data QA'!G44","v":0},{"$f":"'Terrestrial Data QA'!G47","v":0},{"$f":"'Terrestrial Data QA'!G50","v":0},{"$f":"'Terrestrial Data QA'!G54","v":0},{"$f":"'Terrestrial Data QA'!G58","v":0},{"$f":"'Terrestrial Data QA'!G62","v":0},{"$f":"'Terrestrial Data QA'!G66","v":0},{"$f":"'Terrestrial Data QA'!G70","v":0},{"$f":"'Terrestrial Data QA'!G73","v":0},{"$f":"'Terrestrial Data QA'!G77","v":0},{"$f":"'Terrestrial Data QA'!G81","v":0},{"$f":"'Terrestrial Data QA'!G84","v":0},{"$f":"'Terrestrial Data QA'!G90","v":""},{"$f":"'Terrestrial Data QA'!G92","v":{"$error":"#N/A"}}]
[{"$f":"'Terrestrial Data QA'!H11","v":"Answers"},{"$f":"IF('Terrestrial Data QA'!H12=0,\"\",'Terrestrial Data QA'!H12)","v":""},{"$f":"IF('Terrestrial Data QA'!H15=0,\"\",'Terrestrial Data QA'!H15)","v":""},{"$f":"IF('Terrestrial Data QA'!H18=0,\"\",'Terrestrial Data QA'!H18)","v":""},{"$f":"IF('Terrestrial Data QA'!H21=0,\"\",'Terrestrial Data QA'!H21)","v":""},{"$f":"IF('Terrestrial Data QA'!H23=0,\"\",'Terrestrial Data QA'!H23)","v":""},{"$f":"IF('Terrestrial Data QA'!H26=0,\"\",'Terrestrial Data QA'!H26)","v":""},{"$f":"IF('Terrestrial Data QA'!H29=0,\"\",'Terrestrial Data QA'!H29)","v":""},{"$f":"IF('Terrestrial Data QA'!H32=0,\"\",'Terrestrial Data QA'!H32)","v":""},{"$f":"IF('Terrestrial Data QA'!H35=0,\"\",'Terrestrial Data QA'!H35)","v":""},{"$f":"IF('Terrestrial Data QA'!H38=0,\"\",'Terrestrial Data QA'!H38)","v":""},{"$f":"IF('Terrestrial Data QA'!H41=0,\"\",'Terrestrial Data QA'!H41)","v":""},{"$f":"IF('Terrestrial Data QA'!H44=0,\"\",'Terrestrial Data QA'!H44)","v":""},{"$f":"IF('Terrestrial Data QA'!H47=0,\"\",'Terrestrial Data QA'!H47)","v":""},{"$f":"IF('Terrestrial Data QA'!H50=0,\"\",'Terrestrial Data QA'!H50)","v":""},{"$f":"IF('Terrestrial Data QA'!H54=0,\"\",'Terrestrial Data QA'!H54)","v":""},{"$f":"IF('Terrestrial Data QA'!H58=0,\"\",'Terrestrial Data QA'!H58)","v":""},{"$f":"IF('Terrestrial Data QA'!H62=0,\"\",'Terrestrial Data QA'!H62)","v":""},{"$f":"IF('Terrestrial Data QA'!H66=0,\"\",'Terrestrial Data QA'!H66)","v":""},{"$f":"IF('Terrestrial Data QA'!H70=0,\"\",'Terrestrial Data QA'!H70)","v":""},{"$f":"IF('Terrestrial Data QA'!H73=0,\"\",'Terrestrial Data QA'!H73)","v":""},{"$f":"IF('Terrestrial Data QA'!H77=0,\"\",'Terrestrial Data QA'!H77)","v":""},{"$f":"IF('Terrestrial Data QA'!H81=0,\"\",'Terrestrial Data QA'!H81)","v":""},{"$f":"IF('Terrestrial Data QA'!H84=0,\"\",'Terrestrial Data QA'!H84)","v":""}]
[{"$f":"'Terrestrial Data QA'!G3","v":"Species (Scientific name)"},{"$f":"'Terrestrial Data QA'!G4","v":"Lifestage"},{"$f":"'Terrestrial Data QA'!G5","v":"Exposure duration"},{"$f":"'Terrestrial Data QA'!G6","v":"Measure of toxicity"},{"$f":"'Terrestrial Data QA'!G7","v":"Toxicity endpoint"},{"$f":"'Terrestrial Data QA'!G8","v":"Toxicity value"},{"$f":"'Terrestrial Data QA'!C4","v":"Citation"},{"$f":"'Terrestrial Data QA'!G2","v":"Citation No."}]
[{"$f":"'Terrestrial Data QA'!M3","v":""},{"$f":"'Terrestrial Data QA'!P3","v":""},{"$f":"'Terrestrial Data QA'!S3","v":""},{"$f":"'Terrestrial Data QA'!V3","v":""},{"$f":"'Terrestrial Data QA'!Y3","v":""},{"$f":"IF('Terrestrial Data QA'!H8=0,\"\",'Terrestrial Data QA'!H8)","v":""},{"$f":"IF('Terrestrial Data QA'!E4=0,\"\",'Terrestrial Data QA'!E4)","v":""},{"$f":"IF('Terrestrial Data QA'!H2=0,\"\",'Terrestrial Data QA'!H2)","v":""}]
[]
[]
[]
[{"$f":"'Sediment Data QA'!B11","v":"No."},{"$f":"'Sediment Data QA'!B13","v":1},{"$f":"'Sediment Data QA'!B16","v":2},{"$f":"'Sediment Data QA'!B19","v":3},{"$f":"'Sediment Data QA'!B21","v":4},{"$f":"'Sediment Data QA'!B23","v":5},{"$f":"'Sediment Data QA'!B26","v":6},{"$f":"'Sediment Data QA'!B29","v":7},{"$f":"'Sediment Data QA'!B32","v":8},{"$f":"'Sediment Data QA'!B35","v":9},{"$f":"'Sediment Data QA'!B39","v":10},{"$f":"'Sediment Data QA'!B42","v":11},{"$f":"'Sediment Data QA'!B45","v":12},{"$f":"'Sediment Data QA'!B48","v":13},{"$f":"'Sediment Data QA'!B51","v":14},{"$f":"'Sediment Data QA'!B53","v":15},{"$f":"'Sediment Data QA'!B58","v":16.100000000000001},{"$f":"'Sediment Data QA'!B62","v":16.2},{"$f":"'Sediment Data QA'!B66","v":16.3},{"$f":"'Sediment Data QA'!B70","v":16.399999999999999},{"$f":"'Sediment Data QA'!B74","v":16.5},{"$f":"'Sediment Data QA'!B78","v":16.600000000000001},{"$f":"'Sediment Data QA'!B82","v":17},{"$f":"'Sediment Data QA'!B85","v":18},{"$f":"'Sediment Data QA'!B88","v":19},{"$f":"'Sediment Data QA'!B90","v":20},{"$f":"'Sediment Data QA'!B92","v":21},{"$f":"'Sediment Data QA'!C95","v":"Total score"},{"$f":"'Sediment Data QA'!C97","v":"Quality Score"}]
[{"$f":"'Sediment Data QA'!C2","v":"Category"},{"$f":"'Sediment Data QA'!E2","v":"Sediment "},{"$f":"'Sediment Data QA'!C3","v":"Paper and data unique identifier(eg. 1-1,10-150)"},{"$f":"'Sediment Data QA'!E3","v":0}]
[{"$f":"'Sediment Data QA'!G11","v":"Scores"},{"$f":"'Sediment Data QA'!G12","v":0},{"$f":"'Sediment Data QA'!G15","v":0},{"$f":"'Sediment Data QA'!G18","v":0},{"$f":"'Sediment Data QA'!G21","v":0},{"$f":"'Sediment Data QA'!G23","v":0},{"$f":"'Sediment Data QA'!G26","v":0},{"$f":"'Sediment Data QA'!G29","v":0},{"$f":"'Sediment Data QA'!G32","v":0},{"$f":"'Sediment Data QA'!G35","v":0},{"$f":"'Sediment Data QA'!G38","v":0},{"$f":"'Sediment Data QA'!G41","v":0},{"$f":"'Sediment Data QA'!G44","v":0},{"$f":"'Sediment Data QA'!G47","v":0},{"$f":"'Sediment Data QA'!G50","v":0},{"$f":"'Sediment Data QA'!G53","v":0},{"$f":"'Sediment Data QA'!G57","v":0},{"$f":"'Sediment Data QA'!G61","v":0},{"$f":"'Sediment Data QA'!G65","v":0},{"$f":"'Sediment Data QA'!G69","v":0},{"$f":"'Sediment Data QA'!G73","v":0},{"$f":"'Sediment Data QA'!G77","v":0},{"$f":"'Sediment Data QA'!G81","v":0},{"$f":"'Sediment Data QA'!G84","v":0},{"$f":"'Sediment Data QA'!G88","v":0},{"$f":"'Sediment Data QA'!G90","v":0},{"$f":"'Sediment Data QA'!G92","v":0},{"$f":"'Sediment Data QA'!G95","v":""},{"$f":"'Sediment Data QA'!G97","v":{"$error":"#N/A"}}]
[{"$f":"'Sediment Data QA'!H11","v":"Answers"},{"$f":"IF('Sediment Data QA'!H12=\"\",\"\",'Sediment Data QA'!H12)","v":""},{"$f":"IF('Sediment Data QA'!H15=\"\",\"\",'Sediment Data QA'!H15)","v":""},{"$f":"IF('Sediment Data QA'!H18=\"\",\"\",'Sediment Data QA'!H18)","v":""},{"$f":"IF('Sediment Data QA'!H21=\"\",\"\",'Sediment Data QA'!H21)","v":""},{"$f":"IF('Sediment Data QA'!H23=\"\",\"\",'Sediment Data QA'!H23)","v":""},{"$f":"IF('Sediment Data QA'!H26=\"\",\"\",'Sediment Data QA'!H26)","v":""},{"$f":"IF('Sediment Data QA'!H29=\"\",\"\",'Sediment Data QA'!H29)","v":""},{"$f":"IF('Sediment Data QA'!H32=\"\",\"\",'Sediment Data QA'!H32)","v":""},{"$f":"IF('Sediment Data QA'!H35=\"\",\"\",'Sediment Data QA'!H35)","v":""},{"$f":"IF('Sediment Data QA'!H38=\"\",\"\",'Sediment Data QA'!H38)","v":""},{"$f":"IF('Sediment Data QA'!H41=\"\",\"\",'Sediment Data QA'!H41)","v":""},{"$f":"IF('Sediment Data QA'!H44=\"\",\"\",'Sediment Data QA'!H44)","v":""},{"$f":"IF('Sediment Data QA'!H47=\"\",\"\",'Sediment Data QA'!H47)","v":""},{"$f":"IF('Sediment Data QA'!H50=\"\",\"\",'Sediment Data QA'!H50)","v":""},{"$f":"IF('Sediment Data QA'!H53=\"\",\"\",'Sediment Data QA'!H53)","v":""},{"$f":"IF('Sediment Data QA'!H57=\"\",\"\",'Sediment Data QA'!H57)","v":""},{"$f":"IF('Sediment Data QA'!H61=\"\",\"\",'Sediment Data QA'!H61)","v":""},{"$f":"IF('Sediment Data QA'!H65=\"\",\"\",'Sediment Data QA'!H65)","v":""},{"$f":"IF('Sediment Data QA'!H69=\"\",\"\",'Sediment Data QA'!H69)","v":""},{"$f":"IF('Sediment Data QA'!H73=\"\",\"\",'Sediment Data QA'!H73)","v":""},{"$f":"IF('Sediment Data QA'!H77=\"\",\"\",'Sediment Data QA'!H77)","v":""},{"$f":"IF('Sediment Data QA'!H81=\"\",\"\",'Sediment Data QA'!H81)","v":""},{"$f":"IF('Sediment Data QA'!H84=\"\",\"\",'Sediment Data QA'!H84)","v":""},{"$f":"IF('Sediment Data QA'!H88=\"\",\"\",'Sediment Data QA'!H88)","v":""},{"$f":"IF('Sediment Data QA'!H90=\"\",\"\",'Sediment Data QA'!H90)","v":""},{"$f":"IF('Sediment Data QA'!H92=\"\",\"\",'Sediment Data QA'!H92)","v":""}]
[{"$f":"'Sediment Data QA'!G3","v":"Species (Scientific name)"},{"$f":"'Sediment Data QA'!G4","v":"Lifestage"},{"$f":"'Sediment Data QA'!G5","v":"Exposure duration"},{"$f":"'Sediment Data QA'!G6","v":"Measure of toxicity"},{"$f":"'Sediment Data QA'!G7","v":"Toxicity endpoint"},{"$f":"'Sediment Data QA'!G8","v":"Toxicity value"},{"$f":"'Sediment Data QA'!C4","v":"Citation"},{"$f":"'Sediment Data QA'!G2","v":"Citation No."}]
[{"$f":"'Sediment Data QA'!M3","v":""},{"$f":"'Sediment Data QA'!P3","v":""},{"$f":"'Sediment Data QA'!S3","v":""},{"$f":"'Sediment Data QA'!V3","v":""},{"$f":"'Sediment Data QA'!Y3","v":""},{"$f":"IF('Sediment Data QA'!H8=\"\",\"\",'Sediment Data QA'!H8)","v":""},{"$f":"IF('Sediment Data QA'!E4=\"\",\"\",'Sediment Data QA'!E4)","v":""},{"$f":"IF('Sediment Data QA'!H2=\"\",\"\",'Sediment Data QA'!H2)","v":0}]
[{"$f":"'FW nonmetal plant'!B11","v":"No."},{"$f":"'FW nonmetal plant'!B13","v":1},{"$f":"'FW nonmetal plant'!B16","v":2},{"$f":"'FW nonmetal plant'!B19","v":3},{"$f":"'FW nonmetal plant'!B21","v":4},{"$f":"'FW nonmetal plant'!B23","v":5},{"$f":"'FW nonmetal plant'!B26","v":6},{"$f":"'FW nonmetal plant'!B29","v":7},{"$f":"'FW nonmetal plant'!B32","v":8},{"$f":"'FW nonmetal plant'!B35","v":9},{"$f":"'FW nonmetal plant'!B39","v":10},{"$f":"'FW nonmetal plant'!B42","v":11},{"$f":"'FW nonmetal plant'!B45","v":12},{"$f":"'FW nonmetal plant'!B48","v":13},{"$f":"'FW nonmetal plant'!B51","v":14},{"$f":"'FW nonmetal plant'!B53","v":15},{"$f":"'FW nonmetal plant'!B58","v":16.100000000000001},{"$f":"'FW nonmetal plant'!B62","v":17},{"$f":"'FW nonmetal plant'!B65","v":18},{"$f":"'FW nonmetal plant'!C70","v":"Total score"},{"$f":"'FW nonmetal plant'!C72","v":"Quality Score"}]
[{"$f":"'FW nonmetal plant'!C2","v":"Category"},{"$f":"'FW nonmetal plant'!E2","v":"Freshwater/non-metal/plant"},{"$f":"'FW nonmetal plant'!C3","v":"Paper and data unique identifier(eg. 1-1,10-150)"},{"$f":"'FW nonmetal plant'!E3","v":0}]
[{"$f":"'FW nonmetal plant'!G11","v":"Scores"},{"$f":"'FW nonmetal plant'!G12","v":0},{"$f":"'FW nonmetal plant'!G15","v":0},{"$f":"'FW nonmetal plant'!G18","v":0},{"$f":"'FW nonmetal plant'!G21","v":0},{"$f":"'FW nonmetal plant'!G23","v":0},{"$f":"'FW nonmetal plant'!G26","v":0},{"$f":"'FW nonmetal plant'!G29","v":0},{"$f":"'FW nonmetal plant'!G32","v":0},{"$f":"'FW nonmetal plant'!G35","v":0},{"$f":"'FW nonmetal plant'!G38","v":0},{"$f":"'FW nonmetal plant'!G41","v":0},{"$f":"'FW nonmetal plant'!G44","v":0},{"$f":"'FW nonmetal plant'!G47","v":0},{"$f":"'FW nonmetal plant'!G50","v":0},{"$f":"'FW nonmetal plant'!G53","v":0},{"$f":"'FW nonmetal plant'!G57","v":0},{"$f":"'FW nonmetal plant'!G61","v":0},{"$f":"'FW nonmetal plant'!G64","v":0},{"$f":"'FW nonmetal plant'!G70","v":""},{"$f":"'FW nonmetal plant'!G72","v":{"$error":"#N/A"}},{"$f":"'FW nonmetal plant'!H72","v":""}]
[{"$f":"'FW nonmetal plant'!H11","v":"Answers"},{"$f":"IF('FW nonmetal plant'!H12=\"\",\"\",'FW nonmetal plant'!H12)","v":""},{"$f":"IF('FW nonmetal plant'!H15=\"\",\"\",'FW nonmetal plant'!H15)","v":""},{"$f":"IF('FW nonmetal plant'!H18=\"\",\"\",'FW nonmetal plant'!H18)","v":""},{"$f":"IF('FW nonmetal plant'!H21=\"\",\"\",'FW nonmetal plant'!H21)","v":""},{"$f":"IF('FW nonmetal plant'!H23=\"\",\"\",'FW nonmetal plant'!H23)","v":""},{"$f":"IF('FW nonmetal plant'!H26=\"\",\"\",'FW nonmetal plant'!H26)","v":""},{"$f":"IF('FW nonmetal plant'!H29=\"\",\"\",'FW nonmetal plant'!H29)","v":""},{"$f":"IF('FW nonmetal plant'!H32=\"\",\"\",'FW nonmetal plant'!H32)","v":""},{"$f":"IF('FW nonmetal plant'!H35=\"\",\"\",'FW nonmetal plant'!H35)","v":""},{"$f":"IF('FW nonmetal plant'!H38=\"\",\"\",'FW nonmetal plant'!H38)","v":""},{"$f":"IF('FW nonmetal plant'!H41=\"\",\"\",'FW nonmetal plant'!H41)","v":""},{"$f":"IF('FW nonmetal plant'!H44=\"\",\"\",'FW nonmetal plant'!H44)","v":""},{"$f":"IF('FW nonmetal plant'!H47=\"\",\"\",'FW nonmetal plant'!H47)","v":""},{"$f":"IF('FW nonmetal plant'!H53=\"\",\"\",'FW nonmetal plant'!H53)","v":""},{"$f":"IF('FW nonmetal plant'!H53=\"\",\"\",'FW nonmetal plant'!H53)","v":""},{"$f":"IF('FW nonmetal plant'!H57=\"\",\"\",'FW nonmetal plant'!H57)","v":""},{"$f":"IF('FW nonmetal plant'!H61=\"\",\"\",'FW nonmetal plant'!H61)","v":""},{"$f":"IF('FW nonmetal plant'!H64=\"\",\"\",'FW nonmetal plant'!H64)","v":""}]
[{"$f":"'FW nonmetal plant'!G3","v":"Species (Scientific name)"},{"$f":"'FW nonmetal plant'!G4","v":"Lifestage"},{"$f":"'FW nonmetal plant'!G5","v":"Exposure duration"},{"$f":"'FW nonmetal plant'!G6","v":"Measure of toxicity"},{"$f":"'FW nonmetal plant'!G7","v":"Toxicity endpoint"},{"$f":"'FW nonmetal plant'!G8","v":"Toxicity value"},{"$f":"'FW nonmetal plant'!J2","v":"Taxonomic group"},{"$f":"'FW nonmetal plant'!J3","v":"Phylum"},{"$f":"'FW nonmetal plant'!J4","v":"Class"},{"$f":"'FW nonmetal plant'!J5","v":"Media"},{"$f":"'FW nonmetal plant'!J6","v":"Temperature "},{"$f":"'FW nonmetal plant'!J7","v":"Acute Or Chronic "},{"$f":"'FW nonmetal plant'!J8","v":"PH"},{"$f":"'FW nonmetal plant'!J9","v":"Salinity/Conductivity"},{"$f":"'FW nonmetal plant'!C4","v":"Citation"},{"$f":"'FW nonmetal plant'!G2","v":"Citation No."}]
[{"$f":"'FW nonmetal plant'!Q3","v":""},{"$f":"'FW nonmetal plant'!T3","v":""},{"$f":"'FW nonmetal plant'!W3","v":""},{"$f":"'FW nonmetal plant'!Z3","v":""},{"$f":"'FW nonmetal plant'!AC3","v":""},{"$f":"IF('FW nonmetal plant'!H8=\"\",\"\",'FW nonmetal plant'!H8)","v":""},{"$f":"'FW nonmetal plant'!AF3","v":""},{"$f":"'FW nonmetal plant'!AI3","v":""},{"$f":"'FW nonmetal plant'!AO3","v":""},{"$f":"'FW nonmetal plant'!AR3","v":""},{"$f":"'FW nonmetal plant'!AR3","v":""},{"$f":"'FW nonmetal plant'!AU3","v":""},{"$f":"'FW nonmetal plant'!AX3","v":""},{"$f":"'FW nonmetal plant'!BA3","v":"N.A."},{"$f":"IF('FW nonmetal plant'!E4=\"\",\"\",'FW nonmetal plant'!E4)","v":""},{"$f":"IF('FW nonmetal plant'!H2=\"\",\"\",'FW nonmetal plant'!H2)","v":0}]
[{"$f":"'FW metal plant'!B11","v":"No."},{"$f":"'FW metal plant'!B13","v":1},{"$f":"'FW metal plant'!B16","v":2},{"$f":"'FW metal plant'!B19","v":3},{"$f":"'FW metal plant'!B21","v":4},{"$f":"'FW metal plant'!B23","v":5},{"$f":"'FW metal plant'!B26","v":6},{"$f":"'FW metal plant'!B29","v":7},{"$f":"'FW metal plant'!B32","v":8},{"$f":"'FW metal plant'!B35","v":9},{"$f":"'FW metal plant'!B39","v":10},{"$f":"'FW metal plant'!B42","v":11},{"$f":"'FW metal plant'!B45","v":12},{"$f":"'FW metal plant'!B48","v":13},{"$f":"'FW metal plant'!B51","v":14},{"$f":"'FW metal plant'!B53","v":15},{"$f":"'FW metal plant'!B58","v":16.100000000000001},{"$f":"'FW metal plant'!B61","v":16.2},{"$f":"'FW metal plant'!B64","v":16.3},{"$f":"'FW metal plant'!B67","v":16.399999999999999},{"$f":"'FW metal plant'!B70","v":17},{"$f":"'FW metal plant'!B73","v":18},{"$f":"'FW metal plant'!C78","v":"Total score"},{"$f":"'FW metal plant'!C80","v":"Quality Score"}]
[{"$f":"'FW metal plant'!C2","v":"Category"},{"$f":"'FW metal plant'!E2","v":"Freshwater/metal/plant"},{"$f":"'FW metal plant'!C3","v":"Paper and data unique identifier(eg. 1-1,10-150)"},{"$f":"'FW metal plant'!E3","v":0}]
[{"$f":"'FW metal plant'!G11","v":"Scores"},{"$f":"'FW metal plant'!G12","v":0},{"$f":"'FW metal plant'!G15","v":0},{"$f":"'FW metal plant'!G18","v":0},{"$f":"'FW metal plant'!G21","v":0},{"$f":"'FW metal plant'!G23","v":0},{"$f":"'FW metal plant'!G26","v":0},{"$f":"'FW metal plant'!G29","v":0},{"$f":"'FW metal plant'!G32","v":0},{"$f":"'FW metal plant'!G35","v":0},{"$f":"'FW metal plant'!G38","v":0},{"$f":"'FW metal plant'!G41","v":0},{"$f":"'FW metal plant'!G44","v":0},{"$f":"'FW metal plant'!G47","v":0},{"$f":"'FW metal plant'!G50","v":0},{"$f":"'FW metal plant'!G53","v":0},{"$f":"'FW metal plant'!G57","v":0},{"$f":"'FW metal plant'!G60","v":0},{"$f":"'FW metal plant'!G63","v":0},{"$f":"'FW metal plant'!G66","v":0},{"$f":"'FW metal plant'!G69","v":0},{"$f":"'FW metal plant'!G72","v":0},{"$f":"'FW metal plant'!G78","v":""},{"$f":"'FW metal plant'!G80","v":{"$error":"#N/A"}},{"$f":"'FW metal plant'!H80","v":""}]
[{"$f":"'FW metal plant'!H11","v":"Answers"},{"$f":"IF('FW metal plant'!H12=\"\",\"\",'FW metal plant'!H12)","v":""},{"$f":"IF('FW metal plant'!H15=\"\",\"\",'FW metal plant'!H15)","v":""},{"$f":"IF('FW metal plant'!H18=\"\",\"\",'FW metal plant'!H18)","v":""},{"$f":"IF('FW metal plant'!H21=\"\",\"\",'FW metal plant'!H21)","v":""},{"$f":"IF('FW metal plant'!H23=\"\",\"\",'FW metal plant'!H23)","v":""},{"$f":"IF('FW metal plant'!H26=\"\",\"\",'FW metal plant'!H26)","v":""},{"$f":"IF('FW metal plant'!H29=\"\",\"\",'FW metal plant'!H29)","v":""},{"$f":"IF('FW metal plant'!H32=\"\",\"\",'FW metal plant'!H32)","v":""},{"$f":"IF('FW metal plant'!H35=\"\",\"\",'FW metal plant'!H35)","v":""},{"$f":"IF('FW metal plant'!H38=\"\",\"\",'FW metal plant'!H38)","v":""},{"$f":"IF('FW metal plant'!H41=\"\",\"\",'FW metal plant'!H41)","v":""},{"$f":"IF('FW metal plant'!H44=\"\",\"\",'FW metal plant'!H44)","v":""},{"$f":"IF('FW metal plant'!H47=\"\",\"\",'FW metal plant'!H47)","v":""},{"$f":"IF('FW metal plant'!H50=\"\",\"\",'FW metal plant'!H50)","v":""},{"$f":"IF('FW metal plant'!H53=\"\",\"\",'FW metal plant'!H53)","v":""},{"$f":"IF('FW metal plant'!H57=\"\",\"\",'FW metal plant'!H57)","v":""},{"$f":"IF('FW metal plant'!H60=\"\",\"\",'FW metal plant'!H60)","v":""},{"$f":"IF('FW metal plant'!H63=\"\",\"\",'FW metal plant'!H63)","v":""},{"$f":"IF('FW metal plant'!H66=\"\",\"\",'FW metal plant'!H66)","v":""},{"$f":"IF('FW metal plant'!H69=\"\",\"\",'FW metal plant'!H69)","v":""},{"$f":"IF('FW metal plant'!H72=\"\",\"\",'FW metal plant'!H72)","v":""}]
[{"$f":"'FW metal plant'!G3","v":"Species (Scientific name)"},{"$f":"'FW metal plant'!G4","v":"Lifestage"},{"$f":"'FW metal plant'!G5","v":"Exposure duration"},{"$f":"'FW metal plant'!G6","v":"Measure of toxicity"},{"$f":"'FW metal plant'!G7","v":"Toxicity endpoint"},{"$f":"'FW metal plant'!G8","v":"Toxicity value"},{"$f":"'FW metal plant'!J2","v":"Taxonomic group"},{"$f":"'FW metal plant'!J3","v":"Phylum"},{"$f":"'FW metal plant'!J4","v":"Class"},{"$f":"'FW metal plant'!J5","v":"Media"},{"$f":"'FW metal plant'!J6","v":"Temperature "},{"$f":"'FW metal plant'!J7","v":"Acute Or Chronic "},{"$f":"'FW metal plant'!J8","v":"PH"},{"$f":"'FW metal plant'!J9","v":"Salinity/Conductivity"},{"$f":"'FW metal plant'!C4","v":"Citation"},{"$f":"'FW metal plant'!G2","v":"Citation No."}]
[{"$f":"'FW metal plant'!Q3","v":""},{"$f":"'FW metal plant'!T3","v":""},{"$f":"'FW metal plant'!W3","v":""},{"$f":"'FW metal plant'!Z3","v":""},{"$f":"'FW metal plant'!AC3","v":""},{"$f":"IF('FW metal plant'!H8=\"\",\"\",'FW metal plant'!H8)","v":""},{"$f":"'FW metal plant'!AF3","v":""},{"$f":"'FW metal plant'!AI3","v":""},{"$f":"'FW metal plant'!AL3","v":""},{"$f":"'FW metal plant'!AO3","v":""},{"$f":"'FW metal plant'!AR3","v":""},{"$f":"'FW metal plant'!AU3","v":""},{"$f":"'FW metal plant'!AX3","v":""},{"$f":"'FW metal plant'!BA3","v":"N.A."},{"$f":"IF('FW metal plant'!E4=\"\",\"\",'FW metal plant'!E4)","v":""},{"$f":"IF('FW metal plant'!H2=\"\",\"\",'FW metal plant'!H2)","v":0}]
[{"$f":"'FW nonmetal nonplant'!B11","v":"No."},{"$f":"'FW nonmetal nonplant'!B13","v":1},{"$f":"'FW nonmetal nonplant'!B16","v":2},{"$f":"'FW nonmetal nonplant'!B19","v":3},{"$f":"'FW nonmetal nonplant'!B21","v":4},{"$f":"'FW nonmetal nonplant'!B23","v":5},{"$f":"'FW nonmetal nonplant'!B26","v":6},{"$f":"'FW nonmetal nonplant'!B29","v":7},{"$f":"'FW nonmetal nonplant'!B32","v":8},{"$f":"'FW nonmetal nonplant'!B35","v":9},{"$f":"'FW nonmetal nonplant'!B39","v":10},{"$f":"'FW nonmetal nonplant'!B42","v":11},{"$f":"'FW nonmetal nonplant'!B45","v":12},{"$f":"'FW nonmetal nonplant'!B48","v":13},{"$f":"'FW nonmetal nonplant'!B51","v":14},{"$f":"'FW nonmetal nonplant'!B53","v":15},{"$f":"'FW nonmetal nonplant'!B58","v":16.100000000000001},{"$f":"'FW nonmetal nonplant'!B61","v":16.2},{"$f":"'FW nonmetal nonplant'!B64","v":17},{"$f":"'FW nonmetal nonplant'!B67","v":18},{"$f":"'FW nonmetal nonplant'!C72","v":"Total score"},{"$f":"'FW nonmetal nonplant'!C74","v":"Quality Score"}]
[{"$f":"'FW nonmetal nonplant'!C2","v":"Category"},{"$f":"'FW nonmetal nonplant'!E2","v":"Freshwater/non-metal/non- plant"},{"$f":"'FW nonmetal nonplant'!C3","v":"Paper and data unique identifier(eg. 1-1,10-150)"},{"$f":"'FW nonmetal nonplant'!E3","v":0}]
[{"$f":"'FW nonmetal nonplant'!G11","v":"Scores"},{"$f":"'FW nonmetal nonplant'!G12","v":0},{"$f":"'FW nonmetal nonplant'!G15","v":0},{"$f":"'FW nonmetal nonplant'!G18","v":0},{"$f":"'FW nonmetal nonplant'!G21","v":0},{"$f":"'FW nonmetal nonplant'!G23","v":0},{"$f":"'FW nonmetal nonplant'!G26","v":0},{"$f":"'FW nonmetal nonplant'!G29","v":0},{"$f":"'FW nonmetal nonplant'!G32","v":0},{"$f":"'FW nonmetal nonplant'!G35","v":0},{"$f":"'FW nonmetal nonplant'!G38","v":0},{"$f":"'FW nonmetal nonplant'!G41","v":0},{"$f":"'FW nonmetal nonplant'!G44","v":0},{"$f":"'FW nonmetal nonplant'!G47","v":0},{"$f":"'FW nonmetal nonplant'!G50","v":0},{"$f":"'FW nonmetal nonplant'!G53","v":0},{"$f":"'FW nonmetal nonplant'!G57","v":0},{"$f":"'FW nonmetal nonplant'!G60","v":0},{"$f":"'FW nonmetal nonplant'!G63","v":0},{"$f":"'FW nonmetal nonplant'!G66","v":0},{"$f":"'FW nonmetal nonplant'!G72","v":""},{"$f":"'FW nonmetal nonplant'!G74","v":{"$error":"#N/A"}},null,{"$f":"'FW nonmetal nonplant'!H74","v":""}]
[{"$f":"'FW nonmetal nonplant'!H11","v":"Answers"},{"$f":"IF('FW nonmetal nonplant'!H12=\"\",\"\",'FW nonmetal nonplant'!H12)","v":""},{"$f":"IF('FW nonmetal nonplant'!H15=\"\",\"\",'FW nonmetal nonplant'!H15)","v":""},{"$f":"IF('FW nonmetal nonplant'!H18=\"\",\"\",'FW nonmetal nonplant'!H18)","v":""},{"$f":"IF('FW nonmetal nonplant'!H21=\"\",\"\",'FW nonmetal nonplant'!H21)","v":""},{"$f":"IF('FW nonmetal nonplant'!H23=\"\",\"\",'FW nonmetal nonplant'!H23)","v":""},{"$f":"IF('FW nonmetal nonplant'!H26=\"\",\"\",'FW nonmetal nonplant'!H26)","v":""},{"$f":"IF('FW nonmetal nonplant'!H29=\"\",\"\",'FW nonmetal nonplant'!H29)","v":""},{"$f":"IF('FW nonmetal nonplant'!H32=\"\",\"\",'FW nonmetal nonplant'!H32)","v":""},{"$f":"IF('FW nonmetal nonplant'!H35=\"\",\"\",'FW nonmetal nonplant'!H35)","v":""},{"$f":"IF('FW nonmetal nonplant'!H38=\"\",\"\",'FW nonmetal nonplant'!H38)","v":""},{"$f":"IF('FW nonmetal nonplant'!H41=\"\",\"\",'FW nonmetal nonplant'!H41)","v":""},{"$f":"IF('FW nonmetal nonplant'!H44=\"\",\"\",'FW nonmetal nonplant'!H44)","v":""},{"$f":"IF('FW nonmetal nonplant'!H47=\"\",\"\",'FW nonmetal nonplant'!H47)","v":""},{"$f":"IF('FW nonmetal nonplant'!H50=\"\",\"\",'FW nonmetal nonplant'!H50)","v":""},{"$f":"IF('FW nonmetal nonplant'!H53=\"\",\"\",'FW nonmetal nonplant'!H53)","v":""},{"$f":"IF('FW nonmetal nonplant'!H57=\"\",\"\",'FW nonmetal nonplant'!H57)","v":""},{"$f":"IF('FW nonmetal nonplant'!H60=\"\",\"\",'FW nonmetal nonplant'!H60)","v":""},{"$f":"IF('FW nonmetal nonplant'!H63=\"\",\"\",'FW nonmetal nonplant'!H63)","v":""},{"$f":"IF('FW nonmetal nonplant'!H66=\"\",\"\",'FW nonmetal nonplant'!H66)","v":""}]
[{"$f":"'FW nonmetal nonplant'!G3","v":"Species (Scientific name)"},{"$f":"'FW nonmetal nonplant'!G4","v":"Lifestage"},{"$f":"'FW nonmetal nonplant'!G5","v":"Exposure duration"},{"$f":"'FW nonmetal nonplant'!G6","v":"Measure of toxicity"},{"$f":"'FW nonmetal nonplant'!G7","v":"Toxicity endpoint"},{"$f":"'FW nonmetal nonplant'!G8","v":"Toxicity value"},{"$f":"'FW nonmetal nonplant'!J2","v":"Taxonomic group"},{"$f":"'FW nonmetal nonplant'!J3","v":"Phylum"},{"$f":"'FW nonmetal nonplant'!J4","v":"Class"},{"$f":"'FW nonmetal nonplant'!J5","v":"Media"},{"$f":"'FW nonmetal nonplant'!J6","v":"Temperature "},{"$f":"'FW nonmetal nonplant'!J7","v":"Acute Or Chronic "},{"$f":"'FW nonmetal nonplant'!J8","v":"PH"},{"$f":"'FW nonmetal nonplant'!J9","v":"Salinity/Conductivity"},{"$f":"'FW nonmetal nonplant'!C4","v":"Citation"},{"$f":"'FW nonmetal nonplant'!G2","v":"Citation No."}]
[{"$f":"'FW nonmetal nonplant'!Q3","v":""},{"$f":"'FW nonmetal nonplant'!T3","v":""},{"$f":"'FW nonmetal nonplant'!W3","v":""},{"$f":"'FW nonmetal nonplant'!Z3","v":""},{"$f":"'FW nonmetal nonplant'!AC3","v":""},{"$f":"IF('FW nonmetal nonplant'!H8=\"\",\"\",'FW nonmetal nonplant'!H8)","v":""},{"$f":"'FW nonmetal nonplant'!AF3","v":""},{"$f":"'FW nonmetal nonplant'!AI3","v":""},{"$f":"'FW nonmetal nonplant'!AL3","v":""},{"$f":"'FW nonmetal nonplant'!AO3","v":""},{"$f":"'FW nonmetal nonplant'!AR3","v":""},{"$f":"'FW nonmetal nonplant'!AU3","v":""},{"$f":"'FW nonmetal nonplant'!AX3","v":""},{"$f":"'FW nonmetal nonplant'!BA3","v":"N.A."},{"$f":"IF('FW nonmetal nonplant'!E4=\"\",\"\",'FW nonmetal nonplant'!E4)","v":""},{"$f":"IF('FW nonmetal nonplant'!H2=\"\",\"\",'FW nonmetal nonplant'!H2)","v":0}]
[{"$f":"'FW metal nonplant'!B11","v":"No."},{"$f":"'FW metal nonplant'!B13","v":1},{"$f":"'FW metal nonplant'!B16","v":2},{"$f":"'FW metal nonplant'!B19","v":3},{"$f":"'FW metal nonplant'!B21","v":4},{"$f":"'FW metal nonplant'!B23","v":5},{"$f":"'FW metal nonplant'!B26","v":6},{"$f":"'FW metal nonplant'!B29","v":7},{"$f":"'FW metal nonplant'!B32","v":8},{"$f":"'FW metal nonplant'!B35","v":9},{"$f":"'FW metal nonplant'!B39","v":10},{"$f":"'FW metal nonplant'!B42","v":11},{"$f":"'FW metal nonplant'!B45","v":12},{"$f":"'FW metal nonplant'!B48","v":13},{"$f":"'FW metal nonplant'!B51","v":14},{"$f":"'FW metal nonplant'!B53","v":15},{"$f":"'FW metal nonplant'!B58","v":16.100000000000001},{"$f":"'FW metal nonplant'!B61","v":16.2},{"$f":"'FW metal nonplant'!B64","v":16.3},{"$f":"'FW metal nonplant'!B67","v":16.399999999999999},{"$f":"'FW metal nonplant'!B70","v":16.5},{"$f":"'FW metal nonplant'!B73","v":17},{"$f":"'FW metal nonplant'!B76","v":18},{"$f":"'FW metal nonplant'!C81","v":"Total score"},{"$f":"'FW metal nonplant'!C83","v":"Quality Score"}]
[{"$f":"'FW metal nonplant'!C2","v":"Category"},{"$f":"'FW metal nonplant'!E2","v":"Freshwater/metal/non- plant"},{"$f":"'FW metal nonplant'!C3","v":"Paper and data unique identifier(eg. 1-1,10-150)"},{"$f":"'FW metal nonplant'!E3","v":0}]
[{"$f":"'FW metal nonplant'!G11","v":"Scores"},{"$f":"'FW metal nonplant'!G12","v":0},{"$f":"'FW metal nonplant'!G15","v":0},{"$f":"'FW metal nonplant'!G18","v":0},{"$f":"'FW metal nonplant'!G21","v":0},{"$f":"'FW metal nonplant'!G23","v":0},{"$f":"'FW metal nonplant'!G26","v":0},{"$f":"'FW metal nonplant'!G29","v":0},{"$f":"'FW metal nonplant'!G32","v":0},{"$f":"'FW metal nonplant'!G35","v":0},{"$f":"'FW metal nonplant'!G38","v":0},{"$f":"'FW metal nonplant'!G41","v":0},{"$f":"'FW metal nonplant'!G44","v":0},{"$f":"'FW metal nonplant'!G47","v":0},{"$f":"'FW metal nonplant'!G50","v":0},{"$f":"'FW metal nonplant'!G53","v":0},{"$f":"'FW metal nonplant'!G57","v":0},{"$f":"'FW metal nonplant'!G60","v":0},{"$f":"'FW metal nonplant'!G63","v":0},{"$f":"'FW metal nonplant'!G66","v":0},{"$f":"'FW metal nonplant'!G69","v":0},{"$f":"'FW metal nonplant'!G72","v":0},{"$f":"'FW metal nonplant'!G75","v":0},{"$f":"'FW metal nonplant'!G81","v":""},{"$f":"'FW metal nonplant'!G83","v":{"$error":"#N/A"}},{"$f":"'FW metal nonplant'!H83","v":""}]
[{"$f":"'FW metal nonplant'!H11","v":"Answers"},{"$f":"IF('FW metal nonplant'!H12=\"\",\"\",'FW metal nonplant'!H12)","v":""},{"$f":"IF('FW metal nonplant'!H15=\"\",\"\",'FW metal nonplant'!H15)","v":""},{"$f":"IF('FW metal nonplant'!H18=\"\",\"\",'FW metal nonplant'!H18)","v":""},{"$f":"IF('FW metal nonplant'!H21=\"\",\"\",'FW metal nonplant'!H21)","v":""},{"$f":"IF('FW metal nonplant'!H23=\"\",\"\",'FW metal nonplant'!H23)","v":""},{"$f":"IF('FW metal nonplant'!H26=\"\",\"\",'FW metal nonplant'!H26)","v":""},{"$f":"IF('FW metal nonplant'!H29=\"\",\"\",'FW metal nonplant'!H29)","v":""},{"$f":"IF('FW metal nonplant'!H32=\"\",\"\",'FW metal nonplant'!H32)","v":""},{"$f":"IF('FW metal nonplant'!H35=\"\",\"\",'FW metal nonplant'!H35)","v":""},{"$f":"IF('FW metal nonplant'!H38=\"\",\"\",'FW metal nonplant'!H38)","v":""},{"$f":"IF('FW metal nonplant'!H41=\"\",\"\",'FW metal nonplant'!H41)","v":""},{"$f":"IF('FW metal nonplant'!H44=\"\",\"\",'FW metal nonplant'!H44)","v":""},{"$f":"IF('FW metal nonplant'!H47=\"\",\"\",'FW metal nonplant'!H47)","v":""},{"$f":"IF('FW metal nonplant'!H50=\"\",\"\",'FW metal nonplant'!H50)","v":""},{"$f":"IF('FW metal nonplant'!H53=\"\",\"\",'FW metal nonplant'!H53)","v":""},{"$f":"IF('FW metal nonplant'!H57=\"\",\"\",'FW metal nonplant'!H57)","v":""},{"$f":"IF('FW metal nonplant'!H60=\"\",\"\",'FW metal nonplant'!H60)","v":""},{"$f":"IF('FW metal nonplant'!H63=\"\",\"\",'FW metal nonplant'!H63)","v":""},{"$f":"IF('FW metal nonplant'!H66=\"\",\"\",'FW metal nonplant'!H66)","v":""},{"$f":"IF('FW metal nonplant'!H69=\"\",\"\",'FW metal nonplant'!H69)","v":""},{"$f":"IF('FW metal nonplant'!H72=\"\",\"\",'FW metal nonplant'!H72)","v":""},{"$f":"IF('FW metal nonplant'!H75=\"\",\"\",'FW metal nonplant'!H75)","v":""}]
[{"$f":"'FW metal nonplant'!G3","v":"Species (Scientific name)"},{"$f":"'FW metal nonplant'!G4","v":"Lifestage"},{"$f":"'FW metal nonplant'!G5","v":"Exposure duration"},{"$f":"'FW metal nonplant'!G6","v":"Measure of toxicity"},{"$f":"'FW metal nonplant'!G7","v":"Toxicity endpoint"},{"$f":"'FW metal nonplant'!G8","v":"Toxicity value"},{"$f":"'FW metal nonplant'!J2","v":"Taxonomic group"},{"$f":"'FW metal nonplant'!J3","v":"Phylum"},{"$f":"'FW metal nonplant'!J4","v":"Class"},{"$f":"'FW metal nonplant'!J5","v":"Media"},{"$f":"'FW metal nonplant'!J6","v":"Temperature "},{"$f":"'FW metal nonplant'!J7","v":"Acute Or Chronic "},{"$f":"'FW metal nonplant'!J8","v":"PH"},{"$f":"'FW metal nonplant'!J9","v":"Salinity/Conductivity"},{"$f":"'FW metal nonplant'!C4","v":"Citation"},{"$f":"'FW metal nonplant'!G2","v":"Citation No."}]
[{"$f":"'FW metal nonplant'!Q3","v":""},{"$f":"'FW metal nonplant'!T3","v":""},{"$f":"'FW metal nonplant'!W3","v":""},{"$f":"'FW metal nonplant'!Z3","v":""},{"$f":"'FW metal nonplant'!AC3","v":""},{"$f":"IF('FW metal nonplant'!H8=\"\",\"\",'FW metal nonplant'!H8)","v":""},{"$f":"'FW metal nonplant'!AF3","v":""},{"$f":"'FW metal nonplant'!AI3","v":""},{"$f":"'FW metal nonplant'!AL3","v":""},{"$f":"'FW metal nonplant'!AO3","v":""},{"$f":"'FW metal nonplant'!AR3","v":""},{"$f":"'FW metal nonplant'!AU3","v":""},{"$f":"'FW metal nonplant'!AX3","v":""},{"$f":"'FW metal nonplant'!BA3","v":"N.A."},{"$f":"IF('FW metal nonplant'!E4=\"\",\"\",'FW metal nonplant'!E4)","v":""},{"$f":"IF('FW metal nonplant'!H2=\"\",\"\",'FW metal nonplant'!H2)","v":0}]
[{"$f":"'MEW nonplant'!B11","v":"No."},{"$f":"'MEW nonplant'!B13","v":1},{"$f":"'MEW nonplant'!B16","v":2},{"$f":"'MEW nonplant'!B19","v":3},{"$f":"'MEW nonplant'!B21","v":4},{"$f":"'MEW nonplant'!B23","v":5},{"$f":"'MEW nonplant'!B26","v":6},{"$f":"'MEW nonplant'!B29","v":7},{"$f":"'MEW nonplant'!B32","v":8},{"$f":"'MEW nonplant'!B35","v":9},{"$f":"'MEW nonplant'!B39","v":10},{"$f":"'MEW nonplant'!B42","v":11},{"$f":"'MEW nonplant'!B45","v":12},{"$f":"'MEW nonplant'!B48","v":13},{"$f":"'MEW nonplant'!B51","v":14},{"$f":"'MEW nonplant'!B53","v":15},{"$f":"'MEW nonplant'!B58","v":16.100000000000001},{"$f":"'MEW nonplant'!B61","v":16.2},{"$f":"'MEW nonplant'!B64","v":16.3},{"$f":"'MEW nonplant'!B67","v":17},{"$f":"'MEW nonplant'!B70","v":18},{"$f":"'MEW nonplant'!C75","v":"Total score"},{"$f":"'MEW nonplant'!C77","v":"Quality Score"}]
[{"$f":"'MEW nonplant'!C2","v":"Category"},{"$f":"'MEW nonplant'!E2","v":"MEW_nonplant"},{"$f":"'MEW nonplant'!C3","v":"Paper and data unique identifier(eg. 1-1,10-150)"},{"$f":"'MEW nonplant'!E3","v":"1-1"}]
[{"$f":"'MEW nonplant'!G11","v":"Scores"},{"$f":"'MEW nonplant'!G12","v":10},{"$f":"'MEW nonplant'!G15","v":10},{"$f":"'MEW nonplant'!G18","v":5},{"$f":"'MEW nonplant'!G21","v":5},{"$f":"'MEW nonplant'!G23","v":5},{"$f":"'MEW nonplant'!G26","v":5},{"$f":"'MEW nonplant'!G29","v":2},{"$f":"'MEW nonplant'!G32","v":0},{"$f":"'MEW nonplant'!G35","v":5},{"$f":"'MEW nonplant'!G38","v":4},{"$f":"'MEW nonplant'!G41","v":4},{"$f":"'MEW nonplant'!G44","v":0},{"$f":"'MEW nonplant'!G47","v":0},{"$f":"'MEW nonplant'!G50","v":0},{"$f":"'MEW nonplant'!G53","v":4},{"$f":"'MEW nonplant'!G57","v":1},{"$f":"'MEW nonplant'!G60","v":0},{"$f":"'MEW nonplant'!G63","v":3},{"$f":"'MEW nonplant'!G66","v":1},{"$f":"'MEW nonplant'!G69","v":0},{"$f":"'MEW nonplant'!G75","v":64},{"$f":"'MEW nonplant'!G77","v":0.68085106382978722},{"$f":"'MEW nonplant'!H77","v":""}]
[{"$f":"'MEW nonplant'!H11","v":"Answers"},{"$f":"IF('MEW nonplant'!H12=\"\",\"\",'MEW nonplant'!H12)","v":"Yes"},{"$f":"IF('MEW nonplant'!H15=\"\",\"\",'MEW nonplant'!H15)","v":"Stated and defined"},{"$f":"IF('MEW nonplant'!H18=\"\",\"\",'MEW nonplant'!H18)","v":"LC"},{"$f":"IF('MEW nonplant'!H21=\"\",\"\",'MEW nonplant'!H21)","v":50},{"$f":"IF('MEW nonplant'!H23=\"\",\"\",'MEW nonplant'!H23)","v":"No"},{"$f":"IF('MEW nonplant'!H26=\"\",\"\",'MEW nonplant'!H26)","v":""},{"$f":"IF('MEW nonplant'!H29=\"\",\"\",'MEW nonplant'!H29)","v":"Inferred"},{"$f":"IF('MEW nonplant'!H32=\"\",\"\",'MEW nonplant'!H32)","v":"No"},{"$f":"IF('MEW nonplant'!H35=\"\",\"\",'MEW nonplant'!H35)","v":"Seawater"},{"$f":"IF('MEW nonplant'!H38=\"\",\"\",'MEW nonplant'!H38)","v":"Static"},{"$f":"IF('MEW nonplant'!H41=\"\",\"\",'MEW nonplant'!H41)","v":""},{"$f":"IF('MEW nonplant'!H44=\"\",\"\",'MEW nonplant'!H44)","v":"No"},{"$f":"IF('MEW nonplant'!H47=\"\",\"\",'MEW nonplant'!H47)","v":"No"},{"$f":"IF('MEW nonplant'!H50=\"\",\"\",'MEW nonplant'!H50)","v":"Yes"},{"$f":"IF('MEW nonplant'!H53=\"\",\"\",'MEW nonplant'!H53)","v":"No"},{"$f":"IF('MEW nonplant'!H57=\"\",\"\",'MEW nonplant'!H57)","v":"Stated"},{"$f":"IF('MEW nonplant'!H60=\"\",\"\",'MEW nonplant'!H60)","v":"Not measured"},{"$f":"IF('MEW nonplant'!H63=\"\",\"\",'MEW nonplant'!H63)","v":"Stated"},{"$f":"IF('MEW nonplant'!H66=\"\",\"\",'MEW nonplant'!H66)","v":"Stated"},{"$f":"IF('MEW nonplant'!H69=\"\",\"\",'MEW nonplant'!H69)","v":"Yes"}]
[{"$f":"'MEW nonplant'!G3","v":"Species (Scientific name)"},{"$f":"'MEW nonplant'!G4","v":"Lifestage"},{"$f":"'MEW nonplant'!G5","v":"Exposure duration"},{"$f":"'MEW nonplant'!G6","v":"Measure of toxicity"},{"$f":"'MEW nonplant'!G7","v":"Toxicity endpoint"},{"$f":"'MEW nonplant'!G8","v":"Toxicity value"},{"$f":"'MEW nonplant'!J2","v":"Taxonomic group"},{"$f":"'MEW nonplant'!J3","v":"Phylum"},{"$f":"'MEW nonplant'!J4","v":"Class"},{"$f":"'MEW nonplant'!J5","v":"Media"},{"$f":"'MEW nonplant'!J6","v":"Temperature "},{"$f":"'MEW nonplant'!J7","v":"Acute Or Chronic "},{"$f":"'MEW nonplant'!J8","v":"PH"},{"$f":"'MEW nonplant'!J9","v":"Salinity/Conductivity"},{"$f":"'MEW nonplant'!C4","v":"Citation"},{"$f":"'MEW nonplant'!G2","v":"Citation No."}]
[{"$f":"'MEW nonplant'!Q3","v":"Brachionus plicatilis)"},{"$f":"'MEW nonplant'!T3","v":"0.5 h old"},{"$f":"'MEW nonplant'!W3","v":"24 h"},{"$f":"'MEW nonplant'!Z3","v":"LC50"},{"$f":"'MEW nonplant'!AC3","v":"Mortality"},{"$f":"IF('MEW nonplant'!H8=\"\",\"\",'MEW nonplant'!H8)","v":"586 µg/L"},{"$f":"'MEW nonplant'!AF3","v":"Rotifer"},{"$f":"'MEW nonplant'!AI3","v":"?"},{"$f":"'MEW nonplant'!AL3","v":"?"},{"$f":"'MEW nonplant'!AO3","v":"Synthetic seawater"},{"$f":"'MEW nonplant'!AR3","v":"20oC"},{"$f":"'MEW nonplant'!AU3","v":"Acute"},{"$f":"'MEW nonplant'!AX3","v":8},{"$f":"'MEW nonplant'!BA3","v":"20‰"},{"$f":"IF('MEW nonplant'!E4=\"\", \"\",'MEW nonplant'!E4)","v":"Lopez-Galindo et al 2010"},{"$f":"IF('MEW nonplant'!H2=\"\", \"\",'MEW nonplant'!H2)","v":"1"}]
[{"$f":"'MEW plant'!B11","v":"No."},{"$f":"'MEW plant'!B13","v":1},{"$f":"'MEW plant'!B16","v":2},{"$f":"'MEW plant'!B19","v":3},{"$f":"'MEW plant'!B21","v":4},{"$f":"'MEW plant'!B23","v":5},{"$f":"'MEW plant'!B26","v":6},{"$f":"'MEW plant'!B29","v":7},{"$f":"'MEW plant'!B32","v":8},{"$f":"'MEW plant'!B35","v":9},{"$f":"'MEW plant'!B39","v":10},{"$f":"'MEW plant'!B42","v":11},{"$f":"'MEW plant'!B45","v":12},{"$f":"'MEW plant'!B48","v":13},{"$f":"'MEW plant'!B51","v":14},{"$f":"'MEW plant'!B53","v":15},{"$f":"'MEW plant'!B57","v":16.100000000000001},{"$f":"'MEW plant'!B61","v":16.2},{"$f":"'MEW plant'!B64","v":17},{"$f":"'MEW plant'!B67","v":18},{"$f":"'MEW plant'!C72","v":"Total score"},{"$f":"'MEW plant'!C74","v":"Quality Score"}]
[{"$f":"'MEW plant'!C2","v":"Category"},{"$f":"'MEW plant'!E2","v":"MEW_plant"},{"$f":"'MEW plant'!C3","v":"Paper and data unique identifier(eg. 1-1,10-150)"},{"$f":"'MEW plant'!E3","v":"9-3"}]
[{"$f":"'MEW plant'!G11","v":"Scores"},{"$f":"'MEW plant'!G12","v":10},{"$f":"'MEW plant'!G15","v":10},{"$f":"'MEW plant'!G18","v":5},{"$f":"'MEW plant'!G21","v":5},{"$f":"'MEW plant'!G23","v":0},{"$f":"'MEW plant'!G26","v":0},{"$f":"'MEW plant'!G29","v":2},{"$f":"'MEW plant'!G32","v":5},{"$f":"'MEW plant'!G35","v":5},{"$f":"'MEW plant'!G38","v":4},{"$f":"'MEW plant'!G41","v":4},{"$f":"'MEW plant'!G44","v":0},{"$f":"'MEW plant'!G47","v":0},{"$f":"'MEW plant'!G50","v":4},{"$f":"'MEW plant'!G53","v":0},{"$f":"'MEW plant'!G57","v":3},{"$f":"'MEW plant'!G61","v":0},{"$f":"'MEW plant'!G64","v":0},{"$f":"'MEW plant'!G67","v":0},{"$f":"'MEW plant'!G72","v":63},{"$f":"'MEW plant'!G74","v":0.69230769230769229},{"$f":"'MEW plant'!H74","v":""}]
[{"$f":"'MEW plant'!H11","v":"Answers"},{"$f":"IF('MEW plant'!H12=\"\",\"\",'MEW plant'!H12)","v":"Yes"},{"$f":"IF('MEW plant'!H15=\"\",\"\",'MEW plant'!H15)","v":"Yes"},{"$f":"IF('MEW plant'!H18=\"\",\"\",'MEW plant'!H18)","v":"Yes"},{"$f":"IF('MEW plant'!H21=\"\",\"\",'MEW plant'!H21)","v":"Yes"},{"$f":"IF('MEW plant'!H23=\"\",\"\",'MEW plant'!H23)","v":"No"},{"$f":"IF('MEW plant'!H26=\"\",\"\",'MEW plant'!H26)","v":"Not stated"},{"$f":"IF('MEW plant'!H29=\"\",\"\",'MEW plant'!H29)","v":"Inferred"},{"$f":"IF('MEW plant'!H32=\"\",\"\",'MEW plant'!H32)","v":"Yes"},{"$f":"IF('MEW plant'!H35=\"\",\"\",'MEW plant'!H35)","v":"Synthetic seawater"},{"$f":"IF('MEW plant'!H38=\"\",\"\",'MEW plant'!H38)","v":"Flowthrough"},{"$f":"IF('MEW plant'!H41=\"\",\"\",'MEW plant'!H41)","v":"Measured 3 times daily"},{"$f":"IF('MEW plant'!H44=\"\",\"\",'MEW plant'!H44)","v":"No"},{"$f":"IF('MEW plant'!H47=\"\",\"\",'MEW plant'!H47)","v":"No"},{"$f":"IF('MEW plant'!H50=\"\",\"\",'MEW plant'!H50)","v":"Yes"},{"$f":"IF('MEW plant'!H53=\"\",\"\",'MEW plant'!H53)","v":"No estimate"},{"$f":"IF('MEW plant'!H57=\"\",\"\",'MEW plant'!H57)","v":"Not measured"},{"$f":"IF('MEW plant'!H60=\"\",\"\",'MEW plant'!H60)","v":"Not measured"},{"$f":"IF('MEW plant'!H63=\"\",\"\",'MEW plant'!H63)","v":"Stated"},{"$f":"IF('MEW plant'!H66=\"\",\"\",'MEW plant'!H66)","v":"Not measured"}]
[{"$f":"'MEW plant'!G3","v":"Species (Scientific name)"},{"$f":"'MEW plant'!G4","v":"Lifestage"},{"$f":"'MEW plant'!G5","v":"Exposure duration"},{"$f":"'MEW plant'!G6","v":"Measure of toxicity"},{"$f":"'MEW plant'!G7","v":"Toxicity endpoint"},{"$f":"'MEW plant'!G8","v":"Toxicity value"},{"$f":"'MEW plant'!J2","v":"Taxonomic group"},{"$f":"'MEW plant'!J3","v":"Phylum"},{"$f":"'MEW plant'!J4","v":"Class"},{"$f":"'MEW plant'!J5","v":"Media"},{"$f":"'MEW plant'!J6","v":"Temperature "},{"$f":"'MEW plant'!J7","v":"Acute Or Chronic "},{"$f":"'MEW plant'!J8","v":"PH"},{"$f":"'MEW plant'!J9","v":"Salinity/Conductivity"},{"$f":"'MEW plant'!C4","v":"Citation"},{"$f":"'MEW plant'!G2","v":"Citation No."}]
[{"$f":"'MEW plant'!Q3","v":"Palaemonetes pugio"},{"$f":"'MEW plant'!T3","v":0},{"$f":"'MEW plant'!W3","v":"96 h"},{"$f":"'MEW plant'!Z3","v":"Mortality"},{"$f":"'MEW plant'!AC3","v":"LC50"},{"$f":"IF('MEW plant'!H8=\"\",\"\",'MEW plant'!H8)","v":220},{"$f":"'MEW plant'!AF3","v":"Shrimp"},{"$f":"'MEW plant'!AI3","v":"?"},{"$f":"'MEW plant'!AL3","v":"?"},{"$f":"'MEW plant'!AO3","v":"Seawater"},{"$f":"'MEW plant'!AR3","v":"19-28oC"},{"$f":"'MEW plant'!AU3","v":"Acute"},{"$f":"'MEW plant'!AX3","v":"?"},{"$f":"'MEW plant'!BA3","v":"20‰"},{"$f":"IF('MEW plant'!E4=\"\",\"\",'MEW plant'!E4)","v":"Roberts and Gleeson 1978"},{"$f":"IF('MEW plant'!H2=\"\",\"\",'MEW plant'!H2)","v":"9"}]

{"sheet":"FW metal nonplant","index":20,"n_rows":90,"n_cols":54,"rows_kept":90,"cut":false,"hidden":false,"merged":[[3,4,7,4],[9,2,9,4],[11,2,13,2],[11,7,13,7],[14,2,16,2],[14,7,16,7],[17,2,19,2],[17,7,19,7],[20,2,21,2],[20,7,21,7],[22,2,24,2],[22,7,24,7],[25,2,27,2],[25,7,27,7],[28,2,30,2],[28,7,30,7],[31,2,33,2],[31,7,33,7],[34,2,36,2],[34,7,36,7],[37,2,39,2],[37,7,39,7],[40,2,42,2],[40,7,42,7],[43,2,45,2],[43,7,45,7],[46,2,48,2],[46,7,48,7],[49,2,51,2],[49,7,51,7],[62,7,64,7],[74,2,77,2],[74,7,77,7],[52,2,54,2],[52,7,54,7],[56,7,58,7],[65,7,67,7],[68,7,70,7],[71,2,73,2],[71,7,73,7],[59,7,61,7]]}
[null,1,"Fill in the blank cells below, based on information provided in the paper being assessed. You can either pick an option from the dropdown list or add the appropriate detail using the 'Add to list' button. ",null,null,null,null,null,null,null,null,null,null,null,"* All the text in RED are used for drop down list ,make changes with caution."]
[null,null,"Category",{"$f":"IF(AF3=\"\",0,1)","v":0},"Freshwater/metal/non- plant",{"$f":"IF(E3=\"\",0,1)","v":0},"Citation No.",{"$f":"IF(ISERROR(FIND(\"-\",E3)),E3,LEFT(E3,FIND(\"-\",E3)-1))","v":0},null,"Taxonomic group",null,null,null,null,"Species",null,null,"Lifestage",null,null,"Exposure duration",null,null,"Measure of toxicity",null,null,"Toxicity endpoint",null,null,"Taxonomic group",null,null,"Phylum",null,null,"Class",null,null,"Media",null,null,"Temperature ",null,null,"Acute Or Chronic",null,null,"PH",null,null,"Salinity/Comdictivity"]
[null,null,"Paper and data unique identifier(eg. 1-1,10-150)",{"$f":"IF(AI3=\"\",0,1)","v":0},null,{"$f":"IF(E4=\"\",0,1)","v":0},"Species (Scientific name)",null,null,"Phylum",null,null,null,null,"Aedes albopictus",0,{"$f":"IF(P3=0,\"\",INDEX(O3:O111,P3))","v":""},"1 month",0,{"$f":"IF(S3=0,\"\",INDEX(R3:R111,S3))","v":""},"11 hour",0,{"$f":"IF(V3=0,\"\",INDEX(U3:U111,V3))","v":""},"LC50",0,{"$f":"IF(Y3=0,\"\",INDEX(X3:X111,Y3))","v":""},"Mortality",0,{"$f":"IF(AB3=0,\"\",INDEX(AA3:AA111,AB3))","v":""},"Fish",0,{"$f":"IF(AE3=0,\"\",INDEX(AD3:AD111,AE3))","v":""},"Chlorophyta",0,{"$f":"IF(AH3=0,\"\",INDEX(AG3:AG111,AH3))","v":""},"Branchiopoda",0,{"$f":"IF(AK3=0,\"\",INDEX(AJ3:AJ111,AK3))","v":""},"Freshwater",0,{"$f":"IF(AN3=0,\"\",INDEX(AM3:AM111,AN3))","v":""},"15°C",0,{"$f":"IF(AQ3=0,\"\",INDEX(AP3:AP111,AQ3))","v":""},"Acute ",0,{"$f":"IF(AT3=0,\"\",INDEX(AS3:AS111,AT3))","v":""},"N.A.",0,{"$f":"IF(AW3=0,\"\",INDEX(AV3:AV111,AW3))","v":""},null,null,"N.A.",1]
[null,null,"Citation",{"$f":"IF(AL3=\"\",0,1)","v":0},null,{"$f":"IF(H8=\"\",0,1)","v":0},"Lifestage",null,null,"Class",null,null,null,null,"Australian Bass",null,null,"1 year old",null,null,"13 days",null,null,"N.A.",null,null,"N.A.",null,null,"Microalga",null,null,"N.A.",null,null,"Chlorophyceae",null,null,"Marinewater",null,null,"25°C",null,null,"Chronic",null,null,"PH11"]
[null,null,null,{"$f":"IF(AO3=\"\",0,1)","v":0},null,{"$f":"IF(AX3=\"\",0,1)","v":0},"Exposure duration",null,null,"Media",null,null,null,null,"N.A.",null,null,"N.A.",null,null,"N.A.",null,null,"NOEC",null,null,"Reproduction",null,null,"N.A.",null,null,"Tracheophyta",null,null,"N.A.",null,null,"N.A.",null,null,"N.A.",null,null,"N.A.",null,null,"PH7.0"]
[null,null,null,{"$f":"IF(AR3=\"\",0,1)","v":0},null,{"$f":"IF(Q3=\"\",0,1)","v":0},"Measure of toxicity",null,null,"Temperature "]
[null,null,null,{"$f":"IF(AU3=\"\",0,1)","v":0},null,{"$f":"IF(T3=\"\",0,1)","v":0},"Toxicity endpoint",null,null,"Acute Or Chronic "]
[null,null,null,null,null,{"$f":"IF(W3=\"\",0,1)","v":0},"Toxicity value",null,null,"PH"]
[null,2,"Select the appropriate answer option to each question. Comments can be added to the cells in column H.",null,null,{"$f":"IF(Z3=\"\",0,1)","v":0},null,null,null,"Salinity/Conductivity","N.A."]
[null,"*","If the selected answer option does not work try clicking on any other cell first and then click back on the answer option again.",null,null,{"$f":"IF(AC3=\"\",0,1)","v":0}]
[null,"No.","Question","Marks Awarded","Answer Options","Option References","Scores","Answers"]
[null,null,"Was the duration of the exposure stated (e.g. 48 or 96 h)?",10,null,0,{"$f":"IF(F15=0,0,INDEX($D12:$D13,F12,1))","v":0}]
[null,1,null,0]
[]
[null,null,"Was the biological endpoint (e.g. immobilization or population growth) stated and defined (10 marks)? Award 5 marks if the biological endpoint is only stated.",10,null,0,{"$f":"IF(F15=0,0,INDEX($D15:$D17,F15,1))","v":0}]
[null,2,null,5]
[null,null,null,0]
[null,null,"Was the biological effect stated (e.g. LC or NOEC)?",5,null,0,{"$f":"IF(F18=0,0,INDEX($D18:$D19,F18,1))","v":0}]
[null,3,null,0]
[]
[null,4,"Was the biological effect quantified (e.g. 50% effect, 25% effect)? \nNote: The effect for NOEC and LOEC data must be quantified.",5,null,0,{"$f":"IF(F21=0,0,INDEX($D21:$D22,F21,1))","v":0}]
[null,null,null,0]
[null,5,"Were appropriate controls (e.g. a no-toxicant control and/or solvent control) used?",5,null,0,{"$f":"IF(F23=0,0,INDEX($D23:$D24,F23,1))","v":0}]
[null,null,null,0]
[]
[null,6,"Was each control and contaminant concentration at least duplicated?",5,null,0,{"$f":"IF(F26=0,0,INDEX($D26:$D27,F26,1))","v":0}]
[null,null,null,0]
[]
[null,7,"Were test acceptability criteria stated (e.g. mortality in controls must not exceed a certain percentage) (5 marks)?\nOR Were test acceptability criteria inferred (e.g. test method used [USEPA, OECD, ASTM etc.]) (award 2 marks). \nNote: Data that fail the acceptability criteria are automatically deemed to be of unacceptable quality and must not be used. ",5,null,0,{"$f":"IF(F29=0,0,INDEX($D29:$D31,F29,1))","v":0}]
[null,null,null,2]
[null,null,null,0]
[null,8,"Were the characteristics of the test organism (e.g. length, mass, age) stated?",5,null,0,{"$f":"IF(F32=0,0,INDEX($D32:$D34,F32,1))","v":0}]
[null,null,null,0]
[]
[null,9,"Was the type of test media used stated?",5,null,0,{"$f":"IF(F35=0,0,INDEX($D35:$D37,F35,1))","v":0}]
[null,null,null,0]
[]
[null,null,"Was the type of exposure (e.g. static, flow through) stated? ",4,null,0,{"$f":"IF(F38=0,0,INDEX($D38:$D40,F38,1))","v":0}]
[null,10,null,0]
[]
[null,null,"Were the contaminant concentrations measured at the beginning and end of the exposure (4 marks)? Award 2 marks if they were measured only once during the test.\nNote: If the concentrations were not measured then automatically the data cannot be high quality. ",4,null,0,{"$f":"IF(F41=0,0,INDEX($D41:$D43,F41,1))","v":0}]
[null,11,null,2]
[null,null,null,0]
[null,null,"Were parallel reference toxicant toxicity tests conducted?",4,null,0,{"$f":"IF(F44=0,0,INDEX($D44:$D46,F44,1))","v":0}]
[null,12,null,0]
[]
[null,null,"Was there a concentration–response relationship either observable or stated?",4,null,0,{"$f":"IF(F47=0,0,INDEX($D47:$D49,F47,1))","v":0}]
[null,13,null,0]
[]
[null,null,"Was an appropriate statistical method or model used to determine the toxicity?\nNote: They should be accepted by a recognised national or international regulatory body (e.g. USEPA, OECD, ASTM). ",4,null,0,{"$f":"IF(F50=0,0,INDEX($D50:$D52,F50,1))","v":0}]
[null,14,null,0]
[]
[null,15,"For LC/EC/BEC data was an estimate of variability provided? \nOR \nFor NO EC/LOEC data was the significance level 0.05 or less?  \n\n",4,null,0,{"$f":"IF(F53=0,0,INDEX($D53:$D55,F53,1))","v":0}]
[null,null,null,0]
[]
[null,16,"Were the following parameters measured and stated? (3 marks if measured and stated, 1 mark if just measured)."]
[null,null,null,3,null,0,{"$f":"IF(F57=0,0,INDEX($D57:$D59,F57,1))","v":0}]
[null,16.100000000000001,"pH",1]
[null,null,null,0]
[null,null,null,3,null,0,{"$f":"IF(F60=0,0,INDEX($D60:$D62,F60,1))","v":0}]
[null,16.2,"Hardness",1]
[null,null,null,0]
[null,null,null,3,null,0,{"$f":"IF(F63=0,0,INDEX($D63:$D65,F63,1))","v":0}]
[null,16.3,"Alkalinity",1]
[null,null,null,0]
[null,null,null,3,null,0,{"$f":"IF(F66=0,0,INDEX($D66:$D68,F66,1))","v":0}]
[null,16.399999999999999,"Organic carbon concentration",1]
[null,null,null,0]
[null,null,null,3,null,0,{"$f":"IF(F69=0,0,INDEX($D69:$D71,F69,1))","v":0}]
[null,16.5,"Dissolved Oxygen",1]
[null,null,null,0]
[null,null,"Was the temperature measured and stated (3 marks)? Award 1 mark if the temperature was measured but not stated or if only the temperature settings of the room or chamber are stated.",3,null,0,{"$f":"IF(F72=0,0,INDEX($D72:$D74,F72,1))","v":0}]
[null,17,null,1]
[null,null,null,0]
[null,null,"Were test solutions, blanks and/or controls tested for contamination OR were analytical reagent grade chemicals used or the highest possible purity chemicals used for the experiment? (3 marks).",3,null,0,{"$f":"IF(F75=0,0,INDEX($D75:$D76,F75,1))","v":0}]
[null,18,null,0]
[]
[null,null,null,null,null,null,null,null,{"$f":"(COUNTIF(F12:F76,\"=0\"))+COUNTIF(F2:F10,\"=0\")+COUNTIF(D2:D7,\"=0\")","v":37}]
[]
[]
[null,null,"Total score",null,null,null,{"$f":"IF(SUM(G12:G75)=0,\"\",SUM(G12:G75))","v":""}]
[null,null,"Total Max. possible score for the various types of data and contaminants ",null,{"$f":"D12+D15+D18+D21+D23+D26+D29+D32+D35+D38+D41+D44+D47+D50+D53+D57+D66+D69+D72+D75+D63+D60","v":100}]
[null,null,"Quality Score",null,{"$f":"\"= [Total score / Total possible score] * 100 = \"","v":"= [Total score / Total possible score] * 100 = "},null,{"$f":"IF(ISERROR(G81/E82),#N/A,G81/E82)","v":{"$error":"#N/A"}},{"$f":"IF(F41=3,\"The highest possible grade for this datum is acceptable.\",\"\")","v":""}]
[]
[null,null,"H = high quality                           Quality score ≥ 80%     "]
[null,null,"A = acceptable quality         > 50% Quality score < 80%  "]
[null,null,"U = unacceptable quality              Quality score ≤ 50% "]
[]
[3,null,"Click the 'Save & Update' button to save and export the answers to the 'All results' worksheet. "]
[null,null,"Select the 'Reset Answers' button if you wish to clear all answers."]

{"sheet":"FW metal nonplant_WS","index":21,"n_rows":5,"n_cols":25,"rows_kept":5,"cut":false,"hidden":false,"merged":[]}
[]
["Question No.",1,2,3,4,5,6,7,8,9,10,11,12,13,14,15,16.100000000000001,16.2,16.3,16.399999999999999,16.600000000000001,17,18,"Total Score","Quality Score"]
["Short Questions","Duration of the exposure ","Biological endpoint","Biological effect stated or not","Biological effect quantified or not","Appropriate controls","Control & contaminant concentration","Test acceptability criteria","Characteristics of the test organism"," Type of test media","Type of exposure","Contaminant concentrations","Parallel reference toxicant toxicity tests","Concentration–response relationship","Determine the toxicity","NOEC/LOEC or LC/EC/BEC","pH","Hardness","Alkalinity","Organic carbon concentration","Dissolved Oxygen","Temperature","Grade or purity"]
["Marks Awarded ","10 or 0","10,5 or 0","5 or 0 ","5 or 0 ","5 or 0 ","5 or 0 ","5 or 0 ","5 or 0 ","5 or 0 ","4 or 0","4 or 2 or 0","4 or 2","4 or 2","4 or 2","4 or 2","3 or 1 or 0","3 or 1 or 0","3 or 1 or 0","3 or 1 or 0","3 or 1 or 0","3 or 0","3 or 0 "]
["Max. Possible Score",10,10,5,5,5,5,5,5,5,4,4,4,4,4,4,3,3,3,3,3,3,3,{"$f":"SUM(B5:W5)","v":100}]

{"sheet":"FW nonmetal nonplant","index":22,"n_rows":81,"n_cols":53,"rows_kept":81,"cut":false,"hidden":false,"merged":[[3,4,7,4],[9,2,9,4],[11,2,13,2],[11,7,13,7],[14,2,16,2],[14,7,16,7],[17,2,19,2],[17,7,19,7],[20,2,21,2],[20,7,21,7],[22,2,24,2],[22,7,24,7],[25,2,27,2],[25,7,27,7],[28,2,30,2],[28,7,30,7],[31,2,33,2],[31,7,33,7],[34,2,36,2],[34,7,36,7],[37,2,39,2],[37,7,39,7],[40,2,42,2],[40,7,42,7],[43,2,45,2],[43,7,45,7],[46,2,48,2],[46,7,48,7],[49,2,51,2],[49,7,51,7],[65,2,68,2],[65,7,68,7],[59,7,61,7],[52,2,54,2],[52,7,54,7],[56,7,58,7],[62,2,64,2],[62,7,64,7]]}
[null,1,"Fill in the blank cells below, based on information provided in the paper being assessed. You can either pick an option from the dropdown list or add the appropriate detail using the 'Add to list' button. ",null,null,null,null,null,null,null,null,null,null,null,"* All the text in RED are used for drop down list ,make changes with caution."]
[null,null,"Category",{"$f":"IF(AF3=\"\",0,1)","v":0},"Freshwater/non-metal/non- plant",{"$f":"IF(E3=\"\",0,1)","v":0},"Citation No.",{"$f":"IF(ISERROR(FIND(\"-\",E3)),E3,LEFT(E3,FIND(\"-\",E3)-1))","v":0},null,"Taxonomic group",null,null,null,null,"Species",null,null,"Lifestage",null,null,"Exposure duration",null,null,"Measure of toxicity",null,null,"Toxicity endpoint",null,null,"Taxonomic group",null,null,"Phylum",null,null,"Class",null,null,"Media",null,null,"Temperature ",null,null,"Acute Or Chronic",null,null,"PH",null,null,"Salinity/Comdictivity"]
[null,null,"Paper and data unique identifier(eg. 1-1,10-150)",{"$f":"IF(AI3=\"\",0,1)","v":0},null,{"$f":"IF(E4=\"\",0,1)","v":0},"Species (Scientific name)",null,null,"Phylum",null,null,null,null,"Aedes albopictus",0,{"$f":"IF(P3=0,\"\",INDEX(O3:O102,P3))","v":""},"1 month",0,{"$f":"IF(S3=0,\"\",INDEX(R3:R102,S3))","v":""},"11 hour",0,{"$f":"IF(V3=0,\"\",INDEX(U3:U102,V3))","v":""},"LC50",0,{"$f":"IF(Y3=0,\"\",INDEX(X3:X102,Y3))","v":""},"Mortality",0,{"$f":"IF(AB3=0,\"\",INDEX(AA3:AA102,AB3))","v":""},"Fish",0,{"$f":"IF(AE3=0,\"\",INDEX(AD3:AD102,AE3))","v":""},"Chlorophyta",0,{"$f":"IF(AH3=0,\"\",INDEX(AG3:AG102,AH3))","v":""},"Branchiopoda",0,{"$f":"IF(AK3=0,\"\",INDEX(AJ3:AJ102,AK3))","v":""},"Freshwater",0,{"$f":"IF(AN3=0,\"\",INDEX(AM3:AM102,AN3))","v":""},"15°C",0,{"$f":"IF(AQ3=0,\"\",INDEX(AP3:AP102,AQ3))","v":""},"Acute ",0,{"$f":"IF(AT3=0,\"\",INDEX(AS3:AS102,AT3))","v":""},"N.A.",0,{"$f":"IF(AW3=0,\"\",INDEX(AV3:AV102,AW3))","v":""},null,null,"N.A."]
[null,null,"Citation",{"$f":"IF(AL3=\"\",0,1)","v":0},null,{"$f":"IF(H8=\"\",0,1)","v":0},"Lifestage",null,null,"Class",null,null,null,null,"Australian Bass",null,null,"1 year old",null,null,"13 days",null,null,"N.A.",null,null,"N.A.",null,null,"Microalga",null,null,"N.A.",null,null,"Chlorophyceae  ",null,null,"Marinewater",null,null,"25°C",null,null,"Chronic",null,null,"PH11"]
[null,null,null,{"$f":"IF(AO3=\"\",0,1)","v":0},null,{"$f":"IF(W3=\"\",0,1)","v":0},"Exposure duration",null,null,"Media",null,null,null,null,"N.A.",null,null,"N.A.",null,null,"N.A.",null,null,"NOEC",null,null,"Reproduction",null,null,"N.A.",null,null,"Tracheophyta",null,null,"N.A.",null,null,"N.A.",null,null,"N.A.",null,null,"N.A.",null,null,"PH7.0"]
[null,null,null,{"$f":"IF(AR3=\"\",0,1)","v":0},null,{"$f":"IF(Q3=\"\",0,1)","v":0},"Measure of toxicity",null,null,"Temperature "]
[null,null,null,{"$f":"IF(AU3=\"\",0,1)","v":0},null,{"$f":"IF(T3=\"\",0,1)","v":0},"Toxicity endpoint",null,null,"Acute Or Chronic "]
[null,null,null,null,null,{"$f":"IF(W3=\"\",0,1)","v":0},"Toxicity value",null,null,"PH"]
[null,2,"Select the appropriate answer option to each question. Comments can be added to the cells in column H.",null,null,{"$f":"IF(Z3=\"\",0,1)","v":0},null,null,null,"Salinity/Conductivity","N.A."]
[null,"*","If the selected answer option does not work try clicking on any other cell first and then click back on the answer option again.",null,null,{"$f":"IF(AC3=\"\",0,1)","v":0}]
[null,"No.","Question","Marks Awarded","Answer Options","Option References","Scores","Answers"]
[null,null,"Was the duration of the exposure stated (e.g. 48 or 96 h)?",10,null,0,{"$f":"IF(F12=0,0,INDEX($D12:$D13,F12,1))","v":0}]
[null,1,null,0]
[]
[null,null,"Was the biological endpoint (e.g. immobilization or population growth) stated and defined (10 marks)? Award 5 marks if the biological endpoint is only stated.",10,null,0,{"$f":"IF(F15=0,0,INDEX($D15:$D17,F15,1))","v":0}]
[null,2,null,5]
[null,null,null,0]
[null,null,"Was the biological effect stated (e.g. LC or NOEC)?",5,null,0,{"$f":"IF(F18=0,0,INDEX($D18:$D19,F18,1))","v":0}]
[null,3,null,0]
[]
[null,4,"Was the biological effect quantified (e.g. 50% effect, 25% effect)? \nNote: The effect for NOEC and LOEC data must be quantified.",5,null,0,{"$f":"IF(F21=0,0,INDEX($D21:$D22,F21,1))","v":0}]
[null,null,null,0]
[null,5,"Were appropriate controls (e.g. a no-toxicant control and/or solvent control) used?",5,null,0,{"$f":"IF(F23=0,0,INDEX($D23:$D24,F23,1))","v":0}]
[null,null,null,0]
[]
[null,6,"Was each control and contaminant concentration at least duplicated?",5,null,0,{"$f":"IF(F26=0,0,INDEX($D26:$D27,F26,1))","v":0}]
[null,null,null,0]
[]
[null,7,"Were test acceptability criteria stated (e.g. mortality in controls must not exceed a certain percentage) (5 marks)?\nOR Were test acceptability criteria inferred (e.g. test method used [USEPA, OECD, ASTM etc.]) (award 2 marks). \nNote: Data that fail the acceptability criteria are automatically deemed to be of unacceptable quality and must not be used. ",5,null,0,{"$f":"IF(F29=0,0,INDEX($D29:$D31,F29,1))","v":0}]
[null,null,null,2]
[null,null,null,0]
[null,8,"Were the characteristics of the test organism (e.g. length, mass, age) stated?",5,null,0,{"$f":"IF(F32=0,0,INDEX($D32:$D34,F32,1))","v":0}]
[null,null,null,0]
[]
[null,9,"Was the type of test media used stated?",5,null,0,{"$f":"IF(F35=0,0,INDEX($D35:$D37,F35,1))","v":0}]
[null,null,null,0]
[]
[null,null,"Was the type of exposure (e.g. static, flow through) stated? ",4,null,0,{"$f":"IF(F38=0,0,INDEX($D38:$D40,F38,1))","v":0}]
[null,10,null,0]
[]
[null,null,"Were the contaminant concentrations measured at the beginning and end of the exposure (4 marks)? Award 2 marks if they were measured only once during the test.\nNote: If the concentrations were not measured then automatically the data cannot be high quality. ",4,null,0,{"$f":"IF(F41=0,0,INDEX($D41:$D43,F41,1))","v":0}]
[null,11,null,2]
[null,null,null,0]
[null,null,"Were parallel reference toxicant toxicity tests conducted?",4,null,0,{"$f":"IF(F44=0,0,INDEX($D44:$D46,F44,1))","v":0}]
[null,12,null,0]
[]
[null,null,"Was there a concentration–response relationship either observable or stated?",4,null,0,{"$f":"IF(F47=0,0,INDEX($D47:$D49,F47,1))","v":0}]
[null,13,null,0]
[]
[null,null,"Was an appropriate statistical method or model used to determine the toxicity?\nNote: They should be accepted by a recognised national or international regulatory body (e.g. USEPA, OECD, ASTM). ",4,null,0,{"$f":"IF(F50=0,0,INDEX($D50:$D52,F50,1))","v":0}]
[null,14,null,0]
[]
[null,15,"For LC/EC/BEC data was an estimate of variability provided? \nOR \nFor NO EC/LOEC data was the significance level 0.05 or less?  \n\n",4,null,0,{"$f":"IF(F53=0,0,INDEX($D53:$D55,F53,1))","v":0}]
[null,null,null,0]
[]
[null,16,"Were the following parameters measured and stated? (3 marks if measured and stated, 1 mark if just measured)."]
[null,null,null,3,null,0,{"$f":"IF(F57=0,0,INDEX($D57:$D59,F57,1))","v":0}]
[null,16.100000000000001,"pH",1]
[null,null,null,0]
[null,null,null,3,null,0,{"$f":"IF(F60=0,0,INDEX($D60:$D62,F60,1))","v":0}]
[null,16.2,"Dissolved Oxygen",1]
[null,null,null,0]
[null,null,"Was the temperature measured and stated (3 marks)? Award 1 mark if the temperature was measured but not stated or if only the temperature settings of the room or chamber are stated.",3,null,0,{"$f":"IF(F63=0,0,INDEX(D63:D65,F63,1))","v":0}]
[null,17,null,1]
[null,null,null,0]
[null,null,"Were test solutions, blanks and/or controls tested for contamination OR were analytical reagent grade chemicals used or the highest possible purity chemicals used for the experiment? (3 marks).",3,null,0,{"$f":"IF(F66=0,0,INDEX($D66:$D67,F66,1))","v":0}]
[null,18,null,0]
[]
[null,null,null,null,null,null,null,null,{"$f":"(COUNTIF(F12:F67,\"=0\"))+COUNTIF(F2:F10,\"=0\")+COUNTIF(D2:D7,\"=0\")","v":34}]
[]
[]
[null,null,"Total score",null,null,null,{"$f":"IF(SUM(G12:G66)=0,\"\",SUM(G12:G66))","v":""}]
[null,null,"Total Max. possible score for the various types of data and contaminants ",null,{"$f":"D12+D15+D18+D21+D23+D26+D29+D32+D35+D38+D41+D44+D47+D50+D53+D57+D60+D63+D66","v":91}]
[null,null,"Quality Score",null,{"$f":"\"= [Total score / Total possible score] * 100 = \"","v":"= [Total score / Total possible score] * 100 = "},null,{"$f":"IF(ISERROR(G72/E73),#N/A,G72/E73)","v":{"$error":"#N/A"}},{"$f":"IF(F41=3,\"The highest possible grade for this datum is acceptable.\",\"\")","v":""}]
[]
[null,null,"H = high quality                           Quality score ≥ 80%      "]
[null,null,"A = acceptable quality         > 50% Quality score < 80%        "]
[null,null,"U = unacceptable quality              Quality score ≤ 50%  "]
[]
[3,null,"Click the 'Save & Update' button to save and export the answers to the 'All results' worksheet. "]
[null,null,"Select the 'Reset Answers' button if you wish to clear all answers."]

{"sheet":"FW nonmetal nonplant_WS","index":23,"n_rows":3,"n_cols":24,"rows_kept":3,"cut":false,"hidden":false,"merged":[]}
[]
["Question No.",1,2,3,4,5,6,7,8,9,10,11,12,13,14,15,16.100000000000001,16.600000000000001,17,18,"Total Score","Quality Score",null,"Comment "]
["Short Questions","Duration of the exposure ","Biological endpoint","Biological effect stated or not","Biological effect quantified or not","Appropriate controls","Control & contaminant concentration","Test acceptability criteria","Characteristics of the test organism"," Type of test media","Type of exposure","Contaminant concentrations","Parallel reference toxicant toxicity tests","Concentration–response relationship","Determine the toxicity","NOEC/LOEC or LC/EC/BEC","pH","Dissolved oxygen","Temperature","Grade or purity"]

{"sheet":"FW metal plant","index":24,"n_rows":87,"n_cols":53,"rows_kept":87,"cut":false,"hidden":false,"merged":[[3,4,7,4],[9,2,9,4],[11,2,13,2],[11,7,13,7],[14,2,16,2],[14,7,16,7],[17,2,19,2],[17,7,19,7],[20,2,21,2],[20,7,21,7],[22,2,24,2],[22,7,24,7],[25,2,27,2],[25,7,27,7],[28,2,30,2],[28,7,30,7],[31,2,33,2],[31,7,33,7],[34,2,36,2],[34,7,36,7],[37,2,39,2],[37,7,39,7],[40,2,42,2],[40,7,42,7],[43,2,45,2],[43,7,45,7],[46,2,48,2],[46,7,48,7],[49,2,51,2],[49,7,51,7],[71,2,74,2],[71,7,74,7],[52,2,54,2],[52,7,54,7],[68,2,70,2],[68,7,70,7],[65,7,67,7],[56,7,58,7],[59,7,61,7],[62,7,64,7]]}
[null,1,"Fill in the blank cells below, based on information provided in the paper being assessed. You can either pick an option from the dropdown list or add the appropriate detail using the 'Add to list' button. ",null,null,null,null,null,null,null,null,null,null,null,"* All the text in RED are used for drop down list ,make changes with caution."]
[null,null,"Category",{"$f":"IF(AF3=\"\",0,1)","v":0},"Freshwater/metal/plant",{"$f":"IF(E3=\"\",0,1)","v":0},"Citation No.",{"$f":"IF(ISERROR(FIND(\"-\",E3)),E3,LEFT(E3,FIND(\"-\",E3)-1))","v":0},null,"Taxonomic group",null,null,null,null,"Species",null,null,"Lifestage",null,null,"Exposure duration",null,null,"Measure of toxicity",null,null,"Toxicity endpoint",null,null,"Taxonomic group",null,null,"Phylum",null,null,"Class",null,null,"Media",null,null,"Temperature ",null,null,"Acute Or Chronic",null,null,"PH",null,null,"Salinity/Comdictivity"]
[null,null,"Paper and data unique identifier(eg. 1-1,10-150)",{"$f":"IF(AI3=\"\",0,1)","v":0},null,{"$f":"IF(E4=\"\",0,1)","v":0},"Species (Scientific name)",null,null,"Phylum",null,null,null,null,"Aedes albopictus",0,{"$f":"IF(P3=0,\"\",INDEX(O3:O108,P3))","v":""},"1 month",0,{"$f":"IF(S3=0,\"\",INDEX(R3:R108,S3))","v":""},"11 hour",0,{"$f":"IF(V3=0,\"\",INDEX(U3:U108,V3))","v":""},"LC50",0,{"$f":"IF(Y3=0,\"\",INDEX(X3:X108,Y3))","v":""},"Mortality",0,{"$f":"IF(AB3=0,\"\",INDEX(AA3:AA108,AB3))","v":""},"Fish ",0,{"$f":"IF(AE3=0,\"\",INDEX(AD3:AD108,AE3))","v":""},"Chlorophyta",0,{"$f":"IF(AH3=0,\"\",INDEX(AG3:AG108,AH3))","v":""},"Branchiopoda",0,{"$f":"IF(AK3=0,\"\",INDEX(AJ3:AJ108,AK3))","v":""},"Freshwater",0,{"$f":"IF(AN3=0,\"\",INDEX(AM3:AM108,AN3))","v":""},"15°C",0,{"$f":"IF(AQ3=0,\"\",INDEX(AP3:AP108,AQ3))","v":""},"Acute ",0,{"$f":"IF(AT3=0,\"\",INDEX(AS3:AS108,AT3))","v":""},"N.A.",0,{"$f":"IF(AW3=0,\"\",INDEX(AV3:AV108,AW3))","v":""},"Salinity1",null,"N.A."]
[null,null,"Citation",{"$f":"IF(AL3=\"\",0,1)","v":0},null,{"$f":"IF(H8=\"\",0,1)","v":0},"Lifestage",null,null,"Class",null,null,null,null,"Australian Bass",null,null,"1 year old",null,null,"13 days",null,null,"N.A.",null,null,"N.A.",null,null,"Microalga",null,null,"N.A.",null,null,"Chlorophyceae",null,null,"Marinewater",null,null,"25°C",null,null,"Chronic",null,null,"PH11",null,null,"Salinity2"]
[null,null,null,{"$f":"IF(AO3=\"\",0,1)","v":0},null,{"$f":"IF(AX3=\"\",0,1)","v":0},"Exposure duration",null,null,"Media",null,null,null,null,"N.A.",null,null,"N.A.",null,null,"N.A.",null,null,"NOEC",null,null,"Reproduction",null,null,"N.A.",null,null,"Tracheophyta",null,null,"N.A.",null,null,"N.A.",null,null,"N.A.",null,null,"N.A.",null,null,"PH7.0 "]
[null,null,null,{"$f":"IF(AR3=\"\",0,1)","v":0},null,{"$f":"IF(Q3=\"\",0,1)","v":0},"Measure of toxicity",null,null,"Temperature "]
[null,null,null,{"$f":"IF(AU3=\"\",0,1)","v":0},null,{"$f":"IF(T3=\"\",0,1)","v":0},"Toxicity endpoint",null,null,"Acute Or Chronic "]
[null,null,null,null,null,{"$f":"IF(W3=\"\",0,1)","v":0},"Toxicity value",null,null,"PH"]
[null,2,"Select the appropriate answer option to each question. Comments can be added to the cells in column H.",null,null,{"$f":"IF(Z3=\"\",0,1)","v":0},null,null,null,"Salinity/Conductivity","N.A."]
[null,"*","If the selected answer option does not work try clicking on any other cell first and then click back on the answer option again.",null,null,{"$f":"IF(AC3=\"\",0,1)","v":0}]
[null,"No.","Question","Marks Awarded","Answer Options","Option References","Scores","Answers"]
[null,null,"Was the duration of the exposure stated (e.g. 48 or 96 h)?",10,null,0,{"$f":"IF(F15=0,0,INDEX($D12:$D13,F12,1))","v":0}]
[null,1,null,0]
[]
[null,null,"Was the biological endpoint (e.g., immobilization or population growth) stated and defined (10 marks)? Award 5 marks if the biological endpoint is only stated.",10,null,0,{"$f":"IF(F15=0,0,INDEX($D15:$D17,F15,1))","v":0}]
[null,2,null,5]
[null,null,null,0]
[null,null,"Was the biological effect stated (e.g. LC or NOEC)?",5,null,0,{"$f":"IF(F18=0,0,INDEX($D18:$D19,F18,1))","v":0}]
[null,3,null,0]
[]
[null,4,"Was the biological effect quantified (e.g. 50% effect, 25% effect)? \nNote: The effect for NOEC and LOEC data must be quantified.",5,null,0,{"$f":"IF(F21=0,0,INDEX($D21:$D22,F21,1))","v":0}]
[null,null,null,0]
[null,5,"Were appropriate controls (e.g. a no-toxicant control and/or solvent control) used?",5,null,0,{"$f":"IF(F23=0,0,INDEX($D23:$D24,F23,1))","v":0}]
[null,null,null,0]
[]
[null,6,"Was each control and contaminant concentration at least duplicated?",5,null,0,{"$f":"IF(F26=0,0,INDEX($D26:$D27,F26,1))","v":0}]
[null,null,null,0]
[]
[null,7,"Were test acceptability criteria stated (e.g. mortality in controls must not exceed a certain percentage) (5 marks)?\nOR Were test acceptability criteria inferred (e.g. test method used [USEPA, OECD, ASTM etc.]) (award 2 marks). \nNote: Data that fail the acceptability criteria are automatically deemed to be of unacceptable quality and must not be used. ",5,null,0,{"$f":"IF(F29=0,0,INDEX($D29:$D31,F29,1))","v":0}]
[null,null,null,2]
[null,null,null,0]
[null,8,"Were the characteristics of the test organism (e.g. length, mass, age) stated?",5,null,0,{"$f":"IF(F32=0,0,INDEX($D32:$D34,F32,1))","v":0}]
[null,null,null,0]
[]
[null,9,"Was the type of test media used stated?",5,null,0,{"$f":"IF(F35=0,0,INDEX($D35:$D37,F35,1))","v":0}]
[null,null,null,0]
[]
[null,null,"Was the type of exposure (e.g. static, flow through) stated? ",4,null,0,{"$f":"IF(F38=0,0,INDEX($D38:$D40,F38,1))","v":0}]
[null,10,null,0]
[]
[null,null,"Were the contaminant concentrations measured at the beginning and end of the exposure (4 marks)? Award 2 marks if they were measured only once during the test.\nNote: If the concentrations were not measured then automatically the data cannot be high quality. ",4,null,0,{"$f":"IF(F41=0,0,INDEX($D41:$D43,F41,1))","v":0}]
[null,11,null,2]
[null,null,null,0]
[null,null,"Were parallel reference toxicant toxicity tests conducted?",4,null,0,{"$f":"IF(F44=0,0,INDEX($D44:$D46,F44,1))","v":0}]
[null,12,null,0]
[]
[null,null,"Was there a concentration–response relationship either observable or stated?",4,null,0,{"$f":"IF(F47=0,0,INDEX($D47:$D49,F47,1))","v":0}]
[null,13,null,0]
[]
[null,null,"Was an appropriate statistical method or model used to determine the toxicity?\nNote: They should be accepted by a recognised national or international regulatory body (e.g. USEPA, OECD, ASTM). ",4,null,0,{"$f":"IF(F50=0,0,INDEX($D50:$D52,F50,1))","v":0}]
[null,14,null,0]
[]
[null,15,"For LC/EC/BEC data was an estimate of variability provided? \nOR \nFor NO EC/LOEC data was the significance level 0.05 or less?  \n\n",4,null,0,{"$f":"IF(F53=0,0,INDEX($D53:$D55,F53,1))","v":0}]
[null,null,null,0]
[]
[null,16,"Were the following parameters measured and stated? (3 marks if measured and stated, 1 mark if just measured)."]
[null,null,null,3,null,0,{"$f":"IF(F57=0,0,INDEX($D57:$D59,F57,1))","v":0}]
[null,16.100000000000001,"pH ",1]
[null,null,null,0]
[null,null,null,3,null,0,{"$f":"IF(F60=0,0,INDEX($D60:$D62,F60,1))","v":0}]
[null,16.2,"Hardness",1]
[null,null,null,0]
[null,null,null,3,null,0,{"$f":"IF(F63=0,0,INDEX($D63:$D65,F63,1))","v":0}]
[null,16.3,"Alkalinity ",1]
[null,null,null,0]
[null,null,null,3,null,0,{"$f":"IF(F66=0,0,INDEX($D66:$D68,F66,1))","v":0}]
[null,16.399999999999999,"Organic carbon concentration",1]
[null,null,null,0]
[null,null,"Was the temperature measured and stated (3 marks)? Award 1 mark if the temperature was measured but not stated or if only the temperature settings of the room or chamber are stated.",3,null,0,{"$f":"IF(F69=0,0,INDEX($D69:$D71,F69,1))","v":0}]
[null,17,null,1]
[null,null,null,0]
[null,null,"Were test solutions, blanks and/or controls tested for contamination OR were analytical reagent grade chemicals used or the highest possible purity chemicals used for the experiment? (3 marks).",3,null,0,{"$f":"IF(F72=0,0,INDEX($D72:$D73,F72,1))","v":0}]
[null,18,null,0]
[]
[null,null,null,null,null,null,null,null,{"$f":"(COUNTIF(F12:F73,\"=0\"))+COUNTIF(F2:F10,\"=0\")+COUNTIF(D2:D7,\"=0\")","v":36}]
[]
[]
[null,null,"Total score",null,null,null,{"$f":"IF(SUM(G12:G72)=0,\"\",SUM(G12:G72))","v":""}]
[null,null,"Total Max. possible score for the various types of data and contaminants ",null,{"$f":"D12+D15+D18+D21+D23+D26+D29+D32+D35+D38+D41+D44+D47+D50+D53+D57+D66+D69+D72+D60+D63","v":97}]
[null,null,"Quality Score",null,{"$f":"\"= [Total score / Total possible score] * 100 = \"","v":"= [Total score / Total possible score] * 100 = "},null,{"$f":"IF(ISERROR(G78/E79),#N/A,G78/E79)","v":{"$error":"#N/A"}},{"$f":"IF(F41=3,\"The highest possible grade for this datum is acceptable.\",\"\")","v":""}]
[]
[null,null,"H = high quality                           Quality score ≥ 80%      "]
[null,null,"A = acceptable quality         > 50% Quality score < 80%      "]
[null,null,"U = unacceptable quality              Quality score ≤ 50%  "]
[]
[3,null,"Click the 'Save & Update' button to save and export the answers to the 'All results' worksheet. "]
[null,null,"Select the 'Reset Answers' button if you wish to clear all answers."]

{"sheet":"FW metal plant_WS","index":25,"n_rows":5,"n_cols":24,"rows_kept":5,"cut":false,"hidden":false,"merged":[]}
[]
["Question No.",1,2,3,4,5,6,7,8,9,10,11,12,13,14,15,16.100000000000001,16.2,16.3,16.399999999999999,17,18,"Total Score","Quality Score"]
["Short Questions","Duration of the exposure ","Biological endpoint","Biological effect stated or not","Biological effect quantified or not","Appropriate controls","Control & contaminant concentration","Test acceptability criteria","Characteristics of the test organism"," Type of test media","Type of exposure","Contaminant concentrations","Parallel reference toxicant toxicity tests","Concentration–response relationship","Determine the toxicity","NOEC/LOEC or LC/EC/BEC","pH","Hardness","Alkalinity ","Organic carbon concentration","Temperature","Grade or purity"]
["Marks Awarded ","10 or 0","10,5 or 0","5 or 0 ","5 or 0 ","5 or 0 ","5 or 0 ","5 or 0 ","5 or 0 ","5 or 0 ","4 or 0","4 or 2 or 0","4 or 2","4 or 2","4 or 2","4 or 2","3 or 1 or 0","3 or 1 or 0","3 or 1 or 0","3 or 1 or 0","3 or 0","3 or 0 "]
["Max. Possible Score",10,10,5,5,5,5,5,5,5,4,4,4,4,4,4,3,3,3,3,3,3,{"$f":"SUM(B5:V5)","v":97}]

{"sheet":"Sheet18","index":26,"n_rows":0,"n_cols":0,"rows_kept":0,"cut":false,"hidden":false,"merged":[]}

{"sheet":"FW nonmetal plant","index":27,"n_rows":79,"n_cols":53,"rows_kept":79,"cut":false,"hidden":false,"merged":[[3,4,7,4],[9,2,9,4],[11,2,13,2],[11,7,13,7],[14,2,16,2],[14,7,16,7],[17,2,19,2],[17,7,19,7],[20,2,21,2],[20,7,21,7],[22,2,24,2],[22,7,24,7],[25,2,27,2],[25,7,27,7],[28,2,30,2],[28,7,30,7],[31,2,33,2],[31,7,33,7],[34,2,36,2],[34,7,36,7],[37,2,39,2],[37,7,39,7],[40,2,42,2],[40,7,42,7],[43,2,45,2],[43,7,45,7],[46,2,48,2],[46,7,48,7],[49,2,51,2],[49,7,51,7],[60,2,62,2],[60,7,62,7],[63,2,66,2],[63,7,66,7],[52,2,54,2],[52,7,54,7],[56,2,59,2],[56,7,59,7]]}
[null,1,"Fill in the blank cells below, based on information provided in the paper being assessed. You can either pick an option from the dropdown list or add the appropriate detail using the 'Add to list' button. ",null,null,null,null,null,null,null,null,null,null,null,"* All the text in RED are used for drop down list ,make changes with caution."]
[null,null,"Category",{"$f":"IF(AF3=\"\",0,1)","v":0},"Freshwater/non-metal/plant",{"$f":"IF(E3=\"\",0,1)","v":0},"Citation No.",{"$f":"IF(ISERROR(FIND(\"-\",E3)),E3,LEFT(E3,FIND(\"-\",E3)-1))","v":0},null,"Taxonomic group",null,null,null,null,"Species",null,null,"Lifestage",null,null,"Exposure duration",null,null,"Measure of toxicity",null,null,"Toxicity endpoint",null,null,"Taxonomic group",null,null,"Phylum",null,null,"Class",null,null,"Media",null,null,"Temperature ",null,null,"Acute Or Chronic",null,null,"PH",null,null,"Salinity/Conductivity"]
[null,null,"Paper and data unique identifier(eg. 1-1,10-150)",{"$f":"IF(AI3=\"\",0,1)","v":0},null,{"$f":"IF(E4=\"\",0,1)","v":0},"Species (Scientific name)",null,null,"Phylum",null,null,null,null,"Aedes albopictus",0,{"$f":"IF(P3=0,\"\",INDEX(O3:O100,P3))","v":""},"1 month",0,{"$f":"IF(S3=0,\"\",INDEX(R3:R100,S3))","v":""},"11 hours",0,{"$f":"IF(V3=0,\"\",INDEX(U3:U100,V3))","v":""},"LC50",0,{"$f":"IF(Y3=0,\"\",INDEX(X3:X100,Y3))","v":""},"Mortality",0,{"$f":"IF(AB3=0,\"\",INDEX(AA3:AA100,AB3))","v":""},"Fish",0,{"$f":"IF(AE3=0,\"\",INDEX(AD3:AD100,AE3))","v":""},"Chlorophyta",0,{"$f":"IF(AH3=0,\"\",INDEX(AG3:AG100,AH3))","v":""},"Branchiopoda",0,{"$f":"IF(AK3=0,\"\",INDEX(AJ3:AJ102,AK3))","v":""},"Freshwater",0,{"$f":"IF(AN3=0,\"\",INDEX(AM3:AM100,AN3))","v":""},"15°C",0,{"$f":"IF(AQ3=0,\"\",INDEX(AP3:AP100,AQ3))","v":""},"Acute ",0,{"$f":"IF(AT3=0,\"\",INDEX(AS3:AS100,AT3))","v":""},"N.A.",0,{"$f":"IF(AW3=0,\"\",INDEX(AV3:AV100,AW3))","v":""},"30 ppt",null,"N.A."]
[null,null,"Citation",{"$f":"IF(AL3=\"\",0,1)","v":0},null,{"$f":"IF(AX3=\"\",0,1)","v":0},"Lifestage",null,null,"Class",null,null,null,null,"Australian Bass",null,null,"1 year old",null,null,"13 days ",null,null,"N.A.",null,null,"N.A.",null,null,"Microalga",null,null,"N.A.",null,null,"Chlorophyceae",null,null,"Marinewater",null,null,"25°C",null,null,"Chronic",null,null,"PH11",null,null,"150 uS/cm"]
[null,null,null,{"$f":"IF(AO3=\"\",0,1)","v":0},null,{"$f":"IF(H8=\"\",0,1)","v":0},"Exposure duration",null,null,"Media",null,null,null,null,"N.A.",null,null,"N.A.",null,null,"N.A.",null,null,"NOEC",null,null,"Reproduction",null,null,"N.A.",null,null,"Tracheophyta",null,null,"N.A.",null,null,"N.A.",null,null,"N.A.",null,null,"N.A.",null,null,"PH7.0",null,null,"N.A."]
[null,null,null,{"$f":"IF(AR3=\"\",0,1)","v":0},null,{"$f":"IF(Q3=\"\",0,1)","v":0},"Measure of toxicity",null,null,"Temperature "]
[null,null,null,{"$f":"IF(AU3=\"\",0,1)","v":0},null,{"$f":"IF(T3=\"\",0,1)","v":0},"Toxicity endpoint",null,null,"Acute Or Chronic "]
[null,null,null,null,null,{"$f":"IF(W3=\"\",0,1)","v":0},"Toxicity value",null,null,"PH"]
[null,2,"Select the appropriate answer option to each question. Comments can be added to the cells in column H.",null,null,{"$f":"IF(Z3=\"\",0,1)","v":0},null,null,null,"Salinity/Conductivity","N.A."]
[null,"*","If the selected answer option does not work try clicking on any other cell first and then click back on the answer option again.",null,null,{"$f":"IF(AC3=\"\",0,1)","v":0}]
[null,"No.","Question","Marks Awarded","Answer Options","Option References","Scores","Answers"]
[null,null,"Was the duration of the exposure stated (e.g. 48 or 96 h)?",10,null,0,{"$f":"IF(F15=0,0,INDEX($D12:$D13,F12,1))","v":0}]
[null,1,null,0]
[]
[null,null,"Was the biological endpoint (e.g., immobilization or population growth) stated and defined (10 marks)? Award 5 marks if the biological endpoint is only stated.",10,null,0,{"$f":"IF(F15=0,0,INDEX($D15:$D17,F15,1))","v":0}]
[null,2,null,5]
[null,null,null,0]
[null,null,"Was the biological effect stated (e.g. LC or NOEC)?",5,null,0,{"$f":"IF(F18=0,0,INDEX($D18:$D19,F18,1))","v":0}]
[null,3,null,0]
[]
[null,4,"Was the biological effect quantified (e.g. 50% effect, 25% effect)? \nNote: The effect for NOEC and LOEC data must be quantified.",5,null,0,{"$f":"IF(F21=0,0,INDEX($D21:$D22,F21,1))","v":0}]
[null,null,null,0]
[null,5,"Were appropriate controls (e.g. a no-toxicant control and/or solvent control) used?",5,null,0,{"$f":"IF(F23=0,0,INDEX($D23:$D24,F23,1))","v":0}]
[null,null,null,0]
[]
[null,6,"Was each control and contaminant concentration at least duplicated?",5,null,0,{"$f":"IF(F26=0,0,INDEX($D26:$D27,F26,1))","v":0}]
[null,null,null,0]
[]
[null,7,"Were test acceptability criteria stated (e.g. mortality in controls must not exceed a certain percentage) (5 marks)?\nOR Were test acceptability criteria inferred (e.g. test method used [USEPA, OECD, ASTM etc.]) (award 2 marks). \nNote: Data that fail the acceptability criteria are automatically deemed to be of unacceptable quality and must not be used. ",5,null,0,{"$f":"IF(F29=0,0,INDEX($D29:$D31,F29,1))","v":0}]
[null,null,null,2]
[null,null,null,0]
[null,8,"Were the characteristics of the test organism (e.g. length, mass, age) stated?",5,null,0,{"$f":"IF(F32=0,0,INDEX($D32:$D34,F32,1))","v":0}]
[null,null,null,0]
[]
[null,9,"Was the type of test media used stated?",5,null,0,{"$f":"IF(F35=0,0,INDEX($D35:$D37,F35,1))","v":0}]
[null,null,null,0]
[]
[null,null,"Was the type of exposure (e.g. static, flow through) stated? ",4,null,0,{"$f":"IF(F38=0,0,INDEX($D38:$D40,F38,1))","v":0}]
[null,10,null,0]
[]
[null,null,"Were the contaminant concentrations measured at the beginning and end of the exposure (4 marks)? Award 2 marks if they were measured only once during the test.\nNote: If the concentrations were not measured then automatically the data cannot be high quality. ",4,null,0,{"$f":"IF(F41=0,0,INDEX($D41:$D43,F41,1))","v":0}]
[null,11,null,2]
[null,null,null,0]
[null,null,"Were parallel reference toxicant toxicity tests conducted?",4,null,0,{"$f":"IF(F44=0,0,INDEX($D44:$D46,F44,1))","v":0}]
[null,12,null,0]
[]
[null,null,"Was there a concentration–response relationship either observable or stated?",4,null,0,{"$f":"IF(F47=0,0,INDEX($D47:$D49,F47,1))","v":0}]
[null,13,null,0]
[]
[null,null,"Was an appropriate statistical method or model used to determine the toxicity?\nNote: They should be accepted by a recognised national or international regulatory body (e.g. USEPA, OECD, ASTM). ",4,null,0,{"$f":"IF(F50=0,0,INDEX($D50:$D52,F50,1))","v":0}]
[null,14,null,0]
[]
[null,15,"For LC/EC/BEC data was an estimate of variability provided? \nOR \nFor NO EC/LOEC data was the significance level 0.05 or less?  \n\n",4,null,0,{"$f":"IF(F53=0,0,INDEX($D53:$D55,F53,1))","v":0}]
[null,null,null,0]
[]
[null,16,"Were the following parameters measured and stated? (3 marks if measured and stated, 1 mark if just measured)."]
[null,null,"pH",3,null,0,{"$f":"IF(F57=0,0,INDEX($D57:$D59,F57,1))","v":0}]
[null,16.100000000000001,null,1]
[null,null,null,0]
[]
[null,null,"Was the temperature measured and stated (3 marks)? Award 1 mark if the temperature was measured but not stated or if only the temperature settings of the room or chamber are stated.",3,null,0,{"$f":"IF(F61=0,0,INDEX($D61:$D63,F61,1))","v":0}]
[null,17,null,1]
[null,null,null,0]
[null,null,"Were test solutions, blanks and/or controls tested for contamination OR were analytical reagent grade chemicals used or the highest possible purity chemicals used for the experiment? (3 marks).",3,null,0,{"$f":"IF(F64=0,0,INDEX($D64:$D65,F64,1))","v":0}]
[null,18,null,0]
[]
[null,null,null,null,null,null,null,null,{"$f":"COUNTIF(D2:D7,\"=0\")+COUNTIF(F2:F10,\"=0\")+COUNTIF(F12:F64,\"=0\")","v":33}]
[]
[]
[null,null,"Total score",null,null,null,{"$f":"IF(SUM(G12:G67)=0,\"\",SUM(G12:G67))","v":""}]
[null,null,"Total Max. possible score for the various types of data and contaminants ",null,{"$f":"D12+D15+D18+D21+D23+D26+D29+D32+D35+D38+D41+D44+D47+D50+D53+D57+D61+D64","v":88}]
[null,null,"Quality Score",null,{"$f":"\"= [Total score / Total possible score] * 100 = \"","v":"= [Total score / Total possible score] * 100 = "},null,{"$f":"IF(ISERROR(G70/E71),#N/A,G70/E71)","v":{"$error":"#N/A"}},{"$f":"IF(F41=3,\"The highest possible grade for this datum is acceptable.\",\"\")","v":""}]
[]
[null,null,"H = high quality                           Quality score ≥ 80%  "]
[null,null,"A = acceptable quality         > 50% Quality score < 80%     "]
[null,null,"U = unacceptable quality              Quality score ≤ 50%"]
[]
[3,null,"Click the 'Save & Update' button to save and export the answers to the 'All results' worksheet. "]
[null,null,"Select the 'Reset Answers' button if you wish to clear all answers."]

{"sheet":"FW nonmetal plant_WS","index":28,"n_rows":3,"n_cols":22,"rows_kept":3,"cut":false,"hidden":false,"merged":[]}
[]
["Question No.",1,2,3,4,5,6,7,8,9,10,11,12,13,14,15,16.100000000000001,17,18,"Total Score","Quality Score","Comment "]
["Short Questions","Duration of the exposure ","Biological endpoint","Biological effect stated or not","Biological effect quantified or not","Appropriate controls","Control & contaminant concentration","Test acceptability criteria","Characteristics of the test organism"," Type of test media","Type of exposure","Contaminant concentrations","Parallel reference toxicant toxicity tests","Concentration–response relationship","Determine the toxicity","NOEC/LOEC or LC/EC/BEC","pH","Temperature","Grade or purity"]

{"sheet":"MEW nonplant","index":29,"n_rows":84,"n_cols":53,"rows_kept":84,"cut":false,"hidden":false,"merged":[[68,2,71,2],[68,7,71,7],[56,7,58,7],[65,7,67,7],[52,2,54,2],[52,7,54,7],[59,7,61,7],[65,2,67,2],[62,2,64,2],[62,7,64,7],[43,2,45,2],[43,7,45,7],[46,2,48,2],[46,7,48,7],[49,2,51,2],[49,7,51,7],[34,2,36,2],[34,7,36,7],[37,2,39,2],[37,7,39,7],[40,2,42,2],[40,7,42,7],[25,2,27,2],[25,7,27,7],[28,2,30,2],[28,7,30,7],[31,2,33,2],[31,7,33,7],[17,2,19,2],[17,7,19,7],[20,2,21,2],[20,7,21,7],[22,2,24,2],[22,7,24,7],[3,4,7,4],[9,2,9,4],[11,2,13,2],[11,7,13,7],[14,2,16,2],[14,7,16,7]]}
[null,1,"Fill in the blank cells below, based on information provided in the paper being assessed. You can either pick an option from the dropdown list or add the appropriate detail using the 'Add to list' button. ",null,null,{"$f":"IF(BA3=\"\",0,1)","v":1},null,null,null,null,null,null,null,null,"* All the text in RED are used for drop down list ,make changes with caution."]
[null,null,"Category",{"$f":"IF(AF3=\"\",0,1)","v":1},"MEW_nonplant",{"$f":"IF(E3=\"\",0,1)","v":1},"Citation No.",{"$f":"IF(ISERROR(FIND(\"-\",E3)),E3,LEFT(E3,FIND(\"-\",E3)-1))","v":"1"},null,"Taxonomic group",null,null,null,null,"Species",null,null,"Lifestage",null,null,"Exposure duration",null,null,"Measure of toxicity",null,null,"Toxicity endpoint",null,null,"Taxonomic group",null,null,"Phylum",null,null,"Class",null,null,"Media",null,null,"Temperature ",null,null,"Acute Or Chronic",null,null,"PH",null,null,"Salinity/Comdictivity"]
[null,null,"Paper and data unique identifier(eg. 1-1,10-150)",{"$f":"IF(AI3=\"\",0,1)","v":1},"1-1",{"$f":"IF(E4=\"\",0,1)","v":1},"Species (Scientific name)",null,null,"Phylum",null,null,null,null,"Aedes albopictus",49,{"$f":"IF(P3=0,\"\",INDEX(O3:O105,P3))","v":"Brachionus plicatilis)"},"1 month",21,{"$f":"IF(S3=0,\"\",INDEX(R3:R105,S3))","v":"0.5 h old"},"11 hour",21,{"$f":"IF(V3=0,\"\",INDEX(U3:U105,V3))","v":"24 h"},"LC50",12,{"$f":"IF(Y3=0,\"\",INDEX(X3:X105,Y3))","v":"LC50"},"Mortality",5,{"$f":"IF(AB3=0,\"\",INDEX(AA3:AA105,AB3))","v":"Mortality"},"Fish ",27,{"$f":"IF(AE3=0,\"\",INDEX(AD3:AD105,AE3))","v":"Rotifer"},"Chlorophyta",4,{"$f":"IF(AH3=0,\"\",INDEX(AG3:AG105,AH3))","v":"?"},"Branchiopoda",4,{"$f":"IF(AK3=0,\"\",INDEX(AJ3:AJ105,AK3))","v":"?"},"Freshwater",9,{"$f":"IF(AN3=0,\"\",INDEX(AM3:AM105,AN3))","v":"Synthetic seawater"},"15°C",18,{"$f":"IF(AQ3=0,\"\",INDEX(AP3:AP105,AQ3))","v":"20oC"},"Acute",5,{"$f":"IF(AT3=0,\"\",INDEX(AS3:AS105,AT3))","v":"Acute"},"N.A.",13,{"$f":"IF(AW3=0,\"\",INDEX(AV3:AV105,AW3))","v":8},"150 uS/cm",16,{"$f":"IF(AZ3=0,\"\",INDEX(AY3:AY105,AZ3))","v":"20‰"}]
[null,null,"Citation",{"$f":"IF(AL3=\"\",0,1)","v":1},"Lopez-Galindo et al 2010",{"$f":"IF(H8=\"\",0,1)","v":1},"Lifestage",null,null,"Class",null,null,null,null,"Australian Bass",null,null,"1 year old",null,null,"13 days",null,null,"N.A.",null,null,"N.A.",null,null,"Microalga",null,null,"N.A.",null,null,"Chlorophyceae",null,null,"Marinewater",null,null,"25°C",null,null,"Chronic",null,null,"PH11",null,null,"30 ppt"]
[null,null,null,{"$f":"IF(AO3=\"\",0,1)","v":1},null,{"$f":"IF(AX3=\"\",0,1)","v":1},"Exposure duration",null,null,"Media",null,null,null,null,"N.A.",null,null,"N.A.",null,null,"N.A.",null,null,"NOEC",null,null,"Reproduction",null,null,"N.A.",null,null,"Tracheophyta",null,null,"N.A.",null,null,"N.A.",null,null,"N.A.",null,null,"N.A.",null,null,"PH7.0",null,null,"N.A."]
[null,null,null,{"$f":"IF(AR3=\"\",0,1)","v":1},null,{"$f":"IF(Q3=\"\",0,1)","v":1},"Measure of toxicity",null,null,"Temperature ",null,null,null,null,"Crassostra gigas",null,null,"Larvae",null,null,"0.5 h",null,null,"LC50",null,null,"Body length",null,null,"Bivalve",null,null,"?",null,null,"?",null,null,"Seawater",null,null,"20 oC",null,null,"Chronic",null,null,"7.9-8.1",null,null,"30-31 ‰"]
[null,null,null,{"$f":"IF(AU3=\"\",0,1)","v":1},null,{"$f":"IF(T3=\"\",0,1)","v":1},"Toxicity endpoint",null,null,"Acute Or Chronic ",null,null,null,null,"Acartia tonsa",null,null,"0.5 h old",null,null,"96 h",null,null,"NOEC",null,null,"Mortality",null,null,"Rotifer",null,null,null,null,null,null,null,null,"Synthetic seawater",null,null,"25oC",null,null,"Acute",null,null,7.5,null,null,"?"]
[null,null,null,null,null,{"$f":"IF(W3=\"\",0,1)","v":1},"Toxicity value","586 µg/L",null,"PH",null,null,null,null,"Brachionus plicatilis",null,null,"Larvae",null,null,"24 h",null,null,"LC50",null,null,null,null,null,"Amphipod",null,null,null,null,null,null,null,null,"Seawater",null,null,"20oC",null,null,null,null,null,8,null,null,"33.7‰"]
[null,2,"Select the appropriate answer option to each question. Comments can be added to the cells in column H.",null,null,{"$f":"IF(Z3=\"\",0,1)","v":1},null,null,null,"Salinity/Conductivity",null,null,null,null,"Hyale barbicornis",null,null,"Juveniles",null,null,"96 h",null,null,"EC50",null,null,null,null,null,"Shrimp",null,null,null,null,null,null,null,null,"Seawater 22-27‰",null,null,"25oC",null,null,null,null,null,"7.9-8.1",null,null,"28‰"]
[null,"*","If the selected answer option does not work try clicking on any other cell first and then click back on the answer option again.",null,null,{"$f":"IF(AC3=\"\",0,1)","v":1},null,null,null,null,null,null,null,null,"Pandalus danae",null,null,"Juveniles and adults",null,null,"15 min",null,null,"LC50",null,null,null,null,null,"Sea urchin",null,null,null,null,null,null,null,null,"Seawater",null,null,"15oC",null,null,null,null,null,8,null,null,"30-31‰"]
[null,"No.","Question","Marks Awarded","Answer Options","Option References","Scores","Answers",null,null,null,null,null,null,"trongylocentrotus droebachiensis",null,null,"Sperm",null,null,"1 h",null,null,"EC50",null,null,null,null,null,"Sand dollar",null,null,null,null,null,null,null,null,"Synthetic seawater",null,null,"25oC",null,null,null,null,null,"7.9-8.0",null,null,"28‰"]
[null,null,"Was the duration of the exposure stated (e.g. 48 or 96 h)?",10,null,1,{"$f":"IF(F15=0,0,INDEX($D12:$D13,F12,1))","v":10},"Yes",null,null,null,null,null,null,"Strongylocentrotus droebachiensis",null,null,"Larvae",null,null,"48 h",null,null,"LC50",null,null,null,null,null,"Lobster",null,null,null,null,null,null,null,null,null,null,null,"26oC",null,null,null,null,null,7.5,null,null,"33.7‰"]
[null,1,null,0,null,null,null,null,null,null,null,null,null,null,"Dendraster excentricus",null,null,"Adult",null,null,"96 h",null,null,"NOEC",null,null,null,null,null,"Mysid",null,null,null,null,null,null,null,null,null,null,null,"8oC",null,null,null,null,null,8,null,null,"35‰"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Homarus americanus",null,null,"Adult and juvenile",null,null,"24 h",null,null,"LC50",null,null,null,null,null,"Amphipod",null,null,null,null,null,null,null,null,null,null,null,"19-28oC",null,null,null,null,null,7.5,null,null,"20‰"]
[null,null,"Was the biological endpoint (e.g., immobilization or population growth) stated and defined (10 marks)? Award 5 marks if the biological endpoint is only stated.",10,null,1,{"$f":"IF(F15=0,0,INDEX($D15:$D17,F15,1))","v":10},"Stated and defined",null,null,null,null,null,null,"Neomysis sp",null,null,"Juvenile",null,null,"8 d",null,null,null,null,null,null,null,null,"Shrimp",null,null,null,null,null,null,null,null,null,null,null,"20oC",null,null,null,null,null,8,null,null,"15‰"]
[null,2,null,5,null,null,null,null,null,null,null,null,null,null,"Pontogeneia sp",null,null,"Juvenile plus adult",null,null,"96 h",null,null,null,null,null,null,null,null,"Crab",null,null,null,null,null,null,null,null,null,null,null,"8-12oC",null,null,null,null,null,null,null,null,"21‰"]
[null,null,null,0,null,null,null,null,null,null,null,null,null,null,"Anonyx sp",null,null,"Juvenile",null,null,"48 h",null,null,null,null,null,null,null,null,"Fish",null,null,null,null,null,null,null,null,null,null,null,"15oC",null,null,null,null,null,null,null,null,"28‰"]
[null,null,"Was the biological effect stated (e.g. LC or NOEC)?",5,null,1,{"$f":"IF(F18=0,0,INDEX($D18:$D19,F18,1))","v":5},"LC",null,null,null,null,null,null,"Pandalus goniurus",null,null,"Fry",null,null,"96 h",null,null,null,null,null,null,null,null,"Oyster",null,null,null,null,null,null,null,null,null,null,null,"10oC",null,null,null,null,null,null,null,null,"20‰"]
[null,3,null,0,null,null,null,null,null,null,null,null,null,null,"Crangon nigricorda",null,null,"Eggs",null,null,"76 h",null,null,null,null,null,null,null,null,"Fish",null,null,null,null,null,null,null,null,null,null,null,"15oC"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Hemigrapsus nudus",null,null,"Larvae",null,null,"48 h",null,null,null,null,null,null,null,null,"Mysid",null,null,null,null,null,null,null,null,null,null,null,"20oC"]
[null,4,"Was the biological effect quantified (e.g. 50% effect, 25% effect)? \nNote: The effect for NOEC and LOEC data must be quantified.",5,null,1,{"$f":"IF(F21=0,0,INDEX($D21:$D22,F21,1))","v":5},50,null,null,null,null,null,null,"Hemigrapsus oregonensis",null,null,"Juvenile",null,null,"0.5 h",null,null,null,null,null,null,null,null,"Fish"]
[null,null,null,0,null,null,null,null,null,null,null,null,null,null,"Onchorhynchus kisutch",null,null,"Eggs",null,null,"96 h",null,null,null,null,null,null,null,null,"Mysid"]
[null,5,"Were appropriate controls (e.g. a no-toxicant control and/or solvent control) used?",5,null,1,{"$f":"IF(F23=0,0,INDEX($D23:$D24,F23,1))","v":5},"No",null,null,null,null,null,null,"Clupea harengus pailasi",null,null,"0.5 h old",null,null,"24 h",null,null,null,null,null,null,null,null,"Fish"]
[null,null,null,0,null,null,null,null,null,null,null,null,null,null,"Gasterosteus aculaetus",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Amphipod"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Cymatogaster aggregata",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rotifer"]
[null,6,"Was each control and contaminant concentration at least duplicated?",5,null,1,{"$f":"IF(F26=0,0,INDEX($D26:$D27,F26,1))","v":5},null,null,null,null,null,null,null,"Ammodytes hexapterus",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Copepod"]
[null,null,null,0,null,null,null,null,null,null,null,null,null,null,"Parophrys vetulus",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rotifer"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Menidia peninsulae",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Bivalve"]
[null,7,"Were test acceptability criteria stated (e.g. mortality in controls must not exceed a certain percentage) (5 marks)?\nOR Were test acceptability criteria inferred (e.g. test method used [USEPA, OECD, ASTM etc.]) (award 2 marks). \nNote: Data that fail the acceptability criteria are automatically deemed to be of unacceptable quality and must not be used. ",5,null,2,{"$f":"IF(F29=0,0,INDEX($D29:$D31,F29,1))","v":2},"Inferred",null,null,null,null,null,null,"Orizias javonicus",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rotifer"]
[null,null,null,2,null,null,null,null,null,null,null,null,null,null,"Orizias javanicus"]
[null,null,null,0,null,null,null,null,null,null,null,null,null,null,"Pleuronectes platessa"]
[null,8,"Were the characteristics of the test organism (e.g. length, mass, age) stated?",5,null,2,{"$f":"IF(F32=0,0,INDEX($D32:$D34,F32,1))","v":0},"No",null,null,null,null,null,null,"Crassostrea virginica"]
[null,null,null,0,null,null,null,null,null,null,null,null,null,null,"Synnathus focus"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Gobiosoma bosci"]
[null,9,"Was the type of test media used stated?",5,null,1,{"$f":"IF(F35=0,0,INDEX($D35:$D37,F35,1))","v":5},"Seawater",null,null,null,null,null,null,"Synnathus focus"]
[null,null,null,0,null,null,null,null,null,null,null,null,null,null,"Mysidopsis bahia"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Menidia beryllina"]
[null,null,"Was the type of exposure (e.g. static, flow through) stated? ",4,null,1,{"$f":"IF(F38=0,0,INDEX($D38:$D40,F38,1))","v":4},"Static",null,null,null,null,null,null,"Mysidopsis bahia"]
[null,10,null,0,null,null,null,null,null,null,null,null,null,null,"Menidia menidia"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Menidia beryllina"]
[null,null,"Were the contaminant concentrations measured at the beginning and end of the exposure (4 marks)? Award 2 marks if they were measured only once during the test.\nNote: If the concentrations were not measured then automatically the data cannot be high quality. ",4,null,1,{"$f":"IF(F41=0,0,INDEX($D41:$D43,F41,1))","v":4},null,null,null,null,null,null,null,"Morone americana"]
[null,11,null,2,null,null,null,null,null,null,null,null,null,null,"Morone saxitilis"]
[null,null,null,0,null,null,null,null,null,null,null,null,null,null,"Alosa aetvalis"]
[null,null,"Were parallel reference toxicant toxicity tests conducted?",4,null,2,{"$f":"IF(F44=0,0,INDEX($D44:$D46,F44,1))","v":0},"No",null,null,null,null,null,null,"Amphiporeia virgiana"]
[null,12,null,0,null,null,null,null,null,null,null,null,null,null,"Eohaustorius washingtoianus"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Acartia tonsa"]
[null,null,"Was there a concentration–response relationship either observable or stated?",4,null,2,{"$f":"IF(F47=0,0,INDEX($D47:$D49,F47,1))","v":0},"No",null,null,null,null,null,null,"Brachionus plicatilis"]
[null,13,null,0,null,null,null,null,null,null,null,null,null,null,"Acartia tonsa"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Brachionus plicatilis"]
[null,null,"Was an appropriate statistical method or model used to determine the toxicity?\nNote: They should be accepted by a recognised national or international regulatory body (e.g. USEPA, OECD, ASTM). ",4,null,2,{"$f":"IF(F50=0,0,INDEX($D50:$D52,F50,1))","v":0},"Yes",null,null,null,null,null,null,"Crassostrea virginica"]
[null,14,null,0,null,null,null,null,null,null,null,null,null,null,"Brachionus plicatilis)"]
[]
[null,15,"For LC/EC/BEC data was an estimate of variability provided? \nOR \nFor NO EC/LOEC data was the significance level 0.05 or less?  \n\n",4,null,1,{"$f":"IF(F53=0,0,INDEX($D53:$D55,F53,1))","v":4},"No"]
[null,null,null,0]
[]
[null,16,"Were the following parameters measured and stated? (3 marks if measured and stated, 1 mark if just measured)."]
[null,null,null,3,null,2,{"$f":"IF(F57=0,0,INDEX($D57:$D59,F57,1))","v":1},"Stated"]
[null,16.100000000000001,"Conductivity/Salinity",1]
[null,null,null,0]
[null,null,null,3,null,3,{"$f":"IF(F60=0,0,INDEX($D60:$D62,F60,1))","v":0},"Not measured"]
[null,16.2,"Dissolved Oxygen",1]
[null,null,null,0]
[null,null,"pH",3,null,1,{"$f":"IF(F63=0,0,INDEX(D63:D65,F63,1))","v":3},"Stated"]
[null,16.3,null,1]
[null,null,null,0]
[null,null,"Was the temperature measured and stated (3 marks)? Award 1 mark if the temperature was measured but not stated or if only the temperature settings of the room or chamber are stated.\n\n",3,null,2,{"$f":"IF(F66=0,0,INDEX(D66:D68,F66,1))","v":1},"Stated"]
[null,17,null,1]
[null,null,null,0]
[null,null,"Were test solutions, blanks and/or controls tested for contamination OR were analytical reagent grade chemicals used or the highest possible purity chemicals used for the experiment? (3 marks).",3,null,2,{"$f":"IF(F69=0,0,INDEX($D69:$D70,F69,1))","v":0},"Yes"]
[null,18,null,0]
[]
[null,null,null,null,null,null,null,null,{"$f":"(COUNTIF(F12:F70,\"=0\"))+COUNTIF(F1:F10,\"=0\")+COUNTIF(D2:D7,\"=0\")","v":0}]
[]
[]
[null,null,"Total score",null,null,null,{"$f":"IF(SUM(G12:G69)=0,\"\",SUM(G12:G69))","v":64}]
[null,null,"Total Max. possible score for the various types of data and contaminants ",null,{"$f":"D12+D15+D18+D21+D23+D26+D29+D32+D35+D38+D41+D44+D47+D50+D53+D57+D60+D66+D69+D63","v":94}]
[null,null,"Quality Score",null,{"$f":"\"= [Total score / Total possible score] * 100 = \"","v":"= [Total score / Total possible score] * 100 = "},null,{"$f":"IF(ISERROR(G75/E76),#N/A,G75/E76)","v":0.68085106382978722},{"$f":"IF(F41=3,\"The highest possible grade for this datum is acceptable.\",\"\")","v":""}]
[]
[null,null,"H = high quality                           Quality score ≥ 80%"]
[null,null,"A = acceptable quality         > 50% Quality score < 80%  "]
[null,null,"U = unacceptable quality              Quality score ≤ 50%"]
[]
[3,null,"Click the 'Save & Update' button to save and export the answers to the 'All results' worksheet. "]
[null,null,"Select the 'Reset Answers' button if you wish to clear all answers."]

{"sheet":"MEW nonplant_WS","index":30,"n_rows":176,"n_cols":24,"rows_kept":176,"cut":false,"hidden":false,"merged":[]}
[]
["Question No.",1,2,3,4,5,6,7,8,9,10,11,12,13,14,15,16.100000000000001,16.2,16.3,17,18,"Total Score","Quality Score"]
["Short Questions","Duration of the exposure ","Biological endpoint","Biological effect stated or not","Biological effect quantified or not","Appropriate controls","Control & contaminant concentration","Test acceptability criteria","Characteristics of the test organism"," Type of test media","Type of exposure","Contaminant concentrations","Parallel reference toxicant toxicity tests","Concentration–response relationship","Determine the toxicity","NOEC/LOEC or LC/EC/BEC","Conductivity/Salinity","Dissolved Oxygen","PH","Temperature","Grade or purity"]
["Marks Awarded ","10 or 0","10,5 or 0","5 or 0 ","5 or 0 ","5 or 0 ","5 or 0 ","5 or 0 ","5 or 0 ","5 or 0 ","4 or 0","4 or 2 or 0","4 or 2","4 or 2","4 or 2","4 or 2","3 or 1 or 0","3 or 1 or 0","3 or 1 or 0","3 or 0","3 or 0 "]
["Max. Possible Score",10,10,5,5,5,5,5,5,5,4,4,4,4,4,4,3,3,3,3,3,{"$f":"SUM(B5:U5)","v":94}]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","2-1"]
["Scores",10,10,5,5,5,5,2,0,5,4,4,0,0,4,0,1,0,1,1,3,65,0.69148936170212771,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","Three reps","Inferred","No","Seawater","Flowthru","Several times","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","2-2"]
["Scores",10,10,5,5,5,5,2,0,5,4,4,0,0,4,0,1,0,1,1,3,65,0.69148936170212771,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","Three reps","Inferred","No","Seawater","Flowthru","Several times","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","2-3"]
["Scores",10,10,5,5,5,5,2,0,5,4,4,0,0,4,0,1,0,1,1,3,65,0.69148936170212771,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","Three reps","Inferred","No","Seawater","Flowthru","Several times","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","2-4"]
["Scores",10,10,5,5,5,5,2,0,5,4,4,0,0,4,0,1,0,1,1,3,65,0.69148936170212771,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","Three reps","Inferred","No","Seawater","Static","Every 30 min","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","2-5"]
["Scores",10,10,5,5,5,5,2,0,5,4,4,0,0,4,0,1,0,1,1,3,65,0.69148936170212771,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","Three reps","Inferred","No","Seawater","Static","Every 30 min","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","2-4"]
["Scores",10,10,5,5,5,5,2,0,5,4,4,0,0,4,0,1,0,1,1,3,65,0.69148936170212771,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","Three reps","Inferred","No","Seawater","Static","Every 30 min","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","3-1"]
["Scores",10,10,5,5,5,5,2,5,5,4,4,0,0,4,0,3,3,3,3,3,79,0.84042553191489366,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","Three reps","Inferred","No","Seawater","24-h renewal","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","3-2"]
["Scores",10,10,5,5,5,5,2,5,5,4,4,0,0,4,0,3,3,3,3,3,79,0.84042553191489366,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","Three reps","Inferred","No","Seawater","24-h renewal","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","4-1"]
["Scores",10,10,5,5,0,5,2,0,5,4,2,0,0,4,0,3,3,3,3,3,67,0.71276595744680848,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","Three reps","Inferred","No","Seawater","Flow-thru","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","5-1"]
["Scores",10,10,5,5,0,5,2,0,5,4,2,0,0,4,0,0,0,0,1,3,56,0.5957446808510638,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","Three reps","Inferred","No","Seawater","Static","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","5-1"]
["Scores",10,10,5,5,0,5,2,0,5,4,2,0,0,4,0,0,0,0,1,3,56,0.5957446808510638,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","Three reps","Inferred","No","Seawater","Static","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","5-2"]
["Scores",10,10,5,5,0,5,2,0,5,4,2,0,0,4,0,0,0,0,1,3,56,0.5957446808510638,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","Three reps","Inferred","No","Seawater","Static","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","2-6"]
["Scores",10,10,5,5,0,5,2,0,5,4,4,0,0,4,0,3,0,3,3,3,66,0.7021276595744681,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","Three reps","Inferred","No","Seawater","Static","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","4-2"]
["Scores",10,10,5,5,0,0,2,0,5,4,4,0,0,4,0,1,1,1,3,3,58,0.61702127659574468,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Flow thru","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","4-3"]
["Scores",10,10,5,5,0,0,2,0,5,4,4,0,0,4,0,1,1,1,3,3,58,0.61702127659574468,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Flow thru","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","4-4"]
["Scores",10,10,5,5,0,0,2,0,5,4,4,0,0,4,0,1,1,1,3,3,58,0.61702127659574468,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Flow thru","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","4-5"]
["Scores",10,10,5,5,0,0,2,0,5,4,4,0,0,4,0,1,1,1,3,3,58,0.61702127659574468,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Flow thru","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","4-6"]
["Scores",10,10,5,5,0,0,2,0,5,4,4,0,0,4,0,1,1,1,3,3,58,0.61702127659574468,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Flow thru","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","4-7"]
["Scores",10,10,5,5,0,0,2,0,5,4,4,0,0,4,0,1,1,1,3,3,58,0.61702127659574468,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Flow thru","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","4-8"]
["Scores",10,10,5,5,0,0,2,0,5,4,4,0,0,4,0,1,1,1,3,3,58,0.61702127659574468,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Flow thru","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","4-9"]
["Scores",10,10,5,5,0,0,2,0,5,4,4,0,0,4,0,1,1,1,3,3,58,0.61702127659574468,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Flow thru","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","4-10"]
["Scores",10,10,5,5,0,0,2,0,5,4,4,0,0,4,0,1,1,1,3,3,58,0.61702127659574468,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Flow thru","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","4-11"]
["Scores",10,10,5,5,0,0,2,0,5,4,4,0,0,4,0,1,1,1,3,3,58,0.61702127659574468,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Flow thru","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","4-11"]
["Scores",10,10,5,5,0,0,2,0,5,4,4,0,0,4,0,1,1,1,3,3,58,0.61702127659574468,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Flow thru","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","4-12"]
["Scores",10,10,5,5,0,0,2,0,5,4,4,0,0,4,0,1,1,1,3,3,58,0.61702127659574468,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Flow thru","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","4-13"]
["Scores",10,10,5,5,0,0,2,0,5,4,4,0,0,4,0,1,1,1,3,3,58,0.61702127659574468,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Flow thru","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","4-14"]
["Scores",10,10,5,5,0,0,2,0,5,4,4,0,0,4,0,1,1,1,3,3,58,0.61702127659574468,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Flow thru","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","6-1"]
["Scores",10,10,5,5,0,0,2,0,5,4,4,0,0,4,0,3,3,3,3,3,64,0.68085106382978722,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Flow thru","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","6-2"]
["Scores",10,10,5,5,0,0,2,0,5,4,4,0,0,4,0,3,3,3,3,3,64,0.68085106382978722,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Flow thru","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","3-3"]
["Scores",10,10,5,5,0,0,2,0,5,4,4,0,0,4,0,3,3,3,3,3,64,0.68085106382978722,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Flow thru","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","3-3"]
["Scores",10,10,5,5,0,0,2,0,5,4,4,0,0,4,0,3,3,3,3,3,64,0.68085106382978722,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Static 24-h renewal","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","3-3"]
["Scores",10,10,5,5,0,0,2,0,5,4,4,0,0,4,0,3,3,3,3,3,64,0.68085106382978722,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Static 24-h renewal","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","3-4"]
["Scores",10,10,5,5,0,0,2,0,5,4,4,0,0,4,0,3,3,3,3,3,64,0.68085106382978722,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Static 24-h renewal","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","7-1"]
["Scores",10,10,5,5,0,0,2,0,5,4,4,0,0,4,0,1,0,0,3,3,56,0.5957446808510638,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Static 24-h renewal","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","7-2"]
["Scores",10,10,5,5,0,0,2,0,5,4,4,0,0,4,0,1,0,0,3,3,56,0.5957446808510638,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Static 24-h renewal","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","10-1"]
["Scores",10,10,5,5,0,0,0,0,5,4,4,0,0,0,0,3,3,3,3,0,55,0.58510638297872342,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Static 24-h renewal","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","10-2"]
["Scores",10,10,5,5,0,0,0,0,5,4,4,0,0,0,0,3,3,3,3,0,55,0.58510638297872342,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Static 24-h renewal","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","10-3"]
["Scores",10,10,5,5,0,0,0,0,5,4,4,0,0,0,0,3,3,3,3,0,55,0.58510638297872342,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Static 24-h renewal","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","10-2"]
["Scores",10,10,5,5,0,0,0,0,5,4,4,0,0,0,0,3,3,3,3,0,55,0.58510638297872342,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Static 24-h renewal","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","11-1"]
["Scores",10,10,5,5,0,5,0,0,5,4,4,0,0,0,0,3,0,1,3,0,55,0.58510638297872342,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Flow thru","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","11-2"]
["Scores",10,10,5,5,0,5,0,0,5,4,4,0,0,0,0,3,0,1,3,0,55,0.58510638297872342,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Flow thru","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","12-2"]
["Scores",10,10,5,5,0,5,0,0,5,4,4,0,0,0,0,3,0,1,3,0,55,0.58510638297872342,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Flow thru","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","11-2"]
["Scores",10,10,5,5,0,5,0,0,5,4,4,0,0,0,0,3,0,1,3,0,55,0.58510638297872342,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Flow thru","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","12-1"]
["Scores",10,10,5,5,0,5,0,0,5,4,4,0,0,0,0,3,0,1,3,0,55,0.58510638297872342,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Flow thru","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","13-1"]
["Scores",10,10,5,5,0,5,0,0,5,4,4,0,0,0,0,3,1,1,3,0,56,0.5957446808510638,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Flow thru","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","13-2"]
["Scores",10,10,5,5,0,5,0,0,5,4,4,0,0,0,0,3,1,1,3,0,56,0.5957446808510638,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Flow thru","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","13-3"]
["Scores",10,10,5,5,0,5,0,0,5,4,4,0,0,0,0,3,1,1,3,0,56,0.5957446808510638,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Flow thru","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","13-4"]
["Scores",10,10,5,5,0,5,0,0,5,4,4,0,0,0,0,3,1,1,3,0,56,0.5957446808510638,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Flow thru","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","13-5"]
["Scores",10,10,5,5,0,5,0,0,5,4,4,0,0,0,0,3,1,1,3,0,56,0.5957446808510638,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Flow thru","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","14-1"]
["Scores",10,10,5,5,0,5,0,0,5,4,4,0,0,0,0,3,0,3,3,0,57,0.6063829787234043,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Static","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","14-1"]
["Scores",10,10,5,5,0,5,0,0,5,4,4,0,0,0,0,3,0,3,3,0,57,0.6063829787234043,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Static","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","14-2"]
["Scores",10,10,5,5,0,5,0,0,5,4,4,0,0,0,0,3,0,3,3,0,57,0.6063829787234043,""]
["Answers","Yes","Stated and defined","LC",50,"Yes","","Inferred","No","Seawater","Static","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","2-4"]
["Scores",10,10,5,5,0,0,0,0,5,4,2,0,0,0,0,3,0,3,3,0,50,0.53191489361702127,""]
["Answers","Yes","Stated and defined","LC",50,"No","","Inferred","No","Seawater","Static","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","2-2"]
["Scores",10,10,5,5,0,0,0,0,5,4,2,0,0,0,0,3,0,3,3,0,50,0.53191489361702127,""]
["Answers","Yes","Stated and defined","LC",50,"No","","Inferred","No","Seawater","Static","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","2-3"]
["Scores",10,10,5,5,0,0,0,0,5,4,2,0,0,0,0,3,0,3,3,0,50,0.53191489361702127,""]
["Answers","Yes","Stated and defined","LC",50,"No","","Inferred","No","Seawater","Static","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","2-1"]
["Scores",10,10,5,5,0,0,0,0,5,4,2,0,0,0,0,3,0,3,3,0,50,0.53191489361702127,""]
["Answers","Yes","Stated and defined","LC",50,"No","","Inferred","No","Seawater","Static","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]
["Category","MEW_nonplant","Paper and data unique identifier(eg. 1-1,10-150)","1-1"]
["Scores",10,10,5,5,5,5,2,0,5,4,4,0,0,0,4,1,0,3,1,0,64,0.68085106382978722,""]
["Answers","Yes","Stated and defined","LC",50,"No","","Inferred","No","Seawater","Static","","No","No","Yes","No","Stated","Not measured","Stated","Stated","Yes"]

{"sheet":"MEW plant","index":31,"n_rows":81,"n_cols":53,"rows_kept":81,"cut":false,"hidden":false,"merged":[[52,2,54,2],[52,7,54,7],[59,7,61,7],[62,2,64,2],[62,7,64,7],[56,1,58,1],[56,2,58,2],[56,7,58,7],[65,2,68,2],[65,7,68,7],[43,2,45,2],[43,7,45,7],[46,2,48,2],[46,7,48,7],[49,2,51,2],[49,7,51,7],[34,2,36,2],[34,7,36,7],[37,2,39,2],[37,7,39,7],[40,2,42,2],[40,7,42,7],[25,2,27,2],[25,7,27,7],[28,2,30,2],[28,7,30,7],[31,2,33,2],[31,7,33,7],[17,2,19,2],[17,7,19,7],[20,2,21,2],[20,7,21,7],[22,2,24,2],[22,7,24,7],[3,4,7,4],[9,2,9,4],[11,2,13,2],[11,7,13,7],[14,2,16,2],[14,7,16,7]]}
[null,1,"Fill in the blank cells below, based on information provided in the paper being assessed. You can either pick an option from the dropdown list or add the appropriate detail using the 'Add to list' button. ",null,null,{"$f":"IF(BA3=\"\",0,1)","v":1},null,null,null,null,null,null,null,null,"* All the text in RED are used for drop down list ,make changes with caution."]
[null,null,"Category",{"$f":"IF(AF3=\"\",0,1)","v":1},"MEW_plant",{"$f":"IF(E3=\"\",0,1)","v":1},"Citation No.",{"$f":"IF(ISERROR(FIND(\"-\",E3)),E3,LEFT(E3,FIND(\"-\",E3)-1))","v":"9"},null,"Taxonomic group",null,null,null,null,"Species",null,null,"Lifestage",null,null,"Exposure duration",null,null,"Measure of toxicity",null,null,"Toxicity endpoint",null,null,"Taxonomic group",null,null,"Phylum",null,null,"Class",null,null,"Media",null,null,"Temperature ",null,null,"Acute Or Chronic",null,null,"PH",null,null,"Salinity/Comdictivity"]
[null,null,"Paper and data unique identifier(eg. 1-1,10-150)",{"$f":"IF(AI3=\"\",0,1)","v":1},"9-3",{"$f":"IF(E4=\"\",0,1)","v":1},"Species (Scientific name)",null,null,"Phylum",null,null,null,null,"Aedes albopictus",10,{"$f":"IF(P3=0,\"\",INDEX(O3:O102,P3))","v":"Palaemonetes pugio"},"1 month",6,{"$f":"IF(S3=0,\"\",INDEX(R3:R102,S3))","v":0},"11 hour",4,{"$f":"IF(V3=0,\"\",INDEX(U3:U102,V3))","v":"96 h"},"LC50",5,{"$f":"IF(Y3=0,\"\",INDEX(X3:X102,Y3))","v":"Mortality"},"Fish ",6,{"$f":"IF(AB3=0,\"\",INDEX(AA3:AA102,AB3))","v":"LC50"},"Fish ",9,{"$f":"IF(AE3=0,\"\",INDEX(AD3:AD102,AE3))","v":"Shrimp"},"Chlorophyta",4,{"$f":"IF(AH3=0,\"\",INDEX(AG3:AG102,AH3))","v":"?"},"Branchiopoda",4,{"$f":"IF(AK3=0,\"\",INDEX(AJ3:AJ102,AK3))","v":"?"},"Freshwater",7,{"$f":"IF(AN3=0,\"\",INDEX(AM3:AM102,AN3))","v":"Seawater"},"15°C",5,{"$f":"IF(AQ3=0,\"\",INDEX(AP3:AP102,AQ3))","v":"19-28oC"},"Acute",5,{"$f":"IF(AT3=0,\"\",INDEX(AS3:AS102,AT3))","v":"Acute"},"N.A.",4,{"$f":"IF(AW3=0,\"\",INDEX(AV3:AV102,AW3))","v":"?"},"150 uS/cm",7,{"$f":"IF(AZ3=0,\"\",INDEX(AY3:AY102,AZ3))","v":"20‰"}]
[null,null,"Citation",{"$f":"IF(AL3=\"\",0,1)","v":1},"Roberts and Gleeson 1978",{"$f":"IF(H8=\"\",0,1)","v":1},"Lifestage",null,null,"Class",null,null,null,null,"Australian Bass",null,null,"1 year old",null,null,"13 days",null,null,"N.A.",null,null,"Microalga",null,null,"Microalga",null,null,"N.A.",null,null,"Chlorophyceae",null,null,"Marinewater",null,null,"25°C",null,null,"Chronic",null,null,"PH11",null,null,"30 ppt"]
[null,null,null,{"$f":"IF(AO3=\"\",0,1)","v":1},null,{"$f":"IF(AX3=\"\",0,1)","v":1},"Exposure duration",null,null,"Media",null,null,null,null,"N.A.",null,null,"N.A.",null,null,"N.A.",null,null,"NOEC",null,null,"N.A.",null,null,"N.A.",null,null,"Tracheophyta",null,null,"N.A.",null,null,"N.A.",null,null,"N.A.",null,null,"N.A.",null,null,"PH7.0",null,null,"N.A."]
[null,null,null,{"$f":"IF(AR3=\"\",0,1)","v":1},null,{"$f":"IF(Q3=\"\",0,1)","v":1},"Measure of toxicity",null,null,"Temperature ",null,null,null,null,"Isochrysis galbana",null,null,"-",null,null,"96 h",null,null,"Growth",null,null,"IC50",null,null,"Algae",null,null,"?",null,null,"?",null,null,"Seawater",null,null,"20oC",null,null,"Chronic",null,null,"?",null,null,"35‰?"]
[null,null,null,{"$f":"IF(AU3=\"\",0,1)","v":1},null,{"$f":"IF(T3=\"\",0,1)","v":1},"Toxicity endpoint",null,null,"Acute Or Chronic ",null,null,null,null,"Dunaliella salina",null,null,"Larvae",null,null,null,null,null,"Mortality",null,null,"EC10",null,null,"Oyster",null,null,null,null,null,null,null,null,"Synthetic seawater",null,null,"19-28oC",null,null,"Acute",null,null,null,null,null,"19-28‰"]
[null,null,null,null,null,{"$f":"IF(W3=\"\",0,1)","v":1},"Toxicity value",220,null,"PH",null,null,null,null,"Crassostrea virginica",null,null,null,null,null,null,null,null,null,null,null,"LC50",null,null,"Copepod",null,null,null,null,null,null,null,null,"Seawater 20‰",null,null,null,null,null,null,null,null,null,null,null,"15‰"]
[null,2,"Select the appropriate answer option to each question. Comments can be added to the cells in column H.",null,null,{"$f":"IF(Z3=\"\",0,1)","v":1},null,null,null,"Salinity/Conductivity",null,null,null,null,"Acartia tonsa",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Shrimp",null,null,null,null,null,null,null,null,"Seawater",null,null,null,null,null,null,null,null,null,null,null,"20‰"]
[null,"*","If the selected answer option does not work try clicking on any other cell first and then click back on the answer option again.",null,null,{"$f":"IF(AC3=\"\",0,1)","v":1},null,null,null,null,null,null,null,null,"Palaemonetes pugio",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Fish"]
[null,"No.","Question","Marks Awarded","Answer Options","Option References","Scores","Answers",null,null,null,null,null,null,"Menidia menidia",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Shrimp"]
[null,null,"Was the duration of the exposure stated (e.g. 48 or 96 h)?",10,null,1,{"$f":"IF(F15=0,0,INDEX($D12:$D13,F12,1))","v":10},"Yes",null,null,null,null,null,null,"Palaemonetes pugio"]
[null,1,null,0]
[]
[null,null,"Was the biological endpoint (e.g., immobilization or population growth) stated and defined (10 marks)? Award 5 marks if the biological endpoint is only stated.",10,null,1,{"$f":"IF(F15=0,0,INDEX($D15:$D17,F15,1))","v":10},"Yes"]
[null,2,null,5]
[null,null,null,0]
[null,null,"Was the biological effect stated (e.g. LC or NOEC)?",5,null,1,{"$f":"IF(F18=0,0,INDEX($D18:$D19,F18,1))","v":5},"Yes"]
[null,3,null,0]
[]
[null,4,"Was the biological effect quantified (e.g. 50% effect, 25% effect)? \nNote: The effect for NOEC and LOEC data must be quantified.",5,null,1,{"$f":"IF(F21=0,0,INDEX($D21:$D22,F21,1))","v":5},"Yes"]
[null,null,null,0]
[null,5,"Were appropriate controls (e.g. a no-toxicant control and/or solvent control) used?",5,null,2,{"$f":"IF(F23=0,0,INDEX($D23:$D24,F23,1))","v":0},"No"]
[null,null,null,0]
[]
[null,6,"Was each control and contaminant concentration at least duplicated?",5,null,2,{"$f":"IF(F26=0,0,INDEX($D26:$D27,F26,1))","v":0},"Not stated"]
[null,null,null,0]
[]
[null,7,"Were test acceptability criteria stated (e.g. mortality in controls must not exceed a certain percentage) (5 marks)?\nOR Were test acceptability criteria inferred (e.g. test method used [USEPA, OECD, ASTM etc.]) (award 2 marks). \nNote: Data that fail the acceptability criteria are automatically deemed to be of unacceptable quality and must not be used. ",5,null,2,{"$f":"IF(F29=0,0,INDEX($D29:$D31,F29,1))","v":2},"Inferred"]
[null,null,null,2]
[null,null,null,0]
[null,8,"Were the characteristics of the test organism (e.g. length, mass, age) stated?",5,null,1,{"$f":"IF(F32=0,0,INDEX($D32:$D34,F32,1))","v":5},"Yes"]
[null,null,null,0]
[]
[null,9,"Was the type of test media used stated?",5,null,1,{"$f":"IF(F35=0,0,INDEX($D35:$D37,F35,1))","v":5},"Synthetic seawater"]
[null,null,null,0]
[]
[null,null,"Was the type of exposure (e.g. static, flow through) stated? ",4,null,1,{"$f":"IF(F38=0,0,INDEX($D38:$D40,F38,1))","v":4},"Flowthrough"]
[null,10,null,0]
[]
[null,null,"Were the contaminant concentrations measured at the beginning and end of the exposure (4 marks)? Award 2 marks if they were measured only once during the test.\nNote: If the concentrations were not measured then automatically the data cannot be high quality. ",4,null,1,{"$f":"IF(F41=0,0,INDEX($D41:$D43,F41,1))","v":4},"Measured 3 times daily"]
[null,11,null,2]
[null,null,null,0]
[null,null,"Were parallel reference toxicant toxicity tests conducted?",4,null,2,{"$f":"IF(F44=0,0,INDEX($D44:$D46,F44,1))","v":0},"No"]
[null,12,null,0]
[]
[null,null,"Was there a concentration–response relationship either observable or stated?",4,null,2,{"$f":"IF(F47=0,0,INDEX($D47:$D49,F47,1))","v":0},"No"]
[null,13,null,0]
[]
[null,null,"Was an appropriate statistical method or model used to determine the toxicity?\nNote: They should be accepted by a recognised national or international regulatory body (e.g. USEPA, OECD, ASTM). ",4,null,1,{"$f":"IF(F50=0,0,INDEX($D50:$D52,F50,1))","v":4},"Yes"]
[null,14,null,0]
[]
[null,15,"For LC/EC/BEC data was an estimate of variability provided? \nOR \nFor NO EC/LOEC data was the significance level 0.05 or less?  \n\n",4,null,2,{"$f":"IF(F53=0,0,INDEX($D53:$D55,F53,1))","v":0},"No estimate"]
[null,null,null,0]
[]
[null,16,"Were the following parameters measured and stated? (3 marks if measured and stated, 1 mark if just measured)."]
[null,16.100000000000001,"Conductivity/Salinity",3,null,1,{"$f":"IF(F57=0,0,INDEX(D57:D59,F57,1))","v":3},"Not measured"]
[null,null,null,1]
[null,null,null,0]
[null,null,null,3,null,1,{"$f":"IF(F60=0,0,INDEX($D60:$D62,F60,1))","v":3},"Not measured"]
[null,16.2,"pH ",1]
[null,null,null,0]
[null,null,"Was the temperature measured and stated (3 marks)? Award 1 mark if the temperature was measured but not stated or if only the temperature settings of the room or chamber are stated.\n",3,null,1,{"$f":"IF(F63=0,0,INDEX($D63:$D65,F63,1))","v":3},"Stated"]
[null,17,null,1]
[null,null,null,0]
[null,null,"Were test solutions, blanks and/or controls tested for contamination OR were analytical reagent grade chemicals used or the highest possible purity chemicals used for the experiment? (3 marks).",3,null,2,{"$f":"IF(F66=0,0,INDEX($D66:$D67,F66,1))","v":0},"Not measured"]
[null,18,null,0]
[]
[null,null,null,null,null,null,null,null,{"$f":"(COUNTIF(F12:F67,\"=0\"))+COUNTIF(F1:F10,\"=0\")+COUNTIF(D2:D7,\"=0\")","v":0}]
[]
[]
[null,null,"Total score",null,null,null,{"$f":"IF(SUM(G12:G66)=0,\"\",SUM(G12:G66))","v":63}]
[null,null,"Total Max. possible score for the various types of data and contaminants ",null,{"$f":"D12+D15+D18+D21+D23+D26+D29+D32+D35+D38+D41+D44+D47+D50+D53+D60+D63+D66+D57","v":91}]
[null,null,"Quality Score",null,{"$f":"\"= [Total score / Total possible score] * 100 = \"","v":"= [Total score / Total possible score] * 100 = "},null,{"$f":"IF(ISERROR(G72/E73),#N/A,G72/E73)","v":0.69230769230769229},{"$f":"IF(F41=3,\"The highest possible grade for this datum is acceptable.\",\"\")","v":""}]
[]
[null,null,"H = high quality                           Quality score ≥ 80%    "]
[null,null,"A = acceptable quality         > 50% Quality score < 80%  "]
[null,null,"U = unacceptable quality              Quality score ≤ 50%"]
[]
[3,null,"Click the 'Save & Update' button to save and export the answers to the 'All results' worksheet. "]
[null,null,"Select the 'Reset Answers' button if you wish to clear all answers."]

{"sheet":"MEW plant_WS","index":32,"n_rows":26,"n_cols":23,"rows_kept":26,"cut":false,"hidden":false,"merged":[]}
[]
["Question No.",1,2,3,4,5,6,7,8,9,10,11,12,13,14,15,16.100000000000001,16.3,17,18,"Total Score","Quality Score","Comment "]
["Short Questions","Duration of the exposure ","Biological endpoint","Biological effect stated or not","Biological effect quantified or not","Appropriate controls","Control & contaminant concentration","Test acceptability criteria","Characteristics of the test organism"," Type of test media","Type of exposure","Contaminant concentrations","Parallel reference toxicant toxicity tests","Concentration–response relationship","Determine the toxicity","NOEC/LOEC or LC/EC/BEC","Conductivity/Salinity","PH","Temperature","Grade or purity"]
["Marks Awarded ","10 or 0","10,5 or 0","5 or 0 ","5 or 0 ","5 or 0 ","5 or 0 ","5 or 0 ","5 or 0 ","5 or 0 ","4 or 0","4 or 2 or 0","4 or 2","4 or 2","4 or 2","4 or 2","3 or 1 or 0","3 or 1 or 0","3 or 0","3 or 0 "]
["Max. Possible Score",10,10,5,5,5,5,5,5,5,4,4,4,4,4,4,3,3,3,3,{"$f":"SUM(B5:T5)","v":91}]
["Category","MEW_plant","Paper and data unique identifier(eg. 1-1,10-150)","8-1"]
["Scores",10,10,5,5,0,0,2,0,5,4,2,0,0,4,0,0,0,0,0,48,0.52747252747252749,""]
["Answers","Yes","Yes","Yes","Yes","No","Not stated","Inferred","No","Synthetic seawater","Static","Measyred once?","No","No","Yes","No estimate","Not measured","Not measured","Stated","Yes"]
["Category","MEW_plant","Paper and data unique identifier(eg. 1-1,10-150)","8-2"]
["Scores",10,10,5,5,0,0,2,0,5,4,2,0,0,4,0,0,0,0,0,48,0.52747252747252749,""]
["Answers","Yes","Yes","Yes","Yes","No","Not stated","Inferred","No","Synthetic seawater","Static","Measyred once?","No","No","Yes","No estimate","Not measured","Not measured","Stated","Yes"]
["Category","MEW_plant","Paper and data unique identifier(eg. 1-1,10-150)","9-1"]
["Scores",10,10,5,5,0,0,2,5,5,4,4,0,0,4,0,3,0,0,0,63,0.69230769230769229,""]
["Answers","Yes","Yes","Yes","Yes","No","Not stated","Inferred","Yes","Synthetic seawater","Flowthrough","Measured 3 times daily","No","No","Yes","No estimate","Not measured","Not measured","Stated","Not measured"]
["Category","MEW_plant","Paper and data unique identifier(eg. 1-1,10-150)","9-2"]
["Scores",10,10,5,5,0,0,2,5,5,4,4,0,0,4,0,3,0,0,0,63,0.69230769230769229,""]
["Answers","Yes","Yes","Yes","Yes","No","Not stated","Inferred","Yes","Synthetic seawater","Flowthrough","Measured 3 times daily","No","No","Yes","No estimate","Not measured","Not measured","Stated","Not measured"]
["Category","MEW_plant","Paper and data unique identifier(eg. 1-1,10-150)","9-3"]
["Scores",10,10,5,5,0,0,2,5,5,4,4,0,0,4,0,3,0,0,0,63,0.69230769230769229,""]
["Answers","Yes","Yes","Yes","Yes","No","Not stated","Inferred","Yes","Synthetic seawater","Flowthrough","Measured 3 times daily","No","No","Yes","No estimate","Not measured","Not measured","Stated","Not measured"]
["Category","MEW_plant","Paper and data unique identifier(eg. 1-1,10-150)","9-4"]
["Scores",10,10,5,5,0,0,2,5,5,4,4,0,0,4,0,3,0,0,0,63,0.69230769230769229,""]
["Answers","Yes","Yes","Yes","Yes","No","Not stated","Inferred","Yes","Synthetic seawater","Flowthrough","Measured 3 times daily","No","No","Yes","No estimate","Not measured","Not measured","Stated","Not measured"]
["Category","MEW_plant","Paper and data unique identifier(eg. 1-1,10-150)","9-3"]
["Scores",10,10,5,5,0,0,2,5,5,4,4,0,0,4,0,3,0,0,0,63,0.69230769230769229,""]
["Answers","Yes","Yes","Yes","Yes","No","Not stated","Inferred","Yes","Synthetic seawater","Flowthrough","Measured 3 times daily","No","No","Yes","No estimate","Not measured","Not measured","Stated","Not measured"]

{"sheet":"Terrestrial Data QA","index":33,"n_rows":98,"n_cols":25,"rows_kept":98,"cut":false,"hidden":false,"merged":[[80,2,82,2],[80,7,82,7],[83,2,86,2],[83,7,86,7],[76,2,79,2],[76,7,79,7],[3,4,7,4],[53,7,56,7],[57,7,60,7],[37,7,39,7],[40,7,42,7],[43,7,45,7],[46,7,48,7],[34,7,36,7],[28,7,30,7],[31,7,33,7],[61,7,64,7],[65,7,68,7],[11,7,13,7],[49,7,51,7],[14,7,16,7],[22,7,24,7],[25,7,27,7],[17,7,19,7],[20,7,21,7],[11,2,13,2],[20,2,21,2],[22,2,24,2],[25,2,27,2],[14,2,16,2],[17,2,19,2],[72,7,75,7],[34,2,36,2],[28,2,30,2],[57,2,60,2],[37,2,39,2],[40,2,42,2],[72,2,75,2],[43,2,45,2],[31,2,33,2],[69,2,71,2],[46,2,48,2],[49,2,51,2],[53,2,56,2],[61,2,64,2],[65,2,68,2],[69,7,71,7]]}
[null,1,"FILL IN BLANKS BELOW,PICK OPTIONS FROM DROPDOWN LIST",null,null,null,null,null,null,null,"* All the text in Blue are used for drop down list ,make changes with caution."]
[null,null,"Category",null,"Terrestrial Quality",{"$f":"IF(M3=\"\",0,1)","v":0},"Citation No.",{"$f":"IF(ISERROR(FIND(\"-\",E3)),E3,LEFT(E3,FIND(\"-\",E3)-1))","v":0},null,null,"Species",null,null,"Lifestage",null,null,"Exposure duration",null,null,"Measure of toxicity",null,null,"Toxicity endpoint"]
[null,null,"Paper and data unique identifier(eg. 1-1,10-150)",null,null,{"$f":"IF(E3=\"\",0,1)","v":0},"Species (Scientific name)",null,null,null,"Australian Bass",0,{"$f":"IF(L3=0,\"\",INDEX(K3:K47,L3))","v":""},"Phase 1",0,{"$f":"IF(O3=0,\"\",INDEX(N3:N47,O3))","v":""},"1 hour ",0,{"$f":"IF(R3=0,\"\",INDEX(Q3:Q47,R3))","v":""},"Method 1",0,{"$f":"IF(U3=0,\"\",INDEX(T3:T47,U3))","v":""},0.01,0,{"$f":"IF(X3=0,\"\",INDEX(W3:W47,X3))","v":""}]
[null,null,"Citation",null,null,{"$f":"IF(E4=\"\",0,1)","v":0},"Lifestage",null,null,null,"Bala Shark",null,null,"Phase 2",null,null,"2 hours",null,null,"Method 2",null,null,0.02]
[null,null,null,null,null,{"$f":"IF(S3=\"\",0,1)","v":0},"Exposure duration",null,null,null,"Basa",null,null,"Phase 3",null,null,"3 hours",null,null,"Method 3",null,null,0.03]
[null,null,null,null,null,{"$f":"IF(V3=\"\",0,1)","v":0},"Measure of toxicity",null,null,null,"Black Parinha",null,null,"Phase 4",null,null,"4 hours",null,null,"Method 4",null,null,0.04]
[null,null,null,null,null,{"$f":"IF(Y3=\"\",0,1)","v":0},"Toxicity endpoint",null,null,null,"Catfish",null,null,"Phase 5",null,null,"5 Hours",null,null,"Method 5",null,null,0.05]
[null,null,null,null,null,{"$f":"IF(H8=\"\",0,1)","v":0},"Toxicity value",null,null,null,null,null,null,"phase 6"]
[null,2,"CHOOSE ANSWER OPTIONS AND FILL IN ANSWERS IN ANSWER COLUMN",null,null,{"$f":"IF(M3=\"\",0,1)","v":0}]
[null,"*","If had problem click on answer options,click on any  other cells first and then click back again",null,null,{"$f":"IF(P3=\"\",0,1)","v":0}]
[null,"No.","Question","Marks Awarded","Answer Options","Option References","Scores","Answers"]
[null,null,"Was the duration of the exposure stated (e.g., 48 or 96 h)?",10,null,0,{"$f":"IF(F15=0,0,INDEX($D12:$D13,F12,1))","v":0}]
[null,1,null,0]
[]
[null,null,"Was the biological endpoint (e.g., immobilization or population growth) stated and defined (10 marks)? Award 5 marks if the biological endpoint is only stated.",10,null,0,{"$f":"IF(F15=0,0,INDEX($D15:$D17,F15,1))","v":0}]
[null,2,null,5]
[null,null,null,0]
[null,null,"Was the biological effect stated (e.g., LC or NOEC)?",5,null,0,{"$f":"IF(F18=0,0,INDEX($D18:$D19,F18,1))","v":0}]
[null,3,null,0]
[]
[null,4,"Was the biological effect quantified (e.g., 50% effect, 25% effect)? The effect for NOEC and LOEC data must be quantified.",5,null,0,{"$f":"IF(F21=0,0,INDEX($D21:$D22,F21,1))","v":0}]
[null,null,null,0]
[null,5,"Were appropriate controls (e.g., a no-toxicant control and/or solvent control) used?",5,null,0,{"$f":"IF(F23=0,0,INDEX($D23:$D24,F23,1))","v":0}]
[null,null,null,0]
[]
[null,6,"Was each control and contaminant concentration at least duplicated?",5,null,0,{"$f":"IF(F26=0,0,INDEX($D26:$D27,F26,1))","v":0}]
[null,null,null,0]
[]
[null,7,"Were test acceptability criteria stated (e.g., mortality in controls must not exceed a certain percentage) (5 marks)?\nOR\nWere test acceptability criteria inferred (e.g., test method used [USEPA, OECD, ASTM etc]) (award 2 marks). Note: Invalid data must no",5,null,0,{"$f":"IF(F29=0,0,INDEX($D29:$D31,F29,1))","v":0}]
[null,null,null,2]
[null,null,null,0]
[null,8,"Were the characteristics of the test organism (e.g., length, mass, age) stated?",5,null,0,{"$f":"IF(F32=0,0,INDEX($D32:$D34,F32,1))","v":0}]
[null,null,null,0]
[]
[null,9,"Was the type of test media used stated?",5,null,0,{"$f":"IF(F35=0,0,INDEX($D35:$D37,F35,1))","v":0}]
[null,null,null,0]
[]
[null,null,"Were the contaminant concentrations measured?",4,null,0,{"$f":"IF(F38=0,0,INDEX($D38:$D40,F38,1))","v":0}]
[null,10,null,0]
[]
[null,null,"Were parallel reference toxicant toxicity tests conducted?",4,null,0,{"$f":"IF(F41=0,0,INDEX($D41:$D43,F41,1))","v":0}]
[null,11,null,0]
[]
[null,null,"Was there a concentration–response relationship either observable or stated",4,null,0,{"$f":"IF(F44=0,0,INDEX($D44:$D46,F44,1))","v":0}]
[null,12,null,0]
[]
[null,null,"Was an appropriate statistical method or model used to determine the toxicity?",4,null,0,{"$f":"IF(F47=0,0,INDEX($D47:$D49,F47,1))","v":0}]
[null,13,null,0]
[]
[null,14,"For NOEC/LOEC data was the significance level 0.05 or less?   Or                                         For LC/EC/BEC data was an estimate of variability provided?\n\n",4,null,0,{"$f":"IF(F50=0,0,INDEX($D50:$D52,F50,1))","v":0}]
[null,null,null,0]
[]
[null,15,"Were the following parameters measured and stated? (3 marks if measured and stated, 1 if just measured)"]
[null,null,"pH",3,null,0,{"$f":"IF(F54=0,0,INDEX($D54:$D56,F54,1))","v":0}]
[null,15.1,null,1]
[null,null,null,0]
[]
[null,null,"OM or OC content",3,null,0,{"$f":"IF(F58=0,0,INDEX($D58:$D60,F58,1))","v":0}]
[null,15.2,null,1]
[null,null,null,0]
[]
[null,null,"Clay Contect",3,null,0,{"$f":"IF(F62=0,0,INDEX($D62:$D64,F62,1))","v":0}]
[null,15.3,null,1]
[null,null,null,0]
[]
[null,null,"CEC",3,null,0,{"$f":"IF(F66=0,0,INDEX($D66:$D68,F66,1))","v":0}]
[null,15.4,null,1]
[null,null,null,0]
[]
[null,null,"Was the temperature measured and stated?",3,null,0,{"$f":"IF(F70=0,0,INDEX($D70:$D72,F70,1))","v":0}]
[null,16,null,0]
[]
[null,null,"Was the grade or purity of the test contaminant stated?",3,null,0,{"$f":"IF(F73=0,0,INDEX($D73:$D74,F73,1))","v":0}]
[null,17,null,0]
[]
[]
[null,null,"Were other cations and or major soil elements measured?                                                  Or                                                                                                                             Were known interacting elements on bioavailability measured (e.g. Mo for Cu and Cl for Cd)?",3,null,0,{"$f":"IF(F77=0,0,INDEX($D77:$D78,F77,1))","v":0}]
[null,18,null,0]
[]
[]
[null,null,"For spiked soils with metal salts: Were the soils leached after spiking?",3,null,0,{"$f":"IF(F81=0,0,INDEX($D81:$D83,F81,1))","v":0}]
[null,19,null,0]
[]
[null,null,"Were the incubation conditions and duration stated?",3,null,0,{"$f":"IF(F84=0,0,INDEX($D84:$D87,F84,1))","v":0}]
[null,20,null,1]
[null,null,null,0]
[null,null,null,null,null,null,null,null,{"$f":"(COUNTIF(F12:F87,\"=0\"))+COUNTIF(F2:F10,\"=0\")","v":32}]
[]
[]
[null,null,"Total Score",null,null,null,{"$f":"IF(SUM(G12:G84)=0,\"\",SUM(G12:G84))","v":""}]
[null,null,"Total Max. possible score for the various types of data and contaminants ",null,{"$f":"D12+D15+D18+D21+D23+D26+D29+D32+D35+D38+D41+D44+D47+D50+D54+D58+D62+D66+D70+D73+D77+D81+D84","v":102}]
[null,null,"Quality Score",null,{"$f":"\"= [Total score / Total possible score] * 100 = \"","v":"= [Total score / Total possible score] * 100 = "},null,{"$f":"IF(ISERROR(G90/E91),#N/A,G90/E91)","v":{"$error":"#N/A"}}]
[]
[null,null,"H = high quality                           Quality score >=80%      "]
[null,null,"A = acceptable quality         80%>Quality score>50%      "]
[null,null,"U = unacceptable quality              Quality score <=50%  "]
[]
[3,null,"CLICK \"Save&Update\" BUTTON TO SAVE ANSWER TO SAMPLE FINALISED ASSESSMENT SHEET"]

{"sheet":"Terrestrial Quality","index":34,"n_rows":5,"n_cols":26,"rows_kept":5,"cut":false,"hidden":false,"merged":[]}
[]
["Question No.",1,2,3,4,5,6,7,8,9,10,11,12,13,14,15.1,15.2,15.3,15.4,16,17,18,19,20,"Total Score","Quality Score"]
["Short Questions","duration of the exposure  ","biological endpoint","biological effect stated or not","biological effect qualified or not","appropriate controls","control & contaminant concentration","test acceptability criteria ","characteristics of the test organism"," type of test media"," contaminant concentrations "," parallel reference toxicant toxicity","concentration–response relationship"," statistical method or model to determine the toxicity","LC/EC/BEC data","pH","OM or OC content","Clay content","CEC","Temperature","Grade or purity","cations and or major soil elements measured or  interacting elements on bioavailability measured ","soils leached after spiking","incubation conditions and duration"]
["Marks Awarded","10 or 0","10,5 or 0","5 or 0 ","5 or 0 ","5 or 0 ","5 or 0 ","5 ,2 or 0 ","5 or 0 ","5 or 0 ","4 or 0","4 or 0","4 or 0","4 or 0","4 or 0","3,1,or 0","3,1,or 0","3,1,or 0","3,1,or 0","3 or 0","3 or 0","3 or 0","3 or 0","3 or 0"]
["Max. Possible Score",10,10,5,5,5,5,5,5,5,4,4,4,4,4,3,3,3,3,3,3,3,3,3,{"$f":"SUM(B5:X5)","v":102}]

{"sheet":"Sediment Data QA","index":35,"n_rows":103,"n_cols":25,"rows_kept":103,"cut":false,"hidden":false,"merged":[[72,7,75,7],[76,7,79,7],[52,7,54,7],[89,2,90,2],[68,2,71,2],[80,2,82,2],[72,2,75,2],[76,2,79,2],[80,7,82,7],[64,2,67,2],[64,7,67,7],[68,7,71,7],[60,2,63,2],[56,2,59,2],[91,2,92,2],[89,7,90,7],[91,7,92,7],[87,7,88,7],[83,7,86,7],[83,2,86,2],[40,2,42,2],[46,2,48,2],[49,2,51,2],[52,2,54,2],[43,2,45,2],[28,2,30,2],[22,7,24,7],[25,7,27,7],[31,2,33,2],[37,7,39,7],[34,2,36,2],[37,2,39,2],[11,2,13,2],[20,2,21,2],[22,2,24,2],[25,2,27,2],[14,2,16,2],[17,2,19,2],[3,4,7,4],[56,7,59,7],[60,7,63,7],[40,7,42,7],[43,7,45,7],[46,7,48,7],[11,7,13,7],[17,7,19,7],[49,7,51,7],[34,7,36,7],[14,7,16,7],[20,7,21,7],[28,7,30,7],[31,7,33,7]]}
[null,1,"FILL IN BLANKS BELOW,PICK OPTIONS FROM DROPDOWN LIST",null,null,null,null,null,null,null,"* All the text in Blue are used for drop down list ,make changes with caution."]
[null,null,"Category",null,"Sediment ",{"$f":"IF(M3=\"\",0,1)","v":0},"Citation No.",{"$f":"IF(ISERROR(FIND(\"-\",E3)),E3,LEFT(E3,FIND(\"-\",E3)-1))","v":0},null,null,"Species",null,null,"Lifestage",null,null,"Exposure duration",null,null,"Measure of toxicity",null,null,"Toxicity endpoint"]
[null,null,"Paper and data unique identifier(eg. 1-1,10-150)",null,null,{"$f":"IF(E3=\"\",0,1)","v":0},"Species (Scientific name)",null,null,null,"Australian Bass",0,{"$f":"IF(L3=0,\"\",INDEX(K3:K50,L3))","v":""},"Phase 1",0,{"$f":"IF(O3=0,\"\",INDEX(N3:N50,O3))","v":""},"1 hour ",0,{"$f":"IF(R3=0,\"\",INDEX(Q3:Q50,R3))","v":""},"Method 1",0,{"$f":"IF(U3=0,\"\",INDEX(T3:T50,U3))","v":""},0.01,0,{"$f":"IF(X3=0,\"\",INDEX(W3:W50,X3))","v":""}]
[null,null,"Citation",null,null,{"$f":"IF(E4=\"\",0,1)","v":0},"Lifestage",null,null,null,"Bala Shark",null,null,"Phase 10",null,null,"2 hours",null,null,"Method 10",null,null,0.02]
[null,null,null,null,null,{"$f":"IF(S3=\"\",0,1)","v":0},"Exposure duration",null,null,null,"Basa",null,null,"phase 14",null,null,"3 hours",null,null,"Method 2",null,null,0.03]
[null,null,null,null,null,{"$f":"IF(V3=\"\",0,1)","v":0},"Measure of toxicity",null,null,null,"Black Parinha",null,null,"Phase 2",null,null,"4 hours",null,null,"Method 3",null,null,0.04]
[null,null,null,null,null,{"$f":"IF(Y3=\"\",0,1)","v":0},"Toxicity endpoint",null,null,null,"Catfish",null,null,"Phase 3",null,null,"5 hours",null,null,"Method 4",null,null,0.05]
[null,null,null,null,null,{"$f":"IF(H8=\"\",0,1)","v":0},"Toxicity value",null,null,null,"Eel",null,null,"Phase 4",null,null,"6 hours",null,null,"Method 5",null,null,0.06]
[null,2,"CHOOSE ANSWER OPTIONS AND FILL IN ANSWERS IN ANSWER COLUMN",null,null,{"$f":"IF(M3=\"\",0,1)","v":0},null,null,null,null,"Lungfish",null,null,"Phase 5",null,null,"7 hours",null,null,"Method 6",null,null,7.0000000000000007E-2]
[null,"*","If had problem click on answer options,click on any  other cells first and then click back again",null,null,{"$f":"IF(P3=\"\",0,1)","v":0},null,null,null,null,"Murray Cod",null,null,"Phase 6",null,null,"8 hours",null,null,"Method 7",null,null,0.08]
[null,"No.","Question","Marks Awarded","Answer Options","Option References","Scores","Answers",null,null,"Nemo",null,null,"Phase 7 ",null,null,"9 hours",null,null,"Method 8",null,null,0.09]
[null,null,"Was the duration of the exposure stated (e.g., 48 or 96 h)?",10,null,0,{"$f":"IF(F15=0,0,INDEX($D12:$D13,F12,1))","v":0},null,null,null,"Redclaw",null,null,"Phase 8",null,null,null,null,null,null,null,null,0.1]
[null,1,null,0,null,null,null,null,null,null,"Sea Mullet",null,null,"Phase 9"]
[null,null,null,null,null,null,null,null,null,null,"SilverPerch"]
[null,null,"Was the biological endpoint (e.g., immobilization or population growth) stated and defined (10 marks)? Award 5 marks if the biological endpoint is only stated.",10,null,0,{"$f":"IF(F15=0,0,INDEX($D15:$D17,F15,1))","v":0},null,null,null,"Whale"]
[null,2,null,5]
[null,null,null,0]
[null,null,"Was the biological effect stated (e.g., LC or NOEC)?",5,null,0,{"$f":"IF(F18=0,0,INDEX($D18:$D19,F18,1))","v":0}]
[null,3,null,0]
[]
[null,4,"Was the biological effect quantified (e.g., 50% effect, 25% effect)? The effect for NOEC and LOEC data must be quantified.",5,null,0,{"$f":"IF(F21=0,0,INDEX($D21:$D22,F21,1))","v":0}]
[null,null,null,0]
[null,5,"Were appropriate controls (e.g., a no-toxicant control and/or solvent control) used?",5,null,0,{"$f":"IF(F23=0,0,INDEX($D23:$D24,F23,1))","v":0}]
[null,null,null,0]
[]
[null,6,"Was each control and contaminant concentration at least duplicated?",5,null,0,{"$f":"IF(F26=0,0,INDEX($D26:$D27,F26,1))","v":0}]
[null,null,null,0]
[]
[null,7,"Were test acceptability criteria stated (e.g., mortality in controls must not exceed a certain percentage) (5 marks)?\nOR\nWere test acceptability criteria inferred (e.g., test method used [USEPA, OECD, ASTM etc]) (award 2 marks). Note: Invalid data must no",5,null,0,{"$f":"IF(F29=0,0,INDEX($D29:$D31,F29,1))","v":0}]
[null,null,null,2]
[null,null,null,0]
[null,8,"Were the characteristics of the test organism (e.g., length, mass, age) stated?",5,null,0,{"$f":"IF(F32=0,0,INDEX($D32:$D34,F32,1))","v":0}]
[null,null,null,0]
[]
[null,9,"Was the type of test media used stated?",5,null,0,{"$f":"IF(F35=0,0,INDEX($D35:$D37,F35,1))","v":0}]
[null,null,null,0]
[]
[null,null,"Was the type of exposure (e.g. static, flow through) stated? ",4,null,0,{"$f":"IF(F38=0,0,INDEX($D38:$D40,F38,1))","v":0}]
[null,10,null,0]
[]
[null,null,"Were the contaminant concentrations measured?",4,null,0,{"$f":"IF(F41=0,0,INDEX($D41:$D43,F41,1))","v":0}]
[null,11,null,0]
[]
[null,null,"Were parallel reference toxicant toxicity tests conducted?",4,null,0,{"$f":"IF(F44=0,0,INDEX($D44:$D46,F44,1))","v":0}]
[null,12,null,0]
[]
[null,null,"Was there a concentration–response relationship either observable or stated",4,null,0,{"$f":"IF(F47=0,0,INDEX($D47:$D49,F47,1))","v":0}]
[null,13,null,0]
[]
[null,null,"Was an appropriate statistical method or model used to determine the toxicity?",4,null,0,{"$f":"IF(F50=0,0,INDEX($D50:$D52,F50,1))","v":0}]
[null,14,null,0]
[]
[null,15,"For LC/EC/BEC data values derived was an estimate of variability provided? (10/20 effects data desirable)\nOR If NO EC/LOEC data, was the significance level 0.05 or less?                                                 \n\n",4,null,0,{"$f":"IF(F53=0,0,INDEX($D53:$D55,F53,1))","v":0}]
[null,null,null,0]
[]
[null,16,"Were the following parameters measured and stated? (3 marks if measured and stated, 1 if just measured)"]
[null,null,"pH",3,null,0,{"$f":"IF(F57=0,0,INDEX($D57:$D59,F57,1))","v":0}]
[null,16.100000000000001,null,1]
[null,null,null,0]
[]
[null,null,"Particulate organic carbon (POC)",3,null,0,{"$f":"IF(F61=0,0,INDEX($D61:$D63,F61,1))","v":0}]
[null,16.2,null,1]
[null,null,null,0]
[]
[null,null,"Particle size (e.g. <63 µm or silt/clay)",3,null,0,{"$f":"IF(F65=0,0,INDEX($D65:$D67,F65,1))","v":0}]
[null,16.3,null,1]
[null,null,null,0]
[]
[null,null,"Acid-volatile sulfide (AVS) and 1-M HCl extractable metals",3,null,0,{"$f":"IF(F69=0,0,INDEX($D69:$D71,F69,1))","v":0}]
[null,16.399999999999999,null,1]
[null,null,null,0]
[]
[null,null,"Dissolved contaminants (e.g. metals) in porewater or overlying water",3,null,0,{"$f":"IF(F73=0,0,INDEX($D73:$D75,F73,1))","v":0}]
[null,16.5,null,1]
[null,null,null,0]
[]
[null,null,"Dissolved ammonia and sulfide in porewater or overlying water",3,null,0,{"$f":"IF(F77=0,0,INDEX($D77:$D79,F77,1))","v":0}]
[null,16.600000000000001,null,1]
[null,null,null,0]
[]
[null,null,"Was the temperature measured and stated?",3,null,0,{"$f":"IF(F81=0,0,INDEX($D81:$D83,F81,1))","v":0}]
[null,17,null,0]
[]
[null,null,"Was the grade or purity of the test contaminant stated?",3,null,0,{"$f":"IF(F84=0,0,INDEX($D84:$D85,F84,1))","v":0}]
[null,18,null,0]
[]
[]
[null,19,"Was the salinity/conductivity measured and stated?",3,null,0,{"$f":"IF(F88=0,0,INDEX($D88:$D89,F88,1))","v":0}]
[null,null,null,0]
[null,20,"Was the alkalinity, hardness, or concentrations of Ca and Mg measured in the overlying water?Were known interacting elements on bioavailability measured (e.g. Cl for Cd)?",3,null,0,{"$f":"IF(F90=0,0,INDEX($D90:$D91,F90,1))","v":0}]
[null,null,null,0]
[null,21,"For sediments spiked with metal salts were the equilibration conditions adequate?",3,null,0,{"$f":"IF(F92=0,0,INDEX($D92:$D93,F92,1))","v":0}]
[null,null,null,0,null,null,null,null,{"$f":"(COUNTIF(F12:F93,\"=0\"))+COUNTIF(F2:F10,\"=0\")","v":35}]
[]
[null,null,"Total score",null,null,null,{"$f":"IF(SUM(G12:G92)=0,\"\",SUM(G12:G92))","v":""}]
[null,null,"Total Max. possible score for the various types of data and contaminants ",null,{"$f":"D12+D15+D18+D21+D23+D26+D29+D32+D35+D38+D41+D44+D47+D50+D53+D57+D61+D65+D69+D73+D77+D81+D84+D88+D90+D92","v":112}]
[null,null,"Quality Score",null,{"$f":"\"= [Total score / Total possible score] * 100 = \"","v":"= [Total score / Total possible score] * 100 = "},null,{"$f":"IF(ISERROR(G95/E96),#N/A,G95/E96)","v":{"$error":"#N/A"}}]
[]
[null,null,"H = high quality                           Quality score >=80%      "]
[null,null,"A = acceptable quality         80%>Quality score>50%      "]
[null,null,"U = unacceptable quality              Quality score <=50%  "]
[]
[3,null,"CLICK \"Save&Update\" BUTTON TO SAVE ANSWER TO SAMPLE FINALISED ASSESSMENT SHEET"]

{"sheet":"Sediment Quality","index":36,"n_rows":5,"n_cols":29,"rows_kept":5,"cut":false,"hidden":false,"merged":[]}
[]
["Question No.",1,2,3,4,5,6,7,8,9,10,11,12,13,14,15,16.100000000000001,16.2,16.3,16.399999999999999,16.5,16.600000000000001,17,18,19,20,21,"Total Score","Quality Score"]
["Short Questions","duration of the exposure ","biological endpoint","biological effect stated ornot","biological effect quantified or not","appropriate controls","control & contaminant concentration","test acceptability criteria","characteristics of the test organism"," type of test media","type of exposure","contaminant concentrations","parallel reference toxicant toxicity tests","concentration–response relationship","determine the toxicity","LC/EC/BEC ","pH","POC","Particle size","AVS & 1-M HCl extractable metals","Dissolved contaminants","Dissolved ammonia and sulfide","Temperature","Grade or purity"," salinity/conductivity","alkalinity, hardness, or concentrations of Ca and Mg","equilibration conditions "]
["Marks Awarded","10 or 0","10,5 or 0","5 or 0 ","5 or 0 ","5 or 0 ","5 or 0 ","5 or 0 ","5 or 0 ","5 or 0 ","4 or 0","4 or 0","4 or 0","4 or 0","4 or 0","4 or 0","3,1,or 0","3,1,or 0","3,1,or 0","3,1,or 0","3,1,or 0","3,1,or 0","3 or 0","3 or 0","3 or 0","3 or 0"]
["Max. Possible Score",10,10,5,5,5,5,5,5,5,4,4,4,4,4,4,3,3,3,3,3,3,3,3,3,3,3,{"$f":"SUM(B5:AA5)","v":112}]

{"sheet":"Sheet2","index":37,"n_rows":0,"n_cols":0,"rows_kept":0,"cut":false,"hidden":false,"merged":[]}